{"id":1016,"date":"2019-10-31T16:09:21","date_gmt":"2019-10-31T15:09:21","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1016"},"modified":"2019-10-31T16:09:21","modified_gmt":"2019-10-31T15:09:21","slug":"jeudi-31-octobre-n317","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2019\/10\/31\/jeudi-31-octobre-n317\/","title":{"rendered":"Jeudi 31 octobre \u2013 n\u00b0317"},"content":{"rendered":"<h2><strong>\u00ab\u00a0OPINIONS ET ATTENTES DES CADRES\u00a0\u00bb CONF\u00c9RENCE DE PRESSE \u25cf 29 OCTOBRE 2019<\/strong><\/h2>\n<p><strong>L\u2019Ugict-CGT a tenu une conf\u00e9rence de presse le 29 octobre afin de pr\u00e9senter les r\u00e9sultats du barom\u00e8tre \u00ab\u00a0<em>Opinions et attentes des cadres<\/em>\u00a0\u00bb,<\/strong> salaires, pratiques manag\u00e9riales, \u00e9valuation individuelle, association aux strat\u00e9giques, charges de travail, temps de travail, \u00e9thique professionnelle, r\u00e9formes en cours (retraite, assurance ch\u00f4mage\u2026).<\/p>\n<p><strong>Vous trouverez en pi\u00e8ce jointe le dossier de presse ainsi que le barom\u00e8tre cadres <\/strong>r\u00e9alis\u00e9 par <em>Viavoice<\/em> : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2019\/10\/Sondage-cadres-Viavoice-pour-UGICT-CGT-2019-.pdf\">Sondage cadres Viavoice pour UGICT-CGT 2019<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>LANCEURS D\u2019ALERTE SUR LES LIEUX DE TRAVAIL EN EUROPE <\/strong><strong>\u009f<\/strong><strong> 6 &amp; 7 NOVEMBRE <\/strong><strong>\u009f<\/strong><strong> PARIS<\/strong><\/h2>\n<p><strong>Les 6 et 7 novembre Eurocadres et l\u2019Ugict-CGT organisent un s\u00e9minaire sur le th\u00e8me\u00a0: \u00ab\u00a0Lanceurs d\u2019alerte sur les lieux de travail en Europe\u00a0\u00bb<\/strong><\/p>\n<p><em>Au quotidien au travail, la libert\u00e9 d\u2019expression est sans cesse remise en cause, notamment pour l\u2019encadrement transform\u00e9, au nom d\u2019un \u00ab\u00a0devoir de loyaut\u00e9\u00a0\u00bb, en ex\u00e9cutant des directives financi\u00e8res.<\/em><\/p>\n<p><em>Ce s\u00e9minaire europ\u00e9en a lieu dans 4 villes\u00a0: Paris, Grenade, Dublin et Belgrade. \u00c0 Paris, l\u2019Ugict-CGT est charg\u00e9e de sa mise en place. Il se tiendra \u00e0 la Bourse du travail, 29 boulevard du Temple, Paris 75011. <strong>Attention\u00a0! les inscriptions sont limit\u00e9es pour le s\u00e9minaire du 6 novembre toute la journ\u00e9e et le 7 novembre matin.<\/strong><\/em><\/p>\n<p><em>Le s\u00e9minaire sera suivi d\u2019un meeting le 7 novembre, de 14 heures \u00e0 17 heures. Puis de la projection du film \u00ab\u00a0<strong>meeting snowden<\/strong>\u00a0\u00bb de 17 heures \u00e0 19 heures. S\u00e9minaire ouvert \u00e0 toutes et \u00e0 tous (sur inscription).<\/em><\/p>\n<p><strong><em>Voir en pi\u00e8ce jointe courrier aux organisations : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2019\/10\/2019-11-06-07-COURRIER-MEETING-LANCEURS-ALERTE.pdf\">2019 11 06 07 COURRIER MEETING LANCEURS ALERTE<\/a><br \/>\n<\/em><\/strong><\/p>\n<p><strong><em>Programme des 6 &amp; 7 novembre en pi\u00e8ce jointe : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2019\/09\/2019-11-6-7-SEMINAIRE-LANCEURS-DALERTE.pdf\">2019 11 6 7 SEMINAIRE LANCEURS D&rsquo;ALERTE<\/a><br \/>\n<\/em><\/strong><\/p>\n<p><strong><em><u><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdtRvXYXjH3jLpMU9ZJSU1O1vBB-exA5qavY5bDmBKmc-PU3w\/viewform\">S\u2019inscrire au s\u00e9minaire de formation d\u2019Eurocadres \u2192<\/a><\/u><\/em><\/strong><\/p>\n<p><strong><em><u><a href=\"http:\/\/www.ugict.cgt.fr\/ethique-contre-attaques\">S\u2019inscrire au meeting du 7 novembre journ\u00e9e \u2192<\/a><\/u><\/em><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>CADRES INFOS\u00a0: MOBILISATION RETRAITE, \u00c9LECTIONS 2<sup>e<\/sup>ET 3<sup>e<\/sup> COLL\u00c8GES<\/strong><\/h2>\n<p>Pour travailler l\u2019unit\u00e9 du salariat, construire la mobilisation et aider au vote CGT dans les 2<sup>e<\/sup>et 3<sup>e<\/sup> coll\u00e8ges, l\u2019Ugict-CGT va mettre \u00e0 disposition un <em>Cadres Infos<\/em> de 24 pages \u00e0 destination des ICTAM courant novembre, tir\u00e9 \u00e0 300\u00a0000 exemplaires. Il portera sur les sujets d\u2019actualit\u00e9 qui concernent l\u2019encadrement\u00a0: r\u00e9forme des retraites, n\u00e9gociation sur le statut de l\u2019encadrement, r\u00e9forme de l\u2019assurance ch\u00f4mage et de la fonction publique notamment.<\/p>\n<p>En pi\u00e8ces jointes\u00a0:<\/p>\n<ul>\n<li><strong>le courrier conf\u00e9d\u00e9ral<\/strong> pr\u00e9sentant le <em>Cadres Infos<\/em> et le \u00ab\u00a04 pages Retraites\u00a0\u00bb : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2019\/10\/16-10-19-Note-aux-orgas-re\u0301forme-des-retraites.pdf\">16 10 19 &#8211; Note aux orgas &#8211; re\u0301forme des retraites<\/a><\/li>\n<li><strong>la ventilation<\/strong> du <em>Cadres Infos<\/em> (pour tout renseignement, contact\u00a0: Caroline Blanchot\u00a0: <a href=\"mailto:blanchotcaro@yahoo.fr\">blanchotcaro@yahoo.fr<\/a>) : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2019\/10\/Ventilation-cadres-infos-par-re\u0301gion-et-par-departement.xlsx\">Ventilation cadres infos par re\u0301gion et par departement<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong>RETRAITES<\/strong><\/h2>\n<p>Le collectif \u00ab\u00a0Retraites\u00a0\u00bb de l\u2019Ugict-CGT est \u00e0 disposition pour intervenir dans les organisations et\/ou dans les entreprises, notamment dans le cadre des heures d\u2019informations syndicales.<\/p>\n<p>Vous pouvez en faire la demande directement en vous adressant \u00e0\u00a0: <a href=\"mailto:revendicatif@ugict.cgt.fr\">revendicatif@ugict.cgt.fr<\/a><\/p>\n<p>Retrouver tous les outils de la campagne sur le site d\u00e9di\u00e9<strong> <a href=\"x-webdoc:\/\/769C463D-A8C7-4C68-B659-E68738CF8C24\/reforme-retraite.info\/%20\"><em>reforme-retraite.info\/<\/em><\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>AGENDA<\/strong><\/h2>\n<ul>\n<li><strong>28 novembre\u00a0: Pr\u00e9vention des violences sexistes et sexuelles\u00a0: quels moyens d\u2019actions pour les repr\u00e9sentant.e.s du personnel et l\u2019encadrement\u00a0?<\/strong><\/li>\n<\/ul>\n<p>30\u00a0% des femmes disent avoir \u00e9t\u00e9 victimes de harc\u00e8lement sexuel au travail, 80\u00a0% de sexisme, chaque jour, 10 viols ou tentatives de viols se produisent sur un lieu de travail. La CGT et les organisations syndicales ont gagn\u00e9 la cr\u00e9ation dans la loi en 2018 de r\u00e9f\u00e9rent.e.s du personnel et de r\u00e9f\u00e9rent.e.s RH sur les violences sexistes et sexuelles. Cependant, leur r\u00f4le et moyens d\u2019action ne sont pas d\u00e9finis. Cette journ\u00e9e de formation s\u2019adresse prioritairement aux r\u00e9f\u00e9rent.e.s du personnel ou RH, et aux ing\u00e9s, cadres et techs en situation de management. Elle a pour objectif de conna\u00eetre la loi sur la d\u00e9finition des violences, savoir identifier les bonnes pratiques en mati\u00e8re de pr\u00e9vention et savoir comment r\u00e9agir en cas de violences sexistes et sexuelles.<\/p>\n<p><strong><em><u><a href=\"http:\/\/www.ugict.cgt.fr\/articles\/actus\/281119\">Programme et inscriptions \u2192<\/a><\/u><\/em><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>FORMATION<\/strong><\/h2>\n<p><strong>Deuxi\u00e8me semestre 2019<\/strong><\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/stage-national-ugict-cgt\"><strong>\u00catre responsable Ugict-CGT <\/strong><strong>\u2022<\/strong><strong> Contenu, animation et d\u00e9ploiement de l\u2019activit\u00e9 sp\u00e9cifique<\/strong><\/a><\/p>\n<p>du 02 au 06 d\u00e9cembre 2019 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p>Formations th\u00e9matiques<\/p>\n<p><strong>Attention\u00a0! annulation du stage \u00ab\u00a0Comprendre la financiarisation\u2026\u00a0\u00bb<\/strong><\/p>\n<p><em><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/construire-un-management-alternatif\"><strong>Comprendre la financiarisation de l\u2019entreprise et ses incidences pour restaurer le r\u00f4le contributif de l\u2019encadrement<\/strong><\/a><\/em><\/p>\n<p><em>du 24 au 29 novembre 2019 \u2022 Institut du Travail <\/em><em>\u2022 <\/em><em>Strasbourg (67)<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/SitesWeb\"><strong>Communication web\u00a0: Construire et g\u00e9rer un site avec Reference-Syndicale.fr<\/strong><\/a><\/p>\n<p>du 11 au 13 d\u00e9cembre 2019 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Premier semestre 2020<\/strong><\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/stage-national-ugict-cgt\"><strong>\u00catre responsable Ugict-CGT <\/strong><strong>\u2022<\/strong><strong> Contenu, animation et d\u00e9ploiement de l\u2019activit\u00e9 sp\u00e9cifique<\/strong><\/a><\/p>\n<p>du 02 au 06 mars 2020 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p>Formations th\u00e9matiques<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/SitesWeb\"><strong>Communication web\u00a0: Construire et g\u00e9rer un site avec Reference-Syndicale.fr<\/strong><\/a><\/p>\n<p>du 22 au 24 janvier 2020 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/stage-retraite\"><strong>R\u00e9forme des retraites\u00a0: Quels droits, \u00e0 quel \u00e2ge, pour quel niveau de vie\u00a0?<\/strong><\/a><\/p>\n<p>du 10 au 14 f\u00e9vrier 2020 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/SitesWeb\"><strong>Communication web\u00a0: Construire et g\u00e9rer un site avec Reference-Syndicale.fr<\/strong><\/a><\/p>\n<p>du 1<sup>er<\/sup> au 3 avril 2020 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/formation-management-alternatif\"><strong>Quelle strat\u00e9gie syndicale face au Wall Street management\u00a0?<\/strong><\/a><\/p>\n<p>du 28 au 29 avril 2020 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/stage-egalite-professionnelle\"><strong>\u00c9galit\u00e9 professionnelle<\/strong><\/a><\/p>\n<p>du 24 au 29 mai \u2022 Institut du Travail \u2022 Strasbourg (67)<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse <\/strong><a href=\"http:\/\/www.ugict.cgt.fr\/formation\">http:\/\/www.ugict.cgt.fr\/formation<\/a><\/p>\n<p><strong>Pour tout renseignement<\/strong><\/p>\n<p><a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a> \/\u00a0( <a href=\"tel:01%2055%2082%2083%2035\">01 55 82 83 40<\/a>)<\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale <\/strong><strong>\u00e0 l&rsquo;Activit\u00e9 sp\u00e9cifique<\/strong><strong>\u00a0<\/strong><a href=\"http:\/\/ugict.cgt.fr\/a2s\/\"><strong>http:\/\/ugict.cgt.fr\/a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00ab\u00a0OPINIONS ET ATTENTES DES CADRES\u00a0\u00bb CONF\u00c9RENCE DE PRESSE \u25cf 29 OCTOBRE 2019 L\u2019Ugict-CGT a tenu une conf\u00e9rence de presse le 29 octobre afin de pr\u00e9senter les r\u00e9sultats du barom\u00e8tre \u00ab\u00a0Opinions et attentes des cadres\u00a0\u00bb, salaires, pratiques manag\u00e9riales, \u00e9valuation individuelle, association aux strat\u00e9giques, charges de travail, temps de travail, \u00e9thique professionnelle, r\u00e9formes en cours (retraite, assurance [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14,11,6,48,20,5],"class_list":["post-1016","post","type-post","status-publish","format-standard","hentry","category-archives","tag-cadres","tag-elections","tag-formation","tag-lanceur-dalerte","tag-retraites","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1016","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1016"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1016\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1016"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1016"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1016"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}