{"id":1092,"date":"2020-03-25T15:07:01","date_gmt":"2020-03-25T14:07:01","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1092"},"modified":"2020-03-25T15:07:01","modified_gmt":"2020-03-25T14:07:01","slug":"vendredi-27-mars-n335","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2020\/03\/25\/vendredi-27-mars-n335\/","title":{"rendered":"Vendredi 27 mars \u2013 n\u00b0335"},"content":{"rendered":"<h2><strong>POUR FAIRE FACE ET CONSTRUIRE L&rsquo;AVENIR : LUTTEVIRALE.FR<\/strong><\/h2>\n<p>Alors que, selon les chiffres du minist\u00e8re du travail, 60 % des salari\u00e9\u00b7e\u00b7s continuent de travailler sur leur lieu de travail, l\u2019Ugict-CGT, les syndicats CGT de l\u2019inspection du travail et de la Direction Statistique du Minist\u00e8re du Travail (DARES) et des avocat\u00b7e\u00b7s militant\u00b7e\u00b7s lancent\u00a0<strong><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/presse\/pour-garantir-la-sante-et-la-securite-au-travail--lutteviralefr\">luttevirale.fr<\/a>, un site pour t\u00e9moigner, proposer, se d\u00e9fendre, construire les alternatives\u00a0d&rsquo;aujourd&rsquo;hui et de demain<\/strong><\/p>\n<h2><strong>PAS DE CONFINEMENT POUR L&rsquo;ACTION SYNDICALE<\/strong><\/h2>\n<p>L\u2019\u00e9preuve sanitaire, sociale et soci\u00e9tale sans pr\u00e9c\u00e9dent \u00e0 laquelle nous sommes confront\u00e9s, interroge notre mod\u00e8le de soci\u00e9t\u00e9.\u00a0Ing\u00e9nieurs, chefs de projet, cadre, managers de proximit\u00e9, techniciens, agents de ma\u00eetrise l\u2019heure est \u00e0 la mobilisation de nos savoirs et savoir-faire pour<strong> r\u00e9pondre \u00e0 l\u2019urgence, dresser les premiers bilans et construire la soci\u00e9t\u00e9 de demain. <a href=\"http:\/\/www.ugict.cgt.fr\/articles\/actus\/pas-de-confinement\">[Lire la suite]\u00a0<\/a><\/strong> \u00c0 utiliser sans mod\u00e9ration !<\/p>\n<h2><strong>GUIDE T\u00c9L\u00c9TRAVAIL<\/strong><\/h2>\n<p>Fin 2018, l&rsquo;Ugict-CGT publiait \u00ab\u00a0Le guide du t\u00e9l\u00e9travail\u00a0\u00bb, et r\u00e9insiste aujourd&rsquo;hui sur son utilit\u00e9 en mati\u00e8re de connaissance du droit, alors m\u00eame que le \u00ab\u00a0business as usual\u00a0\u00bb est omnipr\u00e9sent dans ce contexte de crise sanitaire. Pour r\u00e9pondre \u00e0 toutes les questions que se posent actuellement les salari\u00e9.e.s, l&rsquo;Ugict-CGT met \u00e0 disposition un site d\u00e9di\u00e9 :<a href=\"https:\/\/guideteletravail.fr\/\"><strong>\u00a0GuideTeletravail.fr<\/strong><\/a><\/p>\n<h2><strong>Covid-19 et t\u00e9l\u00e9travail<\/strong> : <strong><a href=\"http:\/\/www.ugict.cgt.fr\/articles\/references\/teletravail-covid-19\">Le point complet<\/a><\/strong><\/h2>\n<h2><strong>VOTRE SANT\u00c9 AU TRAVAIL \u00c0 L&rsquo;HEURE DE L&rsquo;\u00c9PID\u00c9MIE DE COVID-19<br \/>\n<\/strong><\/h2>\n<p>Le collectif des <strong>\u00ab\u00a0Personnels des services de sant\u00e9 au travail\u00a0\u00bb Ugict-CGT et CGT<\/strong> \u00e9dite une note sur le cadre sp\u00e9cifique de la pr\u00e9vention li\u00e9e aux agents biologiques<em> : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/03\/Votre-santC\u0327-au-travail-et-covid-_19-ACGSV2.pdf\">Votre sante au travail et covid<\/a><\/em><\/p>\n<h2><strong>ATTENTION ! RESPONSABLES&#8230; JUSTICIABLES<br \/>\n<\/strong><\/h2>\n<p>La responsabilit\u00e9 professionnelle est aussi synonyme de responsabilit\u00e9 devant les tribunaux, notamment en mati\u00e8re de sant\u00e9 et de s\u00e9curit\u00e9 des salari\u00e9.e.s ou des publics accueillis. Lire la note de l&rsquo;Ugict-CGT : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/03\/2020-03-24-NOTE-JUSTICIABLES.pdf\">2020 03 24 NOTE JUSTICIABLES<\/a><\/p>\n<h2><strong>EN DIRECT DES ORGAS<br \/>\n<\/strong><\/h2>\n<ul>\n<li><strong>Banques-Assurances<\/strong> : COVID-19 : la CGT lance l&rsquo;alerte face au \u00ab\u00a0<em>business as usual<\/em>\u00a0\u00bb dans les banques et assurances. <a href=\"http:\/\/cgtbanquesassurances.fr\/actualites\/communiques-de-presse\/alerte-covid-19\/\"><strong>[Lire et t\u00e9l\u00e9charger]<\/strong><\/a> le communiqu\u00e9 de presse<\/li>\n<li><strong>Organisations syndicales maritimes<\/strong> : Le secteur maritime se voit particuli\u00e8rement impact\u00e9 par l&rsquo;extension mondiale et inexorable de la pand\u00e9mie COVID-19. En pi\u00e8ce jointe le communiqu\u00e9 de presse : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/03\/COMMUNIQUE-DE-PRESSE-interOS-maritimes-COVID19-23-mars-2020.pdf\">COMMUNIQUE DE PRESSE interOS maritimes &#8211; COVID19 &#8211; 23 mars 2020<\/a><\/li>\n<li><strong>F\u00e9d\u00e9ration CGT Sant\u00e9 Action sociale et UFMICT-CGT<\/strong> :<\/li>\n<\/ul>\n<ul>\n<li><strong><a href=\"http:\/\/www.sante.cgt.fr\/Communique-des-collectifs-des-personnels-de-direction-Sante-et-Action-Sociale\">[Lire et t\u00e9l\u00e9charger]<\/a><\/strong> le communiqu\u00e9 de presse du collectif des <strong>personnels de direction<\/strong> sur la crise sanitaire provoqu\u00e9e par le COVID-19.<\/li>\n<li><strong>UFMICT-CGT &#8211; UNEF<\/strong> : Pendant cette crise sanitaire de grande ampleur, l&rsquo;UMICT-CGT Sant\u00e9 Action sociale et l&rsquo;UNEF tiennent \u00e0 alerter sur le sort r\u00e9serv\u00e9 aux \u00e9tudiant.e.s en soins infirmiers et aux \u00e9l\u00e8ves aide-soignant.e.s. Lire le tract <em>: <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/03\/2020-03-18-COURRIER-UFMICT-UNEF-MINISTRE-VDEF.pdf\">COURRIER UFMICT UNEF MINISTRE <\/a><br \/>\n<\/em><\/li>\n<li><strong>Collectif des infirmier.\u00e8re.s anesth\u00e9sistes<\/strong> : <strong><a href=\"http:\/\/www.sante.cgt.fr\/Communique-du-Collectif-national-des-Infirmiers-Anesthesistes-de-la-CGT\">[Lire et t\u00e9l\u00e9charger]<\/a><\/strong> le communiqu\u00e9 sur les conditions d&rsquo;exercice de leur profession.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>F\u00e9d\u00e9ration CGT des Professionnels de la Vente<\/strong> : En pi\u00e8ce jointe les deux courriers adress\u00e9s \u00e0 Muriel P\u00e9nicaud sur la situation des VRP et commerciaux face \u00e0 la pand\u00e9mie COVID-19 : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/03\/LETTRE-INTER-SYNDICALE-VRP-MINISTRES-DU-TRAVAIL.pdf\">LETTRE INTER SYNDICALE VRP MINISTRES DU TRAVAIL<\/a> et <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/03\/LETTRE-INTER-SYNDICALE-VRP-MINISTRES-DU-TRAVAIL.pdf\">LETTRE INTER SYNDICALE VRP MINISTRES DU TRAVAIL<\/a><\/li>\n<li><strong>F\u00e9d\u00e9ration CGT des Soci\u00e9t\u00e9s d&rsquo;\u00c9tudes<\/strong> : Un nombre croissant d&rsquo;entreprises interpr\u00e8te les d\u00e9crets et d\u00e9cisions gouvernementales \u00e0 leur fa\u00e7on, c&rsquo;est-\u00e0-dire en se souciant plus de leur tr\u00e9sorerie que de la sant\u00e9 des travailleurs\/euses. Lire le communiqu\u00e9 de presse :\u00a0<a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/03\/Quand-les-employeurs-font-passer-leur-profit-avant-la-santC\u0327-des-travailleurseuses.pdf\">Quand-les-employeurs-font-passer-leur-profit-avant-la-sante-des-travailleurseuses<\/a><\/li>\n<\/ul>\n<h2><strong>RECHERCHE : UNE PRESCRIPTION TOTALEMENT INADAPT\u00c9E AU DIAGNOSTIC !<br \/>\n<\/strong><\/h2>\n<p>Se saisissant du moment exceptionnel dans la vie de la nation que repre\u0301sente l\u2019e\u0301pide\u0301mie de Covid-19, le pre\u0301sident de la Re\u0301publique et avec lui le ministre de l\u2019Enseignement supe\u0301rieur, de la Recherche et de l\u2019Innovation annoncent, sans autre forme de concertation, la mise en \u0153uvre d\u2019un ensemble de mesures.<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/presse\/recherche--une-prescription-totalement-inadapte%CC%81e-au-diagnostic\"><strong>[Lire et t\u00e9l\u00e9charger]<\/strong><\/a> le communiqu\u00e9 de presse<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale <\/strong><strong>\u00e0 l&rsquo;Activit\u00e9 sp\u00e9cifique<\/strong><strong>\u00a0<\/strong><a href=\"http:\/\/ugict.cgt.fr\/a2s\/\"><strong>http:\/\/ugict.cgt.fr\/a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>POUR FAIRE FACE ET CONSTRUIRE L&rsquo;AVENIR : LUTTEVIRALE.FR Alors que, selon les chiffres du minist\u00e8re du travail, 60 % des salari\u00e9\u00b7e\u00b7s continuent de travailler sur leur lieu de travail, l\u2019Ugict-CGT, les syndicats CGT de l\u2019inspection du travail et de la Direction Statistique du Minist\u00e8re du Travail (DARES) et des avocat\u00b7e\u00b7s militant\u00b7e\u00b7s lancent\u00a0luttevirale.fr, un site pour [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[57,38,5],"class_list":["post-1092","post","type-post","status-publish","format-standard","hentry","category-archives","tag-coronavirus","tag-protection-sociale","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1092","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1092"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1092\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1092"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1092"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1092"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}