{"id":1190,"date":"2020-08-28T17:07:36","date_gmt":"2020-08-28T15:07:36","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1190"},"modified":"2020-08-28T21:10:25","modified_gmt":"2020-08-28T19:10:25","slug":"vendredi-28-aout-n351","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2020\/08\/28\/vendredi-28-aout-n351\/","title":{"rendered":"Vendredi 28 ao\u00fbt \u2013 n\u00b0351"},"content":{"rendered":"<h2><strong>JOURN\u00c9E D&rsquo;ACTION DU 17 SEPTEMBRE<br \/>\n<\/strong><\/h2>\n<p><strong>Pr\u00e9server l&#8217;emploi et la sant\u00e9 c&rsquo;est possible, c&rsquo;est une question de volont\u00e9 politique !<\/strong><\/p>\n<p>Salari\u00e9.e.s en responsabilit\u00e9, nous avons serr\u00e9 les dents pour faire face au t\u00e9l\u00e9travail \u00ab\u00a0en mode d\u00e9grad\u00e9\u00a0\u00bb. <strong><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/tracts\/tract-17-sept-2020\">[Lire et t\u00e9l\u00e9charger]<\/a><\/strong> le tract d&rsquo;appel \u00e0 la mobilisation du 17 septembre.<\/p>\n<h2><\/h2>\n<h2><strong>COMMENT TRAVAILLER, PRODUIRE, CONSOMMER ET VIVRE AUTREMENT\u00a0?<\/strong><\/h2>\n<p><strong>\u00a0<\/strong><strong>Les Rencontres d&rsquo;Options se tiendront le vendredi 18 septembre 2020 <\/strong><\/p>\n<p>La crise sanitaire in\u00e9dite li\u00e9e \u00e0 la pand\u00e9mie du coronavirus s\u2019ajoute \u00e0 pr\u00e9sent aux crises sociale, \u00e9conomique et environnementale. L\u2019\u00e9pid\u00e9mie a brutalement agi comme un r\u00e9v\u00e9lateur. Nos soci\u00e9t\u00e9s n\u2019ont jamais \u00e9t\u00e9 aussi riches et d\u00e9velopp\u00e9es technologiquement, elles se sont pourtant retrouv\u00e9es totalement d\u00e9munies face \u00e0 la crise sanitaire, contraintes de recourir \u00e0 l\u2019outil frustre et m\u00e9di\u00e9val du confinement <strong><a href=\"http:\/\/www.ugict.cgt.fr\/environnement\">[Lire la suite]<\/a><\/strong><\/p>\n<p>Elles seront partag\u00e9es en trois temps :<\/p>\n<ol>\n<li>Les le\u00e7ons de la crise, l&rsquo;urgence de changer de mod\u00e8le<\/li>\n<li>Produire, consommer, vivre autrement : concilier social et environnemental, est-ce possible ?<\/li>\n<li>Ma\u00eetriser la finalit\u00e9 de notre travail<\/li>\n<\/ol>\n<p>Pour vous inscrire\u00a0: <a href=\"http:\/\/www.ugict.cgt.fr\/environnement\"><strong>via le formulaire en ligne<\/strong><\/a><\/p>\n<p><strong>\u00a0<\/strong><strong><br \/>\n<\/strong><\/p>\n<h2><strong>FORMATIONS ATMP SECOND SEMESTRE 2020<br \/>\n<\/strong><\/h2>\n<ul>\n<li><strong>Mercredi 7 octobre 2020<\/strong> : <strong>Tendances de l\u2019absent\u00e9isme des cadres et \u00e9volution de la protection sociale comme outil de pr\u00e9vention<\/strong> de 14 heures \u00e0 17 heures Salle 13 &#8211; Noyau B &#8211; Rez-de-chauss\u00e9e haut. Pour vous inscrire : <strong><a href=\"https:\/\/ugictcgt.typeform.com\/to\/Y9xwomZ9\">via le formulaire en ligne<\/a><\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Jeudi 8 octobre 2020<\/strong> : <strong>Pr\u00e9ventions des violences sexistes et sexuelles : quels moyens d&rsquo;action pour les repr\u00e9sentant.e.s du personnel et l&rsquo;encadrement ?<\/strong> de 9h30 \u00e0 17 heures Salle 13 &#8211; Noyau B &#8211; Rez-de-chauss\u00e9e haut. Pour vous inscrire : <strong><a href=\"https:\/\/ugictcgt.typeform.com\/to\/Y9xwomZ9\">via le formulaire en ligne<\/a><\/strong><\/li>\n<\/ul>\n<h2><\/h2>\n<h2><strong>CONSEIL NATIONAL UGICT-CGT<\/strong><\/h2>\n<p style=\"margin: 0px; line-height: 115%; text-align: justify;\"><span style=\"font-size: 11pt; font-family: arial, helvetica, sans-serif;\"><strong>Les 18 et 19 novembre prochains se tiendra le Conseil national de l&rsquo;Ugict-CGT<\/strong><\/span><\/p>\n<p style=\"margin: 0px; text-align: justify;\"><span style=\"font-family: arial, helvetica, sans-serif;\">La r\u00e9partition des mandats par organisation ainsi que l&rsquo;ordre du jour seront communiqu\u00e9s prochainement<\/span>.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale <\/strong><strong>\u00e0 l&rsquo;Activit\u00e9 sp\u00e9cifique<\/strong><strong>\u00a0<\/strong><a href=\"http:\/\/ugict.cgt.fr\/a2s\/\"><strong>http:\/\/ugict.cgt.fr\/a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>JOURN\u00c9E D&rsquo;ACTION DU 17 SEPTEMBRE Pr\u00e9server l&#8217;emploi et la sant\u00e9 c&rsquo;est possible, c&rsquo;est une question de volont\u00e9 politique ! Salari\u00e9.e.s en responsabilit\u00e9, nous avons serr\u00e9 les dents pour faire face au t\u00e9l\u00e9travail \u00ab\u00a0en mode d\u00e9grad\u00e9\u00a0\u00bb. [Lire et t\u00e9l\u00e9charger] le tract d&rsquo;appel \u00e0 la mobilisation du 17 septembre. COMMENT TRAVAILLER, PRODUIRE, CONSOMMER ET VIVRE AUTREMENT\u00a0? \u00a0Les [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[49,6,10,2],"class_list":["post-1190","post","type-post","status-publish","format-standard","hentry","category-archives","tag-climat","tag-formation","tag-mobilisation","tag-rencontres-doptions"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1190","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1190"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1190\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1190"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1190"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1190"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}