{"id":1214,"date":"2020-10-29T16:23:12","date_gmt":"2020-10-29T15:23:12","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1214"},"modified":"2020-10-29T16:23:12","modified_gmt":"2020-10-29T15:23:12","slug":"vendredi-30-octobre-n360","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2020\/10\/29\/vendredi-30-octobre-n360\/","title":{"rendered":"Vendredi 30 octobre \u2013 n\u00b0360"},"content":{"rendered":"<h2><strong>T\u00c9L\u00c9TRAVAIL <\/strong><\/h2>\n<p><strong>Webinar : n\u00e9gocier le t\u00e9l\u00e9travail pour gagner des droits<\/strong><br \/>\n<strong>9 novembre 2020 de 12h \u00e0 14h<\/strong> : Le t\u00e9l\u00e9travail : pour qui ? Comment ? Quand ? \u00c0 quel prix ? Quelles sont les r\u00e8gles existantes ? En tant que n\u00e9gociatrice ou n\u00e9gociateur, sur quoi faut-il \u00eatre vigilant\u00b7e lors des n\u00e9gociations ? Que faire en amont ? Quel suivi du d\u00e9ploiement du t\u00e9l\u00e9travail ? Pour vous inscrire au Webinar : <a href=\"https:\/\/ugictcgt.typeform.com\/to\/gj5JQdMr\"><strong>via le formulaire en ligne<\/strong><\/a><\/p>\n<p><strong><a href=\"http:\/\/enqueteteletravail.fr\/\">EnqueteTeletravail.fr<\/a>\u00a0: g\u00e9n\u00e9rez une enqu\u00eate en ligne et portez les aspirations des salari\u00e9\u00b7es<br \/>\n<\/strong>S\u00e9lectionnez parmi une quarantaine de questions pour construire une consultation en ligne sur mesure, menez campagne en vous appuyant sur les aspirations des salari\u00e9\u00b7e\u00b7s, et gagnez des droits pour que le t\u00e9l\u00e9travail soit synonyme de progr\u00e8s <a href=\"http:\/\/www.ugict.cgt.fr\/articles\/actus\/enqueteteletravail\"><strong>[Lire la suite et acc\u00e9der au g\u00e9n\u00e9rateur]<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>D\u00c9CLARATION DE LA FMTS<\/strong><\/h2>\n<p><strong>Non au fanatisme, \u00e0 l\u2019ignorance et \u00e0 l\u2019obscurantisme,<\/strong> <strong>OUI \u00e0 la libert\u00e9 de conscience, \u00e0 la libert\u00e9 d\u2019expression, au d\u00e9bat et \u00e0 la controverse<br \/>\n<\/strong>La FMTS qui est un lieu de d\u00e9bats entre travailleurs scientifiques de tous les continents, de toutes les id\u00e9ologies et croyances est naturellement choqu\u00e9e par ce crime et sa motivation, Elle tient \u00e0 adresser ses condol\u00e9ances aux proches de la victime et manifester sa solidarit\u00e9 avec les coll\u00e8gues fran\u00e7ais.<\/p>\n<p>Ce coll\u00e8gue, Samuel Paty, a \u00e9t\u00e9 l\u00e2chement assassin\u00e9 pour avoir fait son m\u00e9tier de professeur. L\u2019\u00c9cole, comme l\u2019Universit\u00e9, comme la Recherche doivent rester un lieu de circulation des id\u00e9es, de d\u00e9bat et de formation \u00e0 l&rsquo;esprit critique. Ce crime nous rappelle que les libert\u00e9s de conscience et d\u2019expression, la cr\u00e9ation d\u2019une \u00e9ducation ind\u00e9pendante, rassemblant un public et une jeunesse de croyances et d\u2019id\u00e9ologies, d\u2019ethnies et de classes sociales diff\u00e9rentes, furent et sont encore et plus que jamais l\u2019objet de combats essentiels. Nous consid\u00e9rons ces libert\u00e9s et cette \u00e9ducation comme des marches d\u00e9cisives vers l\u2019\u00e9mancipation humaine et des garanties de la continuation de l\u2019aventure humaine <a href=\"http:\/\/www.ugict.cgt.fr\/articles\/actus\/non-au-fanatisme-a-lignorance-et-a-lobscurantisme-oui-a-la-liberte-de-conscience-a-la-liberte-dexpression-au-debat-et-a-la-controverse\"><strong>[Lire la suite]<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>PUBLICATIONS DE L\u2019UGICT<\/strong><\/h2>\n<p>Une fois par mois, l\u2019A2S int\u00e9grera d\u00e9sormais en pi\u00e8ce-jointe un glossaire de tous les contenus r\u00e9cemment publi\u00e9s, les supports et sources pour vous aider \u00e0 suivre l\u2019activit\u00e9 sp\u00e9cifique <strong><br \/>\n<\/strong><\/p>\n<p><a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/10\/2020-10-27-Glossaire-des-publications-Ugict-CGT.pdf\">2020 10 27 Glossaire des publications Ugict-CGT<\/a><\/p>\n<h2><strong><br \/>\n<\/strong><strong>FORMATIONS SECOND SEMESTRE 2020<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>\u009f\u00a0 <strong>Jeudi 19 novembre 2020 : <\/strong><a href=\"https:\/\/ugictcgt.typeform.com\/to\/h6rBTYtq\"><strong>Mutation du travail : Quelle pr\u00e9vention des risques psychosociaux ? Quels outils syndicaux pour intervenir ?<\/strong><\/a><strong><br \/>\n<\/strong>De 9 heures 30 \u00e0 17 heures &#8211; Salle 13 &#8211; Noyau B &#8211; Rez-de-chauss\u00e9e haut<\/p>\n<p>\u009f\u00a0 <strong>Du 14 au 18 d\u00e9cembre 2020<\/strong> : <a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/stage-national-ugict-cgt\"><strong>\u00catre responsable Ugict-CGT <\/strong><strong>\u2022<\/strong><strong> Contenu, animation et d\u00e9ploiement de l\u2019activit\u00e9 sp\u00e9cifique<\/strong><\/a> <strong>(plus que quelques places disponibles)<\/strong><\/p>\n<p>Centre Beno\u00eet Frachon \u2022 Courcelle (91)\u00a0<strong>\u00a0<\/strong><\/p>\n<p>\u009f\u00a0 <strong>Du 16 au 18 d\u00e9cembre 2020<\/strong> : <a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/SitesWeb\"><strong>Communication web\u00a0: Construire et g\u00e9rer un site avec Reference-Syndicale.fr<\/strong><\/a> <strong>(complet)<\/strong><\/p>\n<p>Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<p>\u009f\u00a0 <strong>SNTRS-CGT<\/strong><strong> \u2013 La Direction du CNRS \u00e0 nouveau condamn\u00e9e : un concours chercheur annul\u00e9 par la justice administrative <\/strong><\/p>\n<p>Il y a peu, la Cour administrative d\u2019appel de Paris a annul\u00e9 le concours de recrutement des Charg\u00e9s de Recherche de Classe Normale (CRCN) de la section 37 du Comit\u00e9 national au motif que le d\u00e9classement d&rsquo;un candidat op\u00e9r\u00e9 par le jury d&rsquo;admission reposait non pas sur des motifs scientifiques mais sur \u00ab un motif \u00e9tranger \u00e0 la valeur du candidat \u00bb : la Direction avait fait fi de l&rsquo;\u00e9valuation scientifique et de la coll\u00e9gialit\u00e9 r\u00e9alis\u00e9e dans les sections du Comit\u00e9 national (jurys d\u2019admissibilit\u00e9) <strong>[Pour lire la suite : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/10\/2020-10-27-Communique\u0301-du-SNTRS-CGT.pdf\">2020 10 27 Communique\u0301 du SNTRS-CGT<\/a> ]<\/strong><\/p>\n<p>\u009f\u00a0 <strong>FNIC- CGT \/ CGT SANOFI <\/strong><strong>\u2013 <\/strong><strong>Macron : coup dur pour la relocalisation ! SANOFI ne fabriquera plus en France de principes actifs de m\u00e9dicament<br \/>\n<\/strong>Le 5 novembre 2020 SANOFI commence la proc\u00e9dure d\u2019information consultation sur le projet \u00ab\u00a0Pluton\u00a0\u00bb. La cr\u00e9ation d\u2019une soci\u00e9t\u00e9 dont SANOFI d\u00e9tiendra seulement 30% des parts. Cette soci\u00e9t\u00e9 de production de principes actifs (API) absorbera 6 usines de SANOFI en Europe dont 2 en France. Comble de tout, SANOFI promet que de l\u2019argent public servira de moteur \u00e0 ce d\u00e9mant\u00e8lement <strong>[Pour lire la suite : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/10\/2020-10-28-Communique\u0301-FNIC-CGT-Sanofi.pdf\">2020 10 28 Communique\u0301 FNIC-CGT Sanofi<\/a> ]<\/strong><\/p>\n<p>\u009f\u00a0 <strong>UFICT FNME \u2013 <\/strong><strong>Monopoly dans l\u2019\u00e9nergie : Stop ou encore ? Journ\u00e9e d\u2019action du 3 novembre<br \/>\n<\/strong>EDF d\u00e9coup\u00e9e en morceaux, Engie sans l\u2019eau et ses services\u2026 La CGT y oppose son Programme Progressiste de l\u2019Energie avec en perspective leurs renationalisations. Avec la crise sanitaire et ses r\u00e9percussions \u00e9conomiques, nombre d\u2019entreprises sont sous perfusion. Mais cela n\u2019emp\u00eache pas les grandes man\u0153uvres de se poursuivre : cessions\/acquisitions sont l\u00e9gions dans le secteur de l\u2019\u00e9nergie<strong> <a href=\"https:\/\/ufictfnme.fr\/monopoly-dans-lenergie-stop-ou-encore-journee-daction-du-3-nov-20\/\">[Lire la suite]<\/a><\/strong><\/p>\n<p>\u009f\u00a0 <strong>UGICT-CGT NOKIA \u2013 <\/strong><strong>PSE : des avanc\u00e9es largement insuffisantes. Poursuivons la mobilisation <\/strong>!<br \/>\nL\u2019annulation de 247 suppressions d&#8217;emploi annonc\u00e9e au CSE-C du 23 octobre est une avanc\u00e9e \u00e0 mettre au cr\u00e9dit de la mobilisation des salari\u00e9\u00b7es et de certains \u00e9lu\u00b7es politiques en particulier \u00e0 Lannion. Mais 986 emplois supprim\u00e9s, cela reste inacceptable et tr\u00e8s violent. Ce sont des drames humains en perspective et de l&rsquo;incertitude pour tous. C&rsquo;est environ 30% des effectifs de l&rsquo;entreprise qui disparaissent. La bataille doit continuer par la mobilisation, le soutien aux contre-propositions \u00e9labor\u00e9es par les \u00e9lu\u00b7es et les salari\u00e9\u00b7es <strong>[Pour lire la suite : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/10\/2020-10-28-Tract-CGT-UFICT-CGT-NOKIA.pdf\">2020 10 28 Tract CGT UFICT CGT NOKIA<\/a> ]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse : <\/strong><a href=\"http:\/\/www.ugict.cgt.fr\/formation\">http:\/\/www.ugict.cgt.fr\/formation<\/a><\/p>\n<p><strong>Pour tout renseignement<\/strong> :\u00a0<a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a> \/\u00a0<a href=\"tel:01%2055%2082%2083%2035\">01 55 82 83 40<\/a><\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale\u00a0 <\/strong><strong>\u00e0 l&rsquo;Activit\u00e9 sp\u00e9cifique <\/strong><a href=\"http:\/\/ugict.cgt.fr\/a2s\/\"><strong>http:\/\/ugict.cgt.fr\/a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00c9L\u00c9TRAVAIL Webinar : n\u00e9gocier le t\u00e9l\u00e9travail pour gagner des droits 9 novembre 2020 de 12h \u00e0 14h : Le t\u00e9l\u00e9travail : pour qui ? Comment ? Quand ? \u00c0 quel prix ? Quelles sont les r\u00e8gles existantes ? En tant que n\u00e9gociatrice ou n\u00e9gociateur, sur quoi faut-il \u00eatre vigilant\u00b7e lors des n\u00e9gociations ? Que faire [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6,44,35,5],"class_list":["post-1214","post","type-post","status-publish","format-standard","hentry","category-archives","tag-formation","tag-international","tag-teletravail","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1214","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1214"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1214\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1214"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1214"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1214"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}