{"id":1242,"date":"2020-11-27T11:09:19","date_gmt":"2020-11-27T10:09:19","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1242"},"modified":"2020-11-27T11:11:22","modified_gmt":"2020-11-27T10:11:22","slug":"vendredi-27-novembre-n364","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2020\/11\/27\/vendredi-27-novembre-n364\/","title":{"rendered":"Vendredi 27 novembre \u2013 n\u00b0364"},"content":{"rendered":"<h2><strong>T\u00c9L\u00c9TRAVAIL <\/strong><\/h2>\n<p><strong><br \/>\n<\/strong><strong>URIF\/UGICT\u00a0&#8211; Webinar : n\u00e9gocier le t\u00e9l\u00e9travail pour gagner des droits<br \/>\n<\/strong>Ce webinar est ouvert \u00e0 toutes les personnes en responsabilit\u00e9 syndicale\u00a0en Ile-de France\u00a0amen\u00e9es \u00e0 n\u00e9gocier sur la question du t\u00e9l\u00e9travail (une session ult\u00e9rieure s&rsquo;adressera aux salari\u00e9\u00b7es d\u00e9sireux de connaitre leurs droits).<br \/>\nLe t\u00e9l\u00e9travail : pour qui ? Comment ? Quand ? \u00c0 quel prix ? Quelles sont les r\u00e8gles existantes ? En tant que n\u00e9gociatrice ou n\u00e9gociateur, sur quoi faut-il \u00eatre vigilant\u00b7e lors des n\u00e9gociations ? Que faire en amont ? Quel suivi du d\u00e9ploiement du t\u00e9l\u00e9travail.<br \/>\n<strong>Le 2 d\u00e9cembre 2020, de midi \u00e0 14h, via Zoom. <\/strong><br \/>\nInscription pr\u00e9alable obligatoire\u00a0: <a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/webinar-nego-teletravail\">http:\/\/www.ugict.cgt.fr\/ugict\/formation\/webinar-nego-teletravail<\/a><\/p>\n<p><strong>T\u00e9l\u00e9chargez tous les outils pour les syndicats<\/strong><\/p>\n<p>&#8211; Un g\u00e9n\u00e9rateur d&rsquo;enqu\u00eate pour faire un \u00e9tat des lieux sur le t\u00e9l\u00e9travail et recueillir les aspirations des salari\u00e9.e.s<\/p>\n<p><a href=\"https:\/\/enqueteteletravail.fr\/\"><strong>https:\/\/enqueteteletravail.fr\/<\/strong><\/a><\/p>\n<p>&#8211; Un guide et un accord type pour les n\u00e9gociations d&rsquo;entreprise<\/p>\n<p><a href=\"https:\/\/ugict.cgt.fr\/teletravail\/#outils\"><strong>https:\/\/ugict.cgt.fr\/teletravail\/#outils<\/strong><\/a><\/p>\n<p>&#8211; Un tutoriel vid\u00e9o pour n\u00e9gocier un accord<\/p>\n<p><a href=\"https:\/\/ugict.cgt.fr\/teletravail\/tuto\/\"><strong>https:\/\/ugict.cgt.fr\/teletravail\/tuto\/<\/strong><\/a><\/p>\n<p>&#8211; Une banque d&rsquo;accord t\u00e9l\u00e9travail<\/p>\n<p><a href=\"https:\/\/ugict.cgt.fr\/teletravail\/charger\/\"><strong>https:\/\/ugict.cgt.fr\/teletravail\/charger\/<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Derni\u00e8re minute<\/strong> :\u00a0 le communiqu\u00e9 de presse conf\u00e9d\u00e9ral suite \u00e0 la derni\u00e8re n\u00e9gociation de l\u2019ANI du 26 novembre 2020 : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/11\/CP-CGT-Teletravail-Nouvelle-seance-Nouvelles-inquietudes.pdf\">[CP CGT] Teletravail Nouvelle seance Nouvelles inquietudes<\/a><\/p>\n<h2><strong>LE TRAVAIL EST \u00c0 NOUS<\/strong><\/h2>\n<p><strong>Avec <\/strong>\u00ab <a href=\"https:\/\/letravailestanous.fr\/\"><strong>Letravailestanous<\/strong><\/a> \u00bb <strong>offrons\u00a0 aux ICTAM une autre alternative que de fuir ou subir l&rsquo;entreprise !<\/strong><\/p>\n<p>L&rsquo;UGICT-CGT vous livre un outil pour aller \u00e0 la rencontre des ICTAM, d\u00e9ployer notre syndicalisme, resserrer les liens entre les militants, nos structures territoriales et professionnelles, consolider notre cahier revendicatif <strong>[Voir la pr\u00e9sentation de l\u2019outil : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/11\/20201123-Migration-site-UGICT.pdf\">20201123 &#8211; Migration site UGICT<\/a> <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/11\/2020-11-18-Letravailestanous-pre\u0301sentation-1.pdf\">2020 11 18 Letravailestanous<\/a> ]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>COLLECTIF JEUNES DIPLOM\u00c9\u00b7ES<\/strong><\/h2>\n<p>Le prochain module de formation aura lieu le lundi 30 novembre (9h30\/10h30) sur le th\u00e8me\u00a0: <strong>La communication au service de l&rsquo;activit\u00e9 sp\u00e9cifique [Liste des modules et des dates <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/11\/2020-11-10-Planning-des-formations-en-visioconfe\u0301rence-a\u0300-destination-des-jeunes-diplo\u0302me\u0301.docx\">Planning des formations en visioconfe\u0301rence a\u0300 destination des jeunes diplo\u0302me\u0301<\/a> ].<\/strong><\/p>\n<p>N\u2019h\u00e9sitez pas \u00e0 faire conna\u00eetre ces formations au sein de vos orgas et \u00e0 nous remonter vos demandes pour que nous organisions des s\u00e9ances \u00e0\u00a0: <a href=\"mailto:orga@ugict.cgt.fr\"><strong>orga@ugict.cgt.fr<\/strong><\/a><\/p>\n<h2><\/h2>\n<h2><strong>WEBINAIRES SUR LA COMMUNICATION SYNDICALE<\/strong><\/h2>\n<p><strong>\u00a0<\/strong><strong>S\u00e9rie de webinaires sur la communication syndicale : presse, design, mailings, site et r\u00e9seaux sociaux<\/strong><\/p>\n<p>Comment construire une newsletter ? Comment g\u00e9rer son site\u00a0? Ses r\u00e9seaux\u00a0? Quels moyens et quelle strat\u00e9gie\u00a0? Nous proposons une s\u00e9rie de 6 courts webinaires entre janvier et mars 2021 <strong><a href=\"https:\/\/ugictcgt.fr\/webinaires-com-numerique\/\">[Voir les th\u00e9matiques abord\u00e9es]<\/a><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>MIGRATION DU SITE UGICT-CGT<\/strong><\/h2>\n<p><strong>Tout change, mais rien ne bouge\u00a0!<\/strong><\/p>\n<p>Pendant tout le mois de d\u00e9cembre, le site de l\u2019Ugict-CGT va migrer depuis <a href=\"http:\/\/ugict.cgt.fr\/\">ugict.cgt.fr<\/a> vers <strong><u><a href=\"http:\/\/ugictcgt.fr\/\">ugictcgt.fr<\/a><\/u><\/strong> qui sera d\u00e9sormais sa nouvelle adresse <strong>[Retrouver les raisons et les perspectives de cette migration <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/11\/20201123-Migration-site-UGICT.pdf\">Migration site UGICT<\/a> ]<\/strong><\/p>\n<h2><\/h2>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>SNPEFP-CGT<\/strong><strong>P\u00e9tition <\/strong><strong>:<\/strong> <strong>des droits pour les mod\u00e8les vivants !<br \/>\n<\/strong>Nous alertons sur la situation catastrophique des mod\u00e8les vivants, salari\u00e9s pr\u00e9caires et multi-employeurs. Lors du premier confinement trop de mod\u00e8les n\u2019ont pas \u00e9t\u00e9 r\u00e9mun\u00e9r\u00e9s ou n\u2019ont pas b\u00e9n\u00e9fici\u00e9 du ch\u00f4mage partiel. Les employeurs \u00ab oublieux \u00bb sont nombreux : \u00e9coles sup\u00e9rieures priv\u00e9es comme publiques, ateliers en lien avec l\u2019action culturelle des collectivit\u00e9s territoriales, cours municipaux, conservatoires et centres d\u2019arts etc\u2026 <strong><a href=\"https:\/\/www.change.org\/p\/madame-roselyne-bachelot-ministre-de-la-culture-des-droits-pour-les-mod%C3%A8les-vivants?utm_source=share_petition&amp;utm_medium=custom_url&amp;recruited_by_id=ae9a8cc0-2ce1-11eb-a02b-add488b2ce1d\">[Lire et signer la p\u00e9tition]<\/a><\/strong><\/li>\n<li><strong>CGT RATP <\/strong><\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\"><strong>La lettre d\u2019info<\/strong><strong>\u00a0: un monde d\u2019apr\u00e8s\u2026 les dogmes d\u2019avant !<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Les \u00e9tymologies grecque et chinoise du mot crise (respectivement krisis etWei-ji), quoique distinctes, renvoient dans les deux cas \u00e0 une double signification : danger et d\u00e9cision. La crise porte le danger et invite \u00e0 faire des choix pour reconfigurer notre futur (le \u00ab monde d\u2019apr\u00e8s \u00bb). Malheureusement, les d\u00e9clarations d\u2019un Pr\u00e9sident de la R\u00e9publique d\u00e9couvrant au plein c\u0153ur de la crise que le service public hospitalier n\u2019a pas de prix, comprendre qu\u2019il n\u2019est pas une marchandise, ne suffisent pas \u00e0 rompre avec l\u2019ordre lib\u00e9ral <strong>[Lire la lettre d\u2019info : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/11\/lettre_encadrement_n\u00b08.pdf\">lettre_encadrement_n\u00b08<\/a>]<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li><strong>CGT UFMICT <\/strong><\/li>\n<\/ul>\n<p style=\"padding-left: 40px;\"><strong>Pas de fili\u00e8re s\u00e9lective pour acc\u00e9der au soin psychologique !<\/strong><\/p>\n<p style=\"padding-left: 40px;\">Le scandaleux cahier des charges de l\u2019ARS de Nouvelle Aquitaine concernant les CMPP, fortement soutenu par une d\u00e9l\u00e9gu\u00e9e interminist\u00e9rielle au handicap, n\u2019est qu\u2019un ballon d\u2019essai ! Il inaugure la nouvelle politique de sant\u00e9 issue de la loi du 24 juillet 2019 d\u2019organisation et de transformation du syst\u00e8me de sant\u00e9 en France <strong>[Lire la suite du tract <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2020\/11\/Tract-UFMICT-UFAS-CMPP-Psychologues_20112020.pdf\">Tract UFMICT UFAS CMPP Psychologues<\/a> ]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse : <\/strong><a href=\"http:\/\/www.ugict.cgt.fr\/formation\">http:\/\/www.ugict.cgt.fr\/formation<\/a><\/p>\n<p><strong>Pour tout renseignement<\/strong> :\u00a0<a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a> \/\u00a0<a href=\"tel:01%2055%2082%2083%2035\">01 55 82 83 40<\/a><\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale <\/strong><strong>\u00e0 l&rsquo;Activit\u00e9 sp\u00e9cifique <\/strong><a href=\"http:\/\/ugict.cgt.fr\/a2s\/\"><strong>http:\/\/ugict.cgt.fr\/a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>T\u00c9L\u00c9TRAVAIL URIF\/UGICT\u00a0&#8211; Webinar : n\u00e9gocier le t\u00e9l\u00e9travail pour gagner des droits Ce webinar est ouvert \u00e0 toutes les personnes en responsabilit\u00e9 syndicale\u00a0en Ile-de France\u00a0amen\u00e9es \u00e0 n\u00e9gocier sur la question du t\u00e9l\u00e9travail (une session ult\u00e9rieure s&rsquo;adressera aux salari\u00e9\u00b7es d\u00e9sireux de connaitre leurs droits). Le t\u00e9l\u00e9travail : pour qui ? Comment ? Quand ? \u00c0 quel prix [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[66,16,67,35,23,5],"class_list":["post-1242","post","type-post","status-publish","format-standard","hentry","category-archives","tag-communication","tag-jeunesdiplomes","tag-letravailestanous","tag-teletravail","tag-ufmict","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1242","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1242"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1242\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1242"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1242"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1242"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}