{"id":1280,"date":"2021-01-15T12:06:42","date_gmt":"2021-01-15T11:06:42","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1280"},"modified":"2021-01-15T12:06:42","modified_gmt":"2021-01-15T11:06:42","slug":"vendredi-15-janvier-n369","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2021\/01\/15\/vendredi-15-janvier-n369\/","title":{"rendered":"Vendredi 15 janvier \u2013 n\u00b0369"},"content":{"rendered":"<h2><strong>L\u2019Ugict vous pr\u00e9sente ses v\u0153ux \u00e0 l\u2019occasion de cette nouvelle ann\u00e9e\u00a0: \u00ab\u00a0Ensemble, nous ferons de l\u2019ann\u00e9e 2021 l\u2019ann\u00e9e de l\u2019action\u00a0\u00bb<\/strong><\/h2>\n<p><strong>\u00a0<\/strong>\u00c0 l\u2019occasion de la nouvelle ann\u00e9e, Sophie Binet et Marie-Jos\u00e9 Kotlicki se sont adress\u00e9es directement aux internautes et aux militant\u00b7es pour partager quelques notes d\u2019espoir et d\u2019optimisme pour 2021<strong> <a href=\"https:\/\/ugictcgt.fr\/voeux-2021\/\">[Regarder la vid\u00e9o]<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>T\u00c9L\u00c9TRAVAIL <\/strong><\/h2>\n<p><strong>Webinar &#8211; Heure d\u2019info syndicale sur le t\u00e9l\u00e9travail <\/strong><\/p>\n<p><strong><br \/>\n<\/strong>Comment savoir si j\u2019ai le droit au t\u00e9l\u00e9travail ? Est-ce que l\u2019employeur peut refuser ma demande de t\u00e9l\u00e9travail ? Combien de jours puis-je t\u00e9l\u00e9travailler ? Et si j\u2019ai envie d\u2019arr\u00eater le t\u00e9l\u00e9travail ? Quels sont les frais pris en charge par mon employeur ? Dois-je \u00eatre disponible toute la journ\u00e9e devant mon \u00e9cran ? Quelles donn\u00e9es sont r\u00e9cup\u00e9r\u00e9es par mon employeur de mon pc ? Quelle est ma responsabilit\u00e9 concernant les donn\u00e9es professionnelles ? Que dois-je faire en cas d\u2019accident ? Comment recevoir les infos des syndicats quand on est en t\u00e9l\u00e9travail ?<\/p>\n<p><strong>Le mardi 19 janvier 2021, de 13h \u00e0 14h<\/strong>, la CGT r\u00e9pond en direct aux questions des ing\u00e9s cadres techs sur le t\u00e9l\u00e9travail. Ouvert \u00e0 toutes et tous. Inscription pr\u00e9alable obligatoire :<a href=\"https:\/\/ugictcgt.fr\/webinar-droits-teletravail\/\">https:\/\/ugictcgt.fr\/webinar-droits-teletravail\/<\/a><\/p>\n<h2><\/h2>\n<h2><strong>GAGNER LES TPE CHEZ LES ING\u00c9S, CADRES ET TECHS <\/strong><\/h2>\n<p><strong>Toutes les organisations de la CGT doivent s\u2019inscrire dans la campagne des \u00e9lections TPE. Les \u00e9lections se tiendront du 22 mars au 4 avril 2021.<\/strong><\/p>\n<p>Chaque voix va compter et ce salariat qui p\u00e8se aujourd\u2019hui pr\u00e8s de 5 millions d\u2019\u00e9lecteurs \u2013 presque autant que la fonction publique &#8211; regroupe 40 % d\u2019ICTAM (chiffre DARES). \u00c9videmment ces proportions varient fortement d\u2019un secteur \u00e0 l\u2019autre. De plus, il y a un scrutin propre aux Cadres ce qui conf\u00e8re aux organisations de l\u2019Ugict-CGT une responsabilit\u00e9 toute particuli\u00e8re pour gagner la participation et le vote CGT. Pour rappel un site d\u00e9di\u00e9 CGT \u00e0 cette campagne a \u00e9t\u00e9 cr\u00e9\u00e9 (<a href=\"https:\/\/www.cgt-tpe.fr\/\">https:\/\/www.cgt-tpe.fr\/<\/a>). Il regroupe toutes les expressions, professions de foi et diff\u00e9rents supports de communication \u00e0 disposition.<\/p>\n<p>Par ailleurs, pour vous aider vous trouverez en pi\u00e8ces jointes de cette lettre \u00e9lectronique :<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0 Le \u00ab 4 pages \u00bb sp\u00e9cifique encadrement pour mener la campagne<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Une note conf\u00e9d\u00e9rale aux orgas sur le recours gracieux des \u00e9lecteurs non-inscrits sur les listes et l\u2019utilisation du site \u00ab grand public \u00bb.<\/p>\n<p>&#8211;\u00a0\u00a0 \u00a0L\u2019invitation \u00e0 la journ\u00e9e nationale conf\u00e9d\u00e9rale du 2 mars 2021 des mandat\u00e9\u00b7es dans les Commissions Paritaires R\u00e9gionales et D\u00e9partementales sp\u00e9cifiques aux salari\u00e9\u00b7es des TPE pour les personnes concern\u00e9es (ICTAM mandat\u00e9s).<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pour vous aider \u00e0 cibler les enjeux sur votre p\u00e9rim\u00e8tre et pr\u00e9voir les distributions vous pouvez consulter la carte interactive CGT (<a href=\"https:\/\/carte.cgt-tpe.fr\/\">https:\/\/carte.cgt-tpe.fr\/<\/a>) ainsi que le document Excel en pi\u00e8ce jointe (volume des inscrits par p\u00e9rim\u00e8tre et cat\u00e9gories).<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>GUIDE \u00ab\u00a0ANI ENCADREMENT\u00a0\u00bb<\/strong><strong>\u00a0<\/strong><\/h2>\n<ul>\n<li><strong>Guide\u00a0&#8211; L\u2019ANI encadrement du 28 f\u00e9vrier 2020 : un outil pour n\u00e9gocier de nouveaux droits<br \/>\n<\/strong>L\u2019Accord national interprofessionnel (ANI) relatif aux personnels d\u2019encadrement du 28 f\u00e9vrier 2020 est un socle sur lequel vous pourrez vous appuyer dans chacune de vos n\u00e9gociations de branche ou d\u2019entreprise pour gagner des droits nouveaux pour les ing\u00e9nieurs, cadres, techniciens, agents de ma\u00eetrise mais aussi pour les ouvriers et employ\u00e9\u00b7es <strong><a href=\"https:\/\/ugictcgt.fr\/guide-ani-encadrement\/\">[Lire ou t\u00e9l\u00e9charger le guide]<\/a><\/strong><\/li>\n<\/ul>\n<ul>\n<li><strong>Un projet de d\u00e9cret est soumis \u00e0 la COMAREP<\/strong> (Commission des Accords de Retraite et de Pr\u00e9voyance qui \u00e9met des avis en vue de leur extension) ainsi qu&rsquo;aux membres des Conseils d&rsquo;administration des organismes de S\u00e9curit\u00e9 sociale. Ils sont invit\u00e9s \u00e0 transmettre leurs avis avant le 15 janvier. Quel est le sens de ce projet de d\u00e9cret ?. <strong>[Lire la suite <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/01\/Note-decret-_APEC_cadres.pdf\">Note decret _APEC_cadres<\/a>]<\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong>MOBILISATION DU 4 F\u00c9VRIER 2021<\/strong><\/h2>\n<p><strong>Le droit au travail, un droit universel pour toutes et tous !<\/strong><\/p>\n<p>Durant tout le mois de janvier 2021, dans son \u00e9tablissement ou son service, dans sa profession, quelle que soit sa cat\u00e9gorie socioprofessionnelle, et avec un temps fort unitaire le 4 f\u00e9vrier 2021, ensemble agissons ! <strong>[Lire le tract\u00a0 et la note <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/01\/20201231_DroitTravailUniversel_Tract_SR_CA.pdf\">DroitTravailUniversel<\/a>]<\/strong><\/p>\n<h3><\/h3>\n<h2><strong>GUIDES DE L\u2019UGICT<\/strong><br \/>\n<strong><br \/>\n<\/strong><strong>Guide pratique de l\u2019entretien d\u2019\u00e9valuation<\/strong><\/h2>\n<p>Ce guide dispose de deux versants (c\u00f4t\u00e9 \u00e9valu\u00e9\u00b7es \u009f c\u00f4t\u00e9 \u00e9valuateur\u00b7trices) et traite les dimensions secteur priv\u00e9 et fonction publique. Il est con\u00e7u sous forme de fiches r\u00e9pondant aux questions clefs de cet exercice qu\u2019est l\u2019entretien d\u2019\u00e9valuation. Il vise \u00e0 r\u00e9tablir une certaine \u00e9thique dans le contenu de ces entretiens d\u2019\u00e9valuation en formulant des conseils \u00e0 la fois aux \u00e9valu\u00e9\u00b7es et aux \u00e9valuateur\u00b7trices. <strong><a href=\"https:\/\/ugictcgt.fr\/guide-evaluation\/\">[Lire ou t\u00e9l\u00e9charger le guide]<\/a><\/strong><\/p>\n<h3><strong>Cadre au forfait en jours\u00a0? Retrouvez le guide complet de vos droits<\/strong><\/h3>\n<p>Le forfait jours concerne aujourd\u2019hui 13,8 % du salariat et plus d\u2019un cadre sur deux. La CGT et son Ugict d\u00e9noncent et alertent depuis de nombreuses ann\u00e9es sur l\u2019utilisation abusive du forfait jours. <strong><a href=\"https:\/\/forfaitjours.fr\/\">[Lire ou t\u00e9l\u00e9charger le guide]<\/a><\/strong><\/p>\n<h2><\/h2>\n<h2><strong>WEBINAIRES SUR LA COMMUNICATION SYNDICALE <\/strong><\/h2>\n<p><strong>\u00a0<\/strong><strong>S\u00e9rie de webinaires sur la communication syndicale\u00a0: presse, design, mailings, site et r\u00e9seaux sociaux<\/strong><\/p>\n<p>Comment construire une newsletter\u00a0? Comment g\u00e9rer son site\u00a0? Ses r\u00e9seaux\u00a0? Quels moyens et quelle strat\u00e9gie\u00a0? Nous proposons une s\u00e9rie de 6 courts webinaires entre janvier et mars 2021 <a href=\"https:\/\/ugictcgt.fr\/webinaires-com-numerique\/\"><strong>[Voir les th\u00e9matiques abord\u00e9es]<\/strong><\/a><\/p>\n<p><strong>Prochain Webinaire le 15 janvier 2021 de 13 \u00e0 14 heures<\/strong> \u00a0&#8211; \u00a0<strong>Mailings de masse : formats, contenus, r\u00e8gles l\u00e9gales pour les newsletters <a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_dIHMRktRQv-M23KRqLs-dQ\">[Inscription en ligne]<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>JEUNES DIPLOM\u00c9\u00b7ES<\/strong><\/h2>\n<ul>\n<li><strong>Guide d\u2019introduction au congr\u00e8s de l\u2019Ugict-CGT par le collectif Jeunes dipl\u00f4m\u00e9\u00b7e\u00b7s : Le congr\u00e8s de l\u2019Ugict-CGT : c\u2019est quoi ? <\/strong><\/li>\n<\/ul>\n<p>L&rsquo;Ugict-CGT organise l&rsquo;activit\u00e9 des professions ing\u00e9nieur\u00b7e\u00b7s, cadres, technicien\u00b7ne\u00b7s et agent\u00b7e\u00b7s de ma\u00eetrise au sein de la CGT depuis 1963. Elle compte 80 000 affili\u00e9\u00b7e\u00b7s dans toute la France et dans toutes les professions\u2026 <strong>[Lire le guide <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/01\/12-01-2021-Guide-Jeunes-diplome\u0301s-Congre\u0300s-Ugict-CGT.pdf\">Guide Jeunes diplome\u0301s Congre\u0300s Ugict-CGT<\/a>]<\/strong><\/p>\n<ul>\n<li><strong>Atelier de congr\u00e8s des jeunes dipl\u00f4m\u00e9\u00b7es : responsabilit\u00e9 professionnelle, sommes-nous entre le marteau et l\u2019enclume ?<\/strong><\/li>\n<\/ul>\n<p>Le th\u00e8me de cet atelier est la responsabilit\u00e9 professionnelle. Nous nous demanderons comment ces questions de responsabilit\u00e9 influencent notre travail et nos vies : entre une responsabilit\u00e9 r\u00eav\u00e9e, humaine et exigeante, dot\u00e9e de moyens n\u00e9cessaires pour assumer pleinement nos m\u00e9tiers, et une responsabilit\u00e9 subie, qui r\u00e9duit les professions interm\u00e9diaires \u00e0 une triste courroie de transmission d\u2019une direction d\u00e9connect\u00e9e du terrain.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Rendez-vous le\u00a0<\/strong><strong>jeudi 21 janvier 2021<\/strong><strong>\u00a0\u00e0 12h et jusqu\u2019\u00e0 14h\u00a0: <\/strong><strong>\u00a0<\/strong><\/p>\n<p><strong>\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Lien de la r\u00e9union\u00a0:\u00a0<\/strong><strong><a href=\"https:\/\/us02web.zoom.us\/j\/89296753413\">https:\/\/us02web.zoom.us\/j\/89296753413<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong> Atelier th\u00e9matique sur les revendications sp\u00e9cifiques des ing\u00e9s, cadres, techs <\/strong><\/li>\n<\/ul>\n<p>le\u00a0<strong>04 f\u00e9vrier 2021<\/strong>\u00a0\u00e0 19h sur Zoom.<\/p>\n<p><strong>Lien de la r\u00e9union\u00a0<\/strong><strong><a href=\"https:\/\/us02web.zoom.us\/j\/82072511191\">https:\/\/us02web.zoom.us\/j\/82072511191<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<ul>\n<li><strong>FOMM\u00a0: Non au retour de l\u2019esclavage dans le secteur maritime<\/strong><\/li>\n<\/ul>\n<p>Des temps d\u2019embarquement pouvant atteindre jusqu\u2019\u00e0 20 mois cons\u00e9cutifs ont \u00e9t\u00e9 observ\u00e9s, du fait des difficult\u00e9s d\u2019organiser les rel\u00e8ves \u00e0 cause de la crise sanitaire. \u00a0Jean-Philippe Chateil demande \u00e0 la France et aux \u00e9tats europ\u00e9ens de prendre leurs responsabilit\u00e9s et de faire respecter la r\u00e8glementation aupr\u00e8s des armateurs, \u00e0 l\u2019image de l\u2019Australie <strong>[Lire <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/01\/Journal-2020-12-17-184728.png\" target=\"_blank\" rel=\"noopener noreferrer\">l\u2019article<\/a> ]<br \/>\n<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse : <\/strong><a href=\"http:\/\/www.ugict.cgt.fr\/formation\">http:\/\/www.ugict.cgt.fr\/formation<\/a><\/p>\n<p><strong>Pour tout renseignement<\/strong> :\u00a0<a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a> \/\u00a0<a href=\"tel:01%2055%2082%2083%2035\">01 55 82 83 40<\/a><\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale <\/strong><strong>\u00e0 l<\/strong><strong>\u2019Activit\u00e9 sp\u00e9cifique<\/strong> : \u00a0 <strong><a href=\"https:\/\/ugictcgt.fr\/abonnement-a2s\/\">https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/a><\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>L\u2019Ugict vous pr\u00e9sente ses v\u0153ux \u00e0 l\u2019occasion de cette nouvelle ann\u00e9e\u00a0: \u00ab\u00a0Ensemble, nous ferons de l\u2019ann\u00e9e 2021 l\u2019ann\u00e9e de l\u2019action\u00a0\u00bb \u00a0\u00c0 l\u2019occasion de la nouvelle ann\u00e9e, Sophie Binet et Marie-Jos\u00e9 Kotlicki se sont adress\u00e9es directement aux internautes et aux militant\u00b7es pour partager quelques notes d\u2019espoir et d\u2019optimisme pour 2021 [Regarder la vid\u00e9o] &nbsp; T\u00c9L\u00c9TRAVAIL Webinar [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14,6,4,16,10,35,68,5],"class_list":["post-1280","post","type-post","status-publish","format-standard","hentry","category-archives","tag-cadres","tag-formation","tag-guide","tag-jeunesdiplomes","tag-mobilisation","tag-teletravail","tag-tpe","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1280","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1280"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1280\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1280"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1280"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1280"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}