{"id":1301,"date":"2021-02-05T15:23:45","date_gmt":"2021-02-05T14:23:45","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1301"},"modified":"2021-02-05T15:23:45","modified_gmt":"2021-02-05T14:23:45","slug":"vendredi-5-fevrier-n372","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2021\/02\/05\/vendredi-5-fevrier-n372\/","title":{"rendered":"Vendredi 5 f\u00e9vrier &#8211; N\u00b0372"},"content":{"rendered":"<h2><strong>GAGNER LES TPE CHEZ LES ING\u00c9S, CADRES ET TECHS<\/strong><\/h2>\n<p><strong>Toutes les organisations de la CGT doivent s\u2019inscrire dans la campagne des \u00e9lections TPE. Les \u00e9lections se tiendront du 22 mars au 4 avril 2021.<\/strong><\/p>\n<p>Chaque voix va compter et ce salariat qui p\u00e8se aujourd\u2019hui pr\u00e8s de 5 millions d\u2019\u00e9lecteurs \u2013 presque autant que la fonction publique &#8211; regroupe 40 % d\u2019ICTAM (chiffre DARES). \u00c9videmment ces proportions varient fortement d\u2019un secteur \u00e0 l\u2019autre. De plus, il y a un scrutin propre aux Cadres ce qui conf\u00e8re aux organisations de l\u2019Ugict-CGT une responsabilit\u00e9 toute particuli\u00e8re pour gagner la participation et le vote CGT. Pour rappel un site d\u00e9di\u00e9 CGT \u00e0 cette campagne a \u00e9t\u00e9 cr\u00e9\u00e9 (<a href=\"https:\/\/www.cgt-tpe.fr\/\">https:\/\/www.cgt-tpe.fr\/<\/a>). Il regroupe toutes les expressions, professions de foi et diff\u00e9rents supports de communication \u00e0 disposition.<\/p>\n<p>Par ailleurs, pour vous aider vous trouverez en pi\u00e8ces jointes de cette lettre \u00e9lectronique :<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0 Le \u00ab 4 pages \u00bb sp\u00e9cifique encadrement pour mener la campagne que vous pourrez \u00e9galement retrouver ici\u00a0: <a href=\"https:\/\/ugictcgt.fr\/tpe-2021\/\">https:\/\/ugictcgt.fr\/tpe-2021\/<\/a><\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0Une note conf\u00e9d\u00e9rale aux orgas sur le recours gracieux des \u00e9lecteurs non-inscrits sur les listes et l\u2019utilisation du site \u00ab grand public \u00bb.<\/p>\n<p>&#8211;\u00a0\u00a0 \u00a0L\u2019invitation \u00e0 la journ\u00e9e nationale conf\u00e9d\u00e9rale du 2 mars 2021 des mandat\u00e9\u00b7es dans les Commissions Paritaires R\u00e9gionales et D\u00e9partementales sp\u00e9cifiques aux salari\u00e9\u00b7es des TPE pour les personnes concern\u00e9es (ICTAM mandat\u00e9s).<\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Pour vous aider \u00e0 cibler les enjeux sur votre p\u00e9rim\u00e8tre et pr\u00e9voir les distributions vous pouvez consulter la carte interactive CGT (<a href=\"https:\/\/carte.cgt-tpe.fr\/\">https:\/\/carte.cgt-tpe.fr\/<\/a>) ainsi que le document Excel <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/TPE-2.zip\">TPE <\/a> (volume des inscrits par p\u00e9rim\u00e8tre et cat\u00e9gories).<\/p>\n<h2><strong>JOURN\u00c9E D\u2019\u00c9TUDE SUR LA DETTE PUBLIQUE<\/strong><\/h2>\n<p><strong>Dette Publique, de quoi parle-t-on ? Que faire de la \u201cdette Covid\u201d ?<\/strong><\/p>\n<p>La dette publique occupe et va occuper \u00e0 nouveau les esprits. La crise du COVID fait grimper l\u2019endettement, et sera \u00e0 n\u2019en pas douter utilis\u00e9e pour justifier de nouvelles coupes dans les d\u00e9penses et effectifs publics. Pour r\u00e9sister aux nouvelles pressions aust\u00e9ritaires, il faut savoir de quoi on parle.<\/p>\n<h2><strong><br \/>\nFORMATION D\u00c9FINANCIARISATION DE L\u2019ENTREPRISE <\/strong><\/h2>\n<p><strong>Formation <\/strong><strong>Institut du travail de Strasbourg du 8 au 12 mars<\/strong> <strong>2021<\/strong><\/p>\n<p>Agir avec les ICTAM pour \u00ab d\u00e9financiariser \u00bb l\u2019entreprise est un axe majeur de notre travail syndical. La financiarisation est en effet\u00a0 un obstacle \u00e0 l\u2019exercice de la responsabilit\u00e9 professionnelle et \u00e0 la mise en \u0153uvre de la qualification. C\u2019est un processus d\u2019autant plus d\u00e9l\u00e9t\u00e8re qu\u2019il affecte les fondamentaux de l\u2019entreprise\u00a0 : recherche, ing\u00e9nierie, logistique, management, contr\u00f4le qualit\u00e9,&#8230;<\/p>\n<p>\u00c0 l\u2019issue du stage vous saurez diagnostiquer ce processus d\u00e8s les premiers sympt\u00f4mes et avant que le devenir de l\u2019entreprise ne soit compromis. Vous saurez collecter les informations pertinentes et mobiliser suffisamment en amont les outils disponibles pour contrecarrer les op\u00e9rations de pr\u00e9dation financi\u00e8re. <a href=\"https:\/\/ugictcgt.fr\/stage-definanciarisation\/\">https:\/\/ugictcgt.fr\/stage-definanciarisation\/<\/a> \u00a0<strong>[Voir la fiche d\u2019inscription <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/Fiche-inscription-stage-ugict-strasbourg-08-12-mars-2021.doc\">Fiche inscription-stage-ugict-strasbourg<\/a>]<\/strong><\/p>\n<h2><strong><br \/>\nT\u00c9L\u00c9TRAVAIL <\/strong><\/h2>\n<p>Sur<strong> <a href=\"x-webdoc:\/\/DC98CC4F-472D-4948-9058-BE3F2C256DCA\/teletravail.ugictcgt.fr\">teletravail.ugictcgt.fr<\/a> <\/strong>vous trouverez tous les outils existants et en construction et toute l\u2019actualit\u00e9 du t\u00e9l\u00e9travail, dont des tracts et guides, une banque de donn\u00e9es d\u2019accords, un g\u00e9n\u00e9rateur d\u2019enqu\u00eates en ligne, un mini quizz d\u2019\u00e9t\u00e9 tout en gifs&#8230;<\/p>\n<h2>\n<strong>WEBINAIRES SUR LA COMMUNICATION SYNDICALE <\/strong><\/h2>\n<p><strong>\u00a0<\/strong><strong>S\u00e9rie de webinaires sur la communication syndicale : presse, design, mailings, site et r\u00e9seaux sociaux<\/strong> Comment construire une newsletter\u00a0? Comment g\u00e9rer son site\u00a0? Ses r\u00e9seaux\u00a0? Quels moyens et quelle strat\u00e9gie\u00a0? Nous proposons une s\u00e9rie de 6 courts webinaires entre janvier et mars 2021 <a href=\"https:\/\/ugictcgt.fr\/webinaires-com-numerique\/\"><strong>[Voir les th\u00e9matiques abord\u00e9es]<\/strong><\/a><\/p>\n<p><strong>Prochain Webinaire le 11 f\u00e9vrier 2021 de 13 \u00e0 14 heures<\/strong> \u00a0&#8211; Design : iconographie, conseils, r\u00e8gles l\u00e9gales\u00a0 <a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_Sk5AuonrSqWJs1Hxqu6Ivw\"><strong>[Inscription en ligne]<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>JEUNES DIPLOM\u00c9\u00b7ES<\/strong><\/h2>\n<p><strong>Lundi 15 f\u00e9vrier 2021 \u00e0 19h et jusqu&rsquo;\u00e0 21h sur Zoom se tiendra notre r\u00e9union mensuelle ouverte \u00e0 toutes et tous <\/strong><\/p>\n<p><strong>\u00a0<\/strong>Au programme : actualit\u00e9s de chacun\u00b7e et tous les sujets que vous souhaiterez aborder. Comme les autres \u00e9v\u00e8nements, c&rsquo;est ouvert \u00e0 toutes et tous, n&rsquo;h\u00e9sitez pas \u00e0 inviter vos ami\u00b7e\u00b7s et coll\u00e8gues qui souhaitent d\u00e9couvrir la CGT. Pour se connecter\u00a0: <strong><a href=\"https:\/\/us02web.zoom.us\/j\/88960159500\">https:\/\/us02web.zoom.us\/j\/88960159500<\/a><\/strong><\/p>\n<h2><\/h2>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<p><strong>\u00a0<\/strong><\/p>\n<ul>\n<li><strong>UGICT-CGT NOKIA<\/strong><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><strong>Communiqu\u00e9 : <\/strong><strong>NOKIA CONDAMN\u00c9 POUR TRAVAIL DE NUIT ILLICITE<\/strong><\/p>\n<p>A Nokia-Paris-Saclay l\u2019Intersyndicale et le CSE viennent de gagner une proc\u00e9dure judiciaire<\/p>\n<p>contre l\u2019employeur sur le travail de nuit. En pleine proc\u00e9dure de PSE et en violation de nos accords, la direction a en effet mis en place du travail de nuit et du samedi de novembre \u00e0 fin mars (minimum) pour une quarantaine de salari\u00e9s de Recherche et D\u00e9veloppement (R&amp;D) afin de satisfaire aux exigences du client am\u00e9ricain T-Mobile (TMO), pour acc\u00e9l\u00e9rer le d\u00e9veloppement de nouvelles fonctionnalit\u00e9s 5G dont il a un besoin urgent. <strong>[Lire la suite \u00a0du communiqu\u00e9 <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/Communique-TMO.pdf\">Communique TMO<\/a>]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>UGICT-CGT TCL<\/strong><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><strong>La lettre de l\u2019UGICT-CGT des TCL<\/strong><\/p>\n<p>Ce d\u00e9but d\u2019ann\u00e9e est consacr\u00e9 habituellement \u00e0 pr\u00e9senter les v\u0153ux de bonne ann\u00e9e et \u00e0 faire un retour sur l\u2019ann\u00e9e 2020 pass\u00e9e pour mieux fixer nos objectifs revendicatifs pour 2021. Bien \u00e9videmment, le principal sujet de pr\u00e9occupation de l\u2019ann\u00e9e 2020 a \u00e9t\u00e9 celui de la crise sanitaire qui malheureusement n\u2019en finit plus et devrait perdurer sur l\u2019ann\u00e9e 2021 <strong>[Lire la suite <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/2021-01-lettre-UGICT-janvier-2021.pdf\">lettre UGICT janvier 2021<\/a>]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse : <\/strong><a href=\"http:\/\/www.ugict.cgt.fr\/formation\">http:\/\/www.ugict.cgt.fr\/formation<\/a><\/p>\n<p><strong>Pour tout renseignement<\/strong> :\u00a0<a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a> \/\u00a0<a href=\"tel:01%2055%2082%2083%2035\">01 55 82 83 40<\/a><\/p>\n<p><strong>\u00a0<\/strong>\u00a0<strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale <\/strong><strong>\u00e0 l<\/strong><strong>\u2019Activit\u00e9 sp\u00e9cifique<\/strong>\u00a0 <a href=\"https:\/\/ugictcgt.fr\/abonnement-a2s\/\"><strong>https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>GAGNER LES TPE CHEZ LES ING\u00c9S, CADRES ET TECHS Toutes les organisations de la CGT doivent s\u2019inscrire dans la campagne des \u00e9lections TPE. Les \u00e9lections se tiendront du 22 mars au 4 avril 2021. Chaque voix va compter et ce salariat qui p\u00e8se aujourd\u2019hui pr\u00e8s de 5 millions d\u2019\u00e9lecteurs \u2013 presque autant que la fonction [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[11,6,35,5],"class_list":["post-1301","post","type-post","status-publish","format-standard","hentry","category-archives","tag-elections","tag-formation","tag-teletravail","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1301","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1301"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1301\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1301"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1301"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1301"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}