{"id":1317,"date":"2021-02-26T10:33:08","date_gmt":"2021-02-26T09:33:08","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1317"},"modified":"2021-02-26T10:33:08","modified_gmt":"2021-02-26T09:33:08","slug":"vendredi-26-fevrier-n375","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2021\/02\/26\/vendredi-26-fevrier-n375\/","title":{"rendered":"Vendredi 26 f\u00e9vrier \u2013 N\u00b0375"},"content":{"rendered":"<h2><strong>8 MARS 2021 <\/strong><\/h2>\n<p><strong>Le 8 mars, ce n\u2019est pas la journ\u00e9e de LA femme, ce n\u2019est pas la Saint Valentin ou la f\u00eate des m\u00e8res\u2026 C\u2019est la journ\u00e9e internationale de lutte pour les droits des femmes, c\u2019est le moment de se mobiliser pour gagner enfin l\u2019\u00e9galit\u00e9 !\u00a0 <\/strong><strong><br \/>\n<\/strong>Cette lutte est indispensable, car nous sommes encore tr\u00e8s loin de l\u2019\u00e9galit\u00e9 entre les femmes et les hommes, particuli\u00e8rement au travail\u00a0: les femmes gagnent, en moyenne, toujours 25% de salaire en moins. Chaque\u00a0jour, c\u2019est comme si les femmes arr\u00eataient d\u2019\u00eatre pay\u00e9es \u00e0 15h40 <strong>[<a href=\"http:\/\/www.egalite-professionnelle.cgt.fr\/wp-content\/uploads\/2021\/02\/20200211_EgaliteCordee_Tract_SR.pdf\">T\u00e9l\u00e9charger le tract CGT 8 mars premi\u00e8res de corv\u00e9es<\/a>]<\/strong><\/p>\n<p><strong>\u00a0<\/strong><strong>\u00c0 Paris le lundi 8 mars manifestation unitaire \u00e0 partir de 13h00 &#8211;\u00a0 Port Royal vers R\u00e9publique <\/strong>\u00a0<strong>Pique-nique g\u00e9ant \u00e0 partir de 12h00 &#8211; Temps fort \u00e0 15H40<\/strong><\/p>\n<p>Le tract de l&rsquo;Urif-Cgt pr\u00e9cisant le lieu et l&rsquo;heure de la manifestation : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/tract-8-mars.pdf\">tract 8 mars<\/a><\/p>\n<p><strong>\u00a0<\/strong><strong>\u00a0<\/strong><\/p>\n<h2><strong>GAGNER LES TPE CHEZ LES ING\u00c9S, CADRES ET TECHS<\/strong><\/h2>\n<p><strong>Toutes les organisations de la CGT doivent s\u2019inscrire dans la campagne des \u00e9lections TPE. Les \u00e9lections se tiendront du 22 mars au 4 avril 2021.<\/strong><\/p>\n<p>Chaque voix va compter et ce salariat qui p\u00e8se aujourd\u2019hui pr\u00e8s de 5 millions d\u2019\u00e9lecteurs \u2013 presque autant que la fonction publique &#8211; regroupe 40 % d\u2019ICTAM (chiffre DARES). \u00c9videmment ces proportions varient fortement d\u2019un secteur \u00e0 l\u2019autre. De plus, il y a un scrutin propre aux Cadres ce qui conf\u00e8re aux organisations de l\u2019Ugict-CGT une responsabilit\u00e9 toute particuli\u00e8re pour gagner la participation et le vote CGT.<\/p>\n<p>Le \u00ab 4 pages \u00bb sp\u00e9cifique encadrement pour mener la campagne que vous pourrez \u00e9galement retrouver ici\u00a0: <strong><a href=\"https:\/\/ugictcgt.fr\/tpe-2021\/\">https:\/\/ugictcgt.fr\/tpe-2021\/<\/a><\/strong><\/p>\n<p>Pour les camarades qui souhaitent disposer de la version papier, des exemplaires viennent d&rsquo;\u00eatre adress\u00e9s dans chaque Union D\u00e9partementale. Si cette derni\u00e8re n&rsquo;en dispose pas ou plus,\u00a0vous pouvez contacter le collectif d&rsquo;animation de la campagne : <a href=\"mailto:tpe@cgt.fr\">tpe@cgt.fr<\/a><\/p>\n<p>La \u00a0lettre d&rsquo;info sp\u00e9ciale campagne TPE du 22 f\u00e9vrier 2021 : <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/Elections-TPE_lettre-du-jour_20210224.pdf\">Elections TPE_lettre du jour<\/a><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>19<sup>\u00e8me<\/sup> CONGR\u00c8S DE L\u2019UGICT-CGT<\/strong><\/h2>\n<p><strong>Dans le cadre de son 19<sup>\u00e8me<\/sup> Congr\u00e8s, l\u2019Ugict-CGT organise plusieurs ateliers pr\u00e9paratoires th\u00e9matiques.<br \/>\n<\/strong>En fonction du contexte sanitaire, ces ateliers pourront \u00eatre organis\u00e9s en pr\u00e9sentiel ou en visio. Nous sollicitons chaque organisation pour pr\u00e9voir au moins un atelier pr\u00e9paratoire au congr\u00e8s dans son p\u00e9rim\u00e8tre<strong> [Voir le calendrier ainsi que le kit d\u2019organisation des ateliers <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/19e-Congre\u0300s-Dates-Ateliers-pre\u0301paratoires.pdf\">19e Congre\u0300s Dates Ateliers pre\u0301paratoires<\/a>\u00a0 <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/2021-01-28-CONGRES-Kit-dorganisation-des-ateliers-pre\u0301paratoires.pdf\">CONGRES Kit d&rsquo;organisation des ateliers pre\u0301paratoires<\/a>].<\/strong><\/p>\n<p><strong>Une formation des animateurs et animatrices<\/strong> d&rsquo;ateliers sera organis\u00e9e le <strong><u>2 mars de 9h30 \u00e0 16h00<\/u><\/strong> en pr\u00e9sentiel \u00e0 Montreuil. <strong>En cas de confinement, le format de la formation sera adapt\u00e9 <\/strong><strong><br \/>\nen visio sur une demie journ\u00e9e<\/strong> <strong><a href=\"https:\/\/ugictcgt.typeform.com\/to\/J0OvubgK\">[Inscription en ligne]<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>LE TRAVAIL EST \u00c0 NOUS <\/strong><\/h2>\n<p><strong>Avec <\/strong>\u00ab <a href=\"https:\/\/letravailestanous.fr\/\"><strong>Letravailestanous<\/strong><\/a> \u00bb, <strong>offrons\u00a0aux ICTAM une autre alternative que de fuir ou subir l\u2019entreprise\u00a0!<br \/>\n<\/strong>L\u2019Ugict-CGT vous livre un outil pour aller \u00e0 la rencontre des ICTAM, d\u00e9ployer notre syndicalisme, resserrer les liens entre les militants, nos structures territoriales et professionnelles, consolider notre cahier revendicatif <strong>[Voir la pr\u00e9sentation de l\u2019outil <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/2020-11-18-Letravailestanous-pre\u0301sentation-3.pdf\">Letravailestanous pre\u0301sentation<\/a>]<\/p>\n<p><\/strong><\/p>\n<h2><strong>FORMATION D\u00c9FINANCIARISATION DE L\u2019ENTREPRISE <\/strong><\/h2>\n<p><strong>Formation <\/strong><strong>Institut du travail de Strasbourg du 8 au 12 mars<\/strong> <strong>2021<\/strong><\/p>\n<p>Agir avec les ICTAM pour \u00ab d\u00e9financiariser \u00bb l\u2019entreprise est un axe majeur de notre travail syndical. La financiarisation est en effet\u00a0 un obstacle \u00e0 l\u2019exercice de la responsabilit\u00e9 professionnelle et \u00e0 la mise en \u0153uvre de la qualification. C\u2019est un processus d\u2019autant plus d\u00e9l\u00e9t\u00e8re qu\u2019il affecte les fondamentaux de l\u2019entreprise\u00a0 : recherche, ing\u00e9nierie, logistique, management, contr\u00f4le qualit\u00e9,&#8230;<\/p>\n<p>\u00c0 l\u2019issue du stage vous saurez diagnostiquer ce processus d\u00e8s les premiers sympt\u00f4mes et avant que le devenir de l\u2019entreprise ne soit compromis. Vous saurez collecter les informations pertinentes et mobiliser suffisamment en amont les outils disponibles pour contrecarrer les op\u00e9rations de pr\u00e9dation financi\u00e8re. <strong><a href=\"https:\/\/ugictcgt.fr\/stage-definanciarisation\/\">https:\/\/ugictcgt.fr\/stage-definanciarisation\/<\/a><\/strong> \u00a0<strong>[Voir la fiche d\u2019inscription <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/Fiche-inscription-stage-ugict-strasbourg-08-12-mars-2021.doc\">Fiche inscription-stage-ugict-strasbourg 08 12 mars 2021<\/a>]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>GUIDE PR\u00c9VENIR LES VIOLENCES SEXISTES ET SEXUELLES AU TRAVAIL <\/strong><\/h2>\n<p><strong>\u00a0<\/strong><strong>Chaque jour en France, 10 viols ou tentatives de viols se produisent sur un lieu de travail<\/strong>, 20\u2009% des femmes se disent victimes de harc\u00e8lement sexuel au travail, 80\u2009% de sexisme.<\/p>\n<p>Les violences sexistes et sexuelles sont aussi inflig\u00e9es \u00e0 toutes celles et ceux qui refusent l\u2019assignation \u00e0 leur genre\u00a0et p\u00e9nalisent \u00e9galement les personnes en raison de leurs orientations sexuelles, quel que soit le sexe.<\/p>\n<p>La mise en place de mesures de pr\u00e9vention et de protection des victimes est donc indispensable pour garantir un environnement de travail sans violences. Il s\u2019agit d\u2019une responsabilit\u00e9 directe de l\u2019employeur car elle s\u2019inscrit dans le cadre de son obligation de moyens renforc\u00e9e en mati\u00e8re de sant\u00e9 et de s\u00e9curit\u00e9. Au-del\u00e0 de cette consid\u00e9ration, la mise en place d\u2019un environnement de travail sans violences n\u00e9cessite la mobilisation et la vigilance de tout le collectif de travail. Pour lire la suite\u00a0: <strong><a href=\"https:\/\/ugictcgt.fr\/violences-sexistes-et-sexuelles\/\">Pr\u00e9venir les violences sexistes et sexuelles au travail &#8211; Un guide Ugict &#8211; CGT Ing\u00e9s Cadres Techs<\/a><\/strong> et pour tout renseignement sur la commande du guide : <a href=\"mailto:sec.general@ugict.cgt.fr\">sec.general@ugict.cgt.fr<\/a><\/p>\n<h2>\n<strong>WEBINAIRES SUR LA COMMUNICATION SYNDICALE <\/strong><\/h2>\n<p><strong>\u00a0<\/strong><br \/>\n<strong>S\u00e9rie de webinaires sur la communication syndicale\u00a0: presse, design, mailings, site et r\u00e9seaux sociaux<\/strong> Comment construire une newsletter\u00a0? Comment g\u00e9rer son site\u00a0? Ses r\u00e9seaux\u00a0? Quels moyens et quelle strat\u00e9gie\u00a0? Nous proposons une s\u00e9rie de 6 courts webinaires entre janvier et mars 2021 <a href=\"https:\/\/ugictcgt.fr\/webinaires-com-numerique\/\"><strong>[Voir les th\u00e9matiques abord\u00e9es]<\/strong><\/a><\/p>\n<p>\u00d8\u00a0 <strong>5 mars 2021 de 13 \u00e0 14 heures<\/strong> \u00a0&#8211; Design : iconographie, conseils, r\u00e8gles l\u00e9gales\u00a0<a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_Sk5AuonrSqWJs1Hxqu6Ivw\"><strong>[Inscription en ligne]<\/strong><\/a><\/p>\n<p>\u00d8\u00a0 <strong>11 mars 2021 de 13 \u00e0 14 heures<\/strong> \u00a0&#8211; Strat\u00e9gie : organiser une \u00e9quipe et construire une d\u00e9marche de communication <a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_TJ93RpFATj-NVd2c6YgHmA\"><strong>[Inscription en ligne]<\/strong><\/a><\/p>\n<p>\u00d8\u00a0 <strong>19 mars 2021 de 13 \u00e0 14 heures<\/strong> \u00a0&#8211; Relations presse : information, r\u00e9daction, contacts<a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_VQ02fvweQ4uhEcFsdZL1Jg\"><strong>[Inscription en ligne]<\/strong><\/a><\/p>\n<h2><strong><br \/>\nMANIFESTE POUR LA RESPONSABILIT\u00c9 ENVIRONNEMENTALE<\/strong><\/h2>\n<p><strong>Comment travailler, produire, consommer et vivre autrement ? <\/strong>Pour tenter de r\u00e9pondre \u00e0 cette question qui devient de plus en plus pr\u00e9occupante, l\u2019Ugict-CGT a d\u00e9cid\u00e9 de faire bouger les lignes et a lanc\u00e9 sa campagne intitul\u00e9e \u00ab\u00a0Futurs alternatifs\u00a0\u00bb. Partie d\u2019une journ\u00e9e de rencontres et de d\u00e9bats men\u00e9e aux c\u00f4t\u00e9s de scientifiques et de sp\u00e9cialistes, cette campagne vise \u00e0 concilier enjeux sociaux environnementaux <strong><a href=\"https:\/\/ugictcgt.fr\/lancement-futurs-alternatifs\/\">[Voir le replay des \u00e9missions d\u00e9bats]<\/a><\/strong><\/p>\n<p>\u00c0 l\u2019issue des 3 diffusions, nous avons d\u00e9voil\u00e9 le lundi 15 f\u00e9vrier notre <strong>Manifeste pour la responsabilit\u00e9 environnementale<\/strong> : un manifeste pour proposer des transformations concr\u00e8tes. Un manifeste pour changer profond\u00e9ment le syst\u00e8me, mais pas le climat ! <strong><a href=\"https:\/\/ugictcgt.fr\/environnement\/\">[Lire et t\u00e9l\u00e9charger le manifeste ]<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><strong>\u00a0<\/strong><\/h2>\n<ul>\n<li><strong>SNTRS-CGT<\/strong><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><strong>Lettre ouverte<\/strong> <strong>au Pr\u00e9sident-directeur g\u00e9n\u00e9ral du CNRS\u00a0: que diable le personnel du CNRS irait-il faire dans cette gal\u00e8re ?<\/strong><\/p>\n<p>Monsieur le PDG du CNRS, dans votre communiqu\u00e9 du 17 f\u00e9vrier, vous vous essayez \u00e0 un grand \u00e9cart entre une critique sans appel des propos de votre ministre de tutelle et l\u2019acceptation que le CNRS r\u00e9ponde favorablement \u00e0 sa demande en date du 14 f\u00e9vrier et renouvel\u00e9e le 16 f\u00e9vrier devant l\u2019Assembl\u00e9e nationale<strong> [Lire la suite <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/02\/EN-BREF-N\u00b0556.pdf\">EN BREF N\u00b0556<\/a>]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse : <\/strong><a href=\"http:\/\/www.ugict.cgt.fr\/formation\">http:\/\/www.ugict.cgt.fr\/formation<\/a><\/p>\n<p><strong>Pour tout renseignement<\/strong> :\u00a0<a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a> \/\u00a0<a href=\"tel:01%2055%2082%2083%2035\">01 55 82 83 40<\/a><\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale <\/strong><strong>\u00e0 l<\/strong><strong>\u2019Activit\u00e9 sp\u00e9cifique <\/strong><strong>\u00a0<\/strong><a href=\"https:\/\/ugictcgt.fr\/abonnement-a2s\/\"><strong>https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>8 MARS 2021 Le 8 mars, ce n\u2019est pas la journ\u00e9e de LA femme, ce n\u2019est pas la Saint Valentin ou la f\u00eate des m\u00e8res\u2026 C\u2019est la journ\u00e9e internationale de lutte pour les droits des femmes, c\u2019est le moment de se mobiliser pour gagner enfin l\u2019\u00e9galit\u00e9 !\u00a0 Cette lutte est indispensable, car nous sommes encore [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[26,6,16,61,68,5],"class_list":["post-1317","post","type-post","status-publish","format-standard","hentry","category-archives","tag-egalite","tag-formation","tag-jeunesdiplomes","tag-recherche","tag-tpe","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1317","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1317"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1317\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1317"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1317"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1317"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}