{"id":1376,"date":"2021-05-07T21:39:01","date_gmt":"2021-05-07T19:39:01","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1376"},"modified":"2021-05-07T21:39:01","modified_gmt":"2021-05-07T19:39:01","slug":"vendredi-7-mai-n385","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2021\/05\/07\/vendredi-7-mai-n385\/","title":{"rendered":"Vendredi 7 mai \u2013 N\u00b0385"},"content":{"rendered":"<h2><strong>SUITE DE LA MANIFESTATION DU 1<sup>er<\/sup> MAI \u00c0 PARIS <\/strong><\/h2>\n<p>Suite \u00e0 la manifestation du 1<sup>er<\/sup> mai \u00e0 Paris et particuli\u00e8rement les agressions dont ont \u00e9t\u00e9 victimes les militants et militantes de la CGT en fin de manifestation sur la place de la Nation, l&rsquo;Union R\u00e9gionale Ile-de-France a tenu une conf\u00e9rence de presse le mercredi 5 mai pour revenir sur la manifestation et son d\u00e9roulement <strong>[les diff\u00e9rents de la conf\u00e9rence de presse <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/05\/Confe\u0301rence-de-presse-5-mai.zip\">Confe\u0301rence de presse 5 mai<\/a>]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>RENCONTRES DES \u00c9LU\u00b7ES ET MANDAT\u00c9\u00b7ES<\/strong><\/h2>\n<p>Pour pr\u00e9parer le\u00a019<sup>\u00e8me<\/sup> congr\u00e8s l\u2019Ugict-CGT, la CGT Ing\u00e9s Cadres Techs et <a href=\"https:\/\/urif.cgt.fr\/\">l\u2019Urif-CGT<\/a>organisent une journ\u00e9e des \u00e9lus et mandat\u00e9s ICTAM d\u2019Ile-de-France, <strong>le 20 mai \u00e0 Montreuil,\u00a0dans le patio de la CGT de 9h30 \u00e0 16h30.<\/strong><\/p>\n<p>Dans le cadre du <a href=\"https:\/\/ugictcgt.fr\/tag\/congres-ugict-2018\/\">dernier congr\u00e8s de l\u2019Ugict-CGT \u00e0 Perpignan<\/a>, la d\u00e9cision avait \u00e9t\u00e9 prise d\u2019organiser une rencontre des \u00e9lu\u00b7es et mandat\u00e9\u00b7es ICTAM. Ils et elles indiquent en effet \u00eatre souvent isol\u00e9\u00b7es et en difficult\u00e9 pour exercer leur mandat. Ils et elles n\u2019ont pas toujours les clefs pour mener l\u2019activit\u00e9 sp\u00e9cifique. Le bassin parisien concentre 35\u00a0% des effectifs nationaux de cades et\u00a0 un grand nombre de si\u00e8ges sociaux. Cette journ\u00e9e s\u2019inscrit \u00e0 la fois dans le cadre de la pr\u00e9paration du 19e congr\u00e8s et dans la dynamique amorc\u00e9e par la conf\u00e9d\u00e9ration d\u2019\u00eatre en capacit\u00e9 de pr\u00e9senter des candidat\u00b7es dans tous les coll\u00e8ges. Cette journ\u00e9e, sa pr\u00e9paration, son d\u00e9roul\u00e9 et ses suites seront \u00eatre l\u2019occasion de lancer une dynamique plus globale, dans nos Ufict et les territoires, pour les ancrer dans l\u2019activit\u00e9 sp\u00e9cifique <strong><a href=\"https:\/\/ugictcgt.typeform.com\/to\/asxWkUaX\">[Inscription obligatoire en ligne]<\/a> [Voir le\u00a0 <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/04\/Flyer-Rencontre-Elus-Mandates-Congres.pdf\">Flyer Rencontre Elus Mandates Congres<\/a>]<br \/>\n<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>DONN\u00c9ES DE SANT\u00c9\u00a0: QUELS ENJEUX \u00c0 L\u2019HEURE DU BIG DATA\u00a0?<\/strong><\/h2>\n<p>\u00c0 l\u2019heure o\u00f9 des projets int\u00e9grant des donn\u00e9es de sant\u00e9 \u00e0 grande \u00e9chelle se d\u00e9veloppent tels que STOP COVID, le projet de Passeport vaccinal ou la cr\u00e9ation du Heath Data Hub (aliment\u00e9s notamment par l\u2019Assurance maladie), la question de l\u2019exploitation de ces donn\u00e9es, de leur s\u00e9curit\u00e9 et de leur confidentialit\u00e9 suscitent des d\u00e9bats. Ce webinaire sera l\u2019occasion d\u2019\u00e9changes des regards crois\u00e9s entre responsables mutualistes, syndicaux et collectif citoyens.<\/p>\n<p>L\u2019Union G\u00e9n\u00e9rale des Ing\u00e9nieurs Cadres et Techniciens CGT et la F\u00e9d\u00e9ration des Mutuelles de France organisent un webinaire le mardi 18 mai 2021 de 14h00 \u00e0 15h30 sur le th\u00e8me :\u00a0 \u00ab Donn\u00e9es de sant\u00e9, quels enjeux \u00e0 l\u2019heure du big data \u00bb.<\/p>\n<p>Avec notamment la participation de Mathieu TRUBERT, co-animateur du collectif Num\u00e9rique UGICT-CGT,\u00a0\u00a0\u00a0\u00a0 Patrick JULOU, administrateur de la F\u00e9d\u00e9ration des Mutuelles de France (FMF), Juliette ALIBERT, repr\u00e9sentante du Collectif INTERHOP <strong><a href=\"https:\/\/us02web.zoom.us\/webinar\/register\/WN_pox8uQA_RXmifTK4H8GqMg\">[Inscription obligatoire avant le vendredi 14 mai]<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>WEBINAIRE SUR LE R\u00d4LE DES ING\u00c9NIEURS POUR LA R\u00c9INDUSTRIALISATION <\/strong><\/h2>\n<p>Sanofi, Nokia, Renault, Michelin, Airbus, GE, IBM, etc. Les ing\u00e9nieurs subissent de plein fouet les suppressions d\u2019emplois. Notre secteur productif a \u00e9t\u00e9 d\u00e9pec\u00e9, nos savoir-faire strat\u00e9giques (R&amp;D) transf\u00e9r\u00e9s \u00e0 l\u2019autre bout de la plan\u00e8te, ruinant les bassins d\u2019emploi et notre capacit\u00e9 de production industrielle. Aujourd\u2019hui, la crise sanitaire met cruellement en lumi\u00e8re notre incapacit\u00e9 \u00e0 produire ne serait-ce que des masques en papier\u00a0!<\/p>\n<p>Le patronat fran\u00e7ais a fait le choix de la financiarisation, de la d\u00e9localisation et de la r\u00e9gression salariale, entrainant une in\u00e9vitable baisse de qualit\u00e9 de notre production. \u00a0Dans ce monde globalis\u00e9, l\u2019ing\u00e9nieur en est r\u00e9duit au r\u00f4le d\u2019int\u00e9grateur de syst\u00e8mes sous-trait\u00e9s \u00e0 des fournisseurs fort \u00e9loign\u00e9s g\u00e9ographiquement, perdant de fait toute sa capacit\u00e9 d\u2019innovation et de conception. \u00a0L&rsquo;Ugict-Cgt propose des solutions pour pr\u00e9server les savoir-faire et l\u2019emploi du million d\u2019ing\u00e9nieurs en France, via la relocalisation de nos productions dans le cadre de la transition \u00e9cologique.<\/p>\n<p>L&rsquo;Ugict-Cgt appelle les ing\u00e9nieurs \u00e0 redonner sens \u00e0 leur savoir scientifique et technologique, \u00e0 leur dynamisme, \u00e0 leurs r\u00eaves, pour contrer la doxa ultralib\u00e9rale. La parole des ing\u00e9nieurs doit supplanter celle des financiers, \u00a0ils ont les capacit\u00e9s pour penser et concr\u00e9tiser la n\u00e9cessaire r\u00e9industrialisation de notre pays. Pour plus d&rsquo;informations sur\u00a0 le contenu du webinaire et s&rsquo;inscrire\u00a0: \u00a0<strong><a href=\"https:\/\/ugictcgt.fr\/webinaire-ingenieurs\/\">https:\/\/ugictcgt.fr\/webinaire-ingenieurs\/<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>19<sup>e <\/sup>CONGR\u00c8S DE L\u2019UGICT-CGT<\/strong><\/h2>\n<ul>\n<li><strong>Dans le cadre de son 19<sup>e <\/sup>Congr\u00e8s, l\u2019Ugict-CGT organise plusieurs ateliers pr\u00e9paratoires th\u00e9matiques\u00a0: <\/strong>en fonction du contexte sanitaire, ces ateliers pourront \u00eatre organis\u00e9s en pr\u00e9sentiel ou en visioconf\u00e9rence. Nous sollicitons chaque organisation pour pr\u00e9voir au moins un atelier pr\u00e9paratoire au congr\u00e8s dans son p\u00e9rim\u00e8tre <a href=\"https:\/\/ugictcgt.fr\/kit-ateliers-congres\/\"><strong>[Voir le kit\u00a0 et les dates d\u2019ateliers] <\/strong><\/a><strong><a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/04\/2021-04-09-Kit-organisation-des-ateliers-pre\u0301paratoires-congre\u0300s-1.pdf\">\u00a0Kit organisation des ateliers pre\u0301paratoires congre\u0300s-1<\/a><\/strong><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<p><strong>Deux sessions de formation des animateurs et animatrices sont organis\u00e9e prochainement\u00a0:<\/strong><\/p>\n<p>&#8211;\u00a0\u00a0\u00a0\u00a0 <strong>Mercredi 19 mai \u00a0 <\/strong>9h30 &#8211; 17h00 \u00e0 Montreuil <em>(en pr\u00e9sentiel exclusivement)<br \/>\n<\/em>\u00a0&#8211;\u00a0 \u00a0 <strong>Mercredi 16 juin<\/strong> : 9h30 \u2013 12h30 (en visio exclusivement)<\/p>\n<p><a href=\"https:\/\/ugictcgt.typeform.com\/to\/LIZvPHiW\"><strong>[Inscription en ligne]<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><strong>Atelier pr\u00e9paratoire de congr\u00e8s sur environnement\/industrie &#8211; Jeudi 24 juin 2021 &#8211; Salle Pierre S\u00e9mard \u00e0 Caen <\/strong><\/li>\n<\/ul>\n<p>La CGT Ing\u00e9s Cadres Techs votre UD CGT Calvados et son collectif UGICT organisent une journ\u00e9e sur le sujet de l\u2019industrialisation et respect de l\u2019environnement dans le Calvados inscription par mail \u00e0: <a href=\"mailto:ugict14@orange.fr\">ugict14@orange.fr<\/a> <strong>[Invitation \u00a0<a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/05\/INVITATION-Caen-jeudi-24-juin-2021-ateliers-pre\u0301paratoires-.docx\">Caen jeudi 24 juin 2021 ateliers pre\u0301paratoires<\/a>]<\/strong>,<\/p>\n<p><strong>Retrouvez le calendrier des dates \u00e0 venir <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/05\/Agenda-ateliers-pre\u0301paratoires.xls\">Agenda ateliers pre\u0301paratoires<\/a>. <\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>ENQU\u00caTE SUR L\u2019ENGAGEMENT SYNDICAL DES CADRES <\/strong><\/h2>\n<p>L\u2019Ugict-CGT s\u2019est associ\u00e9e \u00e0 la r\u00e9alisation d\u2019une \u00e9tude sur l&rsquo;engagement syndical des cadres men\u00e9e par une \u00e9quipe de chercheurs en sociologie et en science de gestion des universit\u00e9s d&rsquo;Evry et de Cr\u00e9teil en lien avec l&rsquo;IRES. Dans ce cadre, nous vous invitons \u00e0 r\u00e9pondre au questionnaire se trouvant ci-dessous. Les quelques questions auxquelles nous vous proposons de r\u00e9pondre visent \u00e0 conna\u00eetre votre point de vue sur votre situation professionnelle, sur les raisons qui vous ont conduit(e) \u00e0 vous syndiquer et sur la fa\u00e7on dont vous vivez votre engagement syndical\u00a0:<\/p>\n<p><strong><a href=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdKypxY00pzPEPCEi3KHEpN-Po1kBfo-0fl8hd7UikSCNTdsg\/viewform\">https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSdKypxY00pzPEPCEi3KHEpN-Po1kBfo-0fl8hd7UikSCNTdsg\/viewform<\/a><\/strong><\/p>\n<p>Nous vous invitons \u00e0 relayer cette derni\u00e8re aupr\u00e8s de votre entourage.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<ul>\n<li><strong>UFICT FNME<\/strong><\/li>\n<\/ul>\n<p><strong>N\u00c9GO CLASSIF\/R\u00c9MU : UNE COM\u00c9DIE BURLESQUE DIGNE DE MOLI\u00c8RE<\/strong><\/p>\n<p>Moli\u00e8re occupe une place embl\u00e9matique dans notre culture \u00e0 tel point que la langue fran\u00e7aise est couramment d\u00e9sign\u00e9e par la p\u00e9riphrase \u00ab langue de Moli\u00e8re \u00bb. Les employeurs de la branche des IEG semblent avoir d\u00e9cid\u00e9 de profiter de la n\u00e9gociation sur la r\u00e9mun\u00e9ration\/ classification pour lui rendre un vibrant hommage\u2026<strong> [Lire la suite <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/05\/20210504_Classif_Remu_a_la_Moliere.pdf\">20210504_Classif_Remu_a_la_Moliere<\/a>].<\/strong><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse : <\/strong><a href=\"http:\/\/www.ugict.cgt.fr\/formation\">http:\/\/www.ugict.cgt.fr\/formation<\/a><\/p>\n<p><strong>Pour tout renseignement<\/strong> :\u00a0<a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a> ( <a href=\"tel:01%2055%2082%2083%2035\">01 55 82 83 40)<\/a><\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale <\/strong><strong>\u00e0 l&rsquo;Activit\u00e9 sp\u00e9cifique <\/strong><a href=\"https:\/\/ugictcgt.fr\/abonnement-a2s\/\"><strong>https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>SUITE DE LA MANIFESTATION DU 1er MAI \u00c0 PARIS Suite \u00e0 la manifestation du 1er mai \u00e0 Paris et particuli\u00e8rement les agressions dont ont \u00e9t\u00e9 victimes les militants et militantes de la CGT en fin de manifestation sur la place de la Nation, l&rsquo;Union R\u00e9gionale Ile-de-France a tenu une conf\u00e9rence de presse le mercredi 5 [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[25,6,5],"class_list":["post-1376","post","type-post","status-publish","format-standard","hentry","category-archives","tag-congres","tag-formation","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1376","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1376"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1376\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1376"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1376"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1376"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}