{"id":1466,"date":"2021-10-15T16:20:22","date_gmt":"2021-10-15T14:20:22","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1466"},"modified":"2021-10-15T16:20:22","modified_gmt":"2021-10-15T14:20:22","slug":"vendredi-15-octobre-n401","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2021\/10\/15\/vendredi-15-octobre-n401\/","title":{"rendered":"Vendredi 15 octobre \u2013 N\u00b0401"},"content":{"rendered":"<h2><strong>ANI ENCADREMENT\u00a0<\/strong><\/h2>\n<p><strong>\u00a0<\/strong>D\u2019aucuns l\u2019imaginaient \u00e0 tout jamais perdu du fait de la disparition du r\u00e9gime de retraite compl\u00e9mentaire des cadres et assimil\u00e9s (l\u2019AGIRC). Avec la parution de l\u2019arr\u00eat\u00e9 d\u2019extension de l\u2019Accord National interprofessionnel du 28 f\u00e9vrier 2020 portant diverses orientations pour les personnels cadres (et assimil\u00e9s), ce statut est au contraire appel\u00e9 \u00e0 se renforcer. Toutes les stipulations de l\u2019accord sont d\u00e9sormais obligatoires pour tous les employeurs et les salari\u00e9s relevant de \u00ab l\u2019encadrement \u00bb <strong><a href=\"https:\/\/ugictcgt.fr\/un-avenir-pour-le-statut-de-lencadrement\/\">[Lire le communiqu\u00e9<\/a>]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>RETRAITES\u00a0<\/strong><\/h2>\n<h2><strong>AGIRC-ARRCO : hold-up sur nos points <\/strong><\/h2>\n<p>N\u00e9goci\u00e9 \u00e0 la hussarde pendant les vacances d\u2019\u00e9t\u00e9, un accord sur la retraite compl\u00e9mentaire du priv\u00e9 \u2013 l\u2019AGIRC-ARRCO \u2013 vient d\u2019\u00eatre sign\u00e9 par le Medef , la CFDT et la CFTC qui ne repr\u00e9sentent qu\u2019un tiers des salari\u00e9\u00b7e\u00b7s. Pourtant tou\u00b7te\u00b7s les salari\u00e9\u00b7e\u00b7s en supporteront les cons\u00e9quences <a href=\"https:\/\/ugictcgt.fr\/agirc-arrco-hold-up\/\"><strong>[Lire et t\u00e9l\u00e9charger le tract]<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>LANCEURS D\u2019ALERTE\u00a0<\/strong><\/h2>\n<p><strong>L\u2019Ugict-CGT est membre fondatrice de la Maison des Lanceurs d\u2019Alerte cr\u00e9\u00e9e en 2018.<\/strong> Parmi les activit\u00e9s de la MLA, il y a la transposition de la directive europ\u00e9enne sur les lanceurs d\u2019alerte dans la loi fran\u00e7aise. Cette transposition enrichie des amendements pr\u00e9par\u00e9s par les organisations de la MLA permettrait d&rsquo;am\u00e9liorer l&rsquo;existant d\u00e9coulant des dispositions \u00e9tablies par la loi Sapin 2 pour la transparence, la lutte contre la corruption et la modernisation de la vie \u00e9conomique. Si un travail est engag\u00e9 aupr\u00e8s des parlementaires, il est toutefois n\u00e9cessaire d\u2019\u00e9laborer un rapport de force pour soutenir les propositions visant \u00e0 accro\u00eetre les droits d\u2019interventions des lanceurs d\u2019alerte qu\u2019ils soient personnes physiques ou morales. C\u2019est pourquoi nous t\u2019invitons \u00e0 signer et faire signer la p\u00e9tition\u00a0: <a href=\"https:\/\/loi.mlalerte.org\/je-signe\/\"><strong>https:\/\/loi.mlalerte.org\/je-signe\/<\/strong><\/a><\/p>\n<p><strong>Alors qu\u2019une loi renfor\u00e7ant la protection des lanceurs d\u2019alerte est sur le point d\u2019\u00eatre d\u00e9battue \u00e0 l\u2019Assembl\u00e9e Nationale<\/strong>, plusieurs personnalit\u00e9s issues des m\u00e9dias, du spectacle, du monde associatif ou elles-m\u00eames lanceuses d\u2019alerte, ont apport\u00e9 leur soutien \u00e0 l\u2019appel lanc\u00e9 par la Maison des Lanceurs d\u2019Alerte et la coalition d\u2019organisations r\u00e9unies pour d\u00e9fendre une loi exigeante, dans une s\u00e9rie de vid\u00e9os publi\u00e9es \u00e0 compter de ce jeudi 14 octobre <strong>[Lire et t\u00e9l\u00e9charger le communiqu\u00e9 ]<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>VIE SYNDICALE <\/strong><\/h2>\n<p>Nous souhaitons attirer votre attention sur les questions de vie d\u00e9mocratique et leurs incidences sur la repr\u00e9sentativit\u00e9 syndicale. Comme vous le savez, depuis la loi du 20 ao\u00fbt 2008, la repr\u00e9sentativit\u00e9 d\u2019une organisation doit \u00eatre prouv\u00e9e et il incombe \u00e0 l\u2019organisation dont la repr\u00e9sentativit\u00e9 est contest\u00e9e d\u2019apporter les \u00e9l\u00e9ments de preuve dont elle dispose. Les statuts d\u00e9pos\u00e9s et leurs mises \u00e0 jour ainsi que les \u00e9l\u00e9ments de la transparence financi\u00e8re en font partie <strong>[Lire le courrier de l\u2019espace vie syndicale conf\u00e9d\u00e9ral <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/10\/Aux-secre\u0301taires-ge\u0301ne\u0301raux-des-Unions-De\u0301partementales-et-des-Fe\u0301de\u0301rations-CGT.pdf\">Aux secre\u0301taires ge\u0301ne\u0301raux des Unions De\u0301partementales et des Fe\u0301de\u0301rations CGT<\/a>]<\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>FORMATIONS SYNDICALES <\/strong><\/h2>\n<ul>\n<li><strong>Formation syndicale sur \u00ab\u00a0Le droit \u00e0 la d\u00e9connexion et la pr\u00e9vention des risques psychosociaux\u00a0\u00bb <\/strong><\/li>\n<\/ul>\n<p>L&rsquo;Ugict-CGT a \u00e9t\u00e9 la premi\u00e8re organisation syndicale \u00e0 tirer la sonnette d\u2019alarme sur l\u2019explosion du travail en dehors du temps et du lieu de travail favoris\u00e9 par le management en place et l\u2019hyperconnectivit\u00e9. Apr\u00e8s avoir obtenu dans la loi l&rsquo;obligation de n\u00e9gocier sur le droit \u00e0 la d\u00e9connexion en 2017, l\u2019Ugict-CGT poursuit son action syndicale pour rendre effectif le droit \u00e0 la d\u00e9connexion. Cette formation s&rsquo;adresse aux <a href=\"http:\/\/militant.es\/\">militant.es<\/a> de la CGT qui souhaitent se former et d\u00e9velopper de l&rsquo;activit\u00e9 revendicative sur ce sujet. Gr\u00e2ce au travail syndical accompli depuis pr\u00e8s de 10 ans, ce sont aujourd\u2019hui 69 % des cadres et 61 % des professions interm\u00e9diaires qui veulent disposer d\u2019un droit \u00e0 la d\u00e9connexion effectif <strong>[Voir la fiche descriptive de la formation <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2021\/10\/Formation-e\u0301quilibre-vie-prive\u0301e-vie-professionnelle-et-RPS-fiche-descript....docx\">Formation e\u0301quilibre vie prive\u0301e vie professionnelle et RPS fiche descript&#8230;<\/a>].<\/strong><\/p>\n<p><strong>Lyon\u00a0: le jeudi 21 octobre 2021 de 9h \u00e0 17h \u2013 <\/strong><strong>\u00a0<\/strong><strong>La Bourse du travail <\/strong><\/p>\n<p>Inscription \u00e0 la Commission d\u00e9partementale Ugict-CGT du Rh\u00f4ne <a href=\"mailto:ugict@cgt69.com\"><strong>ugict@cgt69.com<\/strong><\/a><\/p>\n<p>Philippe Godineau\u00a0: <a href=\"callto:06%2058%2096%2093%2058\">06 58 96 93 58<\/a><\/p>\n<p>Sophie Fernandez\u00a0: <a href=\"callto:06%2074%2098%2038%2068\">06 74 98 38 68<\/a><\/p>\n<ul>\n<li><strong>Formation syndicale \u00ab\u00a0Mutation du travail et les Risques psychosociaux\u00a0\u00bb <\/strong><\/li>\n<\/ul>\n<p>Transformation des organisations de travail : l\u2019urgence est \u00e0 la pr\u00e9vention des risques pour la sant\u00e9. \u00c0 l\u2019intensification du travail et \u00e0 la difficult\u00e9 de pr\u00e9server un \u00e9quilibre vie priv\u00e9e &#8211; vie professionnelle, s\u2019ajoutent les \u00e9volutions en cours et \u00e0 venir li\u00e9es \u00e0 la transformation num\u00e9rique. Les entreprises et les administrations ont d\u00e9j\u00e0 entam\u00e9 un processus de transformation profond des organisations du travail qui questionnent\u00a0le sens et la finalit\u00e9 de l\u2019activit\u00e9 professionnelle, le contenu du m\u00e9tier dans sa dimension \u00e9thique et professionnelle, la place accord\u00e9e \u00e0 celles et ceux qui r\u00e9alisent l\u2019activit\u00e9 dans la d\u00e9finition des nouveaux cadres de travail.<\/p>\n<p><strong>Lyon\u00a0: \u00a0le vendredi 22 octobre 2021 de 9h \u00e0 17h \u2013 \u00a0La Bourse du travail<br \/>\n<\/strong>Inscription \u00e0 la Commission d\u00e9partementale Ugict-CGT du Rh\u00f4ne <a href=\"mailto:ugict@cgt69.com\"><strong>ugict@cgt69.com<\/strong><\/a><\/p>\n<p>Philippe Godineau\u00a0: <a href=\"callto:06%2058%2096%2093%2058\">06 58 96 93 58<\/a><\/p>\n<p>Sophie Fernandez\u00a0: <a href=\"callto:06%2074%2098%2038%2068\">06 74 98 38 68<\/a><\/p>\n<ul>\n<li><strong>Formation syndicale \u00ab\u00a0Tendances sur l\u2019absent\u00e9isme des cadres et impacts du t\u00e9l\u00e9travail\u00bb <\/strong><\/li>\n<\/ul>\n<p>Cette formation vous propose de d\u00e9couvrir les principales tendances et sp\u00e9cificit\u00e9s des cadres en mati\u00e8re d&rsquo;arr\u00eats de travail. Elle s&rsquo;articule en deux parties. Une premi\u00e8re partie permettra d&rsquo;avoir une vision globale sur les principaux indicateurs de suivi des arr\u00eats de travail utilis\u00e9s par les institutions de pr\u00e9vention et de sant\u00e9 au travail, de l&rsquo;Assurance Maladie et des organismes compl\u00e9mentaires.<\/p>\n<p><strong>En distanciel\u00a0: le jeudi 21 octobre 2021 de 9h \u00e0 12h30, sur inscription<br \/>\n<\/strong>Pour voir le d\u00e9tail et vous inscrire\u00a0: <a href=\"https:\/\/ugictcgt.fr\/absenteisme-teletravail\/\"><strong>https:\/\/ugictcgt.fr\/absenteisme-teletravail\/<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<ul>\n<li><strong>UFICT MINES \u00c9NERGIE CGT<\/strong><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><strong>Mobilisation\u00a0: LE 19 OCTOBRE, AGISSONS POUR UNE RECONNAISSANCE JUSTE ET \u00c9QUITABLE <\/strong><\/p>\n<p>L&rsquo;Ufict-CGT vous invite \u00e0 vous mobiliser pour la d\u00e9fense du pouvoir d\u2019achat en signant massivement la p\u00e9tition : <strong><a href=\"https:\/\/chng.it\/FH2bdZN9c4\">https:\/\/chng.it\/FH2bdZN9c4<\/a><\/strong> \u00a0et en participant \u00e0 la journ\u00e9e nationale d&rsquo;action du <strong>19 octobre<\/strong>.<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse : <\/strong><strong>\u00a0<\/strong><a href=\"https:\/\/ugictcgt.fr\/formation\/\">https:\/\/ugictcgt.fr\/formation\/<\/a><\/p>\n<p><strong>Pour tout renseignement <\/strong><a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a> ( <a href=\"tel:01%2055%2082%2083%2035\">01 55 82 83 40<\/a><\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale\u00a0 <\/strong><strong>\u00e0 l&rsquo;Activit\u00e9 sp\u00e9cifique <\/strong><a href=\"https:\/\/ugictcgt.fr\/abonnement-a2s\/\"><strong>https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>ANI ENCADREMENT\u00a0 \u00a0D\u2019aucuns l\u2019imaginaient \u00e0 tout jamais perdu du fait de la disparition du r\u00e9gime de retraite compl\u00e9mentaire des cadres et assimil\u00e9s (l\u2019AGIRC). Avec la parution de l\u2019arr\u00eat\u00e9 d\u2019extension de l\u2019Accord National interprofessionnel du 28 f\u00e9vrier 2020 portant diverses orientations pour les personnels cadres (et assimil\u00e9s), ce statut est au contraire appel\u00e9 \u00e0 se renforcer. [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14,25,6,20,34,5],"class_list":["post-1466","post","type-post","status-publish","format-standard","hentry","category-archives","tag-cadres","tag-congres","tag-formation","tag-retraites","tag-statut-encadrement","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1466","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1466"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1466\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1466"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1466"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1466"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}