{"id":1650,"date":"2023-06-30T14:01:44","date_gmt":"2023-06-30T12:01:44","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1650"},"modified":"2023-06-30T14:01:44","modified_gmt":"2023-06-30T12:01:44","slug":"vendredi-30-juin-n469","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2023\/06\/30\/vendredi-30-juin-n469\/","title":{"rendered":"Vendredi 30 juin \u2013 n\u00b0469"},"content":{"rendered":"<h2><b>ENQU\u00caTE ANNUELLE T\u00c9L\u00c9TRAVAIL<\/b><\/h2>\n<p>Enqu\u00eate travail hybride de l&rsquo;Observatoire du t\u00e9l\u00e9travail : un succ\u00e8s ! Plus de 3000 r\u00e9ponses au compteur. On continue ! Voici le lien pour partager l&rsquo;enqu\u00eate :\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/5SVa_UNeosGOzB8n65WpZjeqra3usQ8g10MosPe-31viRZ2AnnfXs356ldlOITd6f_7ZRrHegcCFLsgcwvEsnr4tUcoYOojAPNHGq8QqYNLCccBTlRpCY6ReN729m6AbK-gr1nu9dd1aQfYa3naiGMdHBeI21qvioO8x4MWG7ZDxdWHTIt42-F4AhQwANHOxOn9nSTb9O0Rt8ihbbugzWJlC5dzsp8mx6HregOLtcJO1csNivnQiMfbx2itghV89gYAL4o3WnN0yMNgY8t9suIb0Oj9VOt4Xs_k0GMLgV7zsOgBKlJV7Fn9D_ymhSA2QTjfd3xZPnsKOdgE\">https:\/\/enqueteteletravail.fr\/repondre\/index.php\/634888?lang=fr<\/a>\u00a0.<br \/>\nSi vous souhaitez une enqu\u00eate adapt\u00e9e \u00e0 votre syndicat, contactez : orga@ugictcgt.fr<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/nYVOXTvyZA10qOML-k1Euz7gHpoe1MrwNIl9mlxutSVl-FLjVcJdR_28jkeIl5-CzZbdieDnJsjxqbuIsGQseTTvtGht-kNqw2tzY7-cQRNdSYtscr9pUyqXGtbBNeNTWy_lQ3IQjoI6L4t84K6Kf5b6iUO5w2AbaZmBNEiMWDpRfzHcI1LyT5sYGbtGZQQtWTwvB_5aZqMSuj-dqkOIlFzi3FpsKnCbphzgjntNHW45wZMMDGPxc65FeDyYlRCPSrS4Ow_iVnHUWDZfzj45RcvQCS6AutNL8eYV9j1kh6xl5PpB9soct-gxTmGvYxg4BMlFnud4w0dNg9erE8noj5AXmC5kPXixUZ1Ju3E5AGKWTKGXTGPIX_FdoJkFa1UAEnDPJrDcT48FQHql7VngU16PDY100jgjNzv4_3U7MQsyd_g\" target=\"_blank\" rel=\"noopener\"><strong>Lire et t\u00e9l\u00e9charger le communiqu\u00e9 de presse\u00a0<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>R\u00c9DUCTION DU TEMPS DE TRAVAIL<\/b><\/h2>\n<p>Lors de notre Conseil national du 20 juin, nous avons lanc\u00e9 notre campagne pour la r\u00e9duction du temps de travail. D&rsquo;ores et dej\u00e0, vous trouverez du contenu sur notre\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/EgmqwbaTNjwJtjs3o5nP9B3mcfOo0n_Xk2Nan5DIWiroLkVqpDSAttyp1vveFnRIR2W6OrYs51nU7xyeMXWfs9_QB3_GbkD8d-BDLeYXL6DNVT0frlUHd9hszBgomKAqyLVjtzVAf_Foohh9oP6BBzcCk0qt2NClN7SM0MjZMi8JkC2715a0ijbWGExUXE-aWRu86NHPprHfZxKiJYGtQhhTsb8pRpGC9KrTJfk9n5abwhaSWl_EH5B8dbLvgPJspkY2hoSTJ2WMgbEsA6LQjbsTShYdz4ayTW-gNFFGpyAhPBw\">compte Instagram<\/a>\u00a0et sur notre site les premiers tracts. \u00c0 venir, d&rsquo;autres outils dont vous pourrez consulter la liste dans la pr\u00e9sentation ci-dessous.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/HY9UN2ibocIf4PG_Amw4wA6kV7U_qtktOhmmcKWnokQZXaIfnikYYQpdREzC-1oXPpGEwW5VXpxCnGHkTvLOQ2_aT4un19zC2jnYhOYzgHd6W2x004DfCKfO1xetcOGJVnHHX9ul9712RBEFqr6huKxrnsnEgmNpuPrWea3ju-FjWBvXNRxh97R1Jxcl5OLFNnWeH4kabWEzcCSrTLsq9SoiQjBjxqnHJRk54N96sLmgR9RiFpbGhSZbDZzSxIXYa5sMSMveiEHLV-FodxZ6oGphq-wKIMTTbgJUgap4EJR3RLpZlxeb1Dp8SQb6nAiTtxAYec-0MFY7O4JAw_J0LF5fHkgfTFA316Oq0OMCRypKJU0rzS4vhjG9oZd9_-r9VzNC5ziVl7xVeziEUcG-eMab4PoQc8l14o9zoR615L6MGbhFSzQ\" target=\"_blank\" rel=\"noopener\"><strong>Voir la pr\u00e9sentation faite au CN<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>TRIBUNE ANTI PROC\u00c9DURES-BAILLONS<\/b><\/h2>\n<p>L&rsquo;Ugict est signataire de cette tribune au sujet des proc\u00e9dures-b\u00e2illons, visant \u00e0 interpeller le gouvernement fran\u00e7ais et les institutions europ\u00e9ennes dans le contexte des n\u00e9gociations concernant la future directive anti proc\u00e9dures-b\u00e2illons.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/u877OqQ1dUgaZ_e9niWpZPZ9IlMQnIouaMCEDmQ8QfhZcWmygL3jBuah0SgSTVljkUtYWPzs32A7FvQHtecA5lu6Yt2v1iFf8l-2CrjemODpPHFxuYYDNl_xSZ63gCEUYdCRgBNjbwZ3ZkVkDwEnNGy6eoEJA8hiKxmRRgtdMVeWazGIlZshS93E62AdlMGFANlvk_uOp-K9yx1Q1bKf2Ch4pOsYfCB_CGtyDITZ62d02pwW2-J6HcM9fI-FFHbJt663b3uXL7Dkt4ZMDs5e7-fHJwK6LgYOpFftzA3fVVBZz5RMZbREIulQ9vZtz9YRghVOItpl_MX71R5yvgsDQVS7kdODvP7WU9eHtCVUIYLc6bZvr0W0Pik7SG38xlPnje4Cr-JZaGAgZg1kOhIAkrGKECUH_4A3MPWQ665DUVbIFc9nv5NbAhHV-ruyREs\" target=\"_blank\" rel=\"noopener\"><strong>Lire la tribune<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>TECHNICIEN\u00b7NES DE LA FONCTION PUBLIQUE<\/b><\/h2>\n<p><strong>Nouveau livret : bien travailler dans la Fonction publique, c&rsquo;est encore possible ?<\/strong><\/p>\n<p>Qualit\u00e9 du service public, \u00e9thique professionnelle, expertise : les technicien\u00b7nes et professions interm\u00e9-diaires veulent pouvoir bien travailler. Est-ce encore possible ? Quelles perspectives pour sortir d\u2019une situation d\u00e9grad\u00e9e ?<\/p>\n<p>R\u00e9alis\u00e9 par le collectif Fonction publique, ce livret s\u2019articule autour de trois t\u00e9moignages de technicien\u00b7nes et agent\u00b7es de ma\u00eetrise. Il regroupe \u00e9galement de nombreux chiffres clefs et revendications afin de proposer des pistes pour am\u00e9liorer l\u2019\u00e9tat de nos services publics.<\/p>\n<p>Vous pouvez vous le procurer en version imprim\u00e9e (toute dor\u00e9e \u2b50 !) directement dans les locaux de l\u2019Ugict. La version num\u00e9rique sera tr\u00e8s prochainement consultable sur notre site et sur le kiosque Syndicoop !<\/p>\n<p>&nbsp;<\/p>\n<h2><b>UN NOUVEAU SECR\u00c9TARIAT G\u00c9N\u00c9RAL POUR L&rsquo;UGICT<\/b><\/h2>\n<div>Le Conseil national de l&rsquo;Ugict a valid\u00e9 le 20 juin la proposition de la Commission Ex\u00e9cutive de nommer Caroline Blanchot comme Secr\u00e9taire g\u00e9n\u00e9rale et Agathe Le Berder comme Secr\u00e9taire g\u00e9n\u00e9rale adjointe.<\/div>\n<div><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/AWGK3ySWAMYL6uqKRBTuslakSwqbCA82V2kpNU4Y01FU-LDdfgLgXf3L854zwJn1wJbA-TdlEa9X4EGpmX0IqX-B32t5sKRw-kGyeZqRMWLThg7eKH0l4Qs9mK7MRf47JWQauy6Z9L_zHKPiOFMRSp78Q5yk3XDLe-SAXxtvnCXNI_OT9EEqf7wLYULh_5E8_HtMsOcesDKGfC_qLyMbYALPIzXPOv-kwVy_GOg8RULDBSNXyG6-8eLGC3Ae_KPxzliz7IssVBhitLvVMbwnUxxrkso_i85pJ-1n7dho87kpVcpC7AXx9Qj0oSNEzeSQA8snckDYvWSHsxr5GHl7RC7QK0fD0lAEfXk62_UZ3QL09auH\" target=\"_blank\" rel=\"noopener\"><strong>Lire et t\u00e9l\u00e9charger le communiqu\u00e9 de presse<\/strong><\/a><\/div>\n<h2><\/h2>\n<h2><b>RENCONTRES D&rsquo;<em>OPTIONS<\/em><\/b><\/h2>\n<div>\n<p>Le 21 juin dernier, nous avons tenu nos Rencontres d&rsquo;<em>Options<\/em>\u00a0\u00ab\u00a0Travailler moins, vivre mieux : comment fait-on ?\u00a0\u00bb. 120 personnes \u00e9taient r\u00e9unies au c.e.d.i.a.s \u00e0 Paris pour suivre l&rsquo;\u00e9venement. Un podcast sera disponible en juillet pour \u00e9couter les trois tables rondes. Vous pouvez retrouver quelques photos de cette journ\u00e9e sur notre\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/LVSq1l3UhVob47YqVxfQi9f6Q74uI-oJFTAHYeJ7V9cW4uosez6PY-9p6OvzDL3BCA01vCWsIPLrZebRQSYW8xVcL-UKKmcq6OXhRHh_7aoiyakVAZ7DE_D0tLC6lpUCVtEGh5ZofUJQgOzrreBhQ85phg-eXNhU-pnhsD5nPo5zXGNo2Lh3syvFYcmhhQYS4HghtxYZwrTxQG9Wzn7vm42MQDZP_prfI-Sxl4SQc-pbm8RBiDGFHSq8Ua7pbUQFE5rOcjg3WWSBGKfGo5xvgqNw_fSRf4FqMKdh9J5Iyntmj5c\">compte Instagram<\/a>.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/ppY55NkbrG9jV8zAC6hnUwKO5p9t2MzkxzkchQEEAb1m-4UaaLy67YdV8-noeH5wgOQlp_DDj1NBrCWKT68AKM_Ok5tR782QwsdYfQU8K7qTT1hJevExbBz9y7hYrLiyD03lRUnOxHezCcb6KKtAp4ILyZV4oubXCJOL1XLXbH1EuQDn43UDHxillFzAL3byiMmcPohuZmGqgO9A1cFzE1vd5HNLwi1Az766WWwWPu7xyeLGLmDEvWL7n19Yj99WJ2xPZXciSIKgFrFuwQAnHOHZgWbRTT9gl9iOVUGQ97ICNEfSbXFWbMNvFoJqXD-Yhobn6hZG0QHJHh82DsTVB927NbqPuzCd866QTf-UVjzvvLnkcLlsysjm\">La revue 676<\/a>\u00a0sur la r\u00e9duction du temps de travail sera bient\u00f4t disponible.<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h2><b>AGIR CONTRE LES VIOLENCES SEXISTES ET SEXUELLES AU TRAVAIL<\/b><\/h2>\n<p>L\u2019Ugict-Cgt est laur\u00e9ate de l\u2019appel \u00e0 projets 2022 pour la pr\u00e9vention et la lutte contre les violences sexistes et sexuelles au travail du Minist\u00e8re d\u00e9l\u00e9gu\u00e9 de l\u2019\u00c9galit\u00e9 entre les femmes et les hommes, de la Diversit\u00e9 et de l\u2019\u00c9galit\u00e9 des chances. De nouveaux supports p\u00e9dagogiques, de formation et de communication, sont en cours de d\u00e9veloppement.<\/p>\n<div>L\u2019Ugict-Cgt propose d\u2019ores et d\u00e9j\u00e0 trois outils pour agir concr\u00e8tement dans vos milieux professionnels :<\/div>\n<ul>\n<li>Un webinaire d\u2019une demie-journ\u00e9e en ligne :<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/I7mxkgxZY-vBhAtlssUwFTPiFjLl6pG32zYPYP7JVbGVFxji335zBTtohQ1nnMni8gTPcqkioOLE-ojyZQq-0eezRGEgCfBzqv7n5KbMwkEP5DX8kzJ6Li_6KG5sXYthijQkMVTIV-B7o-SX4B6t15fLg6MEd2s1CALoSvmxHGxJ0ZoJmsCdox2I5mee-lN8QwoqwbNnqnWOvNg91Boi6A-5CnHx4pH5Jn1qnYVv_o97Xr-TR1bvk2Oc02wuPzaMDrIXev42WOw9j6EzJnxlfjHdhVpuy-A7dO1L5uNR5TNnalyfYrM\">\u00a0<\/a><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/8gKP5-_p8P_VpcgSYV6_HFkBw17WUo4btD5_yT4nmFO3GhcPeoaxic5ReX-SLLGmrBY-jQW_Bjq64yiCV23oJU4t8u3ObvCxvKP2SBmRCJuMwJHjeSytwl_LfGrwGLQsKNJUWK7R3-g6DBH5iHG7mrapBrYqUp-On0cyLAYGr7Ov9FEQAGF8cIxsb3wuQ0LqvXDOjwFOaCRmW7F74CUFOwqQm7Ts3w9kLT9pTGhJ4uaY1WtOCOtJsOMU6WUcjSsJ4HERw3kcmMeAVbnBnh5on6DbMPbMTBEU5g\">https:\/\/ugictcgt.fr\/formation-vsst\/<\/a><\/li>\n<li>Un stage de 5 jours \u00e0 l\u2019Institut du travail de Strasbourg sur l\u2019\u00e9galit\u00e9 professionnelle et les femmes cadres :\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/twwaT2T_JNhMUbx7pofUYWOjGMsauQBNxty2antXyjcxNpUHmJrwlrgDszUeRJHVBWqaNwjH5lD4fynPu8fvVNSYkA2PUt6n4K5bTKNb5GsQwCrRNYOtpyjnNRgv6LJdOPtYIs8feoCTgg56eHXn-wxCi9W27KWRn9FSKRZy91T7s1HdfWqFu9qhFFe_Xp1kNtvmsRiloXQO5vDHdIdDjfEGjNuRTC1Wdp6NU0OOT96hbKudg-LZSDwJOLawj3Xe60fVyGsANW99oSS9yW7g44zDiI3QhppjkdRqd6FdSmNQva7XuX4FS3A\">https:\/\/ugictcgt.fr\/stage-egalite-professionnelle\/<\/a><\/li>\n<li>Un g\u00e9n\u00e9rateur d\u2019enqu\u00eate sur les violences sexistes et sexuelles pour recueillir la parole et les attentes de vos coll\u00e8gues :\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/lQ4OhdSQ8hHVm7VoBCB_9nWVuqeuhIOnv0MpECUPgmnxPAt6zKBqY6ilX6kc0TGOVbMSIAFGmjrNPlDvF2trP1TIzbnL15aCjQMzFRYHZyICyZoFIbdMo7PX5BimYWQVeulEtbPieox56yy7pOEPjONHnaQMQA4HgNg39NjrDVf5jn0ir3hkdQxILIwwZjGNS0bWZ5qqkM0UNSXD4qOAJ5tShPkJRyoqtwn0S2GF98vqNCMiL09VE3Qj48m4T0PpAfp6LOjcsU6fuWdmfQH0PA\">https:\/\/ugictcgt.fr\/vsst\/<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><b>FRONT COMMUN CONTRE L\u2019EXTR\u00caME DROITE ET LE LIB\u00c9RALISME<\/b><\/h2>\n<p>La Commission ex\u00e9cutive de l\u2019Ugict-CGT a d\u00e9cid\u00e9 de mettre \u00e0 disposition des organisations de l\u2019Ugict un argumentaire militant afin de construire un front commun contre l\u2019autoritarisme d\u2019\u00c9tat, l\u2019extr\u00eame droite et le lib\u00e9ralisme. Par ailleurs, nous avons des ressources existantes sur notr site internet\u00a0:\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/jlUzDt9NNT6jFxKznzNDvJT--G5mc2uMDMy2TENWCu6ohAtYGQALEZUXUDhZhUcQL6BmvUTKw264cVzmRSk4UX3hQW3iFE3ERPom7RJgb1jgGIj5vskSGlc6z1sR_mKaboNu0b38dB6mu4cR6x9SrpKJD6eYk78Yj9lLr4cVchDyslHcuGMF17YQlWUZtbbEOgKuHRupxblzvZkXSrCrwe8s-FcXl_DfewID_RWDLtHzxC1EVQtOaKHJLZT81Jqq-aeMmpghpRHkAC3i9SUjv6M7S-ZuiktCo2RGmiE-1JErhAn_dTO_aRGZRo_OqtqxdjmcjXNplfts9vS4cIAD39hPS9wKXboRBd59ysPNuJi6Yt4\">voir le dossier extr\u00eame droite<\/a><\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/1YgOa29pfUO1J2-ymZaFGggaEsG_CZZBA68HZx1duBRyU8cPmB23sunYoKN9ic2BN6t4NZCmiDlpPcifIjIgBeZ2p9WIsW-lwS3EM_jdF4AeklPUva-z6cPetNxjf4hlrw5ZHWeprTrtyyQnKVzwtBYv1S2v5ZW9ZFl3Ar8XTo207NpgHCG2cc84rzNbjHFhjnGB28VpNcycbsiNiJMtBM_4WvzaOw7Wai5OblW3GSIGsmLJbDiktv561oulByLGb7RZdImSxmrx-nfImZ-tcaHRDx-AijiiyBkT5xNwBly2Lwr73lneXtPTUjyWOxDYkFVP-UpzMvR27mugPq9ymjVBKULJNRC48FC-G4qPsWsalMNUp47IwKhTReak5nQ2wHGJpV8YLaIPsrEG\" target=\"_blank\" rel=\"noopener\"><strong>Voir et t\u00e9l\u00e9charger l\u2019argumentaire<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>FORMATIONS<\/strong><\/h2>\n<div>\n<div>\n<h3><b>Le calendrier des formations<\/b><\/h3>\n<p><u><strong>Formations courte (demi journ\u00e9e en distanciel)<\/strong><\/u><\/p>\n<div><strong>Management et pr\u00e9vention des risques psychosociaux<br \/>\n<\/strong>Le 23 novembre 2023<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Si3gkN87AjcTnnG4-7ZYCK9JI2CEbjUBa-gYTlYDnonKJrwgq0mRqZOMwati8JhHzH9zmJk3SINHNdZZYSMSY9OqOucm7GXfDsAgYtHq1z0myHget3azr24i5trW5mn_6lRPtZBoM3vr97SLXxfHh9oYkA8t8Rmmr982UdCsLKmIbjgdNO8ZIskD4xqQ2bOWPx9v9Ltgb42q6mLoimqCcHhDNQpcQb6k0C2DV-O1Mk80bU_pY3leRsBDiG3wDqkFiusOGeSowdx0Z87TukxHzy_kwk_IqFEPyrMxxX-KzbNEhVV7RcM90L8\">D\u00e9tails et inscription<\/a><\/div>\n<div><\/div>\n<\/div>\n<div>\n<div><strong>Affections psychiques li\u00e9es aux violences sexistes et sexuelles\u00a0: comment \u00e9valuer leur incidence et d\u00e9velopper une pr\u00e9vention efficace\u00a0?<\/strong><br \/>\nLe 11 septembre 2023<br \/>\nLe 12 d\u00e9cembre 2023<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/SNXY4vKUbbBEIaEZquwLywhVAE8IZfYhBGO4Z50q1OvwenU-OohhNYVReYQBoCeMwAtxp-TvcTSU4FawL3kGjyOMOnYveYReG8AJ0tETgm0uRlMgQloPMf4jtOcOz06slPAW29Iukw16mJIBB-SlUllYQ8ZxU2P8xa1zFoUIBuA_f-24YzKH2kE-m2shewFCG0to6p9j1oOLQdmccjKX4qkMK1xTOLd9pmZVR1DRvq3a8oPaDfSsBpJCgXfZDO-RtvExr2x_GEuTMiV67jC9rMP18HPJPMc-h-R1mxMqxQ\">D\u00e9tails et inscription<\/a><\/div>\n<div><\/div>\n<\/div>\n<div>\n<div><strong>Conna\u00eetre les grandes tendances des arr\u00eats de travail des cadres pour revendiquer une politique de sant\u00e9 au travail<\/strong><\/div>\n<div>\n<div>Le 12 octobre 2023<br \/>\n<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/cxNl-O03niTA-BGBj0EMJj1jTPWTuwpD2aZyLVIDLBFSnWD-aIKoB9a2h8SoYtgjKF84KEgb_ZocDU_xsv3zfDtfkZPUeGW4ye8bnztXomylBp4IyN-HtOJGRQs7f_y0NH5-6drA3__SVBGOiNyBEdOwLW8omZCsb7xt-uylvZs7SuOs_H4ejatQMXslDaWU-zpkZMYXJ9U3FQPsWp5nDemMXt8XPDBIfIcn368LA9NMetufY4eRldPCqtZd85ZzYwa45Zdmgy2F4799e1QEbkc6dvvhvk_no7fNav-Ssrr7C5np3p80mA\">D\u00e9tails et inscription<\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<h3>Stages de formation syndicale (2 \u00e0 5 jours)<\/h3>\n<\/div>\n<div>\n<p><strong>Etre responsable Ugict-CGT<\/strong><\/p>\n<p>Du 9 au 13 octobre 2023<br \/>\n3 au 7 juin 2024<br \/>\n30 septembre au 4 octobre 2024<\/p>\n<div>\n<div><strong>Quelle strat\u00e9gie syndicale face au \u201cWall street management\u201d\u00a0?<\/strong><\/div>\n<div>\n<div>\n<div>Les 15 et 16 novembre 2023<br \/>\n31 janvier et 1er f\u00e9vrier 2024<br \/>\n9 et 10 octobre 2024<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div>\n<div><strong>Gagner les \u00e9lections professionnelles dans les coll\u00e8ges 2 et 3 et dans les cat\u00e9gories A et B de la Fonction publique<\/strong><\/div>\n<div>\n<p>Dates \u00e0 venir<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div><\/div>\n<div><strong>Comprendre la financiarisation de l\u2019entreprise et ses incidences pour restaurer le r\u00f4le contributif de l\u2019encadrement.<\/p>\n<p><\/strong><\/div>\n<div>2 au 5 avril 2024<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div><strong>Egalit\u00e9 professionnelle \u2013 Femmes cadres<\/p>\n<p><\/strong><\/div>\n<div>26 au 31 mai 2024<\/div>\n<div><\/div>\n<div>\n<div><strong>Ma\u00eetriser la technique de l\u2019enqu\u00eate conscientisante<\/strong><\/div>\n<div>\n<p>22 au 26 janvier 2024<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/3hnabu3Lhv7zLAjgbHNtBijfqMeZLHWp3HSj3LzmuArIZ39WrmtJyI5HDYV6jJ4eSYxT1ErKmy3LHfghGjo1dUgUdUtkmHXNzvqcMT6nDXaE_ZWnFUOatnLZfR9iZ8K5uSEUYSRHAxkN1w97GcSN4vQqcC_77FcCVFfeBLiwUV8B1pNbI4rCIltB_MLOs8j7CKozUHW-XK6W2xms1nPneOQWjGikqJoY3KE8NlOLBJS3OFmdmZb55WyyO5sOE8RiTqiVjkD5M_D45ep6WjQZX45Tpl_JcLgUb6IehPRxhqSP4FAQVYABiica\" target=\"_blank\" rel=\"noopener\">Voir\u00a0https:\/\/ugictcgt.fr\/calendrier-formation \/<\/a><\/div>\n<h3><b>Stage communication<\/b><\/h3>\n<p>L\u2019Ugict propose un stage sur une ou deux journ\u00e9es pour apprendre \u00e0 g\u00e9rer un site internet avec le logiciel WordPress sur la plateforme\u00a0<a href=\"http:\/\/reference-synndicale.fr\/\">reference-syndicale.fr<\/a>.<\/p>\n<p>Ce stage peut \u00eatre organis\u00e9 dans les territoires.<\/p>\n<p>Pour avoir plus de renseignements\u00a0:\u00a0<strong><a href=\"mailto:orga@ugict.cgt.fr\">orga@ugict.cgt.fr<\/a><\/strong><\/p>\n<\/div>\n<\/div>\n<h2>PRESSE<\/h2>\n<p>L&rsquo;\u00e9dito d&rsquo;Options &#8211;<strong>\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/WVrK4a9jJn8Id8KE07WP5xOAXajllnOUb7dlwyxWMi-2wZMNslHGf3xWyslIGaQM66YEMTxIR3w7jJX0GcrOZAF5n0Q6mMRJSXHzpc30L2CH9QuOSu6Y8HEr_FeDsRuh14m-axwgFDh1wvraVDz1VEu0Wcmqi2ds_strhSkCuBH21Fl87yyT2-aw5DIQ7d3vDRXsdNo0RAascSQaO3SP2pG3ynZyKT9QdA7GcH4kAIa4UZykjhjKAW6vWeih4Ij9_YYzS92ci8x3BuRDJWj0ji-stJ_EB9ftTTNttTw1Y1_u73GUYfoGt0g4i3-Oy-xwmEzlR3l-sqgqi8hKuu1n05aiSkLjHrCOscDLA9eOv4PPSW8i\">Le travail : un enjeu central pour notre d\u00e9mocratie<\/a><\/strong><\/p>\n<p>Voir l\u2019article sur Lib\u00e9ration\u00a0:<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/8d6G5nMi6IPgIGgu6atniiRefmaprnsOc7ADMT9Z8XrNFWll6deSoZyFpJHrUeS6szdcHH7q25Yx9Nm7rA362KkS8_NmHaWa15CakE_Lj6hhysmXp5MMsSEMir3w-O8tVElUHwPV_3qPTmBHZ7QOwmTB5HaKgMz6T64UdzsqPryI78IdqQEZPa4-4zfdlk944CE_-XdzQRlLWmyR61ZRmKh0KHGvfwLKo60OA-_QlpSHsQ5g1XVTDqzIBdAN5f0mAm1BdKXyxxDcWfMynZ0POssg4XRv22co6fKntGUkOWhjtU-dpU-ZYHdCRZkQG7wW-HTnLChDve7ZcT65GU7fBcbLdITW9Tu-wLhcdo3zkj1ZfQ0y7ADCq3UcbSHKLmurms4A6b81Wd4ndXy5koljDottlmbRFDOB6CNwk4LZGJ16lQ\"><strong>\u00a0La semaine de 4 jours, le mirage du travailler moins<\/strong><\/a><\/p>\n<p>Voir l&rsquo;article sur\u00a0<em>Le Parisien<\/em>\u00a0:<strong>\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/T87zcDbr8iCjugi-MOrd-3xCd6dl2_ZLDl-anam06SXSXn4wpyr6PapKi0qZQokFctOv6OWw-jDdrFlpRwPGHEwOBJrTLl1K2RrKc2CRmdR4aYpa1H1GU1zNSdi2Ps9aBpky1b6fuxU95nsOOoayWRJsaNTsuDZMaOh0Ycmot8fs4BdB_39uFC0u6SlqjIGsNe-YEsWLW7xH4ARo6PQAMmRdSN_ivk6oIdb-452G-lWLRHLVVOh98E6dloUUKG4gahpXoK4vEak6RE4KcDrhKd4qeh0xOjYqqP7EkKUhAbzlllRpcYaAybbMm3NXhH98B9JYGFivZPG8dVYTnimL06GcRaH_6mOMT44R0TwspO2WR1WhHV5nVmRfbKJhrNBzKz2VrRy7O6yydgGDkc2JtygyRNaTLaTI8jLrLqxYZWBaOSG2RDLVnsdpRUXUiSXtnocG60uelA4\">Accidents du travail, stress, management : malaise chez les salari\u00e9s d\u2019A\u00e9roports de Paris<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><b>\u00c9LECTIONS PROFESSIONNELLES DANS LES UNIVERSIT\u00c9S<\/b><\/h2>\n<p>Les personnels des universit\u00e9s (EPSCT), des organismes de recherche (EPST) et de 5 EPIC ont \u00e9t\u00e9 appel\u00e9s \u00e0 \u00e9lire leurs repr\u00e9sentants au Conseil National de l\u2019Enseignement Sup\u00e9rieur et de la Recherche. La CGT progresse en voix et en pourcentage et tout particuli\u00e8rement en ce qui concerne les EPSCT (Universit\u00e9s) et EPST (Organismes de Recherche). Malgr\u00e9 un manque flagrant de communication des directions pour cette campagne, la CGT arrive en 3e position et obtient 7 si\u00e8ges.<\/p>\n<p>Zoom sur quelques r\u00e9sultats de la CGT dans les EPICS (dans 4 EPIC sur 5 la CGT est en 2e position apr\u00e8s la CFDT) :<\/p>\n<p><strong>BRGM : 37.67 %<br \/>\nCEA : 24.78 %<br \/>\nCirad : 30.64 %<\/p>\n<p>CNES : 23.5 %<br \/>\nIFREMER : 40 %<\/strong><\/p>\n<p>Comme elle l\u2019a toujours fait, la CGT dans la diversit\u00e9 de ses coll\u00e8ges entend contribuer au CNESER au renforcement de l\u2019enseignement sup\u00e9rieur et de la recherche dans notre pays et \u00e0 la n\u00e9cessaire prise en compte des revendications des salari\u00e9\u00b7es dans ce secteur. L\u2019enseignement sup\u00e9rieur et la recherche d\u00e9finissent les capacit\u00e9s de notre pays \u00e0 affronter les d\u00e9fis culturels, soci\u00e9taux, \u00e9conomiques et sociaux.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<h3><span style=\"color: #000000;\"><b>CGT FERC SUPP<\/b><\/span><br \/>\nVictoire pour le syndicat CGT du Mus\u00e9um National d\u2019Histoire Naturelle !<\/h3>\n<p>Victoire pour les gr\u00e9vistes du Service des expositions, du Service technique mus\u00e9ographique et du Service mus\u00e9ographique de la Galerie de Pal\u00e9ontologie et d\u2019Anatomie compar\u00e9e !<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/psgcl5QC1OC4fbMwBjHLAdJ1HAJXwmsG8x1MtfTEBBpN05OYyL-6vY31DIR8R1_L86-uiway2Rud3hMvYQgsvcsb1ff8tTXPsB7LKDSF7j6xG4KxI_rfPKLsuOd6lgB2y9S92lfpXfT9PZVgBvnTrnlVkFd1NjwMNCFLb8xe08acVMQjv-rIauNqzRVY9FzoDhXbjErX8cxxKrFiGRc0QcMzLWW8oeMooekDCvi2KiZGHMcrLWjUkTwF7DdKXedQUFKGiAWYArO34aA31OPaW5a-cg_zjkbQFIzU_NCDv92q2eEzliLIMwCiw2FKskfdb8OZ6Z3bC0gufd_FthALT8WFDXx-AcPUsaere3KOSunKe0UeE1sm5Rk\" target=\"_blank\" rel=\"noopener\"><strong>Voir et t\u00e9l\u00e9charger le communiqu\u00e9\u00a0<\/strong><\/a><\/p>\n<h3><b>SNJ CGT<br \/>\n\u00ab\u00a0Libert\u00e9 Hebdo\u00a0\u00bb : une cessation de paiement et un mauvais proc\u00e8s<\/b><\/h3>\n<p>Samedi 24 juin, la direction de Libert\u00e9 Hebdo convoquait les salari\u00e9s du titre \u00e0 une r\u00e9union, ce lundi 26 juin, en leur assurant que le journal bas\u00e9 \u00e0 Lille n\u2019avait \u00ab pas d\u2019autre choix que d\u2019engager une proc\u00e9dure de liquidation judiciaire \u00bb.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/kfRIQGbCKVgh7xRaK3aTGKF9mUQ-mpdR3Pp0dNNHJ87UZ9hJWCjk4vY9xB_czLsrsFcJE9tsb_K4ev6o6BuXkFPKuxG58fxGHR7ZeEEUG_tbmpAL54qo3hLZ1gFOjOGeB9bo7c5K1BIU_B-ycZ4Fr387gnn28pqlD_VARNlHYyDdnaW3e022Bvdsd9jQN6_1PP83izrqVLW7vuJbUQBmRnS-5AoXkGLS_Wn7Cp3iIA0VDauBMdB3f4eav3S54sx5Xnu2YXez1bccUnYshGvzyIG40lf5sU8jWiv2hvtDLMUK1utsrL5-D_9CIs4nsvqNzx1PJEpJR4pYwyCEfI76zGtcHNSUkde2UwqUxGmKYdbyIooCfxm01BfQhH9iInmA\" target=\"_blank\" rel=\"noopener\"><strong>Lire la suite du communiqu\u00e9<\/strong><\/a><\/p>\n<h3><b>FSBPA<br \/>\nEmplois dans les banques : jusqu\u2019o\u00f9 iront-ils ?<\/b><\/h3>\n<p>Apr\u00e8s BNPP Personal finance (cetelem), c&rsquo;est au tour de la Banque Postale d&rsquo;utiliser l&rsquo;argument de la hausse des taux d&rsquo;int\u00earet pour justifier des suppressions d&#8217;emplois pour le premier ou des gels des embauches pour le second.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/nqbqvwXnIeEtT92I3nmn3YeR_14jvLgdkWvBYwKFByYcsbEftw7qMIMs5TCwEOILvJZ1xKmDHmcaKxK85CsugxtF_uOu9lNIPKvlB4hMB8PbH-674fLZ_tW6XaHhzAL57PHtNzovNlOpI0ljMa7SY0jSW8N79zO2Gvx7784Tu2Mt6CG1IYzkfo2PkKs_eicizpiwDYHaneQeZnehc2OZtQRd4lsgoc1khVWUuVfnFYoREeL3LxR0R1yGw_5K68fwxNb1I3niGu_UH2LZmra5S7qP0EcXMwyZ7DaU9R1ELEPNQuA2jIsRSKF7tFo6w7e_oPIvOQs-YfLdLAY0afRTPfaz7TTcaFQncF7rZ1PE\" target=\"_blank\" rel=\"noopener\"><strong>Lire le tract<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div id=\"sb-site\" class=\"global-container\">\n<div class=\"col-lg-8 col-md-8 col-sm-10 col-sm-offset-0 col-xs-12 col-xs-offset-0 animated slideInDown bg-walter\">\n<div id=\"main-content\" class=\"main-content container-fluid\">\n<div id=\"primary\" class=\"content-area\">\n<div id=\"content\" class=\"site-content\" role=\"main\">\n<div class=\"post-container wow fadeIn animated\" data-wow-duration=\"0.5s\">\n<div class=\"row animated fadeIn\">\n<article id=\"post-1646\" class=\"post-1646 post type-post status-publish format-standard hentry category-archives tag-ccn tag-cgt-ferc-sup tag-environnement tag-extreme-droite tag-formation tag-options tag-presse tag-rencontres-doptions tag-rps tag-snj-cgt tag-teletravail tag-ufict-fnme tag-violences\">\n<div class=\"row\">\n<div class=\"entry-content\">\n<div class=\" col-md-10 col-md-offset-1 col-xs-12 col-xs-offset-0 nopadder\">\n<div class=\"entry-text\">\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1642\" src=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/06\/logougict.png\" alt=\"\" width=\"300\" height=\"204\" \/><\/div>\n<div>\n<h4><\/h4>\n<h4><strong>L\u2019Activit\u00e9 Sp\u00e9cifique de la Semaine (A2S) est un bulletin interne de l\u2019Ugict-CGT con\u00e7u comme une boite \u00e0 outils pour aider les syndicats CGT dans l\u2019animation de leur activit\u00e9 en direction des ICTAM.<\/strong><\/h4>\n<\/div>\n<div>Pour inscrire un syndicat ou un responsable \u00e0 la vie syndicale \u00e0 l\u2019Activit\u00e9 Sp\u00e9cifique<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/7Ch87C3IjQNW8WbArOaPkn4Qr71kFg9WDwXvBToFELPGV4JEFlDOlS02Pzc5ClQ5D_TI61ndWBC27X6CgySUd6KUR3Zg9vIZRX9UrQ9e0z-gYoipgmwa4rP13Cw9DYKPQufh_0f_x4BMAyk7IUz8mMW6SKQtgRMSLneQESLpqz3dag4kGsqtJ8XBgyrPN8pakGL5gJD84U_ZgeV4qaE1wYjaU7dKs9ZooapdS1gUzMAh1qn78oxvuItfvNZurWp9tqHF5zyIPJFnZFkzn641AtPhdTGT5qlo7X0JG2EgWrCuRIrngw\">https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/a><\/div>\n<div><\/div>\n<div>Retrouvez chaque semaine l\u2019A2S sur\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/iy034GMGtrM9HY8S5GIUnmrnyWT_y8R7Bz66lmbZK_XHQ7qwkk6L8WWjLfmNhc4ak45utEBugaeq4AlmvjJVyijm-v_c8fnoXWiLc0iF9_8SlO-wCltfaLLVNUcFMud9TycYbvYrkNJM7oNgugaZx_cfOd_IYb2Hdd55uwNugsDJuOgHoeH_WUCpB34k04lrsH_h96uneEXAGia-0e5PBNmn4rLsnY8gUiaqK1zqmcpfaPOZJP-KBXJaQVzC64M0bQ34pfPbwrXAtdGC208vPTo4RhmIo48YRoIM\">syndicoop.fr\/a2s\/<\/a><\/div>\n<div><\/div>\n<div>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse\u00a0:\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/oWRW9xXQwlFgHjFqqQbH6Iff59DYQnSxnEYImTOhD6IeMnGttlU0rMK6UevCpqeLW35jPrLHlHrvh8VS9FBDeUApYNkV1BhCGxQ_WjfUnAJTd4m0CEv34iy5T4cTiwOpi517Se2Qoe31V_0oj007nsAskY4J8skh6hrSOUbjQ9ls0wzGKmIU7rqllKOkVTNbFzYV9SSKN-PmVuu4M963ZIMlLd1kR42vCbTSwoyWWnPpbmWArwXURWIjZ7xWSUEhOiEPveCwIxkPu7YVjPBCj7KEhQs5IZ8z8EZU8TCe9xk\">https:\/\/ugictcgt.fr\/formation\/<\/a><\/div>\n<div><\/div>\n<div>Pour tout renseignement\u00a0:\u00a0<a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a>\u00a0(01 55 82 83 40)<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/article>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>ENQU\u00caTE ANNUELLE T\u00c9L\u00c9TRAVAIL Enqu\u00eate travail hybride de l&rsquo;Observatoire du t\u00e9l\u00e9travail : un succ\u00e8s ! Plus de 3000 r\u00e9ponses au compteur. On continue ! Voici le lien pour partager l&rsquo;enqu\u00eate :\u00a0https:\/\/enqueteteletravail.fr\/repondre\/index.php\/634888?lang=fr\u00a0. Si vous souhaitez une enqu\u00eate adapt\u00e9e \u00e0 votre syndicat, contactez : orga@ugictcgt.fr Lire et t\u00e9l\u00e9charger le communiqu\u00e9 de presse\u00a0 &nbsp; R\u00c9DUCTION DU TEMPS DE TRAVAIL [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[137,26,99,6,102,76,134,35,133,55],"class_list":["post-1650","post","type-post","status-publish","format-standard","hentry","category-archives","tag-droit","tag-egalite","tag-ferc-sup","tag-formation","tag-fspba","tag-snj-cgt","tag-tech","tag-teletravail","tag-temps-de-travail","tag-violences"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1650"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1650\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}