{"id":1686,"date":"2023-10-27T19:19:51","date_gmt":"2023-10-27T17:19:51","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1686"},"modified":"2023-11-06T10:49:33","modified_gmt":"2023-11-06T09:49:33","slug":"vendredi-27-octobre-n482","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2023\/10\/27\/vendredi-27-octobre-n482\/","title":{"rendered":"Vendredi 27 octobre \u2013 N\u00b0482"},"content":{"rendered":"<h2><b>STAGE PROFESSIONS TECHNICIENNES ET INTERMEDIAIRES<\/b><\/h2>\n<p><strong>Ma\u00eetriser les enjeux en interrogeant les sujets d\u2019avenir<\/strong><\/p>\n<p>Du 29 janvier au 02 f\u00e9vrier 2024, l&rsquo;Ugict-CGT organise \u00e0 l&rsquo;Institut du travail de Strasbourg un stage sur les professions techniciennes et interm\u00e9daires. Ce stage gratuit s&rsquo;adresse aux militants qui souhaitent d\u00e9velopper une activit\u00e9 revendicative vers ces salari\u00e9s.<\/p>\n<p><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/nZX6xirhWkIG62VUqb3uQhre2tJQRopWMnnUtMYBo19-0n2RYukysgMw5RM2ehL8f-d49JaVztCFbJ041t_dOBgukInPfNvowPOtw752M94PFl48rZg_MxEmjzuIsjGM6K07pYgO-gKrxBs2Da5mj83pmLptaJTQzYtispi6eMO6ChhSE4tPRr0EOhrQukZIjukNpOjV671GkGsOtkSiuBiHma0L5LgPLxwDLspQyyUmS27GFvu5NkRWzX1FuELnXJE733jW_rJH3Iii_UgQ8bdMW76Za-WYTpWWi9lCzdQsXYuL2Mn0qWBc\" target=\"_blank\" rel=\"noopener\">Pr\u00e9sentation du stage et inscription<\/a><\/p>\n<h2><\/h2>\n<h2><b>RENCONTRES D&rsquo;OPTIONS<br \/>\nCLIMAT : TRANSFORMER LE TRAVAIL POUR REPONDRE A L&rsquo;URGENCE !<\/b><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1684\" src=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat-768x1024.png\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat-768x1024.png 768w, https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat-225x300.png 225w, https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat-1152x1536.png 1152w, https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat.png 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>&nbsp;<\/p>\n<div>Le 14 d\u00e9cembre 2023, l&rsquo;Ugict-CGT organise des rencontre d&rsquo;Options sur la th\u00e9matique de l&rsquo;envronnement dans le 10e arrondissement de Paris \u00e0 la Fabrique R\u00e9publique au 52 ter rue des Vinaigriers.<\/div>\n<div><\/div>\n<div>Les th\u00e8matiques des tables rondes sont :<\/div>\n<div>&#8211; Un mode de production \u00e0 faire bifurquer<\/div>\n<div>&#8211; L&rsquo;entreprise, inadapt\u00e9e aux enjeux ?<\/div>\n<div>&#8211; Les salari\u00e9\u00b7es et syndicats, sentinelles des enjeux environnementaux.<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Y72f79_Si0FhxQW4X69U-wLs5T5FaMuO1fhGbJ0rcqV2G0G4dlGDOm6dTEoCl2RiDlB5kGjFRc6-pz--4rbrX4pxfxxYMmHL0FoiWpHdIPRliiviLz0s85lNqn4evBfpYgL-F13ozTQZ8y-nKze_uIxkabS3aTg11_PJSJMOJYAZPz3TBrqmv1Fw82MyBY1aC6boU4YXvc6Wvl-ZxpmKApGT51-KxgfBwfgLQR8ThodmL3xNeugBg60JqQgR13PImQJkgHAKtBehtgLDZzAHQO57dWHv4XfeVotPauyxxXQ5qg\" target=\"_blank\" rel=\"noopener\"><strong>Lien d&rsquo;inscription<\/strong><\/a><\/div>\n<div><\/div>\n<h2><b>RETRAITES COMPLEMENTAIRES : LA CGT SIGNE L&rsquo;ACCORD<\/b><\/h2>\n<p>Face \u00e0 l\u2019offensive du gouvernement visant \u00e0 ponctionner les ressources du r\u00e9gime sous pr\u00e9texte de financer le minimum contributif de retraite, la CGT exprime sa d\u00e9termination \u00e0 prot\u00e9ger les retraites compl\u00e9mentaires, tout en exprimant des r\u00e9serves. Cette signature doit nous permettre de relancer l\u2019offensive sur la valeur du point et les droits des futurs retrait\u00e9s, en particulier les jeunes g\u00e9n\u00e9rations.<\/p>\n<p><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/LSpB6qpLdYY2FIxO-8iPe2GaPAPFB-J1ll-dFkUSuDYjwYB8blf7zPDD74hvxiXL87okJNq4PZxh84T7NEfXoCrO6A6cWkJFjDYNDV-u9Y6Fr4nLezYYsVr3L1rlda0xQeSDFOyYx0X2ZigPAo-z7EeCZnPG1tUbTx1JOeNImG_gn6eae4fAi06nbBz2lMOG1f_pVntYTzoOrn9zKFOdSvVblvm3nnZUCGuDrBjOLJnA-fK8Mhqy3HRYBfBabJzlsaF_0WD4g2MyBjiTsChLCZq8qJaxy7eMnEsL0UeVddktZ41qt374EKP6eAoCMQX1jiCVZbWJKJGdAefQG207rA\">Lire l&rsquo;article d&rsquo;Options<\/a><\/p>\n<p><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/aYI4izGCKFBahh2YrTt4ZPSIt4P4k1BD8W0rR8lEyLue6eh_o7IgMOe8ZiIqJpGD4NtIJUZAFb9YPcxe1fgHryuf2GgEmDLo9QimeonRoqqRGiYtHrblal899ThBWwyz7APtrxfConpc0Bc_UHb_TIlAoYAHsceKWAqKi7Fmp3aq0bmC5MJeKUPatJhp5jq-1wi2Yk4CzFTKvJ_BWjPwDFvWQRNOWw8vSliBOaYdcSUyFvAMWhCqKdZoODzjAE_RtYKcERqXQrfJuvxvE8cNv5uagA3dEKhpCmB5rS2H4WYJKE69rWd1jA8S_nvXwYR332SPs9ym3welNSRCGPWZ5zwla-flrCtivtRlu3dezalrCD7uzVquJtnvZJLdHFZKLJBKTWuxB21maeFKbyk42mrWITo3RFL9FJdh\" target=\"_blank\" rel=\"noopener\"><strong>Voir le communiqu\u00e9 de presse CGT<\/strong><\/a><\/p>\n<h2><\/h2>\n<h2><b>SALAIRES : GOUVERNEMENT ET PATRONAT REFUSENT DE PAYER NOS QUALIFICATIONS<\/b><\/h2>\n<div>Lors de la Conf\u00e9rence sociale du 16 octobre 2023 la d\u00e9l\u00e9gation CGT \u00e0 laquelle participait l&rsquo;Ugict-CGT a propos\u00e9\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/FMSv6UC-QMrS3S7XVGzjquX1V1JZC2_6qOScR2ydPGiMzimJ70vGloaHVvswHAoGszeirSrK7j0P8g3Odf-Tk4a2uPKnTvfS56uOtl6QD0eUD-nH_eag_8GS80Hp2zZOr97D1Ji449PAA2qsJpBbcpxOSPEThP3PEa-s4fjlvqo0Kl01W3Eb5ZPLjOBCStwFw7F3nV9QBH-_zOkg-PwGtde-RplQDIpaukuSG999Oz5A07IwregigmmhSexn9LI3diddDC4YbzUGzEdi8St5DTwaVKAv082mH21PGLYabPHFXvlAjQVNNxdIBGkpCrhUqeLZ0S3wrMjDIPjIGKM-dpCN9wjBpAkbEwordbaSoWi_gV8Cd4mAQC65iLL-Ae2aHionA3dthjLuwIiS9LD8aczIhILUekBGm5rWLZ3n4gidQV-VO_0\">de nombreuses mesures<\/a>\u00a0pour permettre la reconnaissance salariale des qualifications des Ictam. Gouvernement et patronat s&rsquo;obstinent \u00e0 se concentrer sur les minima de r\u00e9mun\u00e9ration (d\u00e9cryptage \u00e0 venir).<\/div>\n<div><\/div>\n<div>Retrouvez le tract salaire sur notre site.<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/gzHmmF53iei3KXDQ3PaToFZhZFle4wbYbVcJ9pfeasCH7X3Nlrpb0GqMEiQXj6Oe1mAcVLWKcDhgR6w2bUaJLf3Vso5Kv_cSO4P1Im0Xc2hk5u0chGuZSd_64OeOew7Tr5kdGBUyXtnr9u2KBLnHurf2hn8DaPkD7qjI1fQIwBZI_jLhCh3rOOMkz0RAEYGf3rpVzk_ybyRlYmCTy4fZNdo-woGvuz7U2BsyJjRApH4wdxmELIo0OQwy9d7_loo_I7rsUu-M9vEuwRKfX10MhJe97rUBQ3Lf\" target=\"_blank\" rel=\"noopener\"><strong>Voir et t\u00e9l\u00e9charger le tract en couleur et\/ou noir et blanc<\/strong><\/a><\/div>\n<div><\/div>\n<h2><b>CADRES DIRIGEANTS : LA RUPTURE !<\/b><\/h2>\n<div>\n<p>L&rsquo;IFOP a rendu public un sondage sur \u00ab\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/G76SjtYjId2QfNm2KBjpblTno8JrBtuUBjO5UALgiLzD-nucPXcayVKSnz9HO1xKDh6vwnZNQRoIchTtcJ6ClzyavKH2rvAON9zHCZiMrKEOlyL3nbI7kY_HuSyEs0e04AOX1i0FgJ2AB245juupssq56t8wFz3cJhoFweeaUrJbpqbVnluUZ0eVd7Fb4Pt_d9OCSTXf-REodyWvGcU6furFaaOLVm3XUK17fwyyGwlSr-c1p9QIeu8bMC2iua8HdMGFjN7Lgt4xXpwCQKERgaO6QX_6MSDN4tTFSDzUMfIw5BeLVd0qM9ZsSde0g36fDbxjq-YiTpzv2MPpTvxzz7pP-Kx_Iyv8Cs_XYx9XwC08spAIarxzkldxxjYLPLrrGBsuIg\">Le regard des cadres et managers sur les \u00e9volutions de leur entreprise<\/a>\u00ab\u00a0.<\/p>\n<p>Dans cette \u00e9tude les diff\u00e9rentes \u00e9volutions qui semblent plut\u00f4t souhaitables pour les cadres dirigeants sont :<br \/>\n&#8211; le d\u00e9veloppement du t\u00e9l\u00e9travail (68 %)<br \/>\n&#8211; d&rsquo;augmenter l&rsquo;importance des indicateurs autre que financiers (71 %)<br \/>\n&#8211; mettre en place la semaine de quatre jours (65 %).<\/p>\n<\/div>\n<div>Rien d&rsquo;\u00e9tonnant quand dans le m\u00eame temps ils d\u00e9clarent dans le dernier\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/jdyEscK7XnXd7hPtBgVe2OlqSTU-g_6CFW916UPv2LuFc83F-wYODgxt-XT-xaS1jYvPKvcwPgDESVnUPe9ZYzAf_zKBRmVDeBCF9boVP7MgurHMPTRA3UHYqbOK2VHBNF24wWurOuPj6R_u76VJMfkXQgNzA8mdvipL082V54kUYOOl6M7yFWYXyAu7lZv_m293vy4jCAzXNYZnHPZ84CM04N0faw8fRigW_URCRtDLpzIOaTYx026dDbKHxsFKcvKdI0B6plxtnEdBTs3hvovdwHn9XYNsuAcM\">barom\u00e8tre Malakoff Humanis<\/a>\u00a0a 83 % \u00eatre pr\u00e9occup\u00e9s par les situations de fragilit\u00e9 que peuvent conna\u00eetre les salari\u00e9s de leur entreprise. 52 % affirment m\u00eame conna\u00eetre un ou plusieurs salari\u00e9s en situation de fragilit\u00e9 d\u2019origine professionnelle.<\/div>\n<div>Dans le m\u00eame temps, de plus en plus de cadres dirigeants et sup\u00e9rieurs s&rsquo;expriment, y compris par la gr\u00e8ve, pour d\u00e9noncer les d\u00e9rives engendr\u00e9es par le wall street management (gestion court termiste par le seul prisme financier). Le 19 octobre dernier, par exemple, les directeurs-rices du secteur public, et acteurs du secteur sanitaire, social et m\u00e9dico-social se sont mobilis\u00e9.e.s pour l&rsquo;ouverture de v\u00e9ritables n\u00e9gociations sur, entre autres, la r\u00e9forme de la gouvernance des \u00e9tablissements avec les moyens n\u00e9cessaires pour r\u00e9pondre aux besoins de la population et la reconnaissance d\u2019un management alternatif, autour du service public, respectant<br \/>\nnotamment l\u2019autonomie des directeurs-rices et leur droit d\u2019alerte.<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/EpeTn6_KYgOTDIFt1WAgKN5tFKxAG4owuLlVE3WvYKoZ2x33ANPmElhA4kJQRxhdjWksmatn2DjGV_zp8WCMB_grYlVpX9ko___CCTRr77q7NjfLOZOyrF3eiLt5iWLs76TpGFcAGkedcnFpXt9wVfioO6Fjw9estgopfTzReqL-zHCwM2XaC6v1mFBGR0QRPBg_G-aSa-UAfACVKV7TkiZxi4hevwUMtitNCZxxeiCTYN1CkBh8ei-6PeD0DiJj-DH2JPKvaR14Nkm2n4urTAs78I1MsBc8yd9sUfFl7AKPS3L2j3pJZhfGA45Xv3z0pAu9BpcISKyexOyHGoRvZf0krZT-NRBHGexdag\" target=\"_blank\" rel=\"noopener\"><strong>Voir toutes les revendications des directeurs de la sant\u00e9 et de l&rsquo;action sociale<\/strong><\/a><\/div>\n<div><\/div>\n<div>\n<h2><b>FORMATION &lsquo;TEST&rsquo; : STRAT\u00c9GIE SYNDICALE SUR LE FORFAIT JOUR<\/b><\/h2>\n<div>La formation sur la strat\u00e9gie syndicale sur les forfait-jours s\u2019adresse aux UD, UL, UFICT et f\u00e9d\u00e9rations. Elle a pour objectif de donner les outils pour comprendre le forfait-jours dans son entreprise et \u00eatre en mesure d\u2019un combattre les effets n\u00e9fastes, notamment, le cas \u00e9ch\u00e9ant, par le biais d\u2019une ren\u00e9gociation de l\u2019accord d\u2019entreprise.<\/div>\n<div><\/div>\n<div>Cette formation se d\u00e9roulera mercredi 29 novembre, de 9h00 \u00e0 17h00, dans les locaux de l&rsquo;Ugict \u00e0 Montreuil.<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/nPPqPwZOSdOOH9V7ze6KT1FyOhl6KXglVFq0Q3u06-Gqxt-utkEwQUsX6MpbdsWitikrxJKC-0Zy7vIQJug3woXmaMChEK4_bO_qgc1ugXik3J_-toC2FIIaljU_FKEAaYXQwuwMlggKP63fGGDqLCzjkYadSIQzuxhNelPcmEZhl_xkgX8X2WbzISHVNth2amWpEPO65dX-tTMp55XbV1eZnxNe6T0BMsyqnGrr45Abs9kjFYk5Bfu3TlJc1fRJMUV9WyM2rZf1KmgBTwV2jqfpedxS-wdsHC-g-SusTA\" target=\"_blank\" rel=\"noopener\"><strong>S&rsquo;inscrire \u00e0 la formation<\/strong><\/a><\/div>\n<\/div>\n<div>\n<h2><b><br \/>\nOPINIONS ET ATTENTES DES CADRES<\/b><\/h2>\n<p>A l&rsquo;occasion de l&rsquo;initiative de la D\u00e9fense, nous avons d\u00e9voil\u00e9 notre nouveau sondage Viavoice \/ Ugict \/ Secafi cadres.<\/p>\n<p>Les cadres sont de plus en plus nombreux\u00b7ses souhaiter agir collectivement pour gagner de nouveaux droits : 40 % des cadres sont pre\u0302t\u00b7es a\u0300 se syndiquer pour gagner des augmentations de salaire. Un\u00b7e cadre sur trois (32 %) perc\u0327oit de\u0301sormais la CGT comme \u201cefficace\u201d pour de\u0301fendre les inte\u0301re\u0302ts des cadres. Cette confiance en hausse (+7 points) et cette volonte\u0301 de s\u2019organiser est le fruit du mouvement historique contre la re\u0301forme des retraites : pour 51 % des cadres le ro\u0302le de la CGT a en effet e\u0301te\u0301 important dans cette mobilisation.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/gWPTxF09ifNP8I3QIVpPYD9HoooyjcI5GEkd1XV9rDmW4OBihCyvymQhPcN9GFjGVGeeD7XeD2rSvC721J2J3XxUvC57Vb7ZdruGw2IreVkYrpK6SEYtbdqW5wpgx2Q_tRko4aktC67NJ2V3WePTayXUMPLDqxHKVA5fd21xDioZi60drHyHrl78cMaFXKF91G4BsmbIKxK3lJK52IV_q1YszTy_YA-Ehiuw8X_qsuQ3ARy2g7W-VhtBXk1jAY-Tb07jQIDaGzzBlUJ69yJ_7G2NLYke6BYgY65rw4WfkynYZX7jIMzk59qPRao7C7IN1h_LEaCbPMpHIZFYPcGkeJZuycog8eNAjphbKbJ_2aBQVsKlY7RVlcZgyXXc0EXfR-mstSVseMIaDn8CiTuMZkR3do9D3E_EXbL_W0RNt9DjKhWYcsWFl12CAbEDboU4Esw\">Voir la d\u00e9p\u00eache AEF<\/a><\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/l1SR9EgAIrpCVKxeqdMIXGVCd6dUtrTSmBxa7c03xfjhRBco226UAWFCnaCerTnsnHCXGe2WedEkZXz9_GKvuVvNCLZG4dfVv4oY0RjB_A7EykzVJ5ub_MXJcZlSaKGWDnF3audZLViCObcEnvAUZkldacq9ZUxuuxh9aGfX1Yz2zVUJUCH0bQDw9IGjhfZp3L5Rk7DdjrHN-xYcE_Q11yZa58_LCnwFMLnSvC07yC7UT2zEdgxpm0WHxYlAW9QbEsHzr7b2M6eVzLDLO1bT8UMooBa0ow-sEDSeBjGsiKm_qlM\" target=\"_blank\" rel=\"noopener\"><strong>Voir les r\u00e9sultats du barom\u00e8tre<\/strong><\/a><\/p>\n<\/div>\n<div><\/div>\n<h2><b>POUR LA CGT : COMPRENDRE CE QUI ANIME LES NOUVELLES GENERATIONS EST UN ENJEU VITAL<\/b><\/h2>\n<p><strong>Le nouveau num\u00e9ro d&rsquo;Options est paru et en vente<\/strong><\/p>\n<p>De plus en plus dipl\u00f4m\u00e9s,s\u2019impliquent dans le monde du travail en portant toutes leurs contradictions : individualistes et engag\u00e9s ; hyperconnect\u00e9s et attach\u00e9s aux enjeux environnementaux ; centr\u00e9s sur leurs aspirations et solidaires des plus \u00e2g\u00e9s. Options propose de questionner leurs rapport au travail, \u00e0 la citoyennet\u00e9 et \u00e0 la d\u00e9mocratie, moteurs de leur mobilisation dans le mouvement contre la r\u00e9forme des retraites.<\/p>\n<p><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/UMRz3-g4Zlo4yiVzM2b1UDp6kneGOq7-uIwACu8YUFUgWFfb4h9F5cJFgu9C5GcuvqiJWfOzd5jaOSX5Rfozhy6WtXqiBr8xLziShtu1gQALsQlvVkM883Nea1VOltlAse91mF2fB7RyDIqX3iUfZrID6ir5w--BBhDzRoaOEwf9MEJiOvGsFLcT8-LCbC0TIEbYqfvgHhYIKz4lF3mRvBeGI3hOv4PxSJf4ofhI3eSge9gfA8K6ogzr3dhAHyub2jtYV24nIJvFhUsMsrD__yLpKg_C_8UICHwXUcVHaxhB_y6xctOGEMmDNgpEpUVAzhJo7q-zVDr4hH9QqRyJBioftRiyQpOlxRZW26CLe0yS2CDd8zSGk1wcWV0\" target=\"_blank\" rel=\"noopener\">Commande<\/a><\/p>\n<div>Sur cette th\u00e9matique l&rsquo;INSTITUT BONA FID\u00c9 POUR ARTHUR HUNT a publi\u00e9 le 13 octobre une \u00e9tude intitul\u00e9e : \u00ab\u00a0L&rsquo;entreprise en 2030 ? Le regard des jeunes dipl\u00f4m\u00e9s\u00a0\u00bb.<\/div>\n<div><\/div>\n<div>Le rapport \u00e0 l\u2019entreprise des jeunes g\u00e9n\u00e9rations se modifie en profondeur :<\/div>\n<div>&#8211; L\u2019entreprise ne fait plus envie qu\u2019\u00e0 un jeune dipl\u00f4m\u00e9 sur deux<\/div>\n<div>\u00a0&#8211; Deux tiers des jeunes dipl\u00f4m\u00e9s pr\u00e9f\u00e8rent le temps \u00e0 l\u2019argent<\/div>\n<div>&#8211; un sur deux envisage son parcours professionnel hors du salariat permanent<\/div>\n<div>&#8211; un sur dix seulement croit encore \u00e0 une carri\u00e8re lin\u00e9aire au sein de la m\u00eame entreprise<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/XTZ18NeYPPm6WbSyEvv9oEZrY4grwT8rZFpP2KRr4L4rSodTmzCl3i7TM3fnx5W0BsvvLzMwh4Q5uaahtM63CEktMZ-imIm6a8HkyXTEf8rmD4zkSK7jFpXmI8f43o3mYxD4LNMYtQJKvpqr7SPH3-K-hD9s8UXV_W9WbZfY1omc75vwWDcDLt_B4w-sK2iewKk1t61Kycp7mh_dNA5Zc_G2FrSRmAH6exCa1p1bGPEecu_UOONiPzc2fJA4ooIJqWw2eY-LMTy5q5tlhovi5Gv4KMkACzhgG1nRnQvC9fz8vTaqWg19hIHHWTjf4pqhOiNn7XYxHuqqL-Mt0PYfCAqtl_WokTYDxbYGAmG0bV5PU-JnJvyZDV1ARt7a7vYt21zkqRRkNE7k\" target=\"_blank\" rel=\"noopener\"><strong>Voir l&rsquo;\u00e9tude<\/strong><\/a><\/div>\n<div><\/div>\n<div>\n<h2><b>CAMPAGNE R\u00c9DUCTION DU TEMPS DE TRAVAIL<\/b><\/h2>\n<p>Lors de notre Conseil national du 20 juin, nous avons lanc\u00e9 notre campagne pour la r\u00e9duction du temps de travail des ing\u00e9s, cadres et techs.<\/p>\n<p>D\u2019ores et d\u00e9j\u00e0, vous trouverez du contenu sur notre\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/21n-n6fDqhZ2REBTaaZ43rLMsgVmgaB4LNZv5HEVQUwkK4vFnkz7I-wky264_gPxAIquylUdfuPpJDQ9sTdOL2P2QHXuifNkG7_6umTmhPq6ts_1vpWq71GMja5qIShHNi77G8PXCDSNriod6qG8n-XYdQNaqEn-0LxN6HUPfeFiHISttx0tROraos7H8USUyv9sBAyHGZIREg7_ZuEY6AQfxdbdz8rpIxEut9HZWg0-rWh5tnqGftjJueOQLeuG8Tzkt0wBJ2HjaL69G0j77QTUEUHVdSOm1VH1bZpMlBYZARg\">compte Instagram<\/a>\u00a0et sur\u00a0<a href=\"https:\/\/ugictcgt.fr\/reduction-temps-travail\/\" target=\"_blank\" rel=\"noopener\">notre site<\/a>\u00a0les premiers tracts ainsi que les premiers outils\u00a0(<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/aFCVs4UDw1nkrpcJjEzSS49JYk0yEd3kC_4Q8WDeL50v2qn1aZXsW8uibpNJ4iG9zkfbGc_CNfJOwCzSqT2bwLhOSZg7-BeA9G0yZsJF5xnUIUIVuR53G6Vl-Z85-0iNsU4l8mN9i2XWjPOPGSaMQM-pmIqfMoju6JprQ0Np4mZNu4Qsgt4W3EqkTkz66nvoyfCOjsHZ40sd332COuD29zTw3pmNEkhO6r9aNjAt7ef2GnQdkgsWTUpSIoREg97hkSsQtsGZZT-27KhzqaeZQ79pZsY90HnkRW4DB4HqXz17hiXBbpwYb0QgdHx4ZyBQjF2vm3zf8g\">trac<\/a><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/PrufdGNU8jiCKRnEitzGFZiK5jtIE0P726ggyUat5MtZi076EA6UKrVktVfSUuIZKkPHQqE2Y-pLLT_vrS5ObcArbLet0O98_KMVosP1_UpnzFMSd9lrDyqMXqly3ATHrAYKBHheVQsIAr1EcNv6MOtvUytHhq2ymor0Ejt2UMqeaPbEnM4Bp_dpnoxsrmWC6bf9itjyhXfbHgWNV33BCMEXWUrqa0C7zW5qzXVytzAABb5h-3dXydj69a13jLwixeRsV2ZlmiPPchkrVY24IqoE9nvD6Im9sKDxz7m00B_07ckhxfqzBozKiYyY_e-rGcGYEPRr8Q\">t sur le forfait-jour<\/a>,\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/2ZVnleAa5E7Cin2JTS8a2knVGHtQ5rvSka4zIfTuGBYru4LxBLlDg1piHN7hNqUN2Vr_1YtibV16cZv8SVpf2WVvY0a98DdMuUTF2-bl2ap__5PCXuwa4IPcTYPOgwFYml-88JO7szQtRvGErfcnuEQSjj0hRTm1TRFM0kfDN8pfSjGJm_pBkXJSTZHclYZChNxCkyMb9RU2dWZIaLFOHmCEYfrKgw1EQGV5TFj3OxH7oDlRaHeqSpOzTY0d_QovzJRnb8qc227XlZJxF0My8z0U8pwAH1tLxp_vLq2Z9c8AEY7fd8PwxeElhw\">premi\u00e8res affiches <\/a>\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/jFc1TBS50DsFpWURAYru78SRPqYQj1BzwQwr0cJCT1mAj4J7fWBEKOoajtf9vLMrW_S9-fQXyP0MFnU3CrZKRX06A98J_sk_fIJxK2qBG2r9iKNnGfs-4DWjlJJuPItE_X_-aoX0ecPLZwSE8pSjx405rUQDLeszbLwaFSguOOJHK92el3ftwlNLxQcjIy1wezEMdtO_LnYAKqBAZn4r8k_lwJw6u7zATPnsCO-8bhZcD56oZVy9HPoqlH-o0RB2YUBle22Lx9q9KUTWGibVgMjUFsMmMSX1uJv7NzmNHsm3WBFP1Tq71Hv778_w4IcfRdB5kHmDeDZPvuVxHU5dnPtjF_v5scxAbQ\">podcasts<\/a>\u00a0et\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/wq9yTDJ8qb4Rd76WwkCwQaYaBMm1GAuPAnIY53WHg48t63WoZruB2jEgZ1RkYfRj-symg8a0Jr1_hWL7KMquPSGgTJwmc6C1VuF-NFkqBZMID0OEt1rMp1phBb57OVU0BEHMp2-LFaUwcaYh2l-Hu_BTv8e4doagwIxhN_0GMPP5u9mu1R3XxXlLK0ntIrxfPYcTSY_zKq9ABQryp4Y8EOZMLk7SCpmrP5X-M4AofHjLnKNVETHSo0KO0sVXtQMaL16mSeQEWCq35JPS3Ip1R-9GYQaHRnd2O4Yg1NdiehOVBXTa0KxYTItXdwQ\">g\u00e9n\u00e9rateur d&rsquo;enqu\u00eates en ligne<\/a>).<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/wxecKX7uByINEMxdHR6wWes9qiNRk_sHI3aagqLaSA3MQ41mZ4eZHnMrCgpafCDEiSOXZGsZ-d-ZncyXgdX47lLNGrrhk6EgVKOaGEJJJQX_UEX4QblKuIgmlAHESpZk_iNm44QBKkiVeR5aKDixoK-0-H6ZU7QotOx-3LlMzCyyjBAPuah4_Kjg6KQYdNGu6kFsDTuLS1zzHJRT1cVqrgH60l7rMrC8adEAotZWPQi--h_UvFNMTsm_DmLbvPWDsPmtB55DUr7H210tYojbSwOE29zqR8-JcNotb4RESVLak9t4l4xVqBhci9Fiyf5FJtk-DvpZJoTBaS8ZT26q2YF33CrBKJgAwlLpTug\" target=\"_blank\" rel=\"noopener\"><strong>Voir et t\u00e9l\u00e9charger le communiqu\u00e9 de presse<\/strong><\/a><\/p>\n<\/div>\n<h2><b><br \/>\nPODCASTS : \u00ab\u00a0TRAVAIL HYBRIDE\u00a0\u00bb<\/b><\/h2>\n<p>Les Rencontres Options organis\u00e9es le jeudi 15 d\u00e9cembre 2022 ont permis de d\u00e9battre des impacts du t\u00e9l\u00e9travail sur les organisations et le management, que ce soit en terme de temps, d\u2019espace ou d\u2019activit\u00e9. Retrouvez les podcasts issus de ces table-rondes ainsi que les articles parus dans Options \u00e0 cette occasion.<\/p>\n<p><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/h_Bku_MySUeD-NzNgIFpqncxIsm0myVl0QS-7EP84gYDS9a-fymscRL-2IhDLfb-hjwm9VQYF2XbOhsNf5fxLWIj19kUdIFBqh7lz5QRZqOT2TwMS1QyNeMPFv-lLflTl1biYXuMs5BS6u-11BR7ygIw0REmbZQUtpd05YCMRQ-7TcNH3R8jPo31GNQbQatuv1zJry6r5vIGnwofD-UPsXmzPwIvS9SO09nZQIHAbEjGsdmgWZWvWcmuEyk3dP1o3S2OFrhb4Fr5owqJxG-uUeCNIyHpnRDLm76BOTHznwPVdvE\" target=\"_blank\" rel=\"noopener\"><strong>Ecouter les podcasts<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>AGIR CONTRE LES VIOLENCES SEXISTES ET SEXUELLES AU TRAVAIL<\/b><\/h2>\n<p>L\u2019Ugict-Cgt est laur\u00e9ate de l\u2019appel \u00e0 projets 2022 pour la pr\u00e9vention et la lutte contre les violences sexistes et sexuelles au travail du Minist\u00e8re d\u00e9l\u00e9gu\u00e9 de l\u2019\u00c9galit\u00e9 entre les femmes et les hommes, de la Diversit\u00e9 et de l\u2019\u00c9galit\u00e9 des chances. De nouveaux supports p\u00e9dagogiques, de formation et de communication, sont en cours de d\u00e9veloppement.<\/p>\n<div>L\u2019Ugict-Cgt propose d\u2019ores et d\u00e9j\u00e0 trois outils pour agir concr\u00e8tement dans vos milieux professionnels\u00a0:<\/div>\n<ul>\n<li>Un webinaire d\u2019une demie-journ\u00e9e en ligne\u00a0:<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/8gKP5-_p8P_VpcgSYV6_HFkBw17WUo4btD5_yT4nmFO3GhcPeoaxic5ReX-SLLGmrBY-jQW_Bjq64yiCV23oJU4t8u3ObvCxvKP2SBmRCJuMwJHjeSytwl_LfGrwGLQsKNJUWK7R3-g6DBH5iHG7mrapBrYqUp-On0cyLAYGr7Ov9FEQAGF8cIxsb3wuQ0LqvXDOjwFOaCRmW7F74CUFOwqQm7Ts3w9kLT9pTGhJ4uaY1WtOCOtJsOMU6WUcjSsJ4HERw3kcmMeAVbnBnh5on6DbMPbMTBEU5g\">https:\/\/ugictcgt.fr\/formation-vsst\/<\/a><\/li>\n<li>Un stage de 5 jours \u00e0 l\u2019Institut du travail de Strasbourg sur l\u2019\u00e9galit\u00e9 professionnelle et les femmes cadres\u00a0:\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/twwaT2T_JNhMUbx7pofUYWOjGMsauQBNxty2antXyjcxNpUHmJrwlrgDszUeRJHVBWqaNwjH5lD4fynPu8fvVNSYkA2PUt6n4K5bTKNb5GsQwCrRNYOtpyjnNRgv6LJdOPtYIs8feoCTgg56eHXn-wxCi9W27KWRn9FSKRZy91T7s1HdfWqFu9qhFFe_Xp1kNtvmsRiloXQO5vDHdIdDjfEGjNuRTC1Wdp6NU0OOT96hbKudg-LZSDwJOLawj3Xe60fVyGsANW99oSS9yW7g44zDiI3QhppjkdRqd6FdSmNQva7XuX4FS3A\">https:\/\/ugictcgt.fr\/stage-egalite-professionnelle\/<\/a><\/li>\n<li>Un g\u00e9n\u00e9rateur d\u2019enqu\u00eate sur les violences sexistes et sexuelles pour recueillir la parole et les attentes de vos coll\u00e8gues\u00a0:\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/lQ4OhdSQ8hHVm7VoBCB_9nWVuqeuhIOnv0MpECUPgmnxPAt6zKBqY6ilX6kc0TGOVbMSIAFGmjrNPlDvF2trP1TIzbnL15aCjQMzFRYHZyICyZoFIbdMo7PX5BimYWQVeulEtbPieox56yy7pOEPjONHnaQMQA4HgNg39NjrDVf5jn0ir3hkdQxILIwwZjGNS0bWZ5qqkM0UNSXD4qOAJ5tShPkJRyoqtwn0S2GF98vqNCMiL09VE3Qj48m4T0PpAfp6LOjcsU6fuWdmfQH0PA\">https:\/\/ugictcgt.fr\/vsst\/<\/a><\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h2><strong>En direct des orgas<\/strong><\/h2>\n<h3><b>1\u00e8re conf\u00e9rence de l&rsquo;Ufict CGT de la Construction<\/b><\/h3>\n<p>Les 19 et 20 octobre se d\u00e9roulait \u00e0 Montreuil la 1\u00e8re conf\u00e9rence de l&rsquo;Ufict-CGT de la Construction. Une cinquantaine de camarades \u00e9taient r\u00e9uni\u00b7es pour d\u00e9finir les orientations et \u00e9lire une direction.<\/p>\n<h3><b>A Orange, la CGT FAPT s&rsquo;organise pour redonner du sens au travail<\/b><\/h3>\n<p>A quelques semaines des \u00e9lections professionnelles, le 28 septembre, s\u2019est tenu, au si\u00e8ge social d&rsquo;Orange en direct sur les r\u00e9seaux sociaux, une table ronde avec Dani\u00e8le Linhart, sociologue du travail, Caroline Blanchot, secr\u00e9taire g\u00e9n\u00e9rale de l&rsquo;UGICT CGT et Magali Vall\u00e9e, \u00e9lue CGT au Conseil d&rsquo;administration d&rsquo;Orange.<\/p>\n<p>L&rsquo;\u00e9v\u00e9nement fut anim\u00e9 par Sophie Labrune, secr\u00e9taire g\u00e9n\u00e9rale de l&rsquo;UFC. Nous vous proposons de le voir ou le revoir sur la cha\u00eene YouTube de la CGT FAPT.<\/p>\n<p><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/E7P2pibF5NOFosBhoZMpw-ud9XnmoltOYZxeebSLXQ8oCI7AmUkhToYE2y1CfzNlIgGqVz0TaPDFVh8SzCtLxs8DQRhaL7ghsn9nSPLNHfCcZW9VDbyQ3It_1pkUMihqOuS3T5X9BhJBouLGTzjhUG03v3yf6A2ombDaFsYD4nLzN2x7jDC7v1RBfhsUiYSUcloyBCwBk7ed-6BnfzFpXcmdYr_HTU9yT50N6nzWtfijUoT9uGLfH2L6X10Qh-tJN61UcwuRHIzgsZ46Gh3CuQu3ajto0CgyvbOVfIM1OkBOvjZXzBSj6Mwt-ufY\" target=\"_blank\" rel=\"noopener\"><strong>Pour acc\u00e9der au d\u00e9bat<\/strong><\/a><\/p>\n<h3><b>La commission d\u00e9partementale Ugict 69 se d\u00e9ploie chez Cl\u00e9via \u00e0 Jonage<\/b><\/h3>\n<p>Le 19 septembre dernier, \u00e9taient pr\u00e9sent\u00b7es sur le site de jonage, des militant\u00b7es de l&rsquo;Ugict-CGT. Retrouvez l&rsquo;interview de Sophie, technicienne \u00e0 la CPAM, SG Ugict de la CPAM du Rh\u00f4ne.<\/p>\n<p><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/CWuQMhhzRp_97SI45FtXz7r8lVy7hFHQ6EtNqZzbdkWXGeLmGJEPpcUd-kpYKkzvPOocW8HIw6H5muUAB4aiw6tHAtdKWm6JZjPiWDsWcfLgVq9GEmdT9WjL2u-i05sxOD0nA2GLoSdgsfaYIgsQzwL2Cj-8oh5jISXn5mb4moCFgTZ7MKdWFFIyzgQZGyvpHXwvObPOmMf5RUX_dUovLC_e2WisUCpLZl9iGRSncPnmNbK6txSgeaMyN5esSrAjUoK940yAyjofr9zlA0Np_g\" target=\"_blank\" rel=\"noopener\"><strong>Voir la vid\u00e9o<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>PRESSE<\/strong><\/h2>\n<div>&#8211; Voir\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/DkVYQclrodv3uiUROKVxtjK_4fu4ry75IpBJmlI-GLSucC9pA_0Tl2rqrKQbDzXOwe76dCuVcBcxg0vOTmzK43yk1viTT1e4-0l-rnQMB8y8At7MB-zyNyjzYT7I_IsjTsLkzXhjqOuft8Q1Jf0o8-S3CWANqhwvbpIOdeUJTuokAFxs-tn4-V9uygRL7SmZcIHjwxWeg5TvhLKQ4i2OQQjm81yg7QH_ytilyt9XJhQzkQP1vKsjgAJ73mnZ3nCLVsEN0Pmeu07MuQQ_l9ektBWmD7KrIH9UMtOnrpFeEL6PBAzQgtLd0mh-wFNWYlcfpUOAHDuJx2TftSbvtsoy_5L2tSOBUbpZBSTw8MozAXoUkEB9WElGyqSZckq2zF5OTnAdFQIpZhQIGmgmGogppUpdrR65kQr_kWYx1Qz6nou9d9bcO6W6KCPkOw\">l&rsquo;article<\/a>\u00a0sur Cadremploi avec une interview d&rsquo;Agathe Le Berder, Secr\u00e9taire g\u00e9n\u00e9rale adjointe de l&rsquo;Ugict-CGT, sur les salaires des ing\u00e9nieur\u00b7es.<\/div>\n<div><\/div>\n<div>&#8211; Voir l&rsquo;article de l&rsquo;<em>Humanit\u00e9\u00a0<\/em><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/W_je5YfT1mwHRomEOmSSrdcCUYXf2bk9UXxTJMovdqRT415YRo6Ake0d_XRzF6NLoo1JrLpiSJO-r0NSE3NA5hjCpmNhMVYofo49wrzThkRWoulo3JYexhuCqwkMOszzKKq0q_sUUmaPRglKZKRNBc-2pw5zpCXmTpr_WfK4cvHc-NnI76pXXQe1pzpiPn40zSbwdeD8Rk-eCPmN2azujy7eVjXW9X7LNB1dZEzKnv19qXWMX4crnuk3R7L5yFuGEP7_Or7jJ9n9Vl4yB906cBFWU2XDrL4C6zGmzqKUaEhJhr5Is5jHqPGR8EyWTCqC01y3sqQ9GJZSgzIjiB9mNq6UcYXjuRaEOiPqBN0fHEFpdaW5-zDUktf3XQoW_L0J0A_2Fg\">\u00ab\u00a0La CGT aux cadres de la D\u00e9fense : \u00ab Allez-y, cr\u00e9ez votre syndicat ! \u00bb<\/a>\u00ab\u00a0<\/div>\n<div><\/div>\n<h2><strong>AGENDA<\/strong><\/h2>\n<div><strong>2023<\/strong><\/div>\n<div>24\/11 : Commission Ex\u00e9cutive de l\u2019Ugict-CGT<br \/>\n25\/11 : Journ\u00e9e internationale de lutte contre les violences faites aux femmes<\/div>\n<div>30\/11 :\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/ufhkCkEasETlGQWmA2rpLCIP7hjPJEGF92SaVNJCmj4y0V4_Xzn9SZo8Eh8140SkTOP3CYNrhWCQqJdkLlasXobSQccCZu1K-KfFiuIRr1exRFip3hQJxNzykqzoZvjHRxx7Y2FQpmQc75U5yX6Wn5DX0cEkCqWmDU6dU8B5gBQPOe9eussPD5uSplyUMyvsN0zYzmgNZeV7KJtg4thcGyNaFsmRwdYYfOJeA4zo27dEblGmttPQDu0cM65B3fveg1fj_KFfQCuzIdABDhRlhTwycHE1F2yQ25-3jD_d1_dhAwBHakOokxia2wHx0LKsbWvD0e4FJ34FjssNNozztazL4R9dW1XXmYXNR4QPXWP0Fss8d9Zp_OGRg7q7HclTijlwPCjWpXS6H4z5\">Colloque de l&rsquo;IHS CGT sur \u00ab\u00a0Syndicalisme et environnement\u00a0\u00bb<\/a><\/div>\n<div>13\/12 : Manifestation europ\u00e9enne \u00e0 Bruxelles<br \/>\n06\/12 : Publication des r\u00e9sultats de l\u2019enqu\u00eate sur le travail hybride men\u00e9e par <a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Re3tjdxp9aGTyItY34WJrNiA0ZXja2RokxHEw-tGScle_JPHwFsqw2TmcGbURj_OF_FuUKbO8V5DtxWvKT473r5XrMglfUg1S53Wx1rqeanzqmpPXpDrmRpfHlJMVwk7BCzvpLtlTbVW5TZ-g8ZuRj5Ry41Yf--ZPnx9paVd0JWoieM-eTKNg0yNja2PqotK-J70Y7kmIJo-ErBdn1ZeYTdg-zSnmhk7KFOOsfJF5cyhEriOfQPYDF5Pfx1iyTa7ricmoOma\">l\u2019Observatoire du t\u00e9l\u00e9travail<\/a><br \/>\n13\/12 : Conseil National de l\u2019Ugict-CGT<br \/>\n14\/12 :<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Rp3Y3UOwARyJwvx54ZV91z8f7CK4mTuPMcimAmWJ6v7fAtnMQQp3whcb5QZgyNPpRuqkyCQp9boXMcmJv0JbeG5Ifen-LbOgcTZeHOGhFVIqn4T6bjL9oapm2BmYk_BR5pj1UZ3fuxvqGmLHrEcOHRAixQAlsW_p4yI_ALN-4XgW5dzaJgYlO2hyrMcYLVqBTrQSI8KBKSFRCNMIRQzMWWohl4kA4KAoWIlsidPSB0N6BudbXV_cKXOxodI_kr2JXFNci4B3uq8Sm-iOn_8iptDMSmXnfbBSycq6LcPj8psY7YI\">\u00a0Rencontres d\u2019Options \u00ab Climat : transformer le travail pour r\u00e9pondre \u00e0 l\u2019urgence \u00bb<\/a><\/div>\n<div><\/div>\n<div><strong>2024<\/strong><\/div>\n<div>\u00a012\/01 : S\u00e9minaire de l&rsquo;IHS-CGT sur\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/K0i0iAgepSZQDDIZj-mpGQGYcGNpt-SbrRROylQR053U--EUy-_ASkmRDTcfpl_QZzfP59LLjROPEjk94yog6gyQoxeGfQOA0doerReHTPHRis9JzoSOzkyjMPPpj_494sqwMeM-yE9VL4-D79-3luaA-1elwcIv8DT6pE6XSfk74Hx9HGddIMg_QZ4PlOX0UNJDepZ6DZSEMIz_NDbKP3ZXK3AUN_bnOHNcEZLpGl9VCrx0C1LVuzA7EWLu4-4qVuv0xtma_YeYaEYuj2KIrxmAPm1jiWLRdee7fpvx2L110d-HHZR2oBEdIHbFWJeUZbyT29_u_e6ZX45GblGURbtOaT5jcfn1ETc2Z_QZ6gVkJZ_bvU41WTMgnC9QxWI\">\u00ab\u00a0Syndicalisme r\u00e9volutionnaire et CGTU\u00a0\u00bb<\/a><\/div>\n<div>14\/03 ou 19\/11 : Formation des membres de la CE de l&rsquo;Ugict-CGT sur la question des luttes contre les violences sexistes et sexuelles<\/div>\n<div>16\/05 : Rencontres d&rsquo;Options sur la th\u00e9matique de lutte contre les violences sexistes et sexuelles<\/div>\n<div>12\/12 : Rencontres d&rsquo;Options sur la th\u00e9matique \u00ab\u00a0Professions techniciennes et interm\u00e9diaires\u00a0\u00bb<\/div>\n<div><\/div>\n<div>\n<h2><strong>FORMATIONS<\/strong><\/h2>\n<div>\n<div>\n<h3><b>Le calendrier des formations<\/b><\/h3>\n<p><u><strong>Formations courte (demi journ\u00e9e en distanciel)<\/strong><\/u><\/p>\n<div><strong>Management et pr\u00e9vention des risques psychosociaux<br \/>\n<\/strong>Le 23 novembre 2023<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Si3gkN87AjcTnnG4-7ZYCK9JI2CEbjUBa-gYTlYDnonKJrwgq0mRqZOMwati8JhHzH9zmJk3SINHNdZZYSMSY9OqOucm7GXfDsAgYtHq1z0myHget3azr24i5trW5mn_6lRPtZBoM3vr97SLXxfHh9oYkA8t8Rmmr982UdCsLKmIbjgdNO8ZIskD4xqQ2bOWPx9v9Ltgb42q6mLoimqCcHhDNQpcQb6k0C2DV-O1Mk80bU_pY3leRsBDiG3wDqkFiusOGeSowdx0Z87TukxHzy_kwk_IqFEPyrMxxX-KzbNEhVV7RcM90L8\">D\u00e9tails et inscription<\/a><\/div>\n<div><\/div>\n<\/div>\n<div>\n<div><strong>Affections psychiques li\u00e9es aux violences sexistes et sexuelles : comment \u00e9valuer leur incidence et d\u00e9velopper une pr\u00e9vention efficace ?<\/strong><br \/>\nLe 12 d\u00e9cembre 2023<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/SNXY4vKUbbBEIaEZquwLywhVAE8IZfYhBGO4Z50q1OvwenU-OohhNYVReYQBoCeMwAtxp-TvcTSU4FawL3kGjyOMOnYveYReG8AJ0tETgm0uRlMgQloPMf4jtOcOz06slPAW29Iukw16mJIBB-SlUllYQ8ZxU2P8xa1zFoUIBuA_f-24YzKH2kE-m2shewFCG0to6p9j1oOLQdmccjKX4qkMK1xTOLd9pmZVR1DRvq3a8oPaDfSsBpJCgXfZDO-RtvExr2x_GEuTMiV67jC9rMP18HPJPMc-h-R1mxMqxQ\">D\u00e9tails et inscription<\/a><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div>\n<h3>Stages de formation syndicale (2 \u00e0 5 jours)<\/h3>\n<\/div>\n<div>\n<p><strong>Etre responsable Ugict-CGT<\/strong><\/p>\n<p>3 au 7 juin 2024<br \/>\n30 septembre au 4 octobre 2024<\/p>\n<div>\n<div><strong>Quelle strat\u00e9gie syndicale face au \u201cWall street management\u201d\u00a0?<\/strong><\/div>\n<div>\n<div>\n<div>Les 15 et 16 novembre 2023<br \/>\n31 janvier et 1er f\u00e9vrier 2024<br \/>\n9 et 10 octobre 2024<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div>\n<div><strong>Gagner les \u00e9lections professionnelles dans les coll\u00e8ges 2 et 3 et dans les cat\u00e9gories A et B de la Fonction publique<br \/>\n<\/strong>Dates \u00e0 venir<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div><\/div>\n<div><strong>Comprendre la financiarisation de l\u2019entreprise et ses incidences pour restaurer le r\u00f4le contributif de l\u2019encadrement.<\/strong><\/div>\n<div>2 au 5 avril 2024<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div><strong>Egalit\u00e9 professionnelle \u2013 Femmes cadres<\/strong><\/div>\n<div>26 au 31 mai 2024<\/div>\n<div><\/div>\n<div>\n<div><strong>Ma\u00eetriser la technique de l\u2019enqu\u00eate conscientisante<\/strong><\/div>\n<div>\n<p>22 au 26 janvier 2024<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/3hnabu3Lhv7zLAjgbHNtBijfqMeZLHWp3HSj3LzmuArIZ39WrmtJyI5HDYV6jJ4eSYxT1ErKmy3LHfghGjo1dUgUdUtkmHXNzvqcMT6nDXaE_ZWnFUOatnLZfR9iZ8K5uSEUYSRHAxkN1w97GcSN4vQqcC_77FcCVFfeBLiwUV8B1pNbI4rCIltB_MLOs8j7CKozUHW-XK6W2xms1nPneOQWjGikqJoY3KE8NlOLBJS3OFmdmZb55WyyO5sOE8RiTqiVjkD5M_D45ep6WjQZX45Tpl_JcLgUb6IehPRxhqSP4FAQVYABiica\" target=\"_blank\" rel=\"noopener\">Voir\u00a0https:\/\/ugictcgt.fr\/calendrier-formation \/<\/a><\/div>\n<h3><b>Stage communication<\/b><\/h3>\n<p>L\u2019Ugict propose un stage sur une ou deux journ\u00e9es pour apprendre \u00e0 g\u00e9rer un site internet avec le logiciel WordPress sur la plateforme\u00a0<a href=\"http:\/\/reference-synndicale.fr\/\">reference-syndicale.fr<\/a>.<\/p>\n<p>Ce stage peut \u00eatre organis\u00e9 dans les territoires.<\/p>\n<p>Pour avoir plus de renseignements\u00a0:\u00a0<strong><a href=\"mailto:orga@ugict.cgt.fr\">orga@ugict.cgt.fr<\/a><\/strong><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1642\" src=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/06\/logougict.png\" alt=\"\" width=\"300\" height=\"204\" \/><\/div>\n<div>\n<h4><\/h4>\n<h4><strong>L\u2019Activit\u00e9 Sp\u00e9cifique de la Semaine (A2S) est un bulletin interne de l\u2019Ugict-CGT con\u00e7u comme une boite \u00e0 outils pour aider les syndicats CGT dans l\u2019animation de leur activit\u00e9 en direction des ICTAM.<\/strong><\/h4>\n<\/div>\n<div>Pour inscrire un syndicat ou un responsable \u00e0 la vie syndicale \u00e0 l\u2019Activit\u00e9 Sp\u00e9cifique<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/7Ch87C3IjQNW8WbArOaPkn4Qr71kFg9WDwXvBToFELPGV4JEFlDOlS02Pzc5ClQ5D_TI61ndWBC27X6CgySUd6KUR3Zg9vIZRX9UrQ9e0z-gYoipgmwa4rP13Cw9DYKPQufh_0f_x4BMAyk7IUz8mMW6SKQtgRMSLneQESLpqz3dag4kGsqtJ8XBgyrPN8pakGL5gJD84U_ZgeV4qaE1wYjaU7dKs9ZooapdS1gUzMAh1qn78oxvuItfvNZurWp9tqHF5zyIPJFnZFkzn641AtPhdTGT5qlo7X0JG2EgWrCuRIrngw\">https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/a><\/div>\n<div><\/div>\n<div>Retrouvez chaque semaine l\u2019A2S sur\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/iy034GMGtrM9HY8S5GIUnmrnyWT_y8R7Bz66lmbZK_XHQ7qwkk6L8WWjLfmNhc4ak45utEBugaeq4AlmvjJVyijm-v_c8fnoXWiLc0iF9_8SlO-wCltfaLLVNUcFMud9TycYbvYrkNJM7oNgugaZx_cfOd_IYb2Hdd55uwNugsDJuOgHoeH_WUCpB34k04lrsH_h96uneEXAGia-0e5PBNmn4rLsnY8gUiaqK1zqmcpfaPOZJP-KBXJaQVzC64M0bQ34pfPbwrXAtdGC208vPTo4RhmIo48YRoIM\">syndicoop.fr\/a2s\/<\/a><\/div>\n<div><\/div>\n<div>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse\u00a0:\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/oWRW9xXQwlFgHjFqqQbH6Iff59DYQnSxnEYImTOhD6IeMnGttlU0rMK6UevCpqeLW35jPrLHlHrvh8VS9FBDeUApYNkV1BhCGxQ_WjfUnAJTd4m0CEv34iy5T4cTiwOpi517Se2Qoe31V_0oj007nsAskY4J8skh6hrSOUbjQ9ls0wzGKmIU7rqllKOkVTNbFzYV9SSKN-PmVuu4M963ZIMlLd1kR42vCbTSwoyWWnPpbmWArwXURWIjZ7xWSUEhOiEPveCwIxkPu7YVjPBCj7KEhQs5IZ8z8EZU8TCe9xk\">https:\/\/ugictcgt.fr\/formation\/<\/a><\/div>\n<div><\/div>\n<div>Pour tout renseignement\u00a0:\u00a0<a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a>\u00a0(01 55 82 83 40)<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>STAGE PROFESSIONS TECHNICIENNES ET INTERMEDIAIRES Ma\u00eetriser les enjeux en interrogeant les sujets d\u2019avenir Du 29 janvier au 02 f\u00e9vrier 2024, l&rsquo;Ugict-CGT organise \u00e0 l&rsquo;Institut du travail de Strasbourg un stage sur les professions techniciennes et interm\u00e9daires. Ce stage gratuit s&rsquo;adresse aux militants qui souhaitent d\u00e9velopper une activit\u00e9 revendicative vers ces salari\u00e9s. Pr\u00e9sentation du stage et [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[14,151,49,88,6,58,2,20,41,134,133,150,5,143],"class_list":["post-1686","post","type-post","status-publish","format-standard","hentry","category-archives","tag-cadres","tag-cd69","tag-climat","tag-fapt","tag-formation","tag-options","tag-rencontres-doptions","tag-retraites","tag-salaires","tag-tech","tag-temps-de-travail","tag-ufict-construction","tag-vie-syndicale","tag-vsst"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1686"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1686\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1686"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1686"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}