{"id":1699,"date":"2023-12-01T19:32:17","date_gmt":"2023-12-01T18:32:17","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1699"},"modified":"2023-12-04T10:43:45","modified_gmt":"2023-12-04T09:43:45","slug":"vendredi-1er-decembre-n487","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2023\/12\/01\/vendredi-1er-decembre-n487\/","title":{"rendered":"Vendredi 1er d\u00e9cembre \u2013 N\u00b0487"},"content":{"rendered":"<h2><b>Barom\u00e8tre Techs et professions interm\u00e9diaires<\/b><\/h2>\n<p>Ce nouveau sondage montre que les techs et professions interm\u00e9diaires ont un fort sentiment de d\u00e9classement, une perte de pouvoir d&rsquo;achat et des conditions de travail d\u00e9grad\u00e9es. Mais ils et elles sont 76 % \u00e0 d\u00e9clarer \u00eatre pr\u00eats \u00e0 se mobiliser collectivement pour exiger une augmentation salariale et 40 % \u00e0 se syndiquer.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/ZVcK_N2hqobUzuzPcyvwCLR0VIKsUNX6F0BkhVFY4BsEupTACsQNTwWDXb7kX_9ZdF1Wr1BP5aRLVwgwiPr7UDzlRTgLLk-zIrOuGqKdpoQ5ZMWrhcdAipISEau0b_0Pm-ZJl_QK5-Hl7uBsmqxXSv0J6njy6HA3a5nnArktJZ5A-yYKbGw01gdSSz_9kzrgc3NrkRLqwJTKKZN31Tlp8jglZCwQHUoowhPbBtVpOQfxjWbweEim1Cqdkrm7P9CoXi0Dop05htyFHNGZ533oTrIVC1n4nqjSvbF-XtoPhg\" target=\"_blank\" rel=\"noopener\"><strong>Retrouvez ci les r\u00e9sultats du sondage<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>12 DECEMBRE : MANIF EUROPEENNE<\/b><\/h2>\n<p><strong>Euro-manifstation \u00e0 Bruxelles<\/strong><\/p>\n<p>La manifestation europ\u00e9enne initialement pr\u00e9vue le 13 d\u00e9cembre a \u00e9t\u00e9 avanc\u00e9e d&rsquo;une journ\u00e9e par les autorit\u00e9s belges en raison de la tenue du Conseil de l&rsquo;Europe (pour des raisons de s\u00e9curit\u00e9).<\/p>\n<p>Pour nous aider \u00e0 pr\u00e9parer au mieux le cort\u00e8ge de l&rsquo;Ugict avec Eurocadres inscrivez-vous\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/zwVmOC9Ej5Kwfa3PD7e2XUJSZ_K-smFVaQTXmGkbA6akLIqEDwzqRdNpNEEF-dBjlvh2UDUjBYi9E-JpIzHXAscEg5OqILuZpJ4rF94xzqyVqUxzIfrriJPNG0gK26tXRKfcgnW7bqPsK8vLcQDSsju7ON12BJsG214CN__qPpLK2lH_JnEv6fjl7_c23nyuhtgmzJwM47vezJ4k0veJj87H3AyWW-xX4VSNi2OtYYXV3erGMYMcY8LcvXnmYBN6WTFHAvMFY1cEQLXlACDvSHWy1nTls2xpHJjhyxgRphE\">ici.<\/a><\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/hTlbPRgIIv38xagG0pjRh-r7jPLHI2N777Nk0iZnPAbhxdGwDzmLdJHxcumhnrgGwXpDM7TahxAnaI59U1Zez-qSjDDZ67qEnIp3KiasWXFZDaOmwoXnSn6jm0sMknWMfZaq94RqpleikQDDsJbn93xabZe1HQcx4C2ED_FPL8lua6YyIg3cxH5dZVmB9ILWadcYWauWfc54LWLjGavW7N3ixscaxJK4pAhiHCsmT-tw0dCSGAL1uiIWCg4GXlkws6SLL3IPJkbhssM2lEkR_n5xetXIB2lQTC1obvT-5DMulae92EQ1T2JfMMlcYUOxvwr8tnw4-EC6BFt-vTG87YRg0t7n\" target=\"_blank\" rel=\"noopener\">Notes conf\u00e9d\u00e9rales sur la manifestation<\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>UNE ENQUETE D&rsquo;EUROCADRES POUR LES CHERCHEURS\u00b7SES<\/b><\/h2>\n<p>La pand\u00e9mie de COVID-19 a une fois de plus mis en \u00e9vidence l&rsquo;importance de la recherche et du d\u00e9veloppement (R&amp;D) pour relever les d\u00e9fis mondiaux et promouvoir la r\u00e9silience de la soci\u00e9t\u00e9. Cependant, la pr\u00e9carit\u00e9 de l&#8217;emploi dans le monde universitaire, la perte de talents et le manque de s\u00e9curit\u00e9 de l&#8217;emploi pour les chercheurs\u00b7ses suscitent des inqui\u00e9tudes.<\/p>\n<p>En r\u00e9ponse, Eurocadres a lanc\u00e9 un projet visant \u00e0 comprendre l&rsquo;impact du contexte politique europ\u00e9en sur les conditions de travail des chercheurs\u00b7ses, \u00e0 accro\u00eetre la sensibilisation aux conditions de travail et d&#8217;emploi des chercheurs\u00b7ses en Europe et \u00e0 identifier les politiques syndicales et les activit\u00e9s des repr\u00e9sentant\u00b7es des travailleurs\u00b7ses \u00e0 cet \u00e9gard.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/JlF1WUSmjcnw4ovdxPzTK6Behv6tExnrq0nr1UmLOPruwtmvRRvjpJTIbB6pBPA3RcJXJ1BOiq3LJquhj5Aq_ThEsKEXekNH4H3gc0YDcbyTEFCjQRdqa9bkErBEVxgO1RiIcJh7vdUwhi6u8-r_X9mvbbBE2iwdbVFHPkatTdtn5nV_KuckiBPk7R-LcIXt3F9UK_N7c0Bvt-whLnFrVuVKyVHQ5Yf1ftelrHitydWdeLWir_wu3qnN1P_BQnh9BKMyZ6b-7D1nU72Ys6x5mSQrv20hzxLw2y0AAwSJJw\" target=\"_blank\" rel=\"noopener\"><strong>Remplissez ce questionnaire rapide pour recevoir le lien de l&rsquo;enqu\u00eate<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>LE MEDEF CASSE LA NEGO EUROPEENNE SUR LE TELETRAVAIL<\/b><\/h2>\n<div>Hier \u00e0 l&rsquo;issue de nombreuses s\u00e9ances de n\u00e9gociations le patronat europ\u00e9en a annonc\u00e9 son retrait des n\u00e9gociations t\u00e9l\u00e9travail. Le Medef fran\u00e7ais a fortement contribu\u00e9 \u00e0 cette situation inacceptable pour les ing\u00e9s, cadres et techs en France. Cela faisait des mois qu&rsquo;avec Eurocadres nous tentions de gagner un accord qui permette d&rsquo;am\u00e9liorer les conditions de travail des salari\u00e9\u00b7es de nos cat\u00e9gories.<\/div>\n<div><\/div>\n<div>D\u00e9plorant et d\u00e9non\u00e7ant l\u2019\u00e9chec de la n\u00e9gociation, la CGT demande \u00e0 la Commission europ\u00e9enne de pr\u00e9senter une initiative l\u00e9gislative europ\u00e9enne contraignante afin d&rsquo;apporter aux t\u00e9l\u00e9travailleurs\u00b7ses la protection et l\u2019am\u00e9lioration des conditions de travail qu\u2019ils et elles revendiquent et m\u00e9ritent.<\/div>\n<div><\/div>\n<div>\n<div><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/xujUv_3kA99HYb8NlnPvZZRnwzHjMThQt1HTa8ESKq0NV8v0_fzxyyrYs8O-q69sJmRhRO894xR6H3_RyJF7z7Umf1fKVbPgYWSVvEeQNEeDgoEWECijkmiuXkWKBKajiveYeI1zt9gaUGklsksG38dT7fxlBNSCj-yNxwqj9k-WhaF1h2HhKOj4WAJu96RWwoLQGQJe1Y5YA1hWPM2HLs636hPpZdvTxMQId0BBpcLTVkqVfxlPGgeLKy8T95JDRlUjsKLzuJLBBRRG5OEW3uZA2TsTiG9wiDXzUfRb_HM\" target=\"_blank\" rel=\"noopener\"><strong>Voir le communiqu\u00e9 de presse<\/strong><\/a><\/div>\n<\/div>\n<div><\/div>\n<div><\/div>\n<div>\n<div>\n<h2><b>SALAIRES : L&rsquo;URGENCE !<\/b><\/h2>\n<p>Lors de la Conf\u00e9rence sociale du 16 octobre 2023 la d\u00e9l\u00e9gation CGT \u00e0 laquelle participait l&rsquo;Ugict-CGT a propos\u00e9\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/qZ-zQTMqrIDrUAudDT1ns-xbQt3faj2ul8X799hW48kz47dDdXegH_pkFiXJXUy62QeCdAoZB1dTOg1qrpJL9iRJIjosbrHVd8_NZ1rJxEpG5qJ_73A1HBarSgKYahT4ZnjkxU42PvvfKBy8eYj1w8dFAz2JFuE4K1bxuVDL-2OfHTwSgsue6n4meYAhmw85qYl8bJu59husvrIcF0Pff761ZvtZCUkD9Kl5ePQIE5DutVXScccV-eyZy0hbQIJX9FqJNi4GX4nlpXS2CSdFeUKPTy46XB3o5TFHlkyqMhH5QQr9f68Dqm8ou4HuI0gNm7V6Vqi2MZuYWt355eC19B5i2t2XDgoWP6DWe9v9KRwTyJWquDxNa327rvfq3qXTqUSHAzHAJJxsm8KOLaxJGnJaF6oBYFkWCjQYiM6ZYSucQALqzrU\">de nombreuses mesures<\/a>\u00a0pour permettre la reconnaissance salariale des qualifications des Ictam. Gouvernement et patronat s&rsquo;obstinent \u00e0 se concentrer sur les minima de r\u00e9mun\u00e9ration. Un d\u00e9cryptage en ligne en deux parties est disponible sur notre site :\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/waAZ2Da9focBrM-G-5xppmCxaEYDRgNnLYZreK26iftlsYPUEgskJ7-KXXMTfcjc6L3Ewhpg2oHY1oJ1O3PTOuLnEk6ZlBwW_WjZI-M4wsEaG3RikEfgd9H9AjuKCV8juqfSTP55_0xwJRSUZz47kg64jnKpIBXUqpAZ92t7KeeFmPeJTiQjouPsNFgAcrVW8ZjUF_rzM_e4sp5Scpu-rqBXSMVX0nPpZmPxIITYP4ZJjwgJVQV3bsztI84DYyxC-53X2Mzn7xGSIu6TW0LiNbu9fb0Lk_sM3HvetlZDI9aNNCOGivezgaYipT8\">ici\u00a0<\/a>pour la partie 1\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/hm_J9LLvdy3K558VCyVrM_z2jX2qCWkVO_oM9pjHo0X--Q9rzKmoGIyED6LmZwq4WMsrB2IYkm_gl_9gOORmnUrxSYsEet_8GeybeN5W1oRUAYchFC_uhEPkZwqiUFyaCXDnc6LnyxkqkE_985zVpGQugd3-7t1ZuBJam2EdZj0l_b9HKDCaKFY_AqM-sZmUPLQUUPX4X1e7SKXuFcy_hytLijum2-COfvHdEoI-tgxAG5-2df-pgR0nxg8189iDtO5KmHFhKP0n6cb67yQnJKUS9ryuj_ZYIy3X3hyyJM1bK0bqmae8wQ\">et la partie 2 nouvellement en ligne.<\/a><\/p>\n<p>Retrouvez la campagne CGT \u00ab\u00a0Urgence salaires\u00a0\u00bb\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Ll6qhGmi_1HLBuQPLUzIwOVcnBSUSIjIx7n6tfochjyEZ3AxGmj8mN1WniMdYvPbK7AB0NO9cQ-Hc31eeClVDHCZhb0BKSniOBBbS1W8mhZ20_rewd-tVATuTslRtxK4jIpLq1nZRoJK6wqcLNUiL0gJiuOaflN1l31SMKdomY2m7cwgESsaWEwlylRdUdGUIONicFXR63KUQJ_SbNFTzeboEW3IUIkYQF-LxIXT30SO8Z9Ouhn-_s4mOH5l7HpF_DYB4DRSG2ZPjTaYvg4v7MznR_2e3iazISxazHnbMbnm3doxLZgKIwM2wT3a0ZGaDs9GuYGeZPKVOr68FkMgkRyztcZN0ngc_DFiBz-JPC3Rvzzf\">ici<\/a>.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/UMmp2--vWankIdOv7aOJeTabFmkO2Is4N7aKbVwStKuOPNlRsAN_0oWM-AX-8MWAGTmD0wJNZWngTgpP5GW6B1eCPy6c-dC3IEcDo_US7yHg4DCtgMammMY-C1DN6SWojR1Ct5bsR4bLjbputNG40LFDOvqBqLRR-4rJVGpUpOwryoTZ8pFLC7TnpBbPxCxv9VIy-SNIPV3tPdcFN-Pmu_o6_ucbzFbA7v3w46UzLkuzNGI9RHEucyjE8mlkv5lhD9TpsH-yrqjgXyYJ38uZFPYtnVyHgDTsow\" target=\"_blank\" rel=\"noopener\"><strong>Voir et t\u00e9l\u00e9charger le tract en couleur et\/ou noir et blanc<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div>\n<h2><b>RENCONTRES D&rsquo;OPTIONS<br \/>\nCLIMAT : TRANSFORMER LE TRAVAIL POUR REPONDRE A L&rsquo;URGENCE !<\/b><\/h2>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-large wp-image-1684\" src=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat-768x1024.png\" alt=\"\" width=\"768\" height=\"1024\" srcset=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat-768x1024.png 768w, https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat-225x300.png 225w, https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat-1152x1536.png 1152w, https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/10\/ROclimat.png 1200w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/p>\n<p>&nbsp;<\/p>\n<div>Le 14 d\u00e9cembre 2023, l&rsquo;Ugict-CGT organise des rencontre d&rsquo;Options sur la th\u00e9matique de l&rsquo;envronnement dans le 10e arrondissement de Paris \u00e0 la Fabrique R\u00e9publique au 52 ter rue des Vinaigriers.<\/div>\n<div><\/div>\n<div>Les th\u00e8matiques des tables rondes sont :<\/div>\n<div>&#8211; Un mode de production \u00e0 faire bifurquer<\/div>\n<div>&#8211; L&rsquo;entreprise, inadapt\u00e9e aux enjeux ?<\/div>\n<div>&#8211; Les salari\u00e9\u00b7es et syndicats, sentinelles des enjeux environnementaux.<\/div>\n<div><\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Y72f79_Si0FhxQW4X69U-wLs5T5FaMuO1fhGbJ0rcqV2G0G4dlGDOm6dTEoCl2RiDlB5kGjFRc6-pz--4rbrX4pxfxxYMmHL0FoiWpHdIPRliiviLz0s85lNqn4evBfpYgL-F13ozTQZ8y-nKze_uIxkabS3aTg11_PJSJMOJYAZPz3TBrqmv1Fw82MyBY1aC6boU4YXvc6Wvl-ZxpmKApGT51-KxgfBwfgLQR8ThodmL3xNeugBg60JqQgR13PImQJkgHAKtBehtgLDZzAHQO57dWHv4XfeVotPauyxxXQ5qg\" target=\"_blank\" rel=\"noopener\"><strong>Lien d&rsquo;inscription<\/strong><\/a><\/div>\n<div><\/div>\n<div>\n<h2><b>STAGE PROFESSIONS TECHNICIENNES ET INTERMEDIAIRES<\/b><\/h2>\n<p><strong>Ma\u00eetriser les enjeux en interrogeant les sujets d\u2019avenir<\/strong><\/p>\n<p>Du 29 janvier au 02 f\u00e9vrier 2024, l&rsquo;Ugict-CGT organise \u00e0 l&rsquo;Institut du travail de Strasbourg un stage sur les professions techniciennes et interm\u00e9daires. Ce stage gratuit s&rsquo;adresse aux militants qui souhaitent d\u00e9velopper une activit\u00e9 revendicative vers ces salari\u00e9s.<\/p>\n<p><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/nZX6xirhWkIG62VUqb3uQhre2tJQRopWMnnUtMYBo19-0n2RYukysgMw5RM2ehL8f-d49JaVztCFbJ041t_dOBgukInPfNvowPOtw752M94PFl48rZg_MxEmjzuIsjGM6K07pYgO-gKrxBs2Da5mj83pmLptaJTQzYtispi6eMO6ChhSE4tPRr0EOhrQukZIjukNpOjV671GkGsOtkSiuBiHma0L5LgPLxwDLspQyyUmS27GFvu5NkRWzX1FuELnXJE733jW_rJH3Iii_UgQ8bdMW76Za-WYTpWWi9lCzdQsXYuL2Mn0qWBc\" target=\"_blank\" rel=\"noopener\">Pr\u00e9sentation du stage et inscription<\/a><\/p>\n<\/div>\n<h2><b>CAMPAGNE R\u00c9DUCTION DU TEMPS DE TRAVAIL<\/b><\/h2>\n<div>\n<p>Lors de notre Conseil national du 20 juin, nous avons lanc\u00e9 notre campagne pour la r\u00e9duction du temps de travail des ing\u00e9s, cadres et techs.<\/p>\n<p>D\u2019ores et d\u00e9j\u00e0, vous trouverez du contenu sur notre\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/21n-n6fDqhZ2REBTaaZ43rLMsgVmgaB4LNZv5HEVQUwkK4vFnkz7I-wky264_gPxAIquylUdfuPpJDQ9sTdOL2P2QHXuifNkG7_6umTmhPq6ts_1vpWq71GMja5qIShHNi77G8PXCDSNriod6qG8n-XYdQNaqEn-0LxN6HUPfeFiHISttx0tROraos7H8USUyv9sBAyHGZIREg7_ZuEY6AQfxdbdz8rpIxEut9HZWg0-rWh5tnqGftjJueOQLeuG8Tzkt0wBJ2HjaL69G0j77QTUEUHVdSOm1VH1bZpMlBYZARg\">compte Instagram<\/a>\u00a0et sur\u00a0<a href=\"https:\/\/ugictcgt.fr\/reduction-temps-travail\/\" target=\"_blank\" rel=\"noopener\">notre site<\/a>\u00a0les premiers tracts ainsi que les premiers outils\u00a0(<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/aFCVs4UDw1nkrpcJjEzSS49JYk0yEd3kC_4Q8WDeL50v2qn1aZXsW8uibpNJ4iG9zkfbGc_CNfJOwCzSqT2bwLhOSZg7-BeA9G0yZsJF5xnUIUIVuR53G6Vl-Z85-0iNsU4l8mN9i2XWjPOPGSaMQM-pmIqfMoju6JprQ0Np4mZNu4Qsgt4W3EqkTkz66nvoyfCOjsHZ40sd332COuD29zTw3pmNEkhO6r9aNjAt7ef2GnQdkgsWTUpSIoREg97hkSsQtsGZZT-27KhzqaeZQ79pZsY90HnkRW4DB4HqXz17hiXBbpwYb0QgdHx4ZyBQjF2vm3zf8g\">trac<\/a><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/PrufdGNU8jiCKRnEitzGFZiK5jtIE0P726ggyUat5MtZi076EA6UKrVktVfSUuIZKkPHQqE2Y-pLLT_vrS5ObcArbLet0O98_KMVosP1_UpnzFMSd9lrDyqMXqly3ATHrAYKBHheVQsIAr1EcNv6MOtvUytHhq2ymor0Ejt2UMqeaPbEnM4Bp_dpnoxsrmWC6bf9itjyhXfbHgWNV33BCMEXWUrqa0C7zW5qzXVytzAABb5h-3dXydj69a13jLwixeRsV2ZlmiPPchkrVY24IqoE9nvD6Im9sKDxz7m00B_07ckhxfqzBozKiYyY_e-rGcGYEPRr8Q\">t sur le forfait-jour<\/a>,\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/2ZVnleAa5E7Cin2JTS8a2knVGHtQ5rvSka4zIfTuGBYru4LxBLlDg1piHN7hNqUN2Vr_1YtibV16cZv8SVpf2WVvY0a98DdMuUTF2-bl2ap__5PCXuwa4IPcTYPOgwFYml-88JO7szQtRvGErfcnuEQSjj0hRTm1TRFM0kfDN8pfSjGJm_pBkXJSTZHclYZChNxCkyMb9RU2dWZIaLFOHmCEYfrKgw1EQGV5TFj3OxH7oDlRaHeqSpOzTY0d_QovzJRnb8qc227XlZJxF0My8z0U8pwAH1tLxp_vLq2Z9c8AEY7fd8PwxeElhw\">premi\u00e8res affiches <\/a>\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/jFc1TBS50DsFpWURAYru78SRPqYQj1BzwQwr0cJCT1mAj4J7fWBEKOoajtf9vLMrW_S9-fQXyP0MFnU3CrZKRX06A98J_sk_fIJxK2qBG2r9iKNnGfs-4DWjlJJuPItE_X_-aoX0ecPLZwSE8pSjx405rUQDLeszbLwaFSguOOJHK92el3ftwlNLxQcjIy1wezEMdtO_LnYAKqBAZn4r8k_lwJw6u7zATPnsCO-8bhZcD56oZVy9HPoqlH-o0RB2YUBle22Lx9q9KUTWGibVgMjUFsMmMSX1uJv7NzmNHsm3WBFP1Tq71Hv778_w4IcfRdB5kHmDeDZPvuVxHU5dnPtjF_v5scxAbQ\">podcasts<\/a>\u00a0et\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/wq9yTDJ8qb4Rd76WwkCwQaYaBMm1GAuPAnIY53WHg48t63WoZruB2jEgZ1RkYfRj-symg8a0Jr1_hWL7KMquPSGgTJwmc6C1VuF-NFkqBZMID0OEt1rMp1phBb57OVU0BEHMp2-LFaUwcaYh2l-Hu_BTv8e4doagwIxhN_0GMPP5u9mu1R3XxXlLK0ntIrxfPYcTSY_zKq9ABQryp4Y8EOZMLk7SCpmrP5X-M4AofHjLnKNVETHSo0KO0sVXtQMaL16mSeQEWCq35JPS3Ip1R-9GYQaHRnd2O4Yg1NdiehOVBXTa0KxYTItXdwQ\">g\u00e9n\u00e9rateur d&rsquo;enqu\u00eates en ligne<\/a>).<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/wxecKX7uByINEMxdHR6wWes9qiNRk_sHI3aagqLaSA3MQ41mZ4eZHnMrCgpafCDEiSOXZGsZ-d-ZncyXgdX47lLNGrrhk6EgVKOaGEJJJQX_UEX4QblKuIgmlAHESpZk_iNm44QBKkiVeR5aKDixoK-0-H6ZU7QotOx-3LlMzCyyjBAPuah4_Kjg6KQYdNGu6kFsDTuLS1zzHJRT1cVqrgH60l7rMrC8adEAotZWPQi--h_UvFNMTsm_DmLbvPWDsPmtB55DUr7H210tYojbSwOE29zqR8-JcNotb4RESVLak9t4l4xVqBhci9Fiyf5FJtk-DvpZJoTBaS8ZT26q2YF33CrBKJgAwlLpTug\" target=\"_blank\" rel=\"noopener\"><strong>Voir et t\u00e9l\u00e9charger le communiqu\u00e9 de presse<\/strong><\/a><\/p>\n<\/div>\n<div><\/div>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<h3><b>Ufmict sant\u00e9 action sociale : mobilisation des praticien\u00b7nes dipl\u00f4m\u00e9\u00b7es hors-UE<\/b><\/h3>\n<div>Les praticien\u00b7nes dipl\u00f4m\u00e9\u00b7es hors-UE sont plus de 3 000 professionnel\u00b7les dans les h\u00f4pitaux publics et sont maintenu\u00b7es dans la pr\u00e9carit\u00e9 alors qu&rsquo;ils et elles sont les piliers du syst\u00e8me de sant\u00e9.<\/div>\n<div><\/div>\n<div>Ils et elles se mobilisent avec l&rsquo;Ufmict le 29 novembre 2023 devant le minist\u00e8re de la sant\u00e9.<\/div>\n<div><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/HlhYE4mVsLzi2GP3TUP3YQYFElb9zdG-DWwqvc4MIl4qxuGTGByn3fdfwdpeFPIPmN-PJVVjjyE2QiuH8I-xz9RHWyHTB63zpZ43JkS_5v84pcZ-tqkBRCCtC-SZPaPRwF0gmU0zF6JcuVkOkE-oWYAPtzobTZg0u5jjq7GKzx6QpVTXaAeTRnoOlZGV6-x2ieMoB2QBTxAatfiRzW56-OEbHTNpouVAN5hckb9n-hqS9XVsyhd8f5zX6_VfXePMPo-82z3D5nhrofjBUNPSQ0QQE1AkIhVxAjYt2n-b8PgLevQ_mir4evv6yiH5_Gioco9urEmfviZKLdQb0aeUAi4LLuRPCcLz0QBrDWIxuYkK_0g\" target=\"_blank\" rel=\"noopener\"><strong>Voir le tract<\/strong><\/a><\/div>\n<div><\/div>\n<h3><b>Ufict FNME : des r\u00e9sultats \u00e9lectoraux en demi-teinte<\/b><\/h3>\n<p>Pr\u00e8s de 4 salari\u00e9\u00b7es sur 10 ont choisi la CGT pour porter leur voix aupr\u00e8s des directions dans les comit\u00e9s sociaux et \u00e9conomiques (CSE). La forte participation (72%) t\u00e9moigne de l\u2019int\u00e9r\u00eat des agent\u00b7es pour ces \u00e9lections et de l\u2019utilit\u00e9 des organisations syndicales pour am\u00e9liorer leurs conditions de travail.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/dcocSHvL65Clot4p2mubNSS96FFvLz_89XTXwjT-VslbpdXlAzvh4BcRXl5h4ssysBvZb8GqZr1hdZC2FCAx3gfbhSzfuDP5y2-QLoBBLTQJ8y7xJiFTu8BrlnO3YCIj6NjirKfQjMJwSyM9ftHt8Zk8-GcLMD2x9CslHEbW7fJph-S5Ky6g0KFNyaqy8wK_uP2gyGrjrqGOPn8qFNcd6xxYNt1obfHeFGKL0rBU5J3yjyEl7MnAh1fvenwEvh_93X-7J5qQz_ihCxgD9-hCYYbtL0u_cNYlYjHTAkDEN2jQR7xV9ngH9JtrILKvIeEURsNwA7USR8g4r_Nhr0qB-qVv_jU4L85sUo6oqfq30wV8K0f886NztB4-Qx2otOhpUnvLQ9DsHS34ikAoYlZSnWVD5S_hOEJRXPfbew\" target=\"_blank\" rel=\"noopener\"><strong>Voir le communiqu\u00e9<\/strong><\/a><\/p>\n<h3><b>Groupe CGT CESE : Avenir du groupe ATOS, Il est urgent que les repr\u00e9sentants de la nation aient une vision claire de ce qui se passe sur Atos.<\/b><\/h3>\n<p>Lors de la s\u00e9ance pl\u00e9ni\u00e8re du CESE du mardi 28 novembre, le groupe CGT a fait lecture de la d\u00e9claration d&rsquo;actualit\u00e9 propos\u00e9e par Fabienne Tatot. A retrouver en pi\u00e8ce jointe.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/h7lJTw1b6AgFYnfxJpnBe0WALn_B9tdxWs5_YyXjh7Zxhlz4iimhb5jo1GsVg95AYmkdpr01uncOcf8aYE9ISfFZ3_xaZdb7LYdxIcI8namztDk1Z8KHPDZZNYEsx5efr6za55Irl4vAEzRxvJfMsuaYKfg2r7Y2szVIx2b709zzm5v0MpsosRoE1pEYUxjans2QzVFEiKAHcBaHaaeORybLTzR4dbQ6KASbyvWMBkFNG1IsQeA7yaBc7TUYzoTQ4PSNnv4gczkrLGPgI8cZLXZqXj0TyxyCXPuoIHl7gv6hD9udaXSUUPYE07gRjoiTNrwVE4G7A99P4RvVvR-4x14APPgQgTthnlD-zIg2oagbXJA5Nt9XjPKqBg6fegDqHYhxXFnyoiqhwO1saaEKxsBZprb3CPAP0DH1Jw\" target=\"_blank\" rel=\"noopener\"><strong>Voir le commniqu\u00e9<\/strong><\/a><\/p>\n<\/div>\n<h2><\/h2>\n<h2><strong>PRESSE<\/strong><\/h2>\n<div>&#8211; <a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/GNt9Vwk5CtoPXpweds_ysgWfP4D9k5V9QJcCtTLv2ILUceLTxFz5wiZUSLoVL3b-omx26uDU8XsyYLYX4jJNdodu_PL5l46yQ-x2cGdAHb7dc6PbHnkuXUe6-CflmIgTzoBjjlHDUyyT1H3KiteVy7PbCw6wr8oDFlwWPlWjQ_unts69HVxocituy_6qnz_vNMqVnCS4EzJ46yyLTJ78nwNrIr9gpNW3G512JN_O_A9eqLjvVI4fMgdzsQ2OtepBkJ654Ne_kVeaWXkS1d4LhmZJULwI_xMgmMnsg_yY_6-FAVm3Dr3izVVPSrJVyiQ\">Revoir l&rsquo;interview d&rsquo;Agathe Le Berder<\/a>\u00a0par Usul dans l&rsquo;\u00e9mission le Local.<\/div>\n<div><\/div>\n<div>&#8211; Voir l&rsquo;<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/GL0dJ04J_vmzz8gPPUKOO476_M4H13-SEQslOR0tai_QQoW5gDOGI1B3WE9ZcTC-CRyv4ZvD36RgKv_c7AaZvVDbsbY56eHHUSeOBeovKrxv42tbvHjMZaG9EMLlocrgYgP0ATQkE1xlrNLE0W_BJY0NRd9VPhXHVsAsjLIbsypg3O-95Zy1eIhojNdyVSxdvD1My2eRw2kqUXsxnDlTgL4aJ0FGi8zA-qeYnSXWYdjz5FAOb8y-BkJA0ESXyby2VFvVlk724lLH-67EAHir9Ce46gZFDR993GfzHeGxdvAqa1hqwTFp0Y8Al9B1sCsBIppuOt48q8WeIF26HUdEQqFO9_ILrSBpQwWN56uF7chz6HheKjK2aa6wJ73WdD3amfSaueqR5xTpmO25\">interview d&rsquo;Emmanuelle Lavignac<\/a>\u00a0sur les actualit\u00e9s du t\u00e9l\u00e9travail dans Le Bien public.<\/div>\n<p>&#8211; Lire l&rsquo;interview de <a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/oSodwBHuBMCS4K5q49Bh-1s6jYPDFIEwzST17pHxwzggZBevMXSTQg-BHXURRqq29hi786IYCwdfIePtGbhxdM3c_84B3kYEk1plFMizmpunChDtzxRtp72-at6Q7AgMuS77nOZ9RUlds9Gd9-iKMXtSRBOqo3McN-CIdovP-bYUZPTp9RZfpZrPiV9G33MBfXxF3gs7k9Zy2nCBnwhp6bE7P1pJyAEyNL6FqYLCuN9HzAbNwFTywx1JLV5A3Uj79Ng3RjUxr4BklSN03F_rbdg9gZz9Oc8lHsC07a6EGYlRpr50phCwhabNDOK-cMH0pEMbvuRo3TcLdzBekb74_C4iiI7lAX3_mEtPLStCV3LDPzLy_OusjRB_skipFLAtN3iCDWbQ_Wo3fRd_0c0CZkrRkvwo_8vVO5o25zqM-W-5L1vsjLHsWnIlVTwDaghByt50-SQLz3jqhqZEuncA7FZW\">Fabienne tatot\u00a0<\/a>dans le Monde \u00ab\u00a0Les initiatives de r\u00e9duction d\u2019empreinte carbone en entreprise sont loin de faire l\u2019unanimit\u00e9\u00a0\u00bb<\/p>\n<\/div>\n<div>\n<h2><\/h2>\n<h2><strong>AGENDA<\/strong><\/h2>\n<div><strong>2023<\/strong><\/div>\n<div>06\/12 : Publication des r\u00e9sultats de l\u2019enqu\u00eate sur le travail hybride men\u00e9e par <a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Re3tjdxp9aGTyItY34WJrNiA0ZXja2RokxHEw-tGScle_JPHwFsqw2TmcGbURj_OF_FuUKbO8V5DtxWvKT473r5XrMglfUg1S53Wx1rqeanzqmpPXpDrmRpfHlJMVwk7BCzvpLtlTbVW5TZ-g8ZuRj5Ry41Yf--ZPnx9paVd0JWoieM-eTKNg0yNja2PqotK-J70Y7kmIJo-ErBdn1ZeYTdg-zSnmhk7KFOOsfJF5cyhEriOfQPYDF5Pfx1iyTa7ricmoOma\">l\u2019Observatoire du t\u00e9l\u00e9travail<\/a><\/div>\n<div>\n<div>12\/12 : Manifestation europ\u00e9enne \u00e0 Bruxelles<br \/>\n14\/12 :<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/kInoKSnsodjAy5UjB8Sl6h3uyCD6uHrdkcZkXy1wELqGqyHQ0MTrbXBkZ7e-fKljg-KoSF-5Jpl0DbciBxq4JS0tfrnyS_MjMfdFN7ADIzz-q6DeSRCWvkostFJJFlyD9gkng8E1FTV9PTWKzNIUPTKc2Nz7BNW7rzjLNm7LZjNKiODu7sbySS07DbLf5aWLAQRITw-KY5Be5LBHi6f9sJPw656C57HW6HSi1dSip9WBLs6b-Ceq02Gi5CwuG6bfMPux_fES4__wrYVq2q8orWFA747cjuhCdoFklTjqtVU9Kag\">\u00a0Rencontres d\u2019Options \u00ab Climat : transformer le travail pour r\u00e9pondre \u00e0 l\u2019urgence \u00bb<\/a><\/div>\n<div>15\/12 : Conseil National de l\u2019Ugict-CGT (d\u00e9plac\u00e9)<\/div>\n<\/div>\n<div><\/div>\n<div><strong>2024<\/strong><\/div>\n<div>\u00a012\/01 : S\u00e9minaire de l&rsquo;IHS-CGT sur\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/K0i0iAgepSZQDDIZj-mpGQGYcGNpt-SbrRROylQR053U--EUy-_ASkmRDTcfpl_QZzfP59LLjROPEjk94yog6gyQoxeGfQOA0doerReHTPHRis9JzoSOzkyjMPPpj_494sqwMeM-yE9VL4-D79-3luaA-1elwcIv8DT6pE6XSfk74Hx9HGddIMg_QZ4PlOX0UNJDepZ6DZSEMIz_NDbKP3ZXK3AUN_bnOHNcEZLpGl9VCrx0C1LVuzA7EWLu4-4qVuv0xtma_YeYaEYuj2KIrxmAPm1jiWLRdee7fpvx2L110d-HHZR2oBEdIHbFWJeUZbyT29_u_e6ZX45GblGURbtOaT5jcfn1ETc2Z_QZ6gVkJZ_bvU41WTMgnC9QxWI\">\u00ab\u00a0Syndicalisme r\u00e9volutionnaire et CGTU\u00a0\u00bb<\/a><\/div>\n<div>14\/03 ou 19\/11 : Formation des membres de la CE de l&rsquo;Ugict-CGT sur la question des luttes contre les violences sexistes et sexuelles<\/div>\n<div>16\/05 : Rencontres d&rsquo;Options sur la th\u00e9matique de lutte contre les violences sexistes et sexuelles<\/div>\n<div>12\/12 : Rencontres d&rsquo;Options sur la th\u00e9matique \u00ab\u00a0Professions techniciennes et interm\u00e9diaires\u00a0\u00bb<\/div>\n<div><\/div>\n<div>\n<h2><strong>FORMATIONS<\/strong><\/h2>\n<div>\n<div>\n<h3><b>Le calendrier des formations<\/b><\/h3>\n<p><u><strong>Formations courte (demi journ\u00e9e en distanciel)<\/strong><\/u><\/p>\n<\/div>\n<div>\n<div><strong>Affections psychiques li\u00e9es aux violences sexistes et sexuelles : comment \u00e9valuer leur incidence et d\u00e9velopper une pr\u00e9vention efficace ?<\/strong><br \/>\nLe 12 d\u00e9cembre 2023<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/SNXY4vKUbbBEIaEZquwLywhVAE8IZfYhBGO4Z50q1OvwenU-OohhNYVReYQBoCeMwAtxp-TvcTSU4FawL3kGjyOMOnYveYReG8AJ0tETgm0uRlMgQloPMf4jtOcOz06slPAW29Iukw16mJIBB-SlUllYQ8ZxU2P8xa1zFoUIBuA_f-24YzKH2kE-m2shewFCG0to6p9j1oOLQdmccjKX4qkMK1xTOLd9pmZVR1DRvq3a8oPaDfSsBpJCgXfZDO-RtvExr2x_GEuTMiV67jC9rMP18HPJPMc-h-R1mxMqxQ\">D\u00e9tails et inscription<\/a><\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div>\n<h3>Stages de formation syndicale (2 \u00e0 5 jours)<\/h3>\n<\/div>\n<div>\n<p><strong>Etre responsable Ugict-CGT<br \/>\n<\/strong>Courcelle : 3 au 7 juin 2024<br \/>\nCourcelle : 30 septembre au 4 octobre 2024<\/p>\n<div>UD \/CD 35 : 17 au 18 juin 2024<\/div>\n<div><\/div>\n<div>\n<div><strong>Quelle strat\u00e9gie syndicale face au \u201cWall street management\u201d\u00a0?<\/strong><\/div>\n<div>\n<div>\n<div>31 janvier et 1er f\u00e9vrier 2024<br \/>\n9 et 10 octobre 2024<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div>\n<div><strong>Gagner les \u00e9lections professionnelles dans les coll\u00e8ges 2 et 3 et dans les cat\u00e9gories A et B de la Fonction publique<br \/>\n<\/strong><\/p>\n<div>93 : 17 et 18 janvier 2024 et 20 et 21 mars 2024<\/div>\n<div>93 : 18 et 19 septembre 2024 et 13 et 14 novembre 2024<\/div>\n<div>Inscriptions \u00e0 contact@cgt93.fr@cgt93.fr<\/p>\n<div>UD \/CD 38 : 21 au 22 mars 2024 et 13 au 14 mai 2024<\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<div><\/div>\n<div><strong>Comprendre la financiarisation de l\u2019entreprise et ses incidences pour restaurer le r\u00f4le contributif de l\u2019encadrement.<\/strong><\/div>\n<div>2 au 5 avril 2024<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div><strong>Egalit\u00e9 professionnelle \u2013 Femmes cadres<\/strong><\/div>\n<div>26 au 31 mai 2024<\/div>\n<div><\/div>\n<div>\n<div><strong>Ma\u00eetriser la technique de l\u2019enqu\u00eate conscientisante<br \/>\n<\/strong>22 au 26 janvier 2024<\/div>\n<div><\/div>\n<\/div>\n<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/3hnabu3Lhv7zLAjgbHNtBijfqMeZLHWp3HSj3LzmuArIZ39WrmtJyI5HDYV6jJ4eSYxT1ErKmy3LHfghGjo1dUgUdUtkmHXNzvqcMT6nDXaE_ZWnFUOatnLZfR9iZ8K5uSEUYSRHAxkN1w97GcSN4vQqcC_77FcCVFfeBLiwUV8B1pNbI4rCIltB_MLOs8j7CKozUHW-XK6W2xms1nPneOQWjGikqJoY3KE8NlOLBJS3OFmdmZb55WyyO5sOE8RiTqiVjkD5M_D45ep6WjQZX45Tpl_JcLgUb6IehPRxhqSP4FAQVYABiica\" target=\"_blank\" rel=\"noopener\">Voir\u00a0https:\/\/ugictcgt.fr\/calendrier-formation \/<\/a><\/div>\n<h3><b>Stage communication<\/b><\/h3>\n<p>L\u2019Ugict propose un stage sur une ou deux journ\u00e9es pour apprendre \u00e0 g\u00e9rer un site internet avec le logiciel WordPress sur la plateforme\u00a0<a href=\"http:\/\/reference-synndicale.fr\/\">reference-syndicale.fr<\/a>.<\/p>\n<p>Ce stage peut \u00eatre organis\u00e9 dans les territoires.<\/p>\n<p>Pour avoir plus de renseignements\u00a0:\u00a0<strong><a href=\"mailto:orga@ugict.cgt.fr\">orga@ugict.cgt.fr<\/a><\/strong><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1642\" src=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/06\/logougict.png\" alt=\"\" width=\"300\" height=\"204\" \/><\/div>\n<div>\n<h4><\/h4>\n<h4><strong>L\u2019Activit\u00e9 Sp\u00e9cifique de la Semaine (A2S) est un bulletin interne de l\u2019Ugict-CGT con\u00e7u comme une boite \u00e0 outils pour aider les syndicats CGT dans l\u2019animation de leur activit\u00e9 en direction des ICTAM.<\/strong><\/h4>\n<\/div>\n<div>Pour inscrire un syndicat ou un responsable \u00e0 la vie syndicale \u00e0 l\u2019Activit\u00e9 Sp\u00e9cifique<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/7Ch87C3IjQNW8WbArOaPkn4Qr71kFg9WDwXvBToFELPGV4JEFlDOlS02Pzc5ClQ5D_TI61ndWBC27X6CgySUd6KUR3Zg9vIZRX9UrQ9e0z-gYoipgmwa4rP13Cw9DYKPQufh_0f_x4BMAyk7IUz8mMW6SKQtgRMSLneQESLpqz3dag4kGsqtJ8XBgyrPN8pakGL5gJD84U_ZgeV4qaE1wYjaU7dKs9ZooapdS1gUzMAh1qn78oxvuItfvNZurWp9tqHF5zyIPJFnZFkzn641AtPhdTGT5qlo7X0JG2EgWrCuRIrngw\">https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/a><\/div>\n<div><\/div>\n<div>Retrouvez chaque semaine l\u2019A2S sur\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/iy034GMGtrM9HY8S5GIUnmrnyWT_y8R7Bz66lmbZK_XHQ7qwkk6L8WWjLfmNhc4ak45utEBugaeq4AlmvjJVyijm-v_c8fnoXWiLc0iF9_8SlO-wCltfaLLVNUcFMud9TycYbvYrkNJM7oNgugaZx_cfOd_IYb2Hdd55uwNugsDJuOgHoeH_WUCpB34k04lrsH_h96uneEXAGia-0e5PBNmn4rLsnY8gUiaqK1zqmcpfaPOZJP-KBXJaQVzC64M0bQ34pfPbwrXAtdGC208vPTo4RhmIo48YRoIM\">syndicoop.fr\/a2s\/<\/a><\/div>\n<div><\/div>\n<div>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse\u00a0:\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/oWRW9xXQwlFgHjFqqQbH6Iff59DYQnSxnEYImTOhD6IeMnGttlU0rMK6UevCpqeLW35jPrLHlHrvh8VS9FBDeUApYNkV1BhCGxQ_WjfUnAJTd4m0CEv34iy5T4cTiwOpi517Se2Qoe31V_0oj007nsAskY4J8skh6hrSOUbjQ9ls0wzGKmIU7rqllKOkVTNbFzYV9SSKN-PmVuu4M963ZIMlLd1kR42vCbTSwoyWWnPpbmWArwXURWIjZ7xWSUEhOiEPveCwIxkPu7YVjPBCj7KEhQs5IZ8z8EZU8TCe9xk\">https:\/\/ugictcgt.fr\/formation\/<\/a><\/div>\n<div><\/div>\n<div>Pour tout renseignement\u00a0:\u00a0<a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.c<\/a><\/div>\n<\/div>\n<\/div>\n<div>\n<div><\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Barom\u00e8tre Techs et professions interm\u00e9diaires Ce nouveau sondage montre que les techs et professions interm\u00e9diaires ont un fort sentiment de d\u00e9classement, une perte de pouvoir d&rsquo;achat et des conditions de travail d\u00e9grad\u00e9es. Mais ils et elles sont 76 % \u00e0 d\u00e9clarer \u00eatre pr\u00eats \u00e0 se mobiliser collectivement pour exiger une augmentation salariale et 40 % [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[40,157,70,6,10,45,2,41,134,35,133,78,23],"class_list":["post-1699","post","type-post","status-publish","format-standard","hentry","category-archives","tag-assurance-chomage","tag-cese","tag-eurocadres","tag-formation","tag-mobilisation","tag-presse","tag-rencontres-doptions","tag-salaires","tag-tech","tag-teletravail","tag-temps-de-travail","tag-ufict-fnme","tag-ufmict"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1699","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1699"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1699\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1699"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1699"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1699"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}