{"id":1740,"date":"2024-03-29T15:34:20","date_gmt":"2024-03-29T14:34:20","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1740"},"modified":"2024-03-29T15:34:20","modified_gmt":"2024-03-29T14:34:20","slug":"vendredi-29-mars-n502","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2024\/03\/29\/vendredi-29-mars-n502\/","title":{"rendered":"Vendredi 29 mars \u2013 N\u00b0502"},"content":{"rendered":"<h2><b>JOURNEE D&rsquo;ETUDE IA GENERATIVE<\/b><\/h2>\n<p>Le\u00a0<strong>26 avril 2024<\/strong>\u00a0&#8211; patio de la CGT : l&rsquo;Ugict organise une initiative sur l&rsquo;<strong>i<\/strong>ntelligence\u00a0<strong>A<\/strong>rtificielle, avec des tables-rondes et des d\u00e9bats, un repas partag\u00e9 et une exposition de l&rsquo;Apec \u00ab\u00a0Travailler demain : quels futurs se dessinent ?\u00a0\u00bb (programme en cours de finalisation).<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/aFC5I6xtuvAVMtFCKdHT8fevo-7B8h17BzqFrmUkEBk2vNT6bH-egCrwAeLW41yzB9tTVbAE1_ArNTZ6MjVfvbwhwisGdkmKzQqrkYvyeiEdk_wQiyguJLRw5TigIBNduo3q-hac4PsutTLy14XIKxoFRQ0B3Dc7V2gSX16E2SSo88JZKNcvhWPLg2D3g3bju7A6_b_5rzv9VhmZ5NSQRPptSn-vQjv6aqEiAvjlyfYwitHUBaSX9QTcvrrH4qLXkhZGvBovT6BGmZ7h3uMIUbEorhFVB5ANwP6VqIftZF3sB12hjYoC6bmwUFT7u2kG06Df7Witvmx1BNZBE8NdNYRap6m3wXXU88tAzx5p_Bny9UmcIErwTCg_mi0vFcC5zUdsxILJ\" target=\"_blank\" rel=\"noopener\"><strong>Inscription \u00e0 la journ\u00e9e Intelligence Artificielle<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>RENCONTRES D&rsquo;OPTIONS DU 16 MAI<\/b><\/h2>\n<p>Le 16 mai 2024 &#8211; au C\u00e9dias \u00e0 Paris : l&rsquo;Ugict organise ses rencontres d&rsquo;Options sur le th\u00e8me des : \u00ab\u00a0Violences sexistes et sexuelles : la face cach\u00e9e du travail\u00a0\u00bb. Ce sera l&rsquo;occasion d&rsquo;\u00e9voquer les VSS, de l&rsquo;enseignement sup\u00e9rieur au travail, et comment agir face aux violences.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/BmyszgeqPQBPsLhJat5uMR3hqFdmtVUMqFUDUGYDOpwlGLL2DtJ9ywcXnFsZejFXIvUDp4gm6oF_KLD_Nsmcud4j8NzUFfth-JCEWoDr8tXbuDrMQLG49q81HsnBR8t2xBUKPUyvv0Tj4zJ8kSHJ70amTfisW3GgEVfgBHrdFWdu8iv2pjGAO40he6P8hyLXvgN42O4ffuTmQXr8GimdQ4hWeEexSG-UxM7XwVSrXwKa6CIp6dbdth4pgMH1PyhDGpPlyeH2mSzS3GskJODzOFlYJH8s5bdY9ypIOSlC1YBCnT7QAMNIyPsadVD1Web37e-4KCh4\" target=\"_blank\" rel=\"noopener\"><strong>Inscription aux Rencontres d&rsquo;Options<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>CANAL TELEGRAM de L&rsquo;UGICT<\/strong><\/h2>\n<p>L&rsquo;Ugict a d\u00e9sormais un canal T\u00e9l\u00e9gram grand public sur lequel chacun\u00b7e peut s&rsquo;abonner pour suivre nos actus<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/JT37Y7mqWLSeiMlzTgERNsN6St_ryIqjgIIPHBPc-v_tb4UTICvcm4V_05j3VEwekBHiwX8ll6xY6-WLdHvmx-jIjRLQQJVc1mIdE6gQj0vRSOAVZIlyw0pnGAJaSJFW5xEYeNAHvC9pMyOYCYxVAOZdq9rQo39UI2a2xnqkcTcCRScGTMJ3UNKi4FZMuA9uVYpXeD543e9S_b4gqOzoxF_wzerODBeY7_EefKTgzBnfdyBxJM2r9Ns7xWwOB0PlsdLgabFw9mSS\" target=\"_blank\" rel=\"noopener\"><strong>S&rsquo;abonner \u00e0 T\u00e9l\u00e9gram<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>LE SOCIOM\u00c8TRE EST ARRIV\u00c9<\/b><\/h2>\n<p>L\u2019UGICT a cr\u00e9\u00e9 le sociom\u00e8tre de l\u2019encadrant. Un outil indispensable qui permettra aux ICTAM de situer entre environnement hostile ou bienveillant, la qualit\u00e9 de leurs conditions de travail. Vous pouvez venir les r\u00e9cup\u00e9rer dans le locaux de l\u2019UGICT. \u00c0 diffuser largement\u00a0!<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/JcWluo8AbETPAgS77M4jWE-gIKjhuIHPO-uDLI4_1U6zFdDbEnGcbjK71unLkvM_-6TTSUh7sPAyQtq3Jpn7knFX8SVPIlyTST0NdOG6zAusdcNd9NfEvfakIhfeTU-Qaas5itn9VQgxDWx3n6VVTRBouT2atXexDzObC_awFmp1hA6lWaoO8p1Pu5BQ00MPNDaqLHUnb7MnLgMlMRTwqL6LfFVTgebVxq4sRc6UoPfVArjyTlwZyg6BdmPYmfIxYpwwns6K53L6u8aG5OLOm-n-Gh0A8tnOm99_qQ\" target=\"_blank\" rel=\"noopener\"><strong>T\u00e9l\u00e9charger le sociom\u00e8tre<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>IL EST URGENT D&rsquo;OBTENIR DES HAUSSES G\u00c9N\u00c9RALES DE SALAIRES<\/b><\/h2>\n<p>L&rsquo;Ugict s&rsquo;inscrit dans\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/c0x3sFT4hus6RLRi6YzhP4TU06EcKMF5ZxftITBUXpLFBW5WAlgPRHPHU7yX_fixomxJw8iXTRujI65zojGdqWG-aaPruH6SDzxXaz0QqO8k4qM_sF8VbyTTBzf4K5S_9mb60YiCwwezKk27i5RkdCAppl-CamkpcW--Mc2Bg0E-xfHoIf7wQBJv2-KlJ28-ZdvQmRDHLlfWDhXZ-jHHXvB9xm8x4IV_DsadIXSI18MfVptmLsLocbyE6IusRy4DQptpDn4_arHuHfCnAOr9qA\">la campagne conf\u00e9d\u00e9rale \u00ab\u00a0Urgence Salaires\u00a0\u00bb<\/a>\u00a0et propose un tract d&rsquo;appel \u00e0 la journ\u00e9e de mobilisation de la fonction publique pour les r\u00e9mun\u00e9rations du 19 mars.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/HeiPTR75lk4KDXcWQGS51ZKY2um4EfQLoISL8lo8rFjKBemiLCSx2JmZuM90p6blqO-LGIKtow7aEdOVKObr7UWFp0Dv4EDpIqWv1rUtcvMWnT3r5kmNQ05SKV2lcjnOu9uMUs1zDDYA1uIyfn6FLK50hlFLj4WfMxJ_1Ipddgy_Tik8NfpBTVlsyJ-BYOkps-Ifz1fC7MI7n34nHZS5_qtZH6ZlglPda288wPKSInFu8dyYgLBsuXGqFpDOgyeg7gac5HkYZlzMYqbroKyzBeQE1XLxlo9pKY4kYCEPjOm2_C8BY5eBPRe3m1ObZ3QnXMK0b312Zu6cQSYZJvTjgF8fDRzr7vC7QCc7U_f_0pltxtqtI490cA0\" target=\"_blank\" rel=\"noopener\"><strong>T\u00e9l\u00e9charger le tract Ugict pour la fonction publique<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><b>R\u00c9DUCTION DU TEMPS DE TRAVAIL<\/b><\/h2>\n<p>Retrouvez le contenu de la campagne de r\u00e9duction du temps de travail pour les ing\u00e9s, cadres et techs sur notre\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/7JCCAKR7rD07cW0HHjuTuHiDDWAwKYjIeM-cLbJcjhZJrow_gG5g94NaocenVnDbPxyJU2kMAdTOiJedEyyCFYpA1mCOPL4XuONzLKD_3PE2mNyE2iJEGLGQY2TetazSBkZhPQgDHhMf0SiN0r_S4CFmugJF0GyNEyPMTOjWXbfIoBeMs31sW-KXHvO5KIxAiTpk6baomNc2G06m-udEKQykiAnAq2Br_dUm_Wl2sA_RAn_ahAOcHaJuVZ0r6c-Qf4CnGhHOLYaiAfX-eqsy4IBLMDNJeO3loJhyisJimSz8f0sv\">compte Instagram<\/a>\u00a0et\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/kIivxk2t1a0h9ELGBzlqY6LvFcv3f61IY9A20Ih65a67x0RG5qV8q6fQvbc1LBqcwivrJjKYN8nLU7_amhBkeVmA3o7lPd1JxP_fE2EwtF-fKCtQ8jHbWoA9-uJ71SFB0-dZhdNsuo2ZywM7eyv7If1CA3CiJICa-JPzO4cuvIIGKZa7AmQU9EJKes-M7A6OVgZko4SpdS3hZc0ftBhlK7pLrIAXU6x8H3IWm2qpS6aNEFK6V-MsTRm0JvaS2x4zJh70ozTWAP8r6hfr-a9pQhnQLTBYtK6tri6pw07PBnaIEaQ\">sur notre site<\/a>\u00a0les premiers outils (<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/rT4qm75ETklfFigzz5_bUxTBNl2ths2i7mJGo6TLfQOa1LTln7GQv_6vtsrZnnxU8rZvPQOz9lAES5rGzB6A3JOCUOSFYG3ckC_JZxIyU21JjEwZkUhXUt8KNzqBighEDqzYdx0T0lxP_H7Sj4J7pgzyqa-wUFFdGIJFJQK0SPGPct7LCa3X_FBlMLqErKIVcbxU7kmJY9knKTXWGzqA44yUcW6kZcS71gg4eB1A1W1Kb-yj7psSKQsIRB5Zji5SmuVNuV6gTfNl4LbrJIv309-zaSo3mCzuPJmO8Ik-etVYXpwqTkIvMOf1ftkGs9BKwKKWyeQeSFw\">trac<\/a><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/F8oLBq5ELfRiQzBdKKPBGAjAOTFNGd3lC6vyRZMRLuQveNfgaU0loVc8jqRWcvsBb5fJlCpKis_xOPLiHLK4D8WvMs0jHmqSRWSEqNWK1gPpM0aOUI-w8uIIynOowuaGrOIqy1dXsMEEtb2CC6eTPvqBCZheVc64meLj2wER8a8trLKSVrv6smLLb0xcBmyq3N5tXXgZu943a2dh_QcE18mxoNv8DKRxRR-hOx5L3zuy1a3aD5RmchWXZ1oF93tjWANqmAAddvg9ZdU1SXqQWjdiBzdUq_ZQVsUDk4DHSXk7A73zf7m6bU7gM5Yfa-pS0VyF4E_Fs2A\">t sur le forfait-jour<\/a>,\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/zWZOd62WzpVexJ1ZXFyd1jpLffztfBF9tX56QHzRyhhqNqgMdH_JRMrqmzWIQirYGV4y_vyETd2jZWrOqPl0oh8JKXa4LIrYdwI-RlccDTI9s6flKQOBVJyWzqzEYKnmYN4XwQFMpR2Whdyvh6Lik4YnyTZ7cNE98RXdMsuQMJuR0hpGazYA3buSAMW9VvuISqalUasXU5WbRPIpGSqjEtL8u-JInjp2sSoimkr-9_cR0CDC_vmq65fBM0Yp738jiKnrpeD2Zc83UyVxVM5wrgnwzGbdsuInnUCjxF9yxAdA4cY3Df3BTtJaazU\">affiches<\/a>,\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/WZOJreFzPt0C1DDZFN1MCpHo3gDhjOUlYm01lM_fwy2vGAi-XqAw8ZBlBATra0LrhcF1x-czWuHGz-As-RexGwBGKFqEmvJjddBOgRgVLOG_w-GdqJzesDFe5FAMkkBlPJoncGFoAU_xmwwGd8dKwkTQDW-amLsRlT_C1Eo2ErwFxx7do30gMtUxtxE9HkPA0he__jlr-PtiHYNyDQqvx99Cqj2QNdNg72SckXFeENEyTWmO2gBreFNdkgPf0Lyr1-7-gIHGe8yUAtbtS6kW9jUuTjPfWmMFsmR6eScGBexffloyJ5eA3jcY-eQC_yDEFOLUduWOS2qnx5uxgM8JRMtDROINO0se-jFI\">podcasts<\/a>\u00a0et\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/X7zH-C0i8J39mgc5c55wIN7p2ENejP2zP4kZw4np9Ft0UWK8xCLKxhK8tb7b0QZRoSKc1HaYgw5As-pTt7ray_gs2Zm6abyfvonnOYyuymmmkImQ7gDoBRertHqfidfsaDKJyrwha75QYJrkBr-LRSoQdYvMhdvr8LQj9Gke_gWB5P3CKLUidhAGt2JA6g4s87ZO4TFv6WJr2xziflpmjtC8XKvf4wJ6mXrK4GYpBjAqdSLu6iJIrvTHqqRHg9D_TmVUVtm1BT-uTjPsRWaWYirzmpMZcGv_4gTHSc_xj2sTuhnoUd8ceRUTA2k8\">g\u00e9n\u00e9rateur d&rsquo;enqu\u00eates en ligne<\/a>). Ainsi que\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/3pm2Z7GUqVWkcCPhGI2wGCmAOwq78UCqKQgv87gGDX_Lng3WN5EPIkFuL2hBNBV_fkebmy03YqWmD0h-SwbawViScmbbkdSjBvflnVtyhx_Knogb49uS0LISBK90nE7PFm3gFWsb9nIZTjNoDP3vVQo8VOyDVcAp0xYNcB_CZgUFoUws6g-15Tuvk3EctGo5zS-P2lGRroU2i7sLeOsBX2gwshGzHBRjmw5FnF3AHLnXKWlFIuEgKuvbz1Ouha_pzC25Xj8jQE5NglFyvVp9bzNHjq3dWyapWekp_M2WpdagXlGQesYs7IuoJ182vCtxIK5sT41Qjfce2jfUnplku0ha9n1J-w\">le communiqu\u00e9<\/a>\u00a0de r\u00e9ponse \u00e0 l&rsquo;annonce de Gabriel Attal sur la \u00ab\u00a0semaine en 4 jours\u00a0\u00bb.<\/p>\n<p>&nbsp;<\/p>\n<div>\n<h2><b>2024\u00a0: ANNEE DES CONGRES DE SYNDICAT<\/b><\/h2>\n<p>La CE conf\u00e9d\u00e9rale invite les syndicats CGT \u00e0 organiser leur congr\u00e8s (ou, s\u2019ils ont d\u00e9j\u00e0 eu lieu, une assembl\u00e9e g\u00e9n\u00e9rale) en 2024 afin de profiter de la dynamique de la mobilisation contre la r\u00e9forme des retraites et d\u2019int\u00e9grer les nombreux\u00b7ses nouveaux\u00b7elles adh\u00e9rent\u00b7es \u00e0 la vie d\u00e9mocratique de la CGT.<\/p>\n<p>La question de la place des ing\u00e9s, cadres et techs sera centrale dans l\u2019organisation de ces moments d\u00e9mocratiques. L\u2019Ugict se tient \u00e0 la disposition des syndicats pour les aider \u00e0 les pr\u00e9parer.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/RA_BqA5WqRmdTf39UnjcdXcHodP9XunRsizIC1CF4iOuLvY7krDRWVtvoXVdBB3HDzJB1T3Frhk6Vh9aezYAUEKzGZfROf95_0ol1iqqQ5GSzas9S0Zbz8u9SDiQdVVfcEANB54PRFYHImph6GQgIx0gORa0yKhjWmLTOS4RgrDa656WKDeZBnaur-XQ4Z8xtwwU6F9-5WhDCYi3PTCRz0eGbWkYzmegx1LR19ez_EbQDoj_jM00Wh_X5PDdJKy7INu1fGp5drFRrpYngd5gO1dN8wpSirXQ-uX7XddDGg\" target=\"_blank\" rel=\"noopener\"><strong>Lien pour solliciter l\u2019Ugict et ses organisations<\/strong><\/a><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h2><strong>COMMANDER \u00ab\u00a0CADRES &amp; TECHS INFO\u00a0\u00bb<\/strong><\/h2>\n<p>L\u2019Ugict met \u00e0 disposition des syndicats un outil de communication pour les campagnes \u00e9lectorales des \u00e9lections professionnelles. Vous pouvez le t\u00e9l\u00e9charger et\/ou le commander chez l\u2019imprimeur\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/sN65lPXu6LvcHFLYNjFiwHnWwGUDGOXXqeAxFMqLiBgu0aDfDhwjCdzh0cnEj8tvsruyurrCx475LG-x518LveAysPbCyHEzDte9PH3pRUCZtm9Ji-asAuKbhRGmWFL9rm_X4-Wm5oElxm0Y9RBIqmlgLbEsG423ampZXwerDfMWHCFkwlJCj9nXD-MeSLSbE1_UYlH_bze4_g_EbAmxE0HlLwZi7uWblXnNZdePPpMx5Hi38alm0Yqqp_9M_yZ8h_-2Y6TYrh2hPQjSLwV398nu4vCDIK3vwNA229VD-0bP5lu7w1X7sm5t1_vPbIx5o2EaQG1d0Gos0043BEZLkzdGEWcjwTqJ7B3mYQ8jOU2cRkHLlu_UpfSMShF49vp84YlmRgkAaJEbEO0DQlPkJF-pSK0pfsalkEBAesvwuHKlR990UkD3ysLAQftd-1Ys5_Y\">(voir la note m\u00e9thodo ici<\/a>)<strong>.<\/strong><\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/EkbqWL8u0dhMHthTJB3m55Zg5UJJDWci1-lomWpjtoD6nez6IZaHW3tUjstkEF3tWA2Fnix0pfk2JscrwVegay-UL9156W2lYDLakdd3eWx-5nL4rL4JvY22_kIxhoxHUngPDL-WuW8MT7zb14j1r5xaFtG7DTAfveJqCxX1Vmfh4rUClucmQmzpPCBkWR1leQJH7XGk3Xe71wN9H2lNfq5O7i4gWiqjWdPuV4n0wOsDSgnclm4aWNVslm4orqBL3uC4nEnaJbLv-DJeT87-bt-yxc2xUACMWBtrXEjqwDGnq1Ef4edo8SlwHh2EANj5OFAgwnCqhANxSgb_Tc1TER8\" target=\"_blank\" rel=\"noopener\"><strong>Lien vers version PDF<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>OPTIONS<\/strong><\/h2>\n<p><strong>Votre abonnement<br \/>\n<\/strong><\/p>\n<div>\u00c0 partir du num\u00e9ro 679 de mars 2024, si vous ne recevez pas votre journal Options, rapprochez-vous de votre syndicat afin qu\u2019il v\u00e9rifie votre adresse postale dans Cogitiel. En effet l\u2019Ugict a bascul\u00e9 \u00e0 100\u00a0% sur les donn\u00e9es Cogitiel (crois\u00e9es avec Cog\u00e9tise).<\/div>\n<div>Si le probl\u00e8me persiste, merci de nous communiquer vos informations via le formulaire\u00a0:\u00a0<strong><a href=\"https:\/\/ugictcgt.typeform.com\/infos-options\" target=\"_blank\" rel=\"noopener\">https:\/\/ugictcgt.typeform.com\/infos-options<\/a><\/strong><\/div>\n<div><\/div>\n<div><b>La boutique du journal<\/b><\/div>\n<p>Venez visiter la\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/6TIHEis8KDFFMESc72HF8c-XcrgcsBXyywStEmjytNVSxWv16WTloDZQy-sPovxjpLsteViQyS1XzKCAoiTZR-0INWH8EKumRBOdgoFRVxonlw5AE-GASbFXkhFeKb5IO-HDQP5DZgExftXoIoQypXJFEAc-aHhJPG6ttNOEGLR0ZRpDN1fNlTX6cjJA3uI1X2mFFv4NegKhQyLwHccTnDa8vT1KWA_fh3eUlOMFCIkyVQK1HT3IY1qnDr-8kqfLfuxhF5c9JcA_Bf-jdsdQQRnkyX0yGka2rj1F27GgrlMlhn-nyDYGz_TEYUHEfVLVnnGUlA6xMn56wYDzjrT_cyxOQgJDpFg\">boutique du magazine Options<\/a>\u00a0et acheter les num\u00e9ros qui vous int\u00e9ressent.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<h3><strong>ENSEIGNEMENT SUP\u00c9RIEUR ET RECHERCHE<\/strong><\/h3>\n<div><strong>Appel de l&rsquo;intersyndicale de l&rsquo;Enseignement sup\u00e9rieur et de la Recherche<\/strong><\/div>\n<div>Le 2 avril, mobilis\u00e9\u00b7es contre le projet \u00e9ducatif et la r\u00e9forme de la formation des enseignant\u00b7es port\u00e9s par le gouvernement !<\/div>\n<div><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/QoLhM6_-KGHmU8DMmTxJqhJw_R5ip6bg0d2IpXsxN_41hDb6de8UKPVRKc90uA-BsODg77NPvlGy-JgnkcJNky3Rwa4al7TaB5D1Z9zUvh-UD1PBM7bEj5KVsbvLmpmwjFzSmpatb4yQ_-raX_bbdGsL9IEmXkvL5RfUvT_SeWFT61EHENKhVCw3pJT5NZCVi-XxGS_WTYUEWQ0WBl4XOFWdbbONgsquRuUkLzbt0VpmV6fV9UAegmJaMzuPeIHviv2FxDG00aZovdh9a_T12cwWFvSk9bizgpg-ho_p9qY4GXoYyrlPKJfIa9urUP81HsuORWr1KqBwil3B_BzR_6GMOcYR54PlVqwKvXCbt7EY6-FgHpfZ8YpSp8yz9sbTXJ5etZao7p_TWW9MIXdo\" target=\"_blank\" rel=\"noopener\"><strong>Lire\u00a0 et t\u00e9l\u00e9charger l&rsquo;appel \u00e0 la mobilisation<\/strong><\/a><\/div>\n<div><\/div>\n<h3><strong>UFC FAPT<\/strong><\/h3>\n<div><strong>Questionnaire en direction des cadres<\/strong><\/div>\n<div>\u00a0Avec son UFC, la CGT FAPT invite les cadres \u00e0 prendre leur place dans un espace de libert\u00e9, de dialogue, d\u2019\u00e9change et d\u2019action pour leur permettre de d\u00e9cider des choix et des orientations du syndicat.<\/div>\n<div><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/pjjIPBJwWlRS-20d8r6iJp5me4PeIWk9-JSix9LNeUdRxF-qV5unoW-BoT0c7T9Md-mXZRG1AlIM6rwd_I6zOVgNbKm_Do9VhY1OECdlxQv6uSFF1if6prCJxWkj9uRNuNE6SmMk1KVqu2NOwA-uvsKr1E8mkvRuPje3l4sVANqzli_ONgkTVukwQkIJB788Q1gItCEffczoFYpvtQducDY_Hk8yQaTVPDihQ2ZNywblAo0pDYTaGm46U128OV1H55FxRD1QE7R4lXRarGz2kwTWBGHh-688yjbc74uhhlgknC5iMqBVzzAPNuei2bqjr27Oxa0pGLtRspNM854Nu_FZhUzZLKzk6YD3hxwnPEmSAxd1HlWTLk7FowdDzxtJwzS6pPZ9gSOygkMuQqiZjHJomSZjOuNjZp0\">&gt;&gt;&#8230; Cliquez ici pour lire la suite sur le site SVP &#8230;&lt;&lt;<\/a><\/div>\n<div><\/div>\n<h3><strong>SYNDICAT DES JOURNALISTES CGT &#8211; SNJ CGT<\/strong><\/h3>\n<div><strong>Quand la direction du Canard la joue comme Paqua !<\/strong><\/div>\n<div>\u00ab\u00a0<em>Quand on est emmerd\u00e9 par une affaire, il faut susciter une affaire dans l&rsquo;affaire, et si n\u00e9cessaire une autre affaire dans l&rsquo;affaire dans l&rsquo;affaire, jusqu&rsquo;\u00e0 ce que personne n&rsquo;y comprenne plus rien.\u00a0\u00bb<\/em><\/div>\n<div>C&rsquo;est ce \u00ab\u00a0th\u00e9or\u00e8me de Pasqua\u00a0\u00bb, un bon client du\u00a0<em>Canard Encha\u00een\u00e9<\/em>, qui semble inspirer aujourd&rsquo;hui la direction du m\u00eame Canard Encha\u00een\u00e9&#8230;<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/hr_DgrjWRqf5QAorlqd5Vv9RaC3Jw4mbWQLGOYF2mL09CT1Dx4I0h3dpSZLKnNIFYX1KGjDTKndJUtJcQIsnFc8rZvmkJmY6XamFZqespYsldHUZQXDY5Sp3hNGy_AjLVzNcZCpvy_QKPgJrLvvkAgxoQwBEGDjvfHHEBB6wPe-_0KaCa55wuCspBNBrza5Tk7uuXzYDLLk-FItOZ-t31U23S94K_guXGVbQvYgZpHx3ePbd7uyljn_nRF-NqOppBkGvZjgrLDMnYTXNxSHvWjhqs2BQ6D47DdT7Yh3omfL6hPrwDLTiZl5CdIJx2Wz6wbClPuTzP_LFIH--i89Hwf-nEvaZdGfSH-Oowg\" target=\"_blank\" rel=\"noopener\"><strong>Lire\u00a0 et t\u00e9l\u00e9charger le tract<\/strong><\/a><\/div>\n<div><\/div>\n<h3><strong>SYNDICAT DES JOURNALISTES CGT &#8211; SNJ CGT<\/strong><\/h3>\n<div><strong>\u00ab\u00a0LA PROVENCE\u00a0\u00bb : LE SNJ-CGT soutient les salari\u00e9s en gr\u00e8ve pour leur libert\u00e9 \u00e9ditoriale<\/strong><\/div>\n<div>Les salari\u00e9s du quotidien r\u00e9gional\u00a0<em>La Provence<\/em>\u00a0ont vot\u00e9 vendredi 22 mars \u00e0 79 % en faveur d&rsquo;une gr\u00e8s illimit\u00e9e et d&rsquo;une motion de d\u00e9fiance contre leur direction.<\/div>\n<div><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/AHEXe6cI3cbCsHuARAXAWOXKryuqNNX-ngyXHFDR4fb_w8T7E1RryitpHnvC027HbU8kQqqhOhjtglCvIxaIdanXOMlD2Du7NadwOHqnEAmgcuVETztgCIPaNuv9TQo5Ohmk8ini2suorTzY_xZq3iIn_E7ZER3OFbnF-9ju6IApgjowDLpA43uQXBohwSs4mlVAZk24CB4for6_Rpfx1nzSfwMDJFG1H9uRjZ0v_5THwFJpNA679Gr5m5ktt6HzzV7y7nKOo0aTNKKRFqk7ox0jUmPujMalwBPb0YhRIQ-QRKdfUiR8vQqKcqxqGZrjGGtx_cck_j3Kdg89ObTWAZuGAUC-DO0Ba8RDg5c4wFneKxLbzVG-F0bAxrJxadT3vdqJtvrYDGdrw714Jg\" target=\"_blank\" rel=\"noopener\"><strong>Lire\u00a0 et t\u00e9l\u00e9charger le tract<\/strong><\/a><\/div>\n<div><\/div>\n<div>\n<h3><strong>UFCM CHEMINOTS<\/strong><\/h3>\n<div><strong>Liquidation du Fret SNCF, la CGT dit NON !<\/strong><\/div>\n<div>La politique de d\u00e9sindustrialisation de notre pays, notamment l&rsquo;industrie lourde (minerais, charbon, m\u00e9tallurgie, sid\u00e9rurgie&#8230;) marque avec \u00ab\u00a0la fin des 30 glorieuses (1945 &#8211; 1975)\u00a0\u00bb le d\u00e9but du d\u00e9clin du Fret ferroviaire.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/_pmGJ-rpM9d-lAu2CHTLbwDq_tCsEG6azcr5FvnXSO0mP4uIBFTT8XYk2BUFTQKY-9TYDcZg9u0Q6Q8xG_sM9djGwDcJ0dHfm8tVGRZB8oeUvwrS0uNj9PlF1zKOd1SRUYYmXPNtxOA6L3rSKNXIrj-C3jb2CJ-mtxdieCt-IuGy4A0jx6vEmx_opESQhOTMzyUKMJyo6UW6rlz9Hi9jw9OTiBNGT9bB550pQnb7Ziue1AL5shgVdRQg4vjYFgL-fCQIS1rKGgtMc1jDMNyYlawmXe-Ye5gLLyZoLamPu8VDOcIoRExaZBrDDTT_Sy6HcsFvg2iuc6LsNrEdzaKlCWUllm3iyKXHo-3i9qqi1-GJRk_frGPOgAq74YIcPbtnovaNCUAdOSdAXoqfzjTg6hLEgJ-d-4vyd49Ssz5YiuY\" target=\"_blank\" rel=\"noopener\"><strong>Lire le tract<\/strong><\/a><\/div>\n<div><\/div>\n<h3><strong>UFCM CHEMINOTS<\/strong><\/h3>\n<div><strong>Cadres jeunes embauch\u00e9s : pour un parcours d&rsquo;accueil int\u00e9grateur<\/strong><\/div>\n<div>Les jeunes embauch\u00e9s cadres participent \u00e0 la construction du ferroviaire de demain. Ils sont l&rsquo;avenir. Pour ce faire, ils doivent avoir tous les atouts en main.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/WBVnjmuxUwacdgX2ecy2I9fBBQcisRV8i6XNawEFBDIv5Y2t4ScEA8wHLRikUBPV-luUE_4lMzO71Vgczc6TiTX0gLTZQKvgJKupeO1QBjl2Y6B024J0_Ano_lwLga9mwlfwnFiIDSIW4jgLg9BY9UwZSehDpyJXKh8o4ib8FGa1VyAua2IqdkqPRd2laOblrijWE-a7Y4foEVzlFvGNvjPbgttXfGOmpWkEEcH-phCret5NBwLwWdb74aq9Uv1JhRyOWenx0uhPr5_075qHL7ShyNDgBHuSYbqK9vsTOXWfcWOUy690_zxccRd1szcQRd9BWyy1vjkcC3mCkIh9mN2Namy9I5IPk9vzYUUa0QuzvQ2uxvxnCLLGC3qf50Iv6hY2akchHUU80bpltyX5-MCbTkSYgyC54sRAPOfuhfl_Pdk\" target=\"_blank\" rel=\"noopener\"><strong>Lire le tract<\/strong><\/a><\/div>\n<div><\/div>\n<div>\n<h3><strong>OFICT \u00c9QUIPEMENT &#8211; ENVIRONNEMENT<\/strong><\/h3>\n<div><strong>Sant\u00e9, s\u00e9curit\u00e9, conditions de travail, on se mobilise le 25 avril 2024<\/strong><\/div>\n<div>\u00a0Lire les deux tracts \u00e9dit\u00e9 par l&rsquo;Ofict :<\/div>\n<ul>\n<li><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/eY1DxLoJp2GbWsK6d4sZF-Zu0Pdl1x2BSliXxwUX1Wb3EZKQAVIYirRjmwuyM9khI_RrKP9hik-RY8Ycr14_2k9NlbsYq4ALGW0INM8hITC-wNdV0n4gQP5d_YWRIAitxp_EgQjkweEoKows-ZlEWoIUVSpYETzcrX2fJb8lopzrXCK-khaPYIeXoEdmcnkqJETWCYjvLyrnz3VmQCiRkXVo0rn_Qn3kosYGQ1oG-YHTHg3mfP3jEe3HDxk0jkb_JtC0eug9FfrhJvMPOc796yLa1swmSAbTsZTG_Gb6_3jSn9INk5pVqmYySOVjgBIcpsZplAvs34qvbM9aJVjh98NqGMIYQRgj_O9XRqjYm79H_aE7ymKeRAsfaWLQu9S7rDSn67Qo78BlzLDImGrNPrDxGr97aElWiYmmPBPdn5rkybir9u8aBiyitEk\">Temps de travail\u00a0<\/a>: travailler plus de 8 heures par jour nuit \u00e0 la sant\u00e9<\/li>\n<li><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/j1bzvNYMGFABb-kK2mLhQxg-A2pFicminNImjCYAre4vyNyE0x17as_FN879dLhDrSnmarm8xm9iq8z9_EUyaxF_k-4U7UB3AzzJFvDs0uZhQ9ig2GL5eGmkZny-dls_mZw893z3sblkXBYm-6fMY5a91MFE9M6qY90Ai-nqEOTD4DWcGQL2cQmid0_fUVCyt-L1SHb-qjV50FnpmxLCpZUCWZDuchO_PUZjf4F0d9djWPVeIaGJLgb8m38aR3OYhyXDSJZVxfmmq81kkQx0pbMiCyFIkDquY94lpHpwkD4sK6Y6parnf0-HEFcOlVSEhUCFMJwC1_C78n1gdfaxRCm8U9hNQFeCWUjPZSP1QZHJZGOpvL6NHUTkr21yiJ1QeywPWYUBdIneu4UL_d-QyRp9Ab2vok69JFB9Tj4YDz0\">Espace de travail<\/a>\u00a0: Flex office = SBF (sans bureau fixe) ?<\/li>\n<\/ul>\n<\/div>\n<h2><\/h2>\n<h2><strong>PRESSE<\/strong><\/h2>\n<p><strong>ARTICLE DANS LE MONDE<br \/>\nLe burn-out peut frapper tr\u00e8s t\u00f4t : trentenaires et d\u00e9j\u00e0 \u00ab cram\u00e9s \u00bb<br \/>\n<\/strong>En France, de 5 % \u00e0 10 % de la population active souffrirait de cette forme extr\u00eame d\u2019\u00e9puisement. Les jeunes actifs sont loin d\u2019\u00eatre \u00e9pargn\u00e9s, le d\u00e9but de la vie professionnelle constituant une p\u00e9riode particuli\u00e8rement \u00e0 risque.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/W9VTX2vZFOlOw15gsahGVWPiOLlDxTFcSKnIkVNg2wvJEpPHpGWH8MUslHW5d_-ahSTq8XZqEurlPKe1IU4y7nwt38UKxYf_COInwFSzLVV3p9HIuHCPtRce2jn063URpZGla3WN-d6lo72XLxkQjLQNaL2XPykNl0T9TklmzBM9IK4E7o90Ku3I1Cw9abSc8rPjPCBqdUKVk8qRMCWjp_haeaL08woADIDnPJjLLig4K5mzi1qxV_2rhDi2_kfiqi6Z7pzB2zS5pN3Wkt7kHPmXz83O35FwLbuar_sPsldDb1WDB1tKbn-mrHKqeMEEuTPn-qY6mb86_lZ5tgJvvF6s1ZywkycNZIOw3a0eXT4bDXbGDZ2xr3Hn_9a4b6QDOYmFvsuDKLQCvkX4rB6yqu9COHupF64AM4-plKiZWx777A\" target=\"_blank\" rel=\"noopener\"><strong>Lire et t\u00e9l\u00e9charger l&rsquo;article<\/strong><\/a><strong><br \/>\n<\/strong><strong><br \/>\nUn cadre en r\u00e9volte : Marc Verret veut transformer les multinatinales de l&rsquo;int\u00e9rieur<\/strong><strong><br \/>\n<\/strong><\/p>\n<div>\n<div>Mener une action syndicale au sein d\u2019un cabinet du \u201cBig Four\u201d : un combat perdu d\u2019avance ? Pas pour Marc Verret, jeune cadre de l\u2019audit parisien et d\u00e9l\u00e9gu\u00e9 syndical CGT.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/WABBB36Mb988fSJ0s9RoxJ_Gcpv51iubJiB1TZ2Y277UhxhdWHaYvGT66z5wFO_JEwKoHToUheyVx4qB2tNYfNh3oIQ0zREEHrOGBqW6MmRGKsb79-C8t2t2pENN7HGhSwaIrc96T1Y8POXATjvTGtR8UMnk-uIAH_YjVWoX48lw1nz8hHZOJiDguzPKp8cNYxSt50ktDFzvjVbxdssOf0KRBaTeXaqMvdyP9PnamgWeiKTgJ_ep-YCSaDn9Zk3L8csky-zFNpaMzv9dC3_hFtXyWwgyvo3kmq_4-J4YsSoWreWopV93QMClRWuFaL1eZfZ7hTezHHh96dE-ScwfA6AlfZ0bjSbISUdUeJrEhLVBAg\" target=\"_blank\" rel=\"noopener\"><strong>Lire et t\u00e9l\u00e9charger l&rsquo;article<\/strong><\/a><\/p>\n<\/div>\n<div>\n<div><strong>TRIBUNE DANS L&rsquo;HUMANIT\u00c9<\/strong><\/div>\n<div>En ces temps o\u00f9 les actions et propositions revendicative relatives aux CSE et aux activit\u00e9s sociales des salari\u00e9s, se font rares, cette tribune invite \u00e0 retrouver la d\u00e9marche de reconqu\u00eate sociale.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/lv39AS2gP9UOeLHKaAP7puchlOgwTpCaPO5rc09QiBOjU7gF1NPRycdcbpRPdBno8V6d-4WPchJvSoVNs5vfpAP604QztEd1UMrW-5_BGzN1fCMH_WbIZ5spZUCvaOQ1Wvoh7AjfIn2vqzzT20oseC3_uQ_O4ztYmKpwVJSGFxbZbjGuVoiJl5mfSRIUm-1AKIp9q1Nz3T5IHMsNZqcxOhcNbKE0aa6NNs4_EKPyDK_MuWoWgtVueigZRtkUvW8wmjtkTq6v7SjQrtSpJDYANclt2e7vZ-0lynef0efrqTdwfd6WoyEqh9ZS0KMJ3PnhrsmaurH7ZTzS5WulX56iw5p4Tc5yK3vNYpMDVpa6NZ5mblH1Rz34QIo0Vf3AKNA99ajaEwq-XTPdUr73CaJX8K88DJ_3f_zrAVOM4bU\" target=\"_blank\" rel=\"noopener\"><strong>Lire et t\u00e9l\u00e9charger la tribune<\/strong><\/a><\/div>\n<\/div>\n<\/div>\n<\/div>\n<div><\/div>\n<div>\n<div>\n<div>\n<h2><strong>CONGR\u00c8S DES UFICT<\/strong><\/h2>\n<p><strong>2024<\/strong><\/p>\n<\/div>\n<ul>\n<li>23 \u2013 27 sept.\u00a0: UFICT Services Publics \u2013 Martigues (13)<\/li>\n<li>8 \u2013 10 oct.\u00a0: UFICT Livre Communication \u2013 Toulouse (31)<\/li>\n<li>15 \u2013 17 oct.\u00a0: UFCM Cheminots \u2013 Tours (37)<\/li>\n<li>15 \u2013 17 oct.\u00a0: UFICT M\u00e9tallurgie \u2013 Carcans (33)<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<div>\n<h2><strong>AGENDA<\/strong><\/h2>\n<div>\n<p><strong>2024<\/strong><\/p>\n<\/div>\n<div>\n<p>8 et 9 avril :\u00a0<strong>Formation sur l&rsquo;histoire des Mutuelles de France<\/strong> (Montreuil)<br \/>\n16 avril :\u00a0<strong>Colloque unitaire<\/strong> europ\u00e9en sur l\u2019extr\u00eame-droite \u00e0 Paris<br \/>\n25 avril : Commission ex\u00e9cutive de l&rsquo;Ugict<br \/>\n25 avril : <strong>Journ\u00e9e conf\u00e9d\u00e9rale<\/strong>\u00a0en vue de la Journ\u00e9e internationale de\u00a0<strong>pr\u00e9vention des accidents et morts au travail<\/strong> (dimanche 28 avril)<br \/>\n26 avril\u00a0: <strong>Journ\u00e9e d\u2019\u00e9tude Ugict-CGT<\/strong> sur l\u2019Intelligence artificielle \u00e0 Montreuil<br \/>\n1er mai : <strong>Journ\u00e9e internationale des travailleur\u00b7euses<br \/>\n<\/strong>16 mai\u00a0:\u00a0<strong>Rencontres d\u2019Options<\/strong>\u00a0sur la th\u00e9matique de lutte contre les\u00a0<strong>violences sexistes et sexuelles<br \/>\n<\/strong>19 novembre : <strong>Formation des membres de la CE de l\u2019Ugict-CGT sur la question des luttes contre les violences sexistes et sexuelles<br \/>\n<\/strong>25 novembre\u00a0<strong>: Journ\u00e9e contre les violences sexistes et sexuelles<br \/>\n<\/strong>25 novembre au 09 d\u00e9cembre :\u00a0<strong>Elections TPE<br \/>\n<\/strong>12 d\u00e9cembre\u00a0:\u00a0<strong>Rencontres d\u2019Options<\/strong>\u00a0sur la th\u00e9matique\u00a0<strong>\u00ab\u00a0Professions techniciennes et interm\u00e9diaires\u00a0\u00bb<\/strong><\/p>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<div>\n<div>\n<h2><strong>FORMATIONS<\/strong><\/h2>\n<\/div>\n<h3><b>Le calendrier des formations<\/b><\/h3>\n<p><strong>Stages nationaux de formation syndicale (2 \u00e0 5 jours)<\/strong><\/p>\n<div><strong>Egalit\u00e9 professionnelle \u2013 Femmes cadres<\/strong><\/div>\n<ul>\n<li>26 au 31 mai 2024\u00a0<em>(IDT Strasbourg)<\/em><\/li>\n<\/ul>\n<p><strong>\u00catre responsable Ugict-CGT<\/strong><\/p>\n<ul>\n<li>3 au 7 juin 2024\u00a0<em>(Centre Beno\u00eet Frachon \u2013 Courcelle)<\/em><\/li>\n<li>\n<div>30 septembre au 4 octobre 2024\u00a0<em>(Centre Beno\u00eet Frachon \u2013 Courcelle)<\/em><\/div>\n<\/li>\n<\/ul>\n<p><strong>Quelle strat\u00e9gie syndicale face au \u201cWall street management\u201d\u00a0?<\/strong><\/p>\n<ul>\n<li>9 au 10 octobre 2024\u00a0<em>(Centre Beno\u00eet Frachon \u2013 Courcelle)<\/em><\/li>\n<\/ul>\n<\/div>\n<p><strong>Webinaires<\/strong><\/p>\n<div><strong>Management et pr\u00e9vention des risques psychosociaux<\/strong><\/div>\n<ul>\n<li>23 avril 2024<\/li>\n<li>24 septembre 2024<\/li>\n<li>26 novembre 2024<\/li>\n<\/ul>\n<div><strong>Affections li\u00e9es aux violences sexistes et sexuelles\u00a0: comment \u00e9valuer leur incidence et d\u00e9velopper une pr\u00e9vention efficace\u00a0?<\/strong><\/div>\n<ul>\n<li>10 juin 2024<\/li>\n<li>14 octobre 2024<\/li>\n<\/ul>\n<div><strong>Risques psychosociaux\u00a0: travailler \u00e0 partir des grandes tendances des arr\u00eats de travail des cadres pour revendiquer une politique de sant\u00e9 au travail<\/strong><\/div>\n<ul>\n<li>18 octobre 2024<\/li>\n<\/ul>\n<p><strong>Formations syndicales d\u00e9localis\u00e9es \u00e0 la demande des organisations Ugict<\/strong><\/p>\n<p><strong>Gagner les \u00e9lections professionnelles dans les coll\u00e8ges 2 et 3 et dans les cat\u00e9gories A et B de la Fonction publique<\/strong><br \/>\nUD\/CD 93\u00a0: Inscriptions \u00e0\u00a0<a href=\"mailto:contact@cgt93.fr\">contact@cgt93.fr<\/a><\/p>\n<ul>\n<li>18 et 19 septembre 2024 + 13 et 14 novembre 2024<\/li>\n<\/ul>\n<p>UD\/CD 38\u00a0:<\/p>\n<ul>\n<li>13 et 14 mai 2024<\/li>\n<\/ul>\n<p>UD\/CD 44\u00a0:<\/p>\n<ul>\n<li>13 et 14 mai 2024 + 27 et 28 juin 2024<\/li>\n<li>10 et 11 octobre 2024 + 21 et 22 novembre 2024<\/li>\n<\/ul>\n<div>\n<p>UD \/ CD 35<\/p>\n<ul>\n<li>17 au 18 juin 2024<\/li>\n<\/ul>\n<div><strong>Ma\u00eetriser la technique de l\u2019enqu\u00eate conscientisante<\/strong><\/div>\n<ul>\n<li>UD \/CD 44\u00a0: du 02 au 06 d\u00e9cembre 2024<\/li>\n<\/ul>\n<p><a href=\"https:\/\/ugictcgt.fr\/calendrier-formation\/\" target=\"_blank\" rel=\"noopener\">https:\/\/ugictcgt.fr\/calendrier-formation\/<\/a><\/p>\n<\/div>\n<div>\n<div>\n<h3><\/h3>\n<h3><b>Stage communication<\/b><\/h3>\n<p>L\u2019Ugict propose un stage sur une ou deux journ\u00e9es pour apprendre \u00e0 g\u00e9rer un site internet avec le logiciel WordPress sur la plateforme\u00a0<a href=\"http:\/\/reference-synndicale.fr\/\">reference-syndicale.fr<\/a>.<\/p>\n<p>Ce stage peut \u00eatre organis\u00e9 dans les territoires.<\/p>\n<p>Pour avoir plus de renseignements\u00a0:\u00a0<strong><a href=\"mailto:orga@ugict.cgt.fr\">orga@ugict.cgt.fr<\/a><\/strong><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1642\" src=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/06\/logougict.png\" alt=\"\" width=\"300\" height=\"204\" \/><\/div>\n<div>\n<h4><\/h4>\n<h4><strong>L\u2019Activit\u00e9 Sp\u00e9cifique de la Semaine (A2S) est un bulletin interne de l\u2019Ugict-CGT con\u00e7u comme une boite \u00e0 outils pour aider les syndicats CGT dans l\u2019animation de leur activit\u00e9 en direction des ICTAM.<\/strong><\/h4>\n<\/div>\n<div>Pour inscrire un syndicat ou un responsable \u00e0 la vie syndicale \u00e0 l\u2019Activit\u00e9 Sp\u00e9cifique<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/7Ch87C3IjQNW8WbArOaPkn4Qr71kFg9WDwXvBToFELPGV4JEFlDOlS02Pzc5ClQ5D_TI61ndWBC27X6CgySUd6KUR3Zg9vIZRX9UrQ9e0z-gYoipgmwa4rP13Cw9DYKPQufh_0f_x4BMAyk7IUz8mMW6SKQtgRMSLneQESLpqz3dag4kGsqtJ8XBgyrPN8pakGL5gJD84U_ZgeV4qaE1wYjaU7dKs9ZooapdS1gUzMAh1qn78oxvuItfvNZurWp9tqHF5zyIPJFnZFkzn641AtPhdTGT5qlo7X0JG2EgWrCuRIrngw\">https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/a><\/div>\n<div><\/div>\n<div>Retrouvez chaque semaine l\u2019A2S sur\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/iy034GMGtrM9HY8S5GIUnmrnyWT_y8R7Bz66lmbZK_XHQ7qwkk6L8WWjLfmNhc4ak45utEBugaeq4AlmvjJVyijm-v_c8fnoXWiLc0iF9_8SlO-wCltfaLLVNUcFMud9TycYbvYrkNJM7oNgugaZx_cfOd_IYb2Hdd55uwNugsDJuOgHoeH_WUCpB34k04lrsH_h96uneEXAGia-0e5PBNmn4rLsnY8gUiaqK1zqmcpfaPOZJP-KBXJaQVzC64M0bQ34pfPbwrXAtdGC208vPTo4RhmIo48YRoIM\">syndicoop.fr\/a2s\/<\/a><\/div>\n<div><\/div>\n<div>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse\u00a0:\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/oWRW9xXQwlFgHjFqqQbH6Iff59DYQnSxnEYImTOhD6IeMnGttlU0rMK6UevCpqeLW35jPrLHlHrvh8VS9FBDeUApYNkV1BhCGxQ_WjfUnAJTd4m0CEv34iy5T4cTiwOpi517Se2Qoe31V_0oj007nsAskY4J8skh6hrSOUbjQ9ls0wzGKmIU7rqllKOkVTNbFzYV9SSKN-PmVuu4M963ZIMlLd1kR42vCbTSwoyWWnPpbmWArwXURWIjZ7xWSUEhOiEPveCwIxkPu7YVjPBCj7KEhQs5IZ8z8EZU8TCe9xk\">https:\/\/ugictcgt.fr\/formation\/<\/a><\/div>\n<div><\/div>\n<div>\n<p>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse\u00a0:\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/8y90ddr_5sCct9OuG6eBDp-jzK4sxNLYaCbkSN1ViOGGCACbdqGNBJ_BasVFnOtB0VRRKU-sluskLNjLyH5cKHdKeBCZrheKbEV5zRUK__5aMyam1sCGypxIcTZvlT4wl8kx95TPn6r24OXAO_Zohti6vOJwNw6i1J2tRLxtlnBJDrf6MYPVfeNoWQDRhPlrvQcoOrWrEbIsG5rZjWkUNJIl58W_TaTBDAXk1vQBvH0tViUis8kBh2yJnCqCIAJ_pV9Z6gBfNPHm827v4xVpuAD58Eoi\">https:\/\/ugictcgt.fr\/formation\/<\/a><\/p>\n<p>Pour tout renseignement :formation.syndicale@ugict.cgt.fr (01 55 82 83 40)<\/p>\n<\/div>\n<table class=\"rnb-columns-container\" border=\"0\" cellspacing=\"0\" cellpadding=\"0\" align=\"left\">\n<tbody>\n<tr>\n<th class=\"rnb-force-col\" align=\"left\"><\/th>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<\/div>\n<\/div>\n","protected":false},"excerpt":{"rendered":"<p>JOURNEE D&rsquo;ETUDE IA GENERATIVE Le\u00a026 avril 2024\u00a0&#8211; patio de la CGT : l&rsquo;Ugict organise une initiative sur l&rsquo;intelligence\u00a0Artificielle, avec des tables-rondes et des d\u00e9bats, un repas partag\u00e9 et une exposition de l&rsquo;Apec \u00ab\u00a0Travailler demain : quels futurs se dessinent ?\u00a0\u00bb (programme en cours de finalisation). Inscription \u00e0 la journ\u00e9e Intelligence Artificielle &nbsp; RENCONTRES D&rsquo;OPTIONS DU [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[156,54,25,158,6,166,90,58,45,2,41,76,165,167,133,98,168],"class_list":["post-1740","post","type-post","status-publish","format-standard","hentry","category-archives","tag-agenda","tag-cadres-infos","tag-congres","tag-enseignement","tag-formation","tag-intelligence-artificielle","tag-ofict","tag-options","tag-presse","tag-rencontres-doptions","tag-salaires","tag-snj-cgt","tag-sociometre","tag-telegram","tag-temps-de-travail","tag-ufcm","tag-webinaire"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1740","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1740"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1740\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1740"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1740"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1740"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}