{"id":1767,"date":"2024-06-28T19:54:04","date_gmt":"2024-06-28T17:54:04","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1767"},"modified":"2024-06-29T16:26:26","modified_gmt":"2024-06-29T14:26:26","slug":"vendredi-28-juin-n514","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2024\/06\/28\/vendredi-28-juin-n514\/","title":{"rendered":"Vendredi 28 juin  \u2013 N\u00b0514"},"content":{"rendered":"<h2><strong>TOUTES ET TOUS ENSEMBLE MOBILIS\u00c9\u00b7ES CONTRE L&rsquo;EXTR\u00caME DROITE !<\/strong><\/h2>\n<p><strong>\u00c0 lire sur le site de l&rsquo;Ugict<\/strong><\/p>\n<p>L\u2019arriv\u00e9e de l\u2019extr\u00eame-droite \u00e0 la t\u00eate de notre gouvernement n\u2019a jamais \u00e9t\u00e9 une r\u00e9alit\u00e9 aussi tangible. Le Rassemblement National et ses alli\u00e9\u00b7es ne sont pas dans le camp des salari\u00e9\u00b7es, et notamment des ing\u00e9s, cadres et professions techniciennes et interm\u00e9diaires. Bien au contraire.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/VqlkBc7oFTLL5mGoaVwlCCyd1juRKyHErydF6gxpEtC8ofwtbYP_XseGWALyAECSJ0qOa-4e5knP9vU0Rc9DLsEJAxvCDUjcDpHwYl6KxuSR__0uiWtIq7E1F0ggYvQ5ndsOwddh1TrFwI4TQFotpViXiAuwvOQPEHV6V1Dwe3NgGTjLguQExsPGk0wEdHLCUBUNiJu8LPcManLjxVglVeMih3SgyOTOpSQMClRJjUT-otzy1-ECLWZ-RvYCOgtyP6GeCSOv3UlCsf30pViO0tQ_N08dBnBSZxP1BXN93Q4Ze9jjKzK820LbMQ\" target=\"_blank\" rel=\"noopener\"><strong>Pour en savoir plus &gt;&gt;&gt;<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h3><strong>5 conseils pour les ICT CGT pour faire voter contre l\u2019extr\u00eame-droite<\/strong><\/h3>\n<div>Or, celle-ci n\u2019a jamais d\u00e9fendu les droits des salari\u00e9\u00b7es, et en particulier des ing\u00e9s, cadres et techs en tentant de les opposer au reste des travailleur\u00b7euses.<\/div>\n<div>Cependant, rien n\u2019est \u00e9crit d\u2019avance, et la CGT met tout en \u0153uvre pour que l\u2019extr\u00eame droite n\u2019arrive pas au pouvoir.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/i94iACEWRSYj8BiDmj1qju8cnenVQkeitrCuaQu1ieE4zkulOvuYXyiLeHho-3qO_vfdnAgzuEZ1xEGWlh5O0w9ZljtsBeS_MhcYE3j15kDFrmmskTfvU_7fiUUbUGHswgM83LQSlOfA8QuWqBvRTS3vrwLYaq04hsG3S4nx6ZtuAhfJDj7bkhcZNpTA2CFtrl5nTgdHKGIT5UPSuPKvxSoJEJqAxwc7SLREe0mfCEGX3Z-9ZDrt_jENmuXmBcpvosWC7FVORrcKqBp40NC4qrE0XvbEZlk6lHf0ZkMCdp9ivcdyEsMYUbKbC2E5fh0\" target=\"_blank\" rel=\"noopener\"><strong>Lire l&rsquo;article<\/strong><\/a><\/div>\n<div><\/div>\n<h3><strong>Salaires des ing\u00e9s, cadres et techs : quel programme d\u00e9fend votre pouvoir d\u2019achat ?<\/strong><\/h3>\n<div>\u00c0 quelques jours du premier tour des \u00e9lections l\u00e9gislatives, et alors que le d\u00e9bat public est gangr\u00e9n\u00e9 par des pol\u00e9miques outranci\u00e8res plut\u00f4t qu\u2019un d\u00e9bat de fond sur les programmes, nous vous proposons un d\u00e9cryptage des mesures propos\u00e9es et qui concerne nos salaires.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/24sPruG0I5Ey10TjES9ANr1GzUAUaFUitHahso9X0CsuxXk4EhkH8jMjEawinOMizRBgu189hCLUpPNsDZHh1Ts5kWTSCi653SD6NgS1fzPymbJPdBgEx1dR_v9VXQN_sEckZjZKFvrBv64kboWJjPWf-hN0plsQGsvqiw94_LgoXU9706GebxL1Whtfes2HjHdI8yTG0oYn99XqOJJJwiiyQ1benw5qxvojRUy37K-EK7A3R7GdZ9bD3iq06dQ0Zk97CXa1ezQrLJYn0yaG1647z-EZkhtG9LvbUaT8JXPoxei30Su19clb7nrl3v4Y6UAylJuoee47CR_9pd7Kaa1CwKLB7mOpSFOpBqB_S5gM0sMHoxbUPB2NJEob\" target=\"_blank\" rel=\"noopener\"><strong>Lire l&rsquo;article<\/strong><\/a><\/div>\n<div><\/div>\n<h3><strong>Fonction publique<\/strong><\/h3>\n<div>Le risque d\u2019arriv\u00e9e au pouvoir de l\u2019extr\u00eame-droite met en danger le service public, nos conditions de travail et ce qui fait le c\u0153ur de nos missions : notre attachement aux valeurs du service public (\u00e9galit\u00e9, continuit\u00e9, neutralit\u00e9). L&rsquo;Ugict-CGT appelle tou\u00b7tes les agent\u00b7es des cat\u00e9gories A et B de la fonction publique, des cadres de proximit\u00e9 aux cadres dirigeant\u00b7es, \u00e0 se saisir de toutes les libert\u00e9s dont ils et elles disposent pour exercer leur libert\u00e9 d\u2019opinion et d\u2019expression, et \u00e0 voter pour le programme du Nouveau front populaire les 30 juin et 7 juillet 2024.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/7xMk_5YRMk64yJ5FibaBq3geyLBm9yascrmebPnqZUdyMUE2d-6LOfE26ESbG6zZvxK-yw25wpIer2-yGCbg0gRMPLS0Zg2mb27n02tYxkWCTzf96QLgh1xIvU8pieRej5UM_UNwASZgPj_gRHKOJESyP0liz2eEN0IcJDaa9XYcrKhsoJW6H1nINwpANA8eDeOw0McGv3yJ-RKj0VEPXL9gCDhQ4Bd7NRnNe99MQJ6HpdCq5ZEu8uJa60YcNpVSL54XkZNOC2Tw_wH19utsB8YVl9U_YhH2qyJRkv-r82JEd4vvyjvGWuXRGg\" target=\"_blank\" rel=\"noopener\"><strong>Lire l&rsquo;article et t\u00e9l\u00e9charger le tract<\/strong><\/a><\/div>\n<div><\/div>\n<div>\n<h3><strong>8 raisons pour lesquelles le RN ne d\u00e9fend pas nos retraites<\/strong><\/h3>\n<p>Le RN pr\u00e9tend depuis plusieurs ann\u00e9es porter des\u00a0 revendications sociales, en faveur des salari\u00e9\u00b7es. En mati\u00e8re de retraites leur position est claire, l\u2019extr\u00eame-droite n\u2019entend pas mettre en place la retraite \u00e0 60 ans d\u00e9fendue par la CGT<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/rU_x6dU8P3hjSplgipWixz74iQcSGamIBs7U93bH4O5v8QpITxPnfc-BnAOfCFFWr9sOuglngEWTA1Lokght9WRAbLExcdDmq1rmjouIxU8SImdjTLqSMjjZhsz3fyg--xqpECfIu_jxkgrQ4mtKxdBDEotIO2EHnzpAKe3OxKdg3OV8E7xzTo53HATE0aS70HnoOjZQQKuSprdxddudWxTMMr_GsT7oH2xOdQvrDxhx2tLi-ZfC8IXHuPuTb90dZa8nt_FrJ_TnFksBjgIDWhw4K0bChzOb5h0WtXNfjDpu\" target=\"_blank\" rel=\"noopener\"><strong>Lire l&rsquo;article et t\u00e9l\u00e9charger le tract<\/strong><\/a><\/p>\n<\/div>\n<p>&nbsp;<\/p>\n<h3><strong>Elections l\u00e9gislatives : le CESE veut faire entendre la voix de la soci\u00e9t\u00e9 civile<\/strong><\/h3>\n<p>Apr\u00e8s la dissolution de l&rsquo;Assembl\u00e9e nationale, d\u00e9cid\u00e9e par le pr\u00e9sident de la R\u00e9publique, des \u00e9lections l\u00e9gislatives sont organis\u00e9es le 30 juin et le 7 juillet 2024. Alors que s\u2019engage la campagne \u00e9lectorale, le Conseil \u00e9conomique, social et environnemental (CESE), alerte sur la n\u00e9cessit\u00e9 de mieux associer la soci\u00e9t\u00e9 civile \u00e0 l\u2019action publique et rappelle certaines de ses pr\u00e9conisations sur des th\u00e8mes du quotidien des Fran\u00e7ais.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/EnBg1zeVgw9vX_ignTZDvXQlrW0bBNmQAI4ZttRP0_GsYCnAfMFKEK1T3lchRKtYpbzLklhyJnNkMHvoOyE3BHlCWxNTf-TfLwZ-9tK0ztJynkZw9oN3ORt2Wwphzw3SdMUYIQoxOUSSvTV4kGtWjx8wZKlOZhXTxpoLJathBYjgzpnngm7Mes1EpnZZDlj3-NDpVn_fy-w1Izh3EF6Usm-rS_Ga2odCtnJRqsu8W4P77XykrjCBdo0gPmVBJQwCZU8dORGvlpWbSu5bSxrbbI6nN9HvSKeuYCg9VkuN6NroHO9GQkW0k7mspNYWD2frwIfHfVKvN-hJ6DP-HNkh4lWdkKrf8CuBLSatbf_SJBZmMlegymZeEw1DXIXQwS-0jG1B1ZeSsyDCKFY\" target=\"_blank\" rel=\"noopener\"><strong>Lire la d\u00e9claration<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<div>\n<h3><strong>\u00c0 lire sur le site de la CGT<\/strong><\/h3>\n<p>L&rsquo;abstention et l&rsquo;extr\u00eame droite ont atteint un record lors des \u00e9lections europ\u00e9ennes de ce 9 juin. Cette tendance est \u00e0 l&rsquo;oeuvre dans toute l&rsquo;Europe mais la France est le pays dans lequel les listes d&rsquo;extr\u00eame droite font le score le plus \u00e9lev\u00e9 et progressent le plus.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Qm-faFCgytyJeJj-ECy2rSc6swAMHvD7YaZiyTIEz4WQkfL4Y1-9utRondi5C4IS4A58oOC7fgt2LrrI8825p_ubXvb9OHSDVRxhuQThth0wjlnQVD2eKLsz4nN0302LnGI6tJfNgPzSQZFW4wbiRQOdgH3MXYDpppEmT2uGd2kX5tEyVmEBNFZtcGZdrby5t7ZNxNFH1xNpK64lR4T9pgsuO7xJSczFrXp08ssxvHMyxoEFhHSmiGZ3N06WInpBNitT9C3kEyW7kJ35\" target=\"_blank\" rel=\"noopener\"><strong>Tous les \u00e9l\u00e9ments de la campagne &gt;&gt;&gt;<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<h3><strong>D\u00e9claration inter-organisations<\/strong><\/h3>\n<p>Dans une d\u00e9claration commune, un grand nombre d\u2019organisations\u00a0 rappellent notre attachement aux valeurs de solidarit\u00e9 et d\u2019\u00e9galit\u00e9 et la n\u00e9cessit\u00e9 pour battre l\u2019extr\u00eame droite d\u2019agir ensemble pour l\u2019\u00e9mergence d\u2019un changement profond.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Dyaf8e5DvdCn9xQMINiypgDqnj3rpMWcbNFtabY4JH7Er_iDNdyAH7DOpAt1hjptxiSiwbe6RrD5rl8B6sWFyk41PdZBc3Dz18d9iMpkyE4j2k22tHL3DP0FeKtUwWaE4rWHEEw0d5vhbosJyAjFOXLFdOgIi0JASz3-R0EkPd8z4b86b6BKFFItz6hiwp-gWIRSrJiM2pLLqRa-0KS3ZscjXpSda4c76L3PP3ATtgbHTyfB3xpZCs09HzaVMoISNIFknEvy3Xfa9-oCKuc1Kvs0wum-jzYch2DvfZMiKM3IYtb7Eesy-kzm9mDqrmZktTcpNjeD1HRX8lUTqrjJeUermN4Q8PXJTFiQEuGRo474EdGEgYRcG--5gOnYch0kT_b2EeGh40BEWN4r5LmuCg42oAATHgc-8qEZVTraz04rcj95SnPlDiaNmlFfHlGnarfA1jndKNg\" target=\"_blank\" rel=\"noopener\"><strong>Lire la d\u00e9claration<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>MARCHE DES FIERT\u00c9S &#8211; PARIS 2024<\/strong><\/h2>\n<p><strong>Une marche pour l&rsquo;\u00e9galit\u00e9<br \/>\n<\/strong>L\u2019\u00e9dition 2024 de la Marche des fiert\u00e9s de Paris et d\u2019Ile-de-France s\u2019inscrit dans un contexte mondial et europ\u00e9en hostile aux personnes LGBTQIA+. Plus que jamais, cet \u00e9v\u00e9nement revendicatif, politique et festif doit permettre de mettre en lumi\u00e8re les combats des personnes les plus pr\u00e9caris\u00e9es.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Bdkr_vWthh56uSxVmfzzBxWBIqjYTqpIa-pqFmn1aNvOAktSn09Mf4tWGdd2PNVzNytKtYGckmJUciUXXT3aCgxdM6ospc4YRioRvJU7ZPL_LonwdZ0QEj3OaWO2UoBVP5YL6Pl-gUFyTDIppSxgP_HoaGF2srMKTdXvrmeH_6-pqpp0-ejI8w_1HaR_xwaEren3R1VphFZJvBi8MjkSeq_hlFYFz5JvpYC4hwiQ_KoakfQ7C7aw7KWbBcb4Y9CIPk2X3deiaiYNuvNvde9dwjfmdBj2tsKvtP06g9qYHmmpfBZjxA-14ew\" target=\"_blank\" rel=\"noopener\"><strong>Plus d&rsquo;infos &gt;&gt;&gt;<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Lutte contre les violences sexistes et sexuelles au travail &#8211; VSST<\/strong><\/h2>\n<h3><strong>Notre kit de campagne<\/strong><\/h3>\n<p>Dans la suite des Rencontres d&rsquo;Options du 16 mai dernier qui ont \u00e9t\u00e9 tr\u00e8s largement suivies, l\u2019Ugict-CGT d\u00e9ploie son tout premier kit de campagne de lutte contre les violences sexistes et sexuelles au travail (VSST).<\/p>\n<div>Ce kit comprend : 6 affiches informatives ; 1 tract ; 1 g\u00e9n\u00e9rateur d&rsquo;enqu\u00eate sur les violences sexistes, sexuelles et LGBTophobes au travail ; 1 affiche \u00ab\u00a0Rappel du droit\u00a0\u00bb ; 1 d\u00e9pliant \u00ab\u00a0Pr\u00e9venir les VSS au travail\u00a0\u00bb ; 1 violentom\u00e8tre ; 1 rappel des formations syndicales.<\/div>\n<div><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/ffAmRaVtICCNl4QGLZYrprhP0N0lwRvS5zG3avH1S-5FOtGMSGCgZElEjcwGG2ZPWP_eLOc65MRiyNjpHaR0HogR_Rb2qLUL4Y66zOp2NpQFICoOZARp7BLE4peVRLeOjYOsm3A1ipfviIC2oB8waeS7fEgpyeyKZngTf9dIXfSlf8TY1QfsVoR-kJPhMGP2hvnS9QumBOxdynCutcIr61Bo-Ia35JPRelbxxug5a4AKzRfyWRIWsignUsmtRrPg7KsrCfulRYqmLUN2TtSMd1w-fiQ\" target=\"_blank\" rel=\"noopener\"><strong>Retrouver tous les \u00e9l\u00e9ments de la campagne<\/strong><\/a><\/div>\n<h3><strong>\u00c0 lire dans Options num\u00e9ro 680<\/strong><\/h3>\n<div><strong>Combattre les violences sexistes et sexuelles : #YOUTOO !\u00a0<em>(parution le 18 juin)<\/em><\/strong><\/div>\n<div>Des comportements sexistes au viol, en passant par les discriminations salariales ou les moindres promotions, les diff\u00e9rentes expressions des violences sexistes et sexuelles au travail sont d\u00e9sormais identifi\u00e9es. Pourtant, femmes et minorit\u00e9s de genre restent la cible privil\u00e9gi\u00e9e de st\u00e9r\u00e9otypes et, malgr\u00e9 des \u00e9volutions gagn\u00e9es, les in\u00e9galit\u00e9s persistent. Strat\u00e9gies de r\u00e9sistances individuelles, action syndicale collective, analyses universitaires, Options croise les approches pour montrer que l\u2019\u00e9galit\u00e9, toujours \u00e0 conqu\u00e9rir, constitue un enjeu central pour le syndicalisme.<\/div>\n<p>&nbsp;<\/p>\n<h2><strong>RECONNAISSANCES DES QUALIFICATIONS<\/strong><\/h2>\n<div><strong>Classifs &amp; Qualifs&rsquo; : D\u00e9cryptage de la \u00ab\u00a0machine \u00e0 d\u00e9classer\u00a0\u00bb<\/strong><\/div>\n<div>\n<div>La nouvelle convention collective de la m\u00e9tallurgie vient d\u2019entrer en vigueur et bouleverse un syst\u00e8me de classification qui fut en place pendant une cinquantaine d\u2019ann\u00e9es. Quelles sont les cons\u00e9quences pour les ing\u00e9s, cadres et techs, dans la m\u00e9tallurgie et au del\u00e0 ?<\/div>\n<div><strong>Trois podcasts pour r\u00e9pondre \u00e0 toutes vos questions.<\/strong><\/div>\n<div><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/yW2m7YZcF3Agd7vMhzfGqB2JH7vChJ8vKpjNj0N5n4jaxKC9TU-U033vnf-E3NjF-y_puGBJ_0XU_iHt5UDo9c0zEbXZTg6P4q2HMHLu5zGC-3BvBW_i1gkd-yNtkx8cj-TDKGjc5cke0cPKEMqTzqhF03snAdc5xRYgB0zh6E3zUTnlWmkDzuQWuRFZ8rjGjf1__rb-cXuKyNA0Txow9gcubfmgE2n_TKlueZ4_r4_OlzNMlxru4JftJ1ps3cSLL-1U1sblKtNux40h4ZtCkNhihKVEx4WgfELQC5BnrUpxGjsrDSVZShI\" target=\"_blank\" rel=\"noopener\"><strong>Voir les 3 podcasts<\/strong><\/a><\/div>\n<\/div>\n<div><\/div>\n<div>\n<h2>ENVIRONNEMENT<\/h2>\n<h3><strong>RADAR TRAVAIL ENVIRONNEMENT<\/strong><\/h3>\n<div><strong>Urgence climatique, urgence sociale<\/strong><\/div>\n<div>R\u00e9chauffement climatique, effondrement de la biodiversit\u00e9, rar\u00e9faction des ressources naturelles, pollution&#8230; Aurant de sympt\u00f4mes d&rsquo;un mod\u00e8le capitaliste et consommation de masse qui prosp\u00e8re sur les crises et sur l&rsquo;exploitation toujours plus pouss\u00e9e des \u00eatres humains, comme de la nature.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/PV0Ve1FzRFGD19XzvcTnwgfD8bgc62X202YYL3A_aWVTnEKUK44asc-nPZr6udfRazSH2DQJ5p7_gOF_R3D_bSx9AYPW3lS3lNsw27m1Iee9O7kQgv9SjDovtDVvTJyH5UaPf2nJo9CjHBVJYAwlpDd_Ov_WFI6-qzo5Ltrqtcayhc4Ei2Xama-U9dhqgNXRuiVvmBKhLITwXcy2YS_I00ePZHZzSFHBWYORip6L3lBICdcAWMZf05CLTMDNbTRXag3odZF2GU1797xNHAHcAd5JikL--tvFSs9traKQ6QNNb4g3NjTHV74Mz_ADMzuOpiOlw_M1d9IO0TZwl5siiL5Gd6mY3s2wT2P44mwrejO2Eod0otveGGgFxd7JqTq4gnMJY16IEQ8S3KBX4GkquylyqA7dnlBGAe94TgRsQl4yHE_L1oWQ8c1KfKQ67No\" target=\"_blank\" rel=\"noopener\"><strong>Lire la nouvelle pr\u00e9sentation<\/strong><\/a><\/div>\n<\/div>\n<div><\/div>\n<div>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<h3><strong>OFICT CGT ET F\u00c9D\u00c9RATION \u00c9QUIPEMENT ENVIRONNEMENT<\/strong><\/h3>\n<p>Face aux r\u00e9sultat de l&rsquo;extr\u00eame droite aux \u00e9lections europ\u00e9ennes, aux taux d&rsquo;abstention et \u00e0 la dissolution d\u00e9cid\u00e9e par le Pr\u00e9sident de la R\u00e9publique, quelques \u00e9l\u00e9ments sont n\u00e9cessaires \u00e0 avoir en t\u00eate avant de se prononcer dans le urnes, en tant qu&rsquo;agent\u00b7e de la fonction publique d&rsquo;\u00c9tat au minist\u00e8re de l&rsquo;\u00e9cologie<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/fzpLtVh1Xt33EOmjJtFyQMyk-4smcq7xP6fjRo_v5cgc6lZS0kZVdJDKo5wq5peAsumbHe4-w9HQINyxMI8qb_wf783r-lF595uzwms77l9dJG4oaIsSE21nfSL_YInfjbUg1rg0ZOmegRrzrJMwhwODIO1erNkggasWbTWCXAMUlqCws7xpc0KJjC4bavvYrXiqXwGs9MtHiP6BrCJv2WSCVrV2qYOdY5R4F5Pp1N3txdru1JlLpd-ezDaN9wopaK9SJ0c_TChjM3HpNm7A8gJ5TjeEV3eHGl9AasbG477H4w8VTYVYhZM\" target=\"_blank\" rel=\"noopener\"><strong>Lire le tract<\/strong><\/a><\/p>\n<h3><strong>UFICT CGT MINES \u00c9NERGIE<\/strong><\/h3>\n<p>Les prochaines \u00e9lections l\u00e9gislatives rev\u00eatent une importance cruciale dans un contexte politique tendu. Suite aux r\u00e9sultats pr\u00e9occupants de l&rsquo;extr\u00eame droite aux \u00e9lections europ\u00e9ennes et \u00e0 la dissolution sid\u00e9rante de l&rsquo;Assembl\u00e9e nationale, il est essentiel de d\u00e9crypter les enjeux de ce scrutin.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/BIX5qIpRJ5kx9R90OqqbndTcEdvSuUoYxGjdc86FyutakW8dLxurLo0uZebWiHjSCVo8Qu9EOIngZyZOBIZKH6zub6t6J56XMscHuk8ziRVarAyuN4Y19BtgMEHdz-UfA1nJbd1oAIiDqYEdEnO5iiEiNterbE6jXUYazAqNMxsLyYSnJYhu_L-ZuQi_25nGSiUTnXBr_PO535tmtbeaI_0XlQTQjCimzLuCyIBTQ0v3PzrulmWyLUfmegynzxgvChuU66lgpug6oeHVagg7HdY-RNPa-eVnUqb0Gk7jrAhRAQO2hL5gfL5seo0gJFqtc-L0Mh74Jn2ORS0Zs2ujSSbT3lo1E8VszZ9TD83fpCtVBGuhLC6Kh37bNIFu7xVbGzuvIhw1K7iyQvb01SRslO95kU5cHKSuGVTHhIHnN4ECW4ra\" target=\"_blank\" rel=\"noopener\"><strong>Lire le tract<\/strong><\/a><\/p>\n<h3><strong>UFICT CGT SERVICES PUBLICS<\/strong><\/h3>\n<p>La dissolution de l&rsquo;Assembl\u00e9e nationale d\u00e9cid\u00e9e par le pr\u00e9sident de la R\u00e9publique offre l&rsquo;opportunit\u00e9 au Rassemblement National d&rsquo;avoir une majorit\u00e9 parlementaire. Jamais, les conditions n&rsquo;ont \u00e9t\u00e9 aussi favorable pour que l&rsquo;extr\u00eame droit s&#8217;empare du pouvoir. Il est minuit moins une.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/j-8QxUccZW_LHe7iVwZSuJ-MhvXdJjH1Vn68PVGbQg2U8_KImDonDlKXWvvH8kSfMmE_Eo6t1IWDX_f1LAvI7cN0yXCMCL3fmaesuCLWmtAmRaPm17m-g8s4tQeBr-4IKIgApnIjjU80iofNyYRxOz9n3in808-W_a3Mr4t_SS1VZbIM1hR0TrrCYt1DeCddjvSMnWN4dqd5KJEnU9OwvohTNG0b2TkRzAY0t_iNqYCy6cjg0vgNjQd9HsZFvvmNHz_bynZ2nqbFi5NPm6vwyXvU_wGsTAy75iAXsqULtYes6px5PDaQoJxep9yGMs7I61ugnmUHqK811WJKMq6rQ-1ZBXB-edCnWbxOleeYtF2WQFaGbo8xDkaTZ3fIwYjRC4lZrPmn6aKjuR4JakNZV6mutj1t7v0iLXCYEvjomDYktJSU9lSpqvP0EQ\" target=\"_blank\" rel=\"noopener\"><strong>Lire l&rsquo;appel des syndicats Ufict<\/strong><\/a><\/p>\n<h3><strong>CGT FERC SUP<\/strong><\/h3>\n<p>Les repr\u00e9sentant\u00b7es des personnels CGT en FSSSCT <em>(Formation Sp\u00e9cialis\u00e9e en mati\u00e8re de Sant\u00e9, de S\u00e9curit\u00e9 et de Conditions de Travail)<\/em>\u00a0du CSA du Minist\u00e8re de l&rsquo;Enseignement Sup\u00e9rieur et de la Recherche adressent une lettre ouverte sur la situation d&rsquo;un ensemble d&rsquo;\u00e9tablissements de l&rsquo;Enseignement sup\u00e9rieur et de la Recherche \u00e0 la Ministre.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/gfaVwO9FoCGmqHtaAWiI8RU8KwxdUx4FQnlgAcWxXxWMfkjHkNBILKfkwVAs6YcKx-edZDYieBDDyl5kB_BaAkazvNc68CwmVDvaTvSMEKkxdMnpv-Tga1Yiq7Ze80DRxIJ5ERNdYS8iKD2TBFrIdwlr1d52beguWpMLt9L98NId5xPBBg-z13dmQduSSTIy8GUw-rrT0DHBy48V9JZ9R3b59Gubg8G8EWYI0rrsUrLzY9rlTQZhcGWpdHJ9nHTzluw17PgTWNDCrHqdFIJuCrwIE0wMa2C3D-ukt8nkaoTwZ35CX7YXMP2jg8NlAeHiFCxooomANH5CT1KYcpNxQD8Zej92GAlp0EO1l88_QOdYqskxK83XUxT4OySBct8iOYreAb0ijCQtyPQ7Nm5YXL5B3CIoMu-scxvr7QbR43JPMyapvoYk5A\" target=\"_blank\" rel=\"noopener\"><strong>Lire la lettre ouverte<\/strong><\/a><\/p>\n<h3><strong>UFCM CGT CHEMINOTS<\/strong><\/h3>\n<p>L&rsquo;annonce de la dissolution de l&rsquo;Assembl\u00e9e nationale place l&rsquo;extr\u00eame droite \u00e0 la porte du gourvernement. Ces \u00e9v\u00e9nements politiques ne sont pas neutres pour le salariat, qui plus est dans une entreprise publique de service public; lorsque nous sommes salari\u00e9\u00b7es en responsabilit\u00e9 vis-\u00e0-vis de collectifs de travail.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/lSqfWG3AtZIV9H1KLkCGfddIuq8kL0-k9IQjKfrUnsYeYs15xBnbSMmmytO8rF44wJJceGhjhNx8dacZ4XGwE6wqaBYav8THspFZ5px7Ihjxwwdp7ZNSBdktO_hNDmj6FrN9zirvqF9SfCd0jf0fDVsrJt78ixtHI_uZ48AP353qftmVb_6h708HUDvqdGHcrcGNhGUJCi-Rp63ke7VVh1JCssiabm37utdC-UWXvZClInEUHFtvjyWJuhKtCBcGxXkjWEpQdOLExVRZW4OGiTtcycMoIpVHPN_iuHzYAJC_HbXTFx0dIACXmkTfOigSO650fK_EkNO8nCZfjrIQik9G5wo-I7YOTwKcaqp8wmR9DSi1ECXoYdMbc3Nj0FYRFjNZwxFdJAEyYU5T8vAC6An6Msll9mqh6dBvGd3bIUSVoKWDo6laXVE\" target=\"_blank\" rel=\"noopener\"><strong>Lire le tract<\/strong><\/a><\/p>\n<h3><strong>CGT DES JOURNALISTES &#8211; SNJ CGT<\/strong><\/h3>\n<p>Le SNJ-CGT appelle les journalistes \u00e0 faire leur travail d&rsquo;enqu\u00eate et de mise en perspective avec la plus grande rigueur. Ce qui ne pourra que r\u00e9v\u00e9ler le vrai visage de l&rsquo;extr\u00eame droite et des graves dangers qu&rsquo;elle fait courir \u00e0 la d\u00e9mocratie.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/rX6B8bQkG_lBU8wfPAoOJu9FEG1PF1rRtzi59uNb7MDX46hAL7PDwnqyvVDJZHQ4fjgovrCKmqlcchnD8s34jwIu0rMD_xd-oYe6b82y3uDpdcLLQ8SYivj7OsKagJc_zOrVyNakVMSjF8o13dMcWBmKHtfb5C9G--x1u-6NktnM6vjHGXLCjBcnI30QmgIKAhK3OLIULPpSWHUReTv4dlvWWpH2sewYzxBiyLfvmMp3NrzzszGDjdPy4J2i5Gkz3Bc1X0CBLM92IXtyFntCaGWeSftpzB5IxGXR9zt1LHTOAg2_DyzqFD32-Wzu9dgb8yZo1k2nWIFZrXLTLgVKa3lKSaY4hu1KJVgksJHoCVQ-ynXlLMISKL3zZ5l_139yLJTBOx4\" target=\"_blank\" rel=\"noopener\"><strong>Lire le communiqu\u00e9<\/strong><\/a><\/p>\n<h3><strong>CGT DES JOURNALISTES &#8211; SNJ CGT<\/strong><\/h3>\n<p>Alors qu&rsquo;aucune \u00e9tude d&rsquo;impact n&rsquo;a jamais \u00e9t\u00e9 fournie, les durcissements successifs des conditions d&rsquo;inscription et d&rsquo;indemnisation \u00e0 France Travail aggravent la pr\u00e9carit\u00e9 des personnes en recherche d&#8217;emploi.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/j7h1fzfmPDVnCRjYYpsuZJIhKA5FLCa3Pc3-sgXVRQWjvuV_dd40qtob89pX8jOgOF-SN-rWJmJLz7yfgdZPQbKz16TIJjAiA-e-piEQpNmpAcIGVgoxVCiTw4zp_-U5QpBtmXr6mG8b0ZkZKV5ZrqsKDyIgGcdCKuG06TZVIB4H2wXknJFSO5DNAY3bg3Ohvs86DNqW9cNd8A-BqABlqwycmuleaW9W7Oz5gZewjTlFfQjSW4ImFeMDPX5yUE2_koRSNGYg70wkf-cApnqIm1eC-ODll_8WQatdB1q1Rwi1UlB85r6Eo-7nHooLE9e0JsI_tWVkhvPNZ76zep2noLJ-8VkVPq8NV-yWw-66lAyy_HxK-X7e9TM\" target=\"_blank\" rel=\"noopener\"><strong>Lire le communiqu\u00e9<\/strong><\/a><\/p>\n<h3><strong>SNTRS CGT<\/strong><\/h3>\n<p>Le SNTRS-CGT consid\u00e8re que le programme du Nouveau Front Populaire est le seul dans une position de rupture claire avec les politiques men\u00e9es par les gouvernements depuis plusieurs d\u00e9cennies. Ce programme d\u00e9fend, notamment, la fonction publique, le statut g\u00e9n\u00e9ral, est anti-x\u00e9nophobe et d\u00e9fend les droits des travailleurs et travailleuses.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/XlN2Gx0cIBGGC5BFbE80dCsu9SJNsBdAVUJ5ElPa_rCPqiF6UxPRExypsMBMFU1e9svdVw8Cza4EWs2YX042h80S2TPS9Y-z7S5KT41ZoZ6zO_jsraegP9bIr34w5VPlEqDYS_rJ_ijaOPAHb1iF9Me3FT4r60ED7faKikFL1-wYzTOKPSaOQUdEZ9TWGBTE2s6cBlbou6O-IPvoxdFxYp8DAt_NErQQwwoRuLQfWuS__DAaE5PlEwWK1a8r5oq4TBo8-alWCWZ69izQs_hrpP2Lc0AaQ7s3je5ugnOM_4LCAFtaX9-bZ7gXw2wKdFVS5ctVeIRXXs-XR5LFS3ZEbSZoFa2t2MLosYGdzvFSj-BqmAB8g696Q11yeDjYjt18mlnPZOluJzrqGmDlZ4we89Kfyw2WZ5bE\" target=\"_blank\" rel=\"noopener\"><strong>Lire la motion du Conseil syndical\u00a0<\/strong><\/a><\/p>\n<\/div>\n<h2><strong>PRESSE<\/strong><\/h2>\n<h3><strong>PROFESSIONS TECHNICIENNES ET INTERM\u00c9DIAIRES<\/strong><\/h3>\n<p><strong>Opinions &amp; attentes \u2013 Le Barom\u00e8tre Techs 2024<\/strong><br \/>\nCette 10e e\u0301dition du barom\u00e8tre annuel de l\u2019Ugict-CGT\/ViaVoice a e\u0301te\u0301 re\u0301alise\u0301e quelques jours avant que l\u2019extre\u0302me-droite ne soit place\u0301e en te\u0302te des re\u0301sultats des e\u0301lections europe\u0301ennes, et que le Pre\u0301sident de la Re\u0301publique annonce la dissolution de l\u2019Assemble\u0301e nationale. Quelques jours e\u0301galement avant que la CGT ne de\u0301cide de tout mettre en oeuvre pour faire barrage a\u0300 l\u2019extre\u0302me-droite et n\u2019appelle, au vu de la gravite\u0301 de la situation, les salarie\u0301\u00b7es, retraite\u0301\u00b7es et prive\u0301\u00b7es d\u2019emploi a\u0300 aller voter les plus nombreux et nombreuses possibles les 30 juin et 7 juillet pour le programme du Nouveau Front populaire.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/gZ0QsIG-v_btn9ZnqLryLaP3rTx3UBAcTMgDhiOgshBQz4R7OenFc844Uq-Z_TEGIzZeNy36gsWdv_BbAIA9YOkt4Qyi7xrzkA7F9jRcCBzl3RNguuK0t-YDsENROzOEVbqoom28FnKFc8DLTrdzWOinp9_waaUwuXZYHfJ12eTHt6nYOuAJuA749tsHbPkZ3SEFVrgZM3m0GoJRKcCrsYYf5Bd3dSuBI6I9d1RKaRXEcesyPWedDfQZwWEQRAl4TM3D6veqbZIXA1tXMY_dS80adPBkLGzgzkOiq5jGeWMPlSXL-Q\" target=\"_blank\" rel=\"noopener\"><strong>Lire et t\u00e9l\u00e9charger le dossier de presse<\/strong><\/a><\/p>\n<div><strong>A lire dans JournalOptions.fr<\/strong><\/div>\n<div>\n<div>Professions interm\u00e9diaires et techniciennes : derri\u00e8re la col\u00e8re, le d\u00e9classement et l\u2019invisibilisation. Un tiers de ces professions a vot\u00e9 pour les partis d\u2019extr\u00eame droite aux \u00e9lections europ\u00e9ennes. Consacr\u00e9e \u00e0 leurs opinions et attentes, la 10e \u00e9dition du barom\u00e8tre Ugict-Secafi donne des cl\u00e9s pour comprendre les ressorts de ce vote.<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/Ov3uxEkJ10P-vHS-CTyaqsRgyt-MHAbIAvuHk4t5ue988Odkq_zqNRpm_4Q4VypoUpAhBBNWMcTW9-ziC5jFdOo3mNL-I5Lbc6fOnY-aiX4H5FU2k4cfXIWifu9U8tCo31xoS6jAlfbDlbNrAWIb01BzgYFem3Wm0gGOkt3wnggL_v34fjYwp13zAPSIAi97B0pswActibcXmZ848UWgbnsbsM9_gA-DhcTOhPaBCE4hT8qnDjvAV3vGKXuzIHtUj0lkWbSYd4AmfUrJ5MdWKhiwi49SHPaeteFYuAAZ5dDEywraK_ipkUnCfQzQZ18umIg1AECk7j9WlpKgvuA7bpM-6hlsTvaCOVTjqzs9_i2S82wNezbmh-uSxi52DKSj2gFJL2mE36Po7UPOFp85LFZPOwwtrx_JhpVjgLj0Ziu1fUNz2TgmMiPU_A\" target=\"_blank\" rel=\"noopener\"><strong>Lire l&rsquo;article<\/strong><\/a><\/div>\n<\/div>\n<div><\/div>\n<div>\n<div><strong>A lire dans l&rsquo;Humanit\u00e9.fr<\/strong><\/div>\n<div>D\u00e9qualification, salaire en berne&#8230; L&rsquo;Ugict-CGT alerte sur le malaise des professions techniciennes<\/div>\n<\/div>\n<div>\n<div><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/zZawKIY1CH5ujfV0wV8W4jWQtLt1-NgV4aoJr7v_szLu8IrAyKl4coWtzrf9z6ZwHUnUvTlPQoXXdtaWvLkPn2bca0Q7uWCLz7n3huRimxKQCbSvjqgpGRex9vCoT-6Q3iExW1NvDEBHs_z9wzfa9TLQrSlCEyLrSe0Aw4W2M5F0DMK3eiCh5n5fZ6mmDQb6puyzKiFjXkvAkNbl7LbHlZWkngHkN03ThcHMmW8iuxuczaPYTzk6AYhcJomSMsY2eidoA9Aq-utaCEaF2U9h6ckRivuh9kzZ_1U9kFvu9milbEdU9dlPyN5CKYqxA91Y_EpFZE4pvWMw3c27w6C-17mBq1a7-FyGst0ou9kRGl5UGyB7FHmYqcGbQHgtxIEh3g5bAPjiae93TgArZh2kzCnzZr6RVIlFTIvdlbrCSeH246tIk8QYjTUfou-AP1aKWDqH2H4It6OdWjFpVFyj\" target=\"_blank\" rel=\"noopener\"><strong>Lire l&rsquo;article<\/strong><\/a><\/div>\n<\/div>\n<h3><strong>\u00a0A lire dans l&rsquo;AEF<\/strong><\/h3>\n<p>Au travail, les professions interm\u00e9diaires priorisent le salaire et l\u2019\u00e9quilibre des temps de vie (CGT-Ugict)<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/LEE9no3dDMImWqdl95q6vv3L_U_xlc_zW3AbGoJs2UjN6ECyLpZZf6Lc4ovPgjzCX6Uck5hBMyMVRYiDFxQS8irfFZ3xo3KeUd_TUL9baQ0WPcuf00x0GDrJzPkSJ2dOXdQGo6KsaIuij9lX8xHt9gibjQSueXf7uAb1uqtlfmligvaB_A7Z9Y6DUUwF2W-5MfriUwWdAghEJsjBXOPtmQjYXsvcW5L6GxskuMooJQxd8aSWOZvzEfMlomf_iQgwKupu2epLQtvYfZmAin8QCGlrLBbc4Eaug7x0UtUkvLcubKx6EDBKIbvwkKZ_B90QOlNQBEilV_ggKHiX0BPvfcwLZ-VhlbY-aRCNyLKSkOkQoQ1A3hgQJMNdksXWYiJZP84vPcSN7zCsRG8Bw7Ig_GvK96OXjxRKI7I-acvlUL89SFrauCgY75MnHw\" target=\"_blank\" rel=\"noopener\"><strong>Lire la d\u00e9p\u00eache<\/strong><\/a><\/p>\n<h2><\/h2>\n<h2><strong>CANAL TELEGRAM de L&rsquo;UGICT<\/strong><\/h2>\n<p>L&rsquo;Ugict a d\u00e9sormais un canal T\u00e9l\u00e9gram grand public sur lequel chacun\u00b7e peut s&rsquo;abonner pour suivre nos actus<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/JT37Y7mqWLSeiMlzTgERNsN6St_ryIqjgIIPHBPc-v_tb4UTICvcm4V_05j3VEwekBHiwX8ll6xY6-WLdHvmx-jIjRLQQJVc1mIdE6gQj0vRSOAVZIlyw0pnGAJaSJFW5xEYeNAHvC9pMyOYCYxVAOZdq9rQo39UI2a2xnqkcTcCRScGTMJ3UNKi4FZMuA9uVYpXeD543e9S_b4gqOzoxF_wzerODBeY7_EefKTgzBnfdyBxJM2r9Ns7xWwOB0PlsdLgabFw9mSS\" target=\"_blank\" rel=\"noopener\"><strong>S&rsquo;abonner \u00e0 T\u00e9l\u00e9gram<\/strong><\/a><\/p>\n<h2><b>2024\u00a0: ANNEE DES CONGRES DE SYNDICAT<\/b><\/h2>\n<p>La CE conf\u00e9d\u00e9rale invite les syndicats CGT \u00e0 organiser leur congr\u00e8s (ou, s\u2019ils ont d\u00e9j\u00e0 eu lieu, une assembl\u00e9e g\u00e9n\u00e9rale) en 2024 afin de profiter de la dynamique de la mobilisation contre la r\u00e9forme des retraites et d\u2019int\u00e9grer les nombreux\u00b7ses nouveaux\u00b7elles adh\u00e9rent\u00b7es \u00e0 la vie d\u00e9mocratique de la CGT.<\/p>\n<p>La question de la place des ing\u00e9s, cadres et techs sera centrale dans l\u2019organisation de ces moments d\u00e9mocratiques. L\u2019Ugict se tient \u00e0 la disposition des syndicats pour les aider \u00e0 les pr\u00e9parer.<\/p>\n<p><a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/RA_BqA5WqRmdTf39UnjcdXcHodP9XunRsizIC1CF4iOuLvY7krDRWVtvoXVdBB3HDzJB1T3Frhk6Vh9aezYAUEKzGZfROf95_0ol1iqqQ5GSzas9S0Zbz8u9SDiQdVVfcEANB54PRFYHImph6GQgIx0gORa0yKhjWmLTOS4RgrDa656WKDeZBnaur-XQ4Z8xtwwU6F9-5WhDCYi3PTCRz0eGbWkYzmegx1LR19ez_EbQDoj_jM00Wh_X5PDdJKy7INu1fGp5drFRrpYngd5gO1dN8wpSirXQ-uX7XddDGg\" target=\"_blank\" rel=\"noopener\"><strong>Lien pour solliciter l\u2019Ugict et ses organisations<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<div>\n<h2><strong>OPTIONS<\/strong><\/h2>\n<\/div>\n<p><strong>Votre abonnement<br \/>\n<\/strong><\/p>\n<div>\u00c0 partir du num\u00e9ro 679 de mars 2024, si vous ne recevez pas votre journal Options, rapprochez-vous de votre syndicat afin qu\u2019il v\u00e9rifie votre adresse postale dans Cogitiel. En effet l\u2019Ugict a bascul\u00e9 \u00e0 100\u00a0% sur les donn\u00e9es Cogitiel (crois\u00e9es avec Cog\u00e9tise).<\/div>\n<div>Si le probl\u00e8me persiste, merci de nous communiquer vos informations via le formulaire\u00a0:\u00a0<strong><a href=\"https:\/\/ugictcgt.typeform.com\/infos-options\" target=\"_blank\" rel=\"noopener\">https:\/\/ugictcgt.typeform.com\/infos-options<\/a><\/strong><\/div>\n<div><\/div>\n<div><b>La boutique du journal<\/b><\/div>\n<p>Venez visiter la\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/6TIHEis8KDFFMESc72HF8c-XcrgcsBXyywStEmjytNVSxWv16WTloDZQy-sPovxjpLsteViQyS1XzKCAoiTZR-0INWH8EKumRBOdgoFRVxonlw5AE-GASbFXkhFeKb5IO-HDQP5DZgExftXoIoQypXJFEAc-aHhJPG6ttNOEGLR0ZRpDN1fNlTX6cjJA3uI1X2mFFv4NegKhQyLwHccTnDa8vT1KWA_fh3eUlOMFCIkyVQK1HT3IY1qnDr-8kqfLfuxhF5c9JcA_Bf-jdsdQQRnkyX0yGka2rj1F27GgrlMlhn-nyDYGz_TEYUHEfVLVnnGUlA6xMn56wYDzjrT_cyxOQgJDpFg\">boutique du magazine Options<\/a>\u00a0et acheter les num\u00e9ros qui vous int\u00e9ressent.<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>CONGR\u00c8S DES UFICT ET DES CD<\/strong><\/h2>\n<div>\n<div>\n<p><strong>2024<\/strong><\/p>\n<\/div>\n<ul>\n<li>23 \u2013 27 sept.\u00a0: UFICT Services Publics \u2013 Martigues (13)<\/li>\n<li>8 \u2013 10 oct.\u00a0: UFICT Livre Communication \u2013 Toulouse (31)<\/li>\n<li>15 \u2013 17 oct.\u00a0: UFCM Cheminots \u2013 Tours (37)<\/li>\n<li>15 \u2013 17 oct.\u00a0: UFICT M\u00e9tallurgie \u2013 Carcans (33)<\/li>\n<\/ul>\n<\/div>\n<h2><\/h2>\n<h2><strong>AGENDA<\/strong><\/h2>\n<div>\n<p><strong>2024<\/strong><\/p>\n<p>13-14-15 septembre\u00a0:\u00a0<strong>F\u00eate de l&rsquo;Humanit\u00e9<br \/>\n<\/strong>18 novembre : <strong>Atelier d\u00e9ployeurs du RADAR<\/strong> (Montreuil)<br \/>\n25 novembre <strong>: Journ\u00e9e contre les violences sexistes et sexuelles<br \/>\n<\/strong>25 novembre au 09 d\u00e9cembre :\u00a0<strong>Elections TPE<br \/>\n<\/strong>12 d\u00e9cembre\u00a0:\u00a0<strong>Rencontres d\u2019Options<\/strong>\u00a0sur la th\u00e9matique\u00a0<strong>\u00ab\u00a0Professions techniciennes et interm\u00e9diaires\u00a0\u00bb<\/strong><\/p>\n<\/div>\n<div><strong>2025<\/strong><\/div>\n<p>18 &#8211; 21 nov<strong>\u00a0: 20e Congr\u00e8s Ugict-CGT. Metz (57)<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div>\n<h2><strong>FORMATIONS<\/strong><\/h2>\n<\/div>\n<div>\n<div>\n<h3><b>Le calendrier des formations<\/b><\/h3>\n<p><strong>Stages nationaux de formation syndicale (2 \u00e0 5 jours)<\/strong><\/p>\n<p><strong>\u00catre responsable Ugict-CGT<\/strong><\/p>\n<ul>\n<li>\n<div>30 septembre au 4 octobre 2024\u00a0<em>(Centre Beno\u00eet Frachon \u2013 Courcelle)<\/em><\/div>\n<\/li>\n<\/ul>\n<p><strong>Quelle strat\u00e9gie syndicale face au \u201cWall street management\u201d\u00a0?<\/strong><\/p>\n<ul>\n<li>9 au 10 octobre 2024\u00a0<em>(Centre Beno\u00eet Frachon \u2013 Courcelle)<\/em><\/li>\n<\/ul>\n<\/div>\n<p><strong>Webinaires<\/strong><\/p>\n<div><strong>Management et pr\u00e9vention des risques psychosociaux<\/strong><\/div>\n<ul>\n<li>24 septembre 2024<\/li>\n<li>26 novembre 2024<\/li>\n<\/ul>\n<div><strong>Affections li\u00e9es aux violences sexistes et sexuelles\u00a0: comment \u00e9valuer leur incidence et d\u00e9velopper une pr\u00e9vention efficace\u00a0?<\/strong><\/div>\n<ul>\n<li>14 octobre 2024<\/li>\n<\/ul>\n<div><strong>Risques psychosociaux\u00a0: travailler \u00e0 partir des grandes tendances des arr\u00eats de travail des cadres pour revendiquer une politique de sant\u00e9 au travail<\/strong><\/div>\n<ul>\n<li>18 octobre 2024<\/li>\n<\/ul>\n<p><strong>Formations syndicales d\u00e9localis\u00e9es \u00e0 la demande des organisations Ugict<\/strong><\/p>\n<p><strong>Gagner les \u00e9lections professionnelles dans les coll\u00e8ges 2 et 3 et dans les cat\u00e9gories A et B de la Fonction publique<\/strong><br \/>\nUD\/CD 93\u00a0: Inscriptions \u00e0\u00a0<a href=\"mailto:contact@cgt93.fr\">contact@cgt93.fr<\/a><\/p>\n<ul>\n<li>18 et 19 septembre 2024 + 13 et 14 novembre 2024<\/li>\n<\/ul>\n<p>UD\/CD 44\u00a0:<\/p>\n<ul>\n<li>10 et 11 octobre 2024 + 21 et 22 novembre 2024<\/li>\n<\/ul>\n<div>\n<div><strong>Ma\u00eetriser la technique de l\u2019enqu\u00eate conscientisante<\/strong><\/div>\n<ul>\n<li>UD \/CD 44 : du 02 au 06 d\u00e9cembre 2024<\/li>\n<\/ul>\n<p>https:\/\/ugictcgt.fr\/formation-syndicale\/<\/p>\n<\/div>\n<div>\n<div>\n<h3><\/h3>\n<h3><b>Stage communication<\/b><\/h3>\n<p>L\u2019Ugict propose un stage sur une ou deux journ\u00e9es pour apprendre \u00e0 g\u00e9rer un site internet avec le logiciel WordPress sur la plateforme\u00a0<a href=\"http:\/\/reference-synndicale.fr\/\">reference-syndicale.fr<\/a>.<\/p>\n<p>Ce stage peut \u00eatre organis\u00e9 dans les territoires.<\/p>\n<p>Pour avoir plus de renseignements\u00a0:\u00a0<strong><a href=\"mailto:orga@ugict.cgt.fr\">orga@ugict.cgt.fr<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<\/div>\n<div><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-1642\" src=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2023\/06\/logougict.png\" alt=\"\" width=\"300\" height=\"204\" \/><\/div>\n<div>\n<h4><\/h4>\n<h4><strong>L\u2019Activit\u00e9 Sp\u00e9cifique de la Semaine (A2S) est un bulletin interne de l\u2019Ugict-CGT con\u00e7u comme une boite \u00e0 outils pour aider les syndicats CGT dans l\u2019animation de leur activit\u00e9 en direction des ICTAM.<\/strong><\/h4>\n<\/div>\n<div>Pour inscrire un syndicat ou un responsable \u00e0 la vie syndicale \u00e0 l\u2019Activit\u00e9 Sp\u00e9cifique<\/div>\n<div><a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/7Ch87C3IjQNW8WbArOaPkn4Qr71kFg9WDwXvBToFELPGV4JEFlDOlS02Pzc5ClQ5D_TI61ndWBC27X6CgySUd6KUR3Zg9vIZRX9UrQ9e0z-gYoipgmwa4rP13Cw9DYKPQufh_0f_x4BMAyk7IUz8mMW6SKQtgRMSLneQESLpqz3dag4kGsqtJ8XBgyrPN8pakGL5gJD84U_ZgeV4qaE1wYjaU7dKs9ZooapdS1gUzMAh1qn78oxvuItfvNZurWp9tqHF5zyIPJFnZFkzn641AtPhdTGT5qlo7X0JG2EgWrCuRIrngw\">https:\/\/ugictcgt.fr\/abonnement-a2s\/<\/a><\/div>\n<div><\/div>\n<div>Retrouvez chaque semaine l\u2019A2S sur\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/iy034GMGtrM9HY8S5GIUnmrnyWT_y8R7Bz66lmbZK_XHQ7qwkk6L8WWjLfmNhc4ak45utEBugaeq4AlmvjJVyijm-v_c8fnoXWiLc0iF9_8SlO-wCltfaLLVNUcFMud9TycYbvYrkNJM7oNgugaZx_cfOd_IYb2Hdd55uwNugsDJuOgHoeH_WUCpB34k04lrsH_h96uneEXAGia-0e5PBNmn4rLsnY8gUiaqK1zqmcpfaPOZJP-KBXJaQVzC64M0bQ34pfPbwrXAtdGC208vPTo4RhmIo48YRoIM\">syndicoop.fr\/a2s\/<\/a><\/div>\n<div><\/div>\n<div>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse\u00a0:\u00a0<a href=\"http:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/oWRW9xXQwlFgHjFqqQbH6Iff59DYQnSxnEYImTOhD6IeMnGttlU0rMK6UevCpqeLW35jPrLHlHrvh8VS9FBDeUApYNkV1BhCGxQ_WjfUnAJTd4m0CEv34iy5T4cTiwOpi517Se2Qoe31V_0oj007nsAskY4J8skh6hrSOUbjQ9ls0wzGKmIU7rqllKOkVTNbFzYV9SSKN-PmVuu4M963ZIMlLd1kR42vCbTSwoyWWnPpbmWArwXURWIjZ7xWSUEhOiEPveCwIxkPu7YVjPBCj7KEhQs5IZ8z8EZU8TCe9xk\">https:\/\/ugictcgt.fr\/formation\/<\/a><\/div>\n<div><\/div>\n<div>\n<p>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse\u00a0:\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/8y90ddr_5sCct9OuG6eBDp-jzK4sxNLYaCbkSN1ViOGGCACbdqGNBJ_BasVFnOtB0VRRKU-sluskLNjLyH5cKHdKeBCZrheKbEV5zRUK__5aMyam1sCGypxIcTZvlT4wl8kx95TPn6r24OXAO_Zohti6vOJwNw6i1J2tRLxtlnBJDrf6MYPVfeNoWQDRhPlrvQcoOrWrEbIsG5rZjWkUNJIl58W_TaTBDAXk1vQBvH0tViUis8kBh2yJnCqCIAJ_pV9Z6gBfNPHm827v4xVpuAD58Eoi\">https:\/\/ugictcgt.fr\/formation\/<\/a><\/p>\n<p>Pour tout renseignement :formation.syndicale@ugict.cgt.fr (01 55 82 83 40)<\/p>\n<\/div>\n<\/div>\n<\/div>\n<div>\n<p>&nbsp;<\/p>\n<\/div>\n<p><strong>\u00a0<\/strong><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TOUTES ET TOUS ENSEMBLE MOBILIS\u00c9\u00b7ES CONTRE L&rsquo;EXTR\u00caME DROITE ! \u00c0 lire sur le site de l&rsquo;Ugict L\u2019arriv\u00e9e de l\u2019extr\u00eame-droite \u00e0 la t\u00eate de notre gouvernement n\u2019a jamais \u00e9t\u00e9 une r\u00e9alit\u00e9 aussi tangible. Le Rassemblement National et ses alli\u00e9\u00b7es ne sont pas dans le camp des salari\u00e9\u00b7es, et notamment des ing\u00e9s, cadres et professions techniciennes et [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[82,64,25,11,131,6,10,90,58,45,109,41,76,75,105,5,143],"class_list":["post-1767","post","type-post","status-publish","format-standard","hentry","category-archives","tag-cgt-ferc-sup","tag-cheminots","tag-congres","tag-elections","tag-extreme-droite","tag-formation","tag-mobilisation","tag-ofict","tag-options","tag-presse","tag-radar","tag-salaires","tag-snj-cgt","tag-ufict-energie","tag-ufict-services-publics","tag-vie-syndicale","tag-vsst"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1767","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1767"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1767\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1767"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1767"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1767"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}