{"id":1779,"date":"2024-09-04T18:01:44","date_gmt":"2024-09-04T16:01:44","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=1779"},"modified":"2024-09-09T12:07:51","modified_gmt":"2024-09-09T10:07:51","slug":"edition-speciale-fete-de-lhuma","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2024\/09\/04\/edition-speciale-fete-de-lhuma\/","title":{"rendered":"Edition sp\u00e9ciale F\u00eate de l&rsquo;Huma"},"content":{"rendered":"<h2><strong>L&rsquo;Ugict-CGT sera pr\u00e9sente \u00e0 la f\u00eate de l&rsquo;Huma !\u00a0<\/strong><\/h2>\n<p>Comme chaque ann\u00e9e, l&rsquo;Ugict-CGT tiendra un stand au sein du Forum Social de la f\u00eate de l&rsquo;Huma, o\u00f9 vous pourrez retrouver tous les outils les plus r\u00e9cents : affiches, tracts, num\u00e9ros d\u2019Options, mais aussi des tatouages \u00e9ph\u00e9m\u00e8res militants et un mini-kit de lutte contre les violences sexistes et sexuelles au travail !<br \/>\n<strong>Cependant, pour 2024, il y a aussi une nouveaut\u00e9 &#8230;<\/strong><\/p>\n<h2><\/h2>\n<h2><strong>On syndique \u00e0 la F\u00eate de l&rsquo;Huma !<\/strong><\/h2>\n<p>Cette ann\u00e9e, la CGT et son union g\u00e9n\u00e9rale des ing\u00e9s, cadres et techs lancent une op\u00e9ration de syndicalisation massive des personnes pr\u00e9sentes \u00e0 la F\u00eate de l\u2019Huma les 13, 14 et 15 septembre.<\/p>\n<p>De nombreux\u00b7ses salari\u00e9\u00b7es se disent pr\u00eat\u00b7es \u00e0 se syndiquer, mais l&rsquo;occasion ne se pr\u00e9sente pas toujours \u00e0 elles et eux. Faisons de la F\u00eate de l&rsquo;Huma&rsquo; une occasion pour elles et eux de sauter le pas !<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/j5vSMD3CP4uOPA1R2wqEPfL99CFQqIJ0kC3y7B50Y_uqmEANrOh2q26oMR0uAbAcrf1Q6H1I9cetRT_dAEVaxZL39_tAUYxqlAJYGDC2xSYkHL9lPruISgYEVLZGW_z13-coyUAudYeK7jtAoVx4gIS5u1eKVb2Dzey-SoIOO7S0UWzIX5Fq--mcE5XtLpcfnUpDPSmzHJ6wiJgUivKHe87dcVt7rKs3p6rMd2rUSZ41Ib00DRToy0ZEtFdnffQM8ekTFt_oM113-wpz51jLCc_tZJUnC9WSnGZTqLUrE_tRk1ACQxxefWAYTIHpFckhjjKz9wA0jA\" target=\"_blank\" rel=\"noopener\"><strong>Lire l&rsquo;article\u00a0<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>On recherche des militant\u00b7es CGT\u00a0<\/strong><\/h2>\n<p>Pour pouvoir syndiquer un maximum de personnes, il faut qu&rsquo;il y ait le plus de militant\u00b7es CGT possible afin de les accueillir et de leur expliquer la d\u00e9marche CGT.<\/p>\n<p>\ud83d\udcf2 Pour donner un coup de main sur un cr\u00e9neau (3h) Inscrivez-vous et les syndiqu\u00e9\u00b7es CGT volontaires de vos organisations sur le formulaire ci-dessous :<br \/>\n<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/x49s7_FiQLKmK362uoCuYnoNFU8-RnvOT4PIc4n3vdF6ZaTzIwTFfGSf1T1tFhQNRu0NvHvPPDbN0ryJhHqPfWC066U7tkR9AMZp9ZmrnSfhnPds6IQyxFyk766lKsbTKOJh28BZ8KBShx2p-A4bVFHOW6xsCiIAPJLeFGuP8f5vFei8SCrGCfUwdlvZdaAoHcwZxzHNm6dbqtT5x_tU_X66e87JxPG7B0eczThZrlaqPoJbYWVXq3B-KqvUSGv56xPpfgCNvM_K1o6OS_2D6YJgRR7neC9jmjgVbkrHwYPjcMPk3nW4aoUefw7D_YpSN9fctzshLgqzRSAVLoCRFcEao_-b5jUrHVgQyvh71Xja0SSJAu8EkUvBD5LMhwlJ\" target=\"_blank\" rel=\"noopener\"><strong>Inscription sur Typeform<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>Participez \u00e0 la r\u00e9union d&rsquo;information !<\/strong><\/h2>\n<p>Afin de vous expliquer l&rsquo;op\u00e9ration plus en d\u00e9tails et de vous fournir tous les outils n\u00e9cessaires, deux r\u00e9unions Zoom auront lieu :<\/p>\n<p><strong>Lundi 9 septembre,\u00a0<\/strong>de 18h \u00e0 19h :<strong>\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/rw9XDom1jZStEESn8oBZhIikji-SlaMUgH7KHWtXhxn4MQfAOq795oXSfF-5ltZ5qqcqDoNfn_B3weqP_WfUkCo5i6ddLsIEfKunt9Kr957eLZy_mKrIFyZcKCZZqVFhYwSoYBNEOYi76qcUJxsGA262ZAKm9MR4b1-S_smmyax3yNFf6qomXHeKkWATQwufKwNejEtwyf9XVKxVw5oX2vyhMz4dK0O56-qNGFZnEA8sgsfsRmlF5X7e4DgytCC6t4msaLaUb9Xd-47upu8RIPewNZrcvWUehPBfWKiN-MgYaV5XaincB9-cdrmJxE9K7UaDZ2zVcSPa8ewnpzwU7Erz24mwBAk2uSon3ZXMoJ3gWsiXhiQ4\">cliquer ici pour obtenir le lien Zoom\u00a0<\/a><\/strong><\/p>\n<p><strong>Mercredi 11 septembre,\u00a0<\/strong>de 12h30 \u00e0 13h30<strong>\u00a0:\u00a0<a href=\"https:\/\/r.info.ugict-cgt.fr\/mk\/cl\/f\/0Gy9Fey3xwfeJIxitwz-vV397V0Ec9eOaBpAQtTrxfLuEUnzgRiTfap66jZLEezcZNMH6WpyPT9ZgRwLb5hZC3r0lQUZ8cnjuBdigUYEqdeMbawKH8YNTlzkauZpZtyJSEAYb0ZnFeWtFFZWkOvwtcUfhjSMdY7jTeKGHYqh5AwJrNtonL8haCvDY3QCqfBscifnHLsmPzWsNnjJUzqFXzEnz5nJI5e_nZ5T8S-m155gYq1FaY-SrDJkcwxfklR09lkpVW0JSn4DsjDPujKercqym8K4KYR4etFDldZULRPDBKRTs4mK1DxyLxPfGDdjILwQVdJCHCWe4BaIu0VOJTmysIh-XoOymb1ThMtjnk71d_lsMHXa\">cliquer ici pour obtenir le lien Zoom\u00a0<\/a><\/strong><\/p>\n<p>Merci \u00e0 vous !<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L&rsquo;Ugict-CGT sera pr\u00e9sente \u00e0 la f\u00eate de l&rsquo;Huma !\u00a0 Comme chaque ann\u00e9e, l&rsquo;Ugict-CGT tiendra un stand au sein du Forum Social de la f\u00eate de l&rsquo;Huma, o\u00f9 vous pourrez retrouver tous les outils les plus r\u00e9cents : affiches, tracts, num\u00e9ros d\u2019Options, mais aussi des tatouages \u00e9ph\u00e9m\u00e8res militants et un mini-kit de lutte contre les violences [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[183],"class_list":["post-1779","post","type-post","status-publish","format-standard","hentry","category-archives","tag-fete-de-lhuma"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1779","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=1779"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/1779\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=1779"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=1779"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=1779"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}