{"id":991,"date":"2019-09-05T17:01:20","date_gmt":"2019-09-05T15:01:20","guid":{"rendered":"https:\/\/syndicoop.fr\/a2s\/?p=991"},"modified":"2019-09-05T17:01:20","modified_gmt":"2019-09-05T15:01:20","slug":"vendredi-6-septembre-n309","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/a2s\/2019\/09\/05\/vendredi-6-septembre-n309\/","title":{"rendered":"Vendredi 6 septembre \u2013 n\u00b0309"},"content":{"rendered":"<h2><strong>24 SEPTEMBRE\u00a0: JOURN\u00c9E D\u2019ACTION<\/strong><\/h2>\n<p>Les ing\u00e9nieurs et les cadres ont toujours \u00e9t\u00e9 consid\u00e9r\u00e9s comme un \u00ab\u00a0laboratoire\u00a0\u00bb des transformations du travail avant de les g\u00e9n\u00e9raliser \u00e0 l\u2019ensemble des salari\u00e9s. Les r\u00e9formes en cours n\u2019\u00e9chappent pas \u00e0 cette logique..<\/p>\n<p>Portons nos revendications lors des initiatives organis\u00e9es durant la journ\u00e9e d\u2019actions du 24 septembre prochain.<\/p>\n<p><strong><a href=\"http:\/\/www.ugict.cgt.fr\/articles\/references\/cadrebashing\">[Lire et t\u00e9l\u00e9charger]<\/a><\/strong> le tract Ugict-CGT \u00ab\u00a0Le CadreBashing, ou l\u2019art de d\u00e9tourner l\u2019attention\u00a0\u00bb en direction des ICTAM pour mieux comprendre les enjeux de la mobilisation.<\/p>\n<p>T\u00e9l\u00e9chargement direct via Syndicoop\u00a0: <strong><a href=\"https:\/\/syndicoop.fr\/mutuelle\/tracts\/cadre-bashing\/\">https:\/\/syndicoop.fr\/mutuelle\/tracts\/cadre-bashing\/<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>SEMAINE DE D\u00c9PLOIEMENT<\/strong><\/h2>\n<p>Dans le cadre de la semaine d\u2019action conf\u00e9d\u00e9rale, les commissions d\u00e9partementales et les unions f\u00e9d\u00e9rales sont sollicit\u00e9es pour \u00e9laborer des initiatives de d\u00e9ploiement, de syndicalisation et de participation aux prochaines manifestations en direction des ICTAM.<\/p>\n<p>L\u2019Ugict-CGT met \u00e0 votre disposition le tract \u00ab\u00a0<a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/tracts\/pourquoi-se-syndiquer\">Pourquoi se syndiquer\u00a0?\u00a0<\/a>\u00bb<\/p>\n<p>&nbsp;<\/p>\n<h2><strong>F\u00caTE DE L\u2019HUMANIT\u00c9 2019<\/strong><\/h2>\n<p>Comme chaque ann\u00e9e, l&rsquo;Ugict-CGT sera pr\u00e9sente au Forum social de la F\u00eate de l&rsquo;Humanit\u00e9 les 13, 14 et 15 septembre 2019.<\/p>\n<p><strong>Nous invitons tous les camarades pr\u00e9sent.e.s \u00e0 la F\u00eate \u00e0 venir aider \u00e0 la tenue du stand\u00a0:<\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><a href=\"https:\/\/doodle.com\/poll\/cscvg7sx4bqf5v73\"><strong>S\u2019inscrire ici<\/strong><\/a><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>CAMPAGNE RETRAITES<\/strong><\/h2>\n<p><em>Alors que le gouvernement joue l\u2019opacit\u00e9, l\u2019Ugict-CGT lance, dans le cadre de la campagne conf\u00e9d\u00e9ral \u00ab\u00a0<strong><a href=\"https:\/\/www.cgt.fr\/sites\/default\/files\/2019-03\/Tract%20retraite.pdf\">pas de hasard pour ma retraite\u00a0<\/a><\/strong>\u00bb, <\/em><a href=\"x-webdoc:\/\/1E688954-86E4-443E-B787-672D048B4714\/reforme-retraite.info\/%20\"><strong><em>reforme-retraite.info\/<\/em><\/strong><\/a><em> pour permettre \u00e0 l\u2019encadrement de comprendre les enjeux concrets de la r\u00e9forme des retraites et les diff\u00e9rents choix possibles. <\/em><\/p>\n<p>&nbsp;<\/p>\n<p><strong>[<\/strong><strong>Lire]<\/strong> la note aux organisations sur le lancement de la campagne Retraites Ugict-CGT <em>: <a href=\"https:\/\/syndicoop.fr\/a2s\/wp-content\/uploads\/sites\/17\/2019\/07\/2019-07-01-CAMPAGNE-RETRAITE-UGICT-NOTE-AUX-ORGAS.pdf\">2019 07 01 CAMPAGNE RETRAITE UGICT NOTE AUX ORGAS<\/a><br \/>\n<\/em><\/p>\n<p>&nbsp;<\/p>\n<p>Retrouvez tous les outils de cette campagne\u00a0:<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li><a href=\"https:\/\/reforme-retraite.info\/simulateur\/\">Le calculateur de la baisse des pensions<\/a><\/li>\n<li><a href=\"https:\/\/reforme-retraite.info\/questions\/\">Check Retraite les questions taboues<\/a><\/li>\n<li><a href=\"https:\/\/reforme-retraite.info\/comparateurs\/\">Le comparateur Avant \/ Apr\u00e8s la r\u00e9forme<\/a><\/li>\n<li><a href=\"https:\/\/reforme-retraite.info\/decodeur-macron\/\">Le d\u00e9codeur de la pens\u00e9e Start Up Nation<\/a><\/li>\n<li><a href=\"https:\/\/reforme-retraite.info\/affiches\/\">Le g\u00e9n\u00e9rateur d\u2019affiches en 3 clics<\/a><\/li>\n<li><a href=\"https:\/\/reforme-retraite.info\/chaud\/\">Tract retraite<\/a><\/li>\n<li><a href=\"https:\/\/reforme-retraite.info\/capitalisation-vs-repartition\/\">Le vrai enjeu cotiser ou \u00e9pargner ?<\/a><\/li>\n<li><a href=\"https:\/\/reforme-retraite.info\/formation\/\">La formation pour tout comprendre<\/a><\/li>\n<\/ul>\n<h2><\/h2>\n<h2><strong>26 SEPTEMBRE JOURN\u00c9E D\u2019\u00c9TUDE\u00a0: L&rsquo;UGICT-CGT VS\/ LA R\u00c9FORME DES RETRAITES<\/strong><\/h2>\n<p>R\u00e9forme Macron et rapport Delevoye : quels impacts sur les ing\u00e9s cadres techs et maitrises\u00a0? Quelles sont les propositions alternatives de l&rsquo;Ugict-CGT et les outils de mobilisations mis \u00e0 disposition des ICTAM\u00a0?<\/p>\n<p>&nbsp;<\/p>\n<p>Inscription via ce lien\u00a0<strong><a href=\"https:\/\/ugictcgt.typeform.com\/to\/WtnHlh\">https:\/\/ugictcgt.typeform.com\/to\/WtnHlh<\/a><\/strong><\/p>\n<p>&nbsp;<\/p>\n<h2><strong>9 OCTOBRE\u00a0: PROFESSIONS INTERM\u00c9DIAIRES\u00a0: DES IDENTIT\u00c9S PROFESSIONNELLES DIVERSES, UN M\u00caME BESOIN DE RECONNAISSANCE<\/strong><\/h2>\n<p>Journ\u00e9e d&rsquo;\u00e9tude et de d\u00e9bats. Entr\u00e9e libre sur inscription, dans la limite des places disponibles.<\/p>\n<p>Au si\u00e8ge de la CGT, 263 rue de Paris \u00e0 Montreuil<\/p>\n<p>&nbsp;<\/p>\n<ul>\n<li>Programme de la journ\u00e9e\u00a0<a href=\"http:\/\/www.ugict.cgt.fr\/tam\">http:\/\/www.ugict.cgt.fr\/tam<\/a><\/li>\n<li>Inscriptions en ligne\u00a0<strong><a href=\"http:\/\/www.ugict.cgt.fr\/tam\/inscription\">http:\/\/www.ugict.cgt.fr\/tam\/inscription<\/a><\/strong><\/li>\n<li>Affiche en pi\u00e8ce jointe et ici :\u00a0<strong><a href=\"https:\/\/syndicoop.fr\/mutuelle\/tracts\/tam\/\">https:\/\/syndicoop.fr\/mutuelle\/tracts\/tam\/<\/a><\/strong><\/li>\n<\/ul>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>EN DIRECT DES ORGAS<\/strong><\/h2>\n<p><strong>La CD UGICT-CGT 44\u00a0<\/strong> organise le vendredi 20 septembre 2019 dans le cadre de la Digital Week deux tables rondes\u00a0:<\/p>\n<ul>\n<li>9 heures 30\u00a0: \u00ab\u00a0Comment le num\u00e9rique bouscule le rapport salarial et le syndicalisme\u00a0?\u00a0\u00bb<\/li>\n<li>14 heures\u00a0: \u00ab\u00a0Le monde du travail et le digital au f\u00e9minin\u00a0\u00bb<\/li>\n<\/ul>\n<p>Un point presse aura lieu \u00e0 11 heures 30 \u00e0 la Maison des syndicats avec la participation de Sophie Binet, co-secr\u00e9taire g\u00e9n\u00e9rale de l\u2019Ugict-CGT.<\/p>\n<p>L\u2019Ugict-CGT pr\u00e9sentera \u00e0 cette occasion l\u2019application \u00ab\u00a0Le num\u00e9rique autrement\u00a0\u00bb, sa d\u00e9marche et ses solutions pour pr\u00e9venir la souffrance au travail et les risques psychosociaux.<\/p>\n<p>Programme et inscription<strong> <a href=\"http:\/\/lacgt44.fr\/spip.php?article2232\">&gt;&gt;&gt; ici<\/a><\/strong><\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<p><strong>SAINT-DENIS (93)<\/strong>\u00a0: Un collectif ICT issu de l\u2019union locale va organiser des permanences tous les premiers jeudis de chaque mois sur l\u2019esplanade \u00e0 la sortie du RER D<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Banque de France<\/strong>\u00a0: Suite aux \u00e9lections, la CGT Banque de France passe premi\u00e8re organisation syndicale et organise un plan de d\u00e9ploiement en direction des cadres.<\/p>\n<p><strong>\u00a0<\/strong><\/p>\n<h2><strong>FORMATION<\/strong><\/h2>\n<p><strong>Deuxi\u00e8me semestre 2019<\/strong><\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/stage-national-ugict-cgt\"><strong>\u00catre responsable Ugict-CGT <\/strong><strong>\u2022<\/strong><strong> Contenu, animation et d\u00e9ploiement de l\u2019activit\u00e9 sp\u00e9cifique<\/strong><\/a><\/p>\n<p>du 02 au 06 d\u00e9cembre 2019 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p>Formations th\u00e9matiques<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/stage-retraite\"><strong>Retraites\u00a0: Cons\u00e9quences des r\u00e9formes adopt\u00e9es depuis 1993 et perspectives<\/strong><\/a><\/p>\n<p>du 04 au 08 novembre 2019 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/construire-un-management-alternatif\"><strong>Comprendre la financiarisation de l\u2019entreprise et ses incidences pour restaurer le r\u00f4le contributif de l\u2019encadrement<\/strong><\/a><\/p>\n<p>du 24 au 29 novembre 2019 \u2022 Institut du Travail \u2022 Strasbourg (67)<\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"http:\/\/www.ugict.cgt.fr\/ugict\/formation\/SitesWeb\"><strong>Communication web\u00a0: Construire et g\u00e9rer un site avec Reference-Syndicale.fr<\/strong><\/a><\/p>\n<p>du 11 au 13 d\u00e9cembre 2019 \u2022 Centre Beno\u00eet Frachon \u2022 Courcelle (91)<\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour s\u2019inscrire ou consulter notre offre de formation, une seule adresse <\/strong><a href=\"http:\/\/www.ugict.cgt.fr\/formation\">http:\/\/www.ugict.cgt.fr\/formation<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour tout renseignement<\/strong><\/p>\n<p><a href=\"mailto:formation.syndicale@ugict.cgt.fr\">formation.syndicale@ugict.cgt.fr<\/a> \/\u00a0( <a href=\"tel:01%2055%2082%2083%2035\">01 55 82 83 40)<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><strong>Pour inscrire un syndicat ou un responsable \u00e0 la Vie syndicale <\/strong><\/p>\n<p><strong>\u00e0 l&rsquo;Activit\u00e9 sp\u00e9cifique\u00a0<\/strong> <a href=\"http:\/\/ugict.cgt.fr\/a2s\/\"><strong>http:\/\/ugict.cgt.fr\/a2s\/<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>24 SEPTEMBRE\u00a0: JOURN\u00c9E D\u2019ACTION Les ing\u00e9nieurs et les cadres ont toujours \u00e9t\u00e9 consid\u00e9r\u00e9s comme un \u00ab\u00a0laboratoire\u00a0\u00bb des transformations du travail avant de les g\u00e9n\u00e9raliser \u00e0 l\u2019ensemble des salari\u00e9s. Les r\u00e9formes en cours n\u2019\u00e9chappent pas \u00e0 cette logique.. Portons nos revendications lors des initiatives organis\u00e9es durant la journ\u00e9e d\u2019actions du 24 septembre prochain. [Lire et t\u00e9l\u00e9charger] [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[6,10,50,20,5],"class_list":["post-991","post","type-post","status-publish","format-standard","hentry","category-archives","tag-formation","tag-mobilisation","tag-professions-techniciennes","tag-retraites","tag-vie-syndicale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/991","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/comments?post=991"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/posts\/991\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/media?parent=991"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/categories?post=991"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/a2s\/wp-json\/wp\/v2\/tags?post=991"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}