{"id":107,"date":"2014-01-31T14:37:58","date_gmt":"2014-01-31T13:37:58","guid":{"rendered":"https:\/\/syndicoop.fr\/empreintes\/?p=107"},"modified":"2017-04-19T14:40:46","modified_gmt":"2017-04-19T12:40:46","slug":"democratie-directe-et-democratie-syndicale-1-archives-empreintes-n6","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/empreintes\/2014\/01\/31\/democratie-directe-et-democratie-syndicale-1-archives-empreintes-n6\/","title":{"rendered":"D\u00e9mocratie directe et d\u00e9mocratie syndicale #1 (Archives Empreintes n\u00b06)"},"content":{"rendered":"<p>Contribution de Jocelyne Guiheu, du bureau de l\u2019IHS- UGICT, ancienne responsable de l\u2019UGICT et l\u2019UFMICT sant\u00e9<\/p>\n<p>Pratiques antagonistes ou compl\u00e9mentaires pour des enjeux d\u00e9mocratiques dans l\u2019entreprise et l\u2019intervention dans les crit\u00e8res de gestion ?<!--more--><\/p>\n<p>Ces questions dans notre histoire mondiale politique contemporaine, et l\u2019histoire du syndicalisme fran\u00e7ais, l\u2019histoire de la CGT ont en permanence interrog\u00e9 nos pratiques d\u00e9mocratiques. Fallait-il et faut-il privil\u00e9gier l\u2019une par rapport \u00e0 l\u2019autre ? Eviter la d\u00e9mocratie directe marquerait-elle une posture de classe ? Lui laisser toute la place, n\u2019est ce pas se nier comme syndicalisme r\u00e9volutionnaire ? Adopter une hi\u00e9rarchie des pratiques d\u00e9mocratiques, n\u2019est ce pas se priver d\u2019une v\u00e9ritable analyse de notre syndicalisme de classe et de masse avec son UGICT pour les cadres et techniciens ?<\/p>\n<p>Dans certaines luttes r\u00e9centes illustrant ce propos, l\u2019enjeu n\u2019\u00e9tait-il pas de ne plus exister au profit des courants r\u00e9formistes des Coordinations dans la sant\u00e9, le secteur social ? Les courants pro-d\u00e9mocratie directe des courants du Socialisme Libertaire et des Anarchistes activistes, ont d\u00e9velopp\u00e9 la th\u00e8se d\u2019un antagonisme d\u00e9finitif entre ces pratiques.<\/p>\n<p>Des exp\u00e9riences d\u2019auto gestion dans certains pays d\u2019Am\u00e9rique Latine, sont venues s\u2019ancrer apr\u00e8s 1968 dans le milieu associatif fran\u00e7ais et mouvements citoyens (exp : Riposte La\u00efque,Valeurs et D\u00e9mocratie, etc&#8230;.) venant impr\u00e9gner de nombreux citoyens par ailleurs salari\u00e9s des cat\u00e9gories ICT.<\/p>\n<p>La bataille id\u00e9ologique du lib\u00e9ralisme financier s\u2019est alli\u00e9e \u00e0 cette m\u00e9fiance \u00abambiante\u00bb contre le syndicalisme r\u00e9volutionnaire, la CGT et son UGICT, puisque seule \u00e0 proposer des revendications \u00e0 l\u2019entreprise susceptibles d\u2019inverser la financiarisation .<br \/>\nL\u2019\u00e9volution du salariat, les exigences de changement sur des questions sociales, \u00e9cologiques,le poids des m\u00e9dias sur ces sujets ont fait la part belle \u00e0 tout un discours g\u00e9n\u00e9reux mais \u00abanti pouvoir\u00bb et \u00e0 une d\u00e9sertification syndicale r\u00e9volutionnaire, au profit de syndicats r\u00e9formistes et des associations professionnelles.<\/p>\n<h5>Nous l\u2019avons v\u00e9rifi\u00e9 dans la lutte des travailleurs sociaux, assistantes sociales et \u00e9ducateurs de 1992, la lutte des infirmiers avec l\u2019\u00e9mergence de coordinations. L\u00e0 o\u00f9 le syndicalisme CGT s\u2019affaiblissait.<\/h5>\n<p>Nous avons eu \u00e0 imaginer comment reprendre toute notre place syndicale en \u00e9tant partout pour faire connaitre nos analyses, d\u00e9battre en AG, ne pas imposer un discours de ceux qui ont tout vu et tout compris, nous appuyer sur ce d\u00e9bat de d\u00e9mocratie directe pour l\u00e9gitimer nos propositions revendicatives et y rallier la majorit\u00e9 !<\/p>\n<p>Ne refusant jamais le dialogue avec les coordinations, voire les int\u00e9grant, m\u00eame si entre nous \u00e0 la CGT le d\u00e9bat du \u00abcomment faire\u00bb \u00e9tait parfois difficile !<\/p>\n<p>Militants de l\u2019UFMICT, nous n\u2019 \u00e9tions pas spontan\u00e9ment acquis \u00e0 cette id\u00e9e de la compl\u00e9mentarit\u00e9. C\u2019est la lutte et sa nouvelle forme de d\u00e9mocratie directe qui nous a fait d\u00e9finir nos postures syndicales.<\/p>\n<p>Dans ces luttes, la composante majoritaire \u00abf\u00e9minine\u00bb exer\u00e7ant des m\u00e9tiers de soins travers\u00e9s par les th\u00e9ories du \u00abCare\u00bb, des formations diplomates issues du milieu religieux, et renforc\u00e9es par les th\u00e8ses p\u00e9tainistes (surintendantes d\u2019usine, visiteuses sociales des familles ) n\u2019ont pas pr\u00e9par\u00e9 ces milieux \u00e0 une r\u00e9flexion r\u00e9volutionnaire! Par contre les th\u00e8ses du corporatisme s\u2019y sont d\u00e9velopp\u00e9es ainsi que des m\u00e9thodologies caritatives venant des \u00e9tats-Unis.<\/p>\n<p>Dans ce contexte il \u00e9tait illusoire et nous serions all\u00e9s \u00e0 une exclusion si nous n\u2019avions pas d\u00e9cid\u00e9 de \u00abcoller\u00bb \u00e0 cette coordination en gardant notre identit\u00e9 de syndicat r\u00e9volutionnaire pour obtenir la validation de nos propositions CGT, UFMICT, UGICT.<\/p>\n<p>De m\u00eame en 2011 et 2012, la lutte des cadres de sant\u00e9 de l\u2019AP-HP a impos\u00e9 cette alternance des pratiques:<br \/>\n&#8211; assembl\u00e9es g\u00e9n\u00e9rales de tous les cadres de sant\u00e9 ;<br \/>\n&#8211; r\u00e9unions dans les h\u00f4pitaux pour d\u00e9finir les revendications locales ;<br \/>\n&#8211; r\u00e9unions des SMICT et syndicats CGT locaux ;<br \/>\n&#8211; r\u00e9union du collectif cadres USAP;<br \/>\n&#8211; r\u00e9unions de la coordination des syndicats AP-HP.<\/p>\n<p>Cette volont\u00e9 expresse que chacun puisse avoir la parole est une n\u00e9cessit\u00e9. C\u2019est difficile et fatigant ! Dans ces d\u00e9bats d\u2019AG, les syndicalistes que nous sommes \u00e9valuent le manque d\u2019informations des salari\u00e9s. La complexit\u00e9 des strat\u00e9gies de management est souvent inconnue. Dans ces AG de la d\u00e9mocratie directe, nous apportons les explications, les analyses, dans un riche d\u00e9bat contradictoire. Il y plus de richesses \u00e0 y d\u00e9couvrir que de peurs \u00e0 affronter. Un sociologue disait en 2004, \u00ab Ce qui menace la d\u00e9mocratie, n\u2019est pas son exc\u00e8s, mais son d\u00e9faut \u00bb.<\/p>\n<p>T\u00e9l\u00e9chargez le bulletin n\u00b06 :\u00a0<a href=\"https:\/\/syndicoop.fr\/empreintes\/wp-content\/uploads\/sites\/16\/2014\/01\/IHS-6.pdf\">IHS 6<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contribution de Jocelyne Guiheu, du bureau de l\u2019IHS- UGICT, ancienne responsable de l\u2019UGICT et l\u2019UFMICT sant\u00e9 Pratiques antagonistes ou compl\u00e9mentaires pour des enjeux d\u00e9mocratiques dans l\u2019entreprise et l\u2019intervention dans les crit\u00e8res de gestion ?<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[12],"class_list":["post-107","post","type-post","status-publish","format-standard","hentry","category-archives","tag-democratie"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/107","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/comments?post=107"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/107\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media?parent=107"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/categories?post=107"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/tags?post=107"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}