{"id":114,"date":"2014-12-17T14:44:51","date_gmt":"2014-12-17T13:44:51","guid":{"rendered":"https:\/\/syndicoop.fr\/empreintes\/?p=114"},"modified":"2017-04-19T14:46:12","modified_gmt":"2017-04-19T12:46:12","slug":"archive-empreintes-n9","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/empreintes\/2014\/12\/17\/archive-empreintes-n9\/","title":{"rendered":"Archive Empreintes n\u00b09"},"content":{"rendered":"<div class=\"intro\">\n<p>Num\u00e9ro sp\u00e9cial consacr\u00e9 au compte rendu de l\u2019Assembl\u00e9e G\u00e9n\u00e9rale du 6 novembre 2014<\/p>\n<\/div>\n<p><!--more--><\/p>\n<p>Le Conseil scientifique de l\u2019IHS-UGICT s\u2019est r\u00e9uni le 6 novembre, juste avant l\u2019Assembl\u00e9e g\u00e9n\u00e9rale. Les historiens et les sociologues qui le composent ont \u00e9t\u00e9 vivement inte\u0301ress\u00e9s par la pr\u00e9sentation du travail accompli jusqu\u2019ici par notre Institut : la journ\u00e9e d\u2019\u00e9tude sur la formation permanente, les expositions du cinquantenaire de l\u2019UGICT, la table ronde sur l\u2019historique et les perspectives du statut de cadre, \u00ab L\u2019impensable syndicalisme \u00bb de G\u00e9rard Salkowsky.<\/p>\n<p><strong>Ils l\u2019ont \u00e9t\u00e9, plus encore, par les projets envisag\u00e9s pour la prochaine p\u00e9riode:<\/strong><\/p>\n<ol>\n<li>encore et toujours la formation \u00abtout au long de la vie\u00bb comme on la d\u00e9signe aujourd\u2019hui avec l\u2019apparition r\u00e9cente d\u2019une prise de conscience, dans le milieu des grandes e\u0301coles, d\u2019une articulation, ne\u0301cessaire mais actuellement absente, entre la premie\u0300re formation et les besoins qui se manifestent<\/li>\n<li>les professions de sant\u00e9 et d\u2019action sociale ;<\/li>\n<li>l\u2019aptitude du mouvement syndical a\u0300 prendre en compte les probl\u00e8mes de la profession, du m\u00e9tier, ce qui a \u00e9t\u00e9\u00a0 l\u2019une des sp\u00e9cificit\u00e9s de l\u2019UGICT.<\/li>\n<\/ol>\n<p>Merci a\u0300 Corine Delmas, Ginette Francequin, Guy Groux, Dani\u00e8le Linhart et St\u00e9phane Sirot dont nous attendons certainement autant qu\u2019ils attendent de nous.<\/p>\n<p>T\u00c9L\u00c9CHARGER LE BULLETIN :\u00a0<a href=\"https:\/\/syndicoop.fr\/empreintes\/wp-content\/uploads\/sites\/16\/2017\/04\/EMPREINTES-N\u00b09.pdf\">EMPREINTES N\u00b09<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Num\u00e9ro sp\u00e9cial consacr\u00e9 au compte rendu de l\u2019Assembl\u00e9e G\u00e9n\u00e9rale du 6 novembre 2014<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[3],"class_list":["post-114","post","type-post","status-publish","format-standard","hentry","category-archives","tag-assemblee-generale"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/114","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/comments?post=114"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/114\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media?parent=114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/categories?post=114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/tags?post=114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}