{"id":1151,"date":"2022-11-21T12:30:16","date_gmt":"2022-11-21T11:30:16","guid":{"rendered":"https:\/\/syndicoop.fr\/empreintes\/?p=1151"},"modified":"2022-11-21T12:34:12","modified_gmt":"2022-11-21T11:34:12","slug":"augmentation-en-somme-fixe-ou-en-pourcentage","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/empreintes\/2022\/11\/21\/augmentation-en-somme-fixe-ou-en-pourcentage\/","title":{"rendered":"Augmentation en somme fixe ou en pourcentage"},"content":{"rendered":"<p>Le nivellement des salaires par le bas, leur tassement, est un objectif de tout le temps du patronat.<\/p>\n<p>Son action pour ne pas reconna\u00eetre \u00e0 leur juste prix les qualifications, c\u2019est-\u00e0-dire la force de travail mise en \u0153uvre, redouble d\u2019autant au fur et \u00e0 mesure que celles-ci se d\u00e9veloppent et que leur niveau progresse.<\/p>\n<p>C\u2019est la raison pour laquelle, d\u00e8s les ann\u00e9es 1980, la CGT d\u00e9finit le SMIC comme un salaire minimum correspondant \u00e0 ce qu\u2019a besoin pour vivre un salari\u00e9 sans qualification particuli\u00e8re. D\u00e8s lors qu\u2019un salari\u00e9 acquiert par ses dipl\u00f4mes, sa formation ou son exp\u00e9rience une qualification plus \u00e9lev\u00e9e, celle-ci, mesur\u00e9e par une classification, doit donner lieu \u00e0 un salaire plus \u00e9lev\u00e9 \u00e9galement.<\/p>\n<p>Ces principes de base sont contourn\u00e9s \u00e0 chaque fois que des augmentations en somme fixe interviennent, laissant de c\u00f4t\u00e9 la reconnaissance salariale de la qualification. La qualification est d\u00e9valoris\u00e9e chaque fois que tout ou partie du salaire qui lui correspond ne suit pas l\u2019inflation.<\/p>\n<p>La plupart des luttes des salari\u00e9s qualifi\u00e9s \u00e0 responsabilit\u00e9, singuli\u00e8rement des professions techniciennes, porte sur la reconnaissance de leur qualification dans leur responsabilit\u00e9 et dans le salaire. L\u2019ignorer revient \u00e0 laisser s\u2019op\u00e9rer des oppositions entre cat\u00e9gories de salari\u00e9s qui n\u2019ont pas lieu d\u2019\u00eatre, d\u00e8s lors qu\u2019il s\u2019agit de rassembler tout le salariat face \u00e0 la classe dominante.<\/p>\n<p>Les ing\u00e9nieurs, cadres et techniciens seront d\u2019autant plus impliqu\u00e9s dans les luttes salariales que les revendications de hausse du salaire seront formul\u00e9es en pourcentage car boost\u00e9es par leurs aspirations \u00e0 ce que leur qualification soit reconnue.<\/p>\n<p style=\"text-align: right;\">Jean-Fran\u00e7ois Bolzinger<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le nivellement des salaires par le bas, leur tassement, est un objectif de tout le temps du patronat. Son action pour ne pas reconna\u00eetre \u00e0 leur juste prix les qualifications, c\u2019est-\u00e0-dire la force de travail mise en \u0153uvre, redouble d\u2019autant au fur et \u00e0 mesure que celles-ci se d\u00e9veloppent et que leur niveau progresse. C\u2019est [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1156,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[23],"tags":[],"class_list":["post-1151","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-edito"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/1151","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/comments?post=1151"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/1151\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media\/1156"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media?parent=1151"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/categories?post=1151"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/tags?post=1151"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}