{"id":117,"date":"2016-02-29T15:07:37","date_gmt":"2016-02-29T14:07:37","guid":{"rendered":"https:\/\/syndicoop.fr\/empreintes\/?p=117"},"modified":"2017-04-19T15:14:02","modified_gmt":"2017-04-19T13:14:02","slug":"archive-empreintes-n14","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/empreintes\/2016\/02\/29\/archive-empreintes-n14\/","title":{"rendered":"Archive Empreintes N\u00b014"},"content":{"rendered":"<div class=\"intro\">\n<p>Nous commen\u00e7ons l\u2019ann\u00e9e 2016 avec 71 adh\u00e9rents (42 individuels et 29 Unions f\u00e9d\u00e9rales ou commissions d\u00e9partementales), le double des ann\u00e9es pr\u00e9c\u00e9dentes.<\/p>\n<\/div>\n<p><!--more--><\/p>\n<p>L\u2019Assembl\u00e9e g\u00e9n\u00e9rale, dont vous trouverez le compte rendu dans cette livraison d\u2019empreintes a fait le bilan d\u2019une activit\u00e9 r\u00e9guli\u00e8re et riche. Nous existons depuis sept ans. nous avons d\u00e9sormais une vue plus concr\u00e8te de la fa\u00e7on d\u2019\u00eatre utile \u00e0 l\u2019Ugict et \u00e0 l\u2019ensemble de la Cgt. nous participons aux initiatives de l\u2019lHS-Cgt, aux c\u00f4t\u00e9s de nombreux autres IHS.<\/p>\n<p>La question des archives, le bien le plus pr\u00e9cieux de l\u2019Ugict, reste le d\u00e9fi le plus difficile \u00e0 relever ; nous avan\u00e7ons dans la mise au point de la d\u00e9mat\u00e9rialisation : num\u00e9riser les documents anciens mais aussi normaliser les r\u00e8gles de production au jour le jour de documents num\u00e9riques nouveaux (textes et images) afin d\u2019en faciliter l\u2019archivage. nous y consacrons un maximum d\u2019efforts. et pour cela, nous ne serons jamais trop nombreux.<\/p>\n<p><strong><em>Andr\u00e9 Jaegl\u00e9 pr\u00e9sident de l\u2019IHS-Ugict<\/em><\/strong><\/p>\n<h2>Sommaire :<\/h2>\n<ul>\n<li>Compte rendu de l\u2019assembl\u00e9e g\u00e9n\u00e9rale de l\u2019IHS-Ugict du 10 d\u00e9cembre 2015<\/li>\n<li>8 mars : femmes cadres; le rapport au 2\u00e8me congr\u00e8s de l\u2019Ugic (1967)<\/li>\n<\/ul>\n<p>T\u00c9L\u00c9CHARGER :\u00a0<a href=\"https:\/\/syndicoop.fr\/empreintes\/wp-content\/uploads\/sites\/16\/2017\/04\/EMPREINTES-N\u00b014-1.pdf\">EMPREINTES N\u00b014<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous commen\u00e7ons l\u2019ann\u00e9e 2016 avec 71 adh\u00e9rents (42 individuels et 29 Unions f\u00e9d\u00e9rales ou commissions d\u00e9partementales), le double des ann\u00e9es pr\u00e9c\u00e9dentes.<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[],"class_list":["post-117","post","type-post","status-publish","format-standard","hentry","category-archives"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/117","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/comments?post=117"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/117\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media?parent=117"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/categories?post=117"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/tags?post=117"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}