{"id":1193,"date":"2023-03-09T13:03:45","date_gmt":"2023-03-09T12:03:45","guid":{"rendered":"https:\/\/syndicoop.fr\/empreintes\/?p=1193"},"modified":"2023-03-09T16:29:33","modified_gmt":"2023-03-09T15:29:33","slug":"metallurgie-1972-les-cadres-adversaires-ou-allies","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/empreintes\/2023\/03\/09\/metallurgie-1972-les-cadres-adversaires-ou-allies\/","title":{"rendered":"M\u00e9tallurgie 1972 : Les cadres, adversaires ou alli\u00e9s ?"},"content":{"rendered":"<p><em>Nous reproduisons ici quelques extraits d\u2019une brochure r\u00e9alis\u00e9e en novembre 1972 par la f\u00e9d\u00e9ration de la m\u00e9tallurgie (FTM) CGT, pr\u00e9c\u00e9dant la mise sur pied de l\u2019Ufict M\u00e9tallurgie quelques mois plus tard en janvier 1973<\/em>. Le principe de ralliement des non-ouvriers \u00e0 la classe ouvri\u00e8re est d\u00e9pass\u00e9. <em>L\u2019implication des ICT dans le mouvement mai 68 a bouscul\u00e9 les choses, m\u00eame si<\/em> l<em>a conception d\u2019alliance entre ouvriers et ICT qui pr\u00e9vaut \u00e0 l\u2019\u00e9poque ne sera v\u00e9ritablement remplac\u00e9e par la conception de rassemblement du salariat qu\u2019au sortir de la p\u00e9riode du programme commun de la gauche<\/em>.<\/p>\n<p>&nbsp;<\/p>\n<h3>Le cadre hier, le cadre aujourd\u2019hui<\/h3>\n<p>Il y a quelques ann\u00e9es seulement, il \u00e9tait impensable \u00bb que les ing\u00e9nieurs, les cadres, les techniciens et agents de ma\u00eetrise puissent s&rsquo;inscrire dans un mouvement syndical. Ils \u00e9taient peu nombreux faisant presque partie de la famille du\u00a0\u00a0 patron. SI cela existe encore de nos jours de ci, de l\u00e0, aujourd&rsquo;hui ils sont des milliers, de plus en plus \u00e9loign\u00e9s des banquiers, des Dassault, des Boussac, des Schneider, etc. ; on les appelle cadres sup\u00e9rieurs, cadres ou cadres moyens comme les techniciens et les agents de ma\u00eetrise.<\/p>\n<p>Dans le m\u00eame temps qu&rsquo;ils s&rsquo;\u00e9loignent du \u00ab soleil \u00bb, sauf quelque 1 % de grands \u00ab managers \u00bb irr\u00e9cup\u00e9rables, dans leur grande masse ils voient leur situation professionnelle ou sociale, ou les deux, se d\u00e9t\u00e9riorer.<\/p>\n<p>Plus ils deviennent nombreux, et c&rsquo;est le cas actuellement, plus ils co\u00fbtent au patron et cela est \u00e0 retrancher de ses profits, alors&#8230; ils se retrouvent comme les ouvriers, devant le m\u00eame rapace.<\/p>\n<p>D&rsquo;autre part, plus le capital devient la propri\u00e9t\u00e9 d\u2019une minorit\u00e9 de capitalistes plus les grandes d\u00e9cisions financi\u00e8res et techniques leur \u00e9chappent, plus leur libert\u00e9 de cr\u00e9ation ou de d\u00e9cision est limit\u00e9e.<\/p>\n<p>Ils ex\u00e9cutent ce qui est d\u00e9cid\u00e9 par d&rsquo;autres : la gestion, l&rsquo;administration, la technique, l&rsquo;\u00e9tude, les m\u00e9thodes sont morcel\u00e9es, ils se retrouveront dans l&rsquo;un ou l&rsquo;autre secteur d&rsquo;activit\u00e9 toujours plus cloisonn\u00e9s et devant ex\u00e9cuter.<\/p>\n<p>Dans le m\u00eame temps, les ouvriers doivent se battre de plus en plus fort, de plus en plus souvent, tous ensemble, contre la politique sociale qui leur est faite.<\/p>\n<p>Les ing\u00e9nieurs, les cadres, les techniciens, le constatent et y r\u00e9fl\u00e9chissent ; de plus en plus ils soutiennent l\u2019action des travailleurs ou y participent.<\/p>\n<p>C&rsquo;est ainsi qu&rsquo;en 1963, les ing\u00e9nieurs des Mines ont fait preuve d&rsquo;une neutralit\u00e9 bienveillante vis-\u00e0-vis des mineurs en gr\u00e8ve.<\/p>\n<p>Quelques ann\u00e9es plus tard, chez NEYRPIC, les ing\u00e9nieurs, les cadres, les techniciens refusaient d&rsquo;appliquer une politique patronale contraire aux int\u00e9r\u00eats des ouvriers plac\u00e9s sous leurs ordres et, depuis il y a eu 1968&#8230;<\/p>\n<p>C&rsquo;est en 1968 que l&rsquo;on a bien vu que, saisissant la lutte des ouvriers, les ing\u00e9nieurs, les cadres et les techniciens remettaient en cause le droit divin du patronat.<\/p>\n<p>Autrement dit, de plus en plus ils remettent en cause les d\u00e9cisions des monopoles, pour eux-m\u00eames, et pour les ouvriers. Cela nous permet de dire que les ing\u00e9nieurs, les cadres et les techniciens tendent \u00e0 \u00e9chapper \u00e0 la mainmise du patronat sur eux.<\/p>\n<p>C&rsquo;est un grave probl\u00e8me pour les monopoles car, pour faire face \u00e0 la concurrence, pour am\u00e9liorer la productivit\u00e9, pour accro\u00eetre les profits, ils ont besoin, non seulement de faire pression sur les aspirations \u00e9conomiques, sociales et politiques des ouvriers, mais il leur faut que tout l&rsquo;encadrement lui-m\u00eame \u00ab se d\u00e9voue \u00bb pour r\u00e9aliser leur objectifs.<\/p>\n<p>Autrement dit, les monopoles ont besoin de gagner les ing\u00e9nieurs, les cadres et les techniciens \u00e0 leur objectif de profits maximum.<\/p>\n<p>Pour cela ils manient \u00e0 la fois le b\u00e2ton et la carotte car, si les ing\u00e9nieurs, les cadres et les techniciens n\u2019adh\u00e8rent pas aux objectifs que se\u00a0 fixent les monopoles, alors toute leur politique est remise en cause puisque d\u00e9j\u00e0, les ouvriers les rejettent.<\/p>\n<p>D&rsquo;o\u00f9 l&rsquo;intense bataille d&rsquo;intoxication men\u00e9e par le patronat et le pouvoir en direction des ing\u00e9nieurs, des cadres, et techniciens.<\/p>\n<p>Pour le patronat et le pouvoir, tous les moyens sont bons pourvu qu&rsquo;ils permettent de gagner les ICT \u00e0 leurs vues, cela aidant \u00e0 les imposer \u00e0 la classe ouvri\u00e8re,<\/p>\n<p>Ceci conduit les monopoles \u00e0 vouloir isoler les ing\u00e9nieurs, les cadres et les techniciens de la classe ouvri\u00e8re, voire \u00e0 les dresser contre elle.<\/p>\n<p>\u2026<\/p>\n<h3>Une position de classe\u00a0: les cadres nos alli\u00e9s.<\/h3>\n<p>La constatation que nous pouvons faire, est qu&rsquo;il s&rsquo;agit donc de salari\u00e9s ayant comme les ouvriers des pr\u00e9occupations \u00e0 satisfaire.<\/p>\n<p>Ce sont donc des salari\u00e9s qui ont \u00e0 d\u00e9fendre des besoins contre le patronat.<\/p>\n<p>Ce serait une erreur de confondre la masse des ing\u00e9nieurs, cadres, techniciens et agents de ma\u00eetrise avec les actionnaires des entreprises capitalistes ou avec quelques grands commis irr\u00e9cup\u00e9rables ne repr\u00e9sentant qu\u2019environ 1 % de la masse de ces salari\u00e9s.<\/p>\n<p>Nous devons avoir pr\u00e9sent \u00e0 l&rsquo;esprit, que c&rsquo;est le capitaliste qui a besoin de ces salari\u00e9s, mais il presse sur leur masse salariale, comme il presse sur celle des ouvriers et des employ\u00e9s.<\/p>\n<p>Nous devons \u00eatre conscients que, toutes d\u00e9marches revendicatives des uns et des autres, ne peuvent que se dresser contre le m\u00eame exploiteur.<\/p>\n<p>Ce serait faire le jeu du patronat que de consid\u00e9rer qu&rsquo;il puisse y avoir des antagonismes d\u2019int\u00e9r\u00eats entre les ICT et les ouvriers, alors que la contradiction principale d&rsquo;int\u00e9r\u00eats se situe bien entre l&rsquo;ensemble des salari\u00e9s et le capital.<\/p>\n<p>\u2026<\/p>\n<h3>Face au capital, une seule organisation de masse et d\u00e9mocratique, la CGT<\/h3>\n<p>Comme le pr\u00e9cisent les statuts de la CGT, il suffit d&rsquo;\u00eatre salari\u00e9 pour \u00eatre admis dans ses rangs\u00a0:<\/p>\n<p>\u00ab La Conf\u00e9d\u00e9ration G\u00e9n\u00e9rale du Travail, r\u00e9gie par les pr\u00e9sents statuts, groupe toutes les organisations rassemblant, sans distinction d&rsquo;opinions politiques, philosophiques et religieuses, les salari\u00e9s conscients de la lutte \u00e0 mener pour d\u00e9fendre leurs int\u00e9r\u00eats moraux et professionnels. \u00bb<\/p>\n<p>La CGT est donc une organisation de masse puisqu&rsquo;elle peut regrouper en son sein l&rsquo;ensemble des salari\u00e9s face au capital.<\/p>\n<p>C&rsquo;est dans ce sens qu&rsquo;il faut comprendre que la CGT est une organisation de classe pour tous les salari\u00e9s.<\/p>\n<p>Il s&rsquo;agit, par cons\u00e9quent, de faire leur place, toute leur place aux ICT dans la CGT.<\/p>\n<p>C&rsquo;est ainsi, que la CGT a cr\u00e9\u00e9 en son sein l\u2019UGICT coordonnant, impulsant l&rsquo;activit\u00e9 de toutes les organisations d\u2019ing\u00e9nieurs, de cadres et de techniciens suivant les diff\u00e9rentes branches d&rsquo;industrie.<\/p>\n<p>Nous sommes, par cons\u00e9quent, oppos\u00e9s \u00e0 une organisation du type de la CGC laquelle entend isoler les ing\u00e9nieurs, les cadres, les techniciens, les agents de ma\u00eetrise de la classe ouvri\u00e8re.<\/p>\n<p>De m\u00eame nous ne pouvons partager l&rsquo;orientation de la CFDT tendant \u00e0 les mettre objectivement dans le m\u00eame moule que les ouvriers.\u00a0 C&rsquo;est pourquoi nous disons que la CGT est l&rsquo;organisation de classe et de masse comportant des syndicats d&rsquo;ouvriers et des syndicats d&rsquo;ICT.<\/p>\n<p>D&rsquo;ailleurs dans les statuts de la FTM, il est dit :<\/p>\n<p>\u00ab\u00a0Les employ\u00e9s, techniciens, dessinateurs et agents de ma\u00eetrise, ou les employ\u00e9s d&rsquo;une part, les techniciens, dessinateurs et agents de ma\u00eetrise d\u2019autre part, constituent leurs propres Syndicats. Les cadres et ing\u00e9nieurs s&rsquo;organisent dans le cadre de leur syndicat national le SNCIM (syndicat national des ing\u00e9nieurs et cadres de la m\u00e9tallurgie) \u00bb<\/p>\n<p>Ces syndicats adh\u00e9rant \u00e0 la F\u00e9d\u00e9ration, aux UD, donc \u00e0 la CGT.<\/p>\n<p>\u2026<\/p>\n<h3>Pourquoi une Union F\u00e9d\u00e9rale d\u2019ICT\u00a0?<\/h3>\n<p>Pour mener jusqu&rsquo;au bout une activit\u00e9 sp\u00e9cifique dans notre F\u00e9d\u00e9ration, Il nous faut donner les moyens aux organisations sp\u00e9cifiques de pouvoir coordonner leurs actions, de pouvoir impulser cette action, de pouvoir traduire l&rsquo;orientation des USTM (union syndicale des travailleurs de la m\u00e9tallurgie) et comit\u00e9s de coordination, des syndicats d&rsquo;entreprises ou locaux, afin de gagner les ICT \u00e0 l&rsquo;action.<\/p>\n<p>Nous pensons que les ing\u00e9nieurs, les cadres et les techniciens doivent pouvoir coordonner leurs efforts, s&rsquo;adresser eux-m\u00eames \u00e0 leurs coll\u00e8gues, les mobiliser aux c\u00f4t\u00e9s des ouvriers et favoriser une CGT de masse et d\u00e9mocratique.<\/p>\n<p>Dans ce sens, nous convions les syndiqu\u00e9s, les organisations \u00e0 diff\u00e9rents \u00e9chelons, \u00e0 prendre toutes les initiatives possibles conduisant \u00e0 la fois au d\u00e9veloppement de nos bases organis\u00e9es et \u00e0 leur coordination.<\/p>\n<p>L\u2019Union f\u00e9d\u00e9rale sera l\u2019\u00e9manation de toutes les organisations sp\u00e9cifiques.<\/p>\n<p>L\u2019Union f\u00e9d\u00e9rale d\u00e9finira et mettra en \u0153uvre l\u2019action de la F\u00e9d\u00e9ration parmi les ing\u00e9nieurs, les cadres, les techniciens et les agents de ma\u00eetrise en proc\u00e9dant de la m\u00eame orientation qui a conduit la CGT \u00e0 la cr\u00e9ation de I\u2019UGICT \u00e0 laquelle les ICT de la m\u00e9tallurgie adh\u00e8reront.<\/p>\n<p>L\u2019Union F\u00e9d\u00e9rale assurera l\u2019information, la liaison, la coordination des organisations sp\u00e9cifiques dans l\u2019orientation et des actions de la FTM.<\/p>\n<p>L\u2019Union F\u00e9d\u00e9rale pourra repr\u00e9senter les ICT et agents de ma\u00eetrise dans les commissions et organismes f\u00e9d\u00e9raux et l\u2019informera par tous les moyens des probl\u00e8mes particuliers \u00e0 ces salari\u00e9s.<\/p>\n<p>L\u2019Union F\u00e9d\u00e9rale assurera la liaison de ces cat\u00e9gories de salari\u00e9s et leur proposera des modalit\u00e9s d\u2019actions qui tiennent compte de leurs pr\u00e9occupations et conditions sp\u00e9cifiques.<\/p>\n<p>Pourront faire partie de l\u2019Union F\u00e9d\u00e9rale, les ing\u00e9nieurs, les cadres et aussi les techniciens qui seront int\u00e9ress\u00e9s au premier chef, par la plate-forme revendicative qui leur sera propos\u00e9e.<\/p>\n<p>Nous pensons, en particulier, que les contrema\u00eetres, les dessinateurs d\u2019\u00e9tudes, les pr\u00e9parateurs, les programmeurs, les technico-commerciaux, les informaticiens, les \u00e9lectroniciens, auront toute leur place dans l\u2019Union F\u00e9d\u00e9rale, partie prenante de la F\u00e9d\u00e9ration des Travailleurs de la M\u00e9tallurgie.<\/p>\n<p>Les ICT doivent pouvoir intervenir dans les choix et les orientations, pouvoir sortir du domaine limit\u00e9 o\u00f9 le patronat les confine, intervenir sur les objectifs sociaux et \u00e9conomiques du pays.<\/p>\n<p>Pour cela, il faut une v\u00e9ritable d\u00e9mocratie leur permettant avec les ouvriers, les employ\u00e9s, de d\u00e9terminer les grands choix de l\u2019\u00e9conomie du pays.<\/p>\n<p>Avec les ouvriers, ils ont tout \u00e0 gagner \u00e0 appliquer leurs connaissances dans le but de satisfaire les besoins de notre peuple et non le profit.<\/p>\n<p>L\u00e0 encore, les int\u00e9r\u00eats des uns et des autres convergent contre le capital.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nous reproduisons ici quelques extraits d\u2019une brochure r\u00e9alis\u00e9e en novembre 1972 par la f\u00e9d\u00e9ration de la m\u00e9tallurgie (FTM) CGT, pr\u00e9c\u00e9dant la mise sur pied de l\u2019Ufict M\u00e9tallurgie quelques mois plus tard en janvier 1973. Le principe de ralliement des non-ouvriers \u00e0 la classe ouvri\u00e8re est d\u00e9pass\u00e9. L\u2019implication des ICT dans le mouvement mai 68 a [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":1204,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2],"tags":[34],"class_list":["post-1193","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-archives","tag-metallurgie"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/1193","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/comments?post=1193"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/1193\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media\/1204"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media?parent=1193"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/categories?post=1193"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/tags?post=1193"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}