{"id":734,"date":"2018-01-14T10:45:22","date_gmt":"2018-01-14T09:45:22","guid":{"rendered":"https:\/\/syndicoop.fr\/empreintes\/?p=734"},"modified":"2018-01-14T10:45:22","modified_gmt":"2018-01-14T09:45:22","slug":"voeux-et-perspectives-pour-2018","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/empreintes\/2018\/01\/14\/voeux-et-perspectives-pour-2018\/","title":{"rendered":"V\u0153ux et perspectives pour 2018"},"content":{"rendered":"<p>Chers amis<\/p>\n<p>Permettez-moi tout d\u2019abord, au nom de l\u2019IHS Ugict, de vous souhaiter une bonne et heureuse ann\u00e9e et une bonne sant\u00e9 pour vous et vos proches. Souhaitons aussi ensemble une belle ann\u00e9e de d\u00e9veloppement pour notre Institut. La pertinence de son existence n\u2019est plus \u00e0 d\u00e9montrer bien qu\u2019elle soit toujours \u00e0 conforter.<\/p>\n<p>A l\u2019occasion du 18<sup>\u00e8me<\/sup> congr\u00e8s de l\u2019Ugict, qui se tiendra en mars \u00e0 Perpignan, nous \u00e9diterons un fascicule retra\u00e7ant les 10 ans de son activit\u00e9. Nous avons \u00e9galement l\u2019intention de poursuivre l\u2019expression des militants Ugict qui ont v\u00e9cu les gr\u00e8ves de mai juin 68 puisque nous c\u00e9l\u00e9brons cette ann\u00e9e le 50<sup>\u00e8me<\/sup> anniversaire de ce grand mouvement social. Nous faisons d\u2019ailleurs appel \u00e0 contribution des militants Ugict qui ont v\u00e9cu cette p\u00e9riode pour en t\u00e9moigner.<\/p>\n<p>Nous entamons \u00e9galement un travail sur la question de l\u2019industrie dans notre pays. L\u2019Ugict depuis sa cr\u00e9ation et tout au long de ces derni\u00e8res ann\u00e9es, des syndicats et militants sp\u00e9cifiques ont en tant que tels, contribu\u00e9 \u00e0 l\u2019expression et aux luttes de la CGT, fait des propositions, pour la sauvegarde et le d\u00e9veloppement du potentiel industriel de la France. Dans ce domaine aussi n\u2019h\u00e9sitez pas \u00e0 t\u00e9moigner.<\/p>\n<p>D\u2019autres chantiers sont en cours ou en projet dont nous parlerons dans notre fascicule d\u00e9cennal\u00a0!<\/p>\n<p>Enfin, vous constatez que ce nouveau N\u00b0 d\u2019Empreintes vous est pr\u00e9sent\u00e9 sous la forme nouvelle de News- letter. Comme quoi\u00a0! Travailler sur le pass\u00e9 n\u2019interdit pas la modernit\u00e9. Cela devrait nous permettre \u00a0une r\u00e9alisation plus souple et vous permettre une lecture plus agile\u00a0!<\/p>\n<p>Souhaitons qu\u2019il en soit ainsi\u00a0!<\/p>\n<p>Julien GUERIN<\/p>\n<p>Responsable de la publication<\/p>\n<p>NB: Ce texte est destin\u00e9 \u00e0 la publication du n\u00b0 19 d&rsquo;Empreintes.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chers amis Permettez-moi tout d\u2019abord, au nom de l\u2019IHS Ugict, de vous souhaiter une bonne et heureuse ann\u00e9e et une bonne sant\u00e9 pour vous et vos proches. Souhaitons aussi ensemble une belle ann\u00e9e de d\u00e9veloppement pour notre Institut. La pertinence de son existence n\u2019est plus \u00e0 d\u00e9montrer bien qu\u2019elle soit toujours \u00e0 conforter. A l\u2019occasion [&hellip;]<\/p>\n","protected":false},"author":349,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-734","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/734","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/users\/349"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/comments?post=734"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/734\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media?parent=734"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/categories?post=734"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/tags?post=734"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}