{"id":770,"date":"2018-05-22T20:21:05","date_gmt":"2018-05-22T18:21:05","guid":{"rendered":"https:\/\/syndicoop.fr\/empreintes\/?p=770"},"modified":"2018-05-22T20:21:05","modified_gmt":"2018-05-22T18:21:05","slug":"ihs-et-experts","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/empreintes\/2018\/05\/22\/ihs-et-experts\/","title":{"rendered":"IHS et experts"},"content":{"rendered":"<p>R\u00e9flexions sur le travail conjoint des experts, juristes, historiens et militants syndicalistes dans nos instituts.<\/p>\n<p>Depuis la mise en place des diff\u00e9rends instituts auxquels je participe \u2013IHS FTM m\u00e9tallurgie, IHS Ufict m\u00e9tallurgie, IHS Ugict-, je me bats pour que soit retenue l\u2019id\u00e9e suivante : le r\u00f4le de nos instituts n\u2019est pas de chanter la gloire de notre mouvement syndical et des militants notoires du mouvement ouvrier, mais plut\u00f4t de revisiter de mani\u00e8re objective ce qu\u2019ont \u00e9t\u00e9 nos analyses, prises de positions et actions, avec leurs ombres et leurs lumi\u00e8res, sans vouloir donner de le\u00e7ons aux jeunes dirigeants actuels de nos organisations, et dans le seul soucis de savoir avec eux d\u2019o\u00f9 nous venons collectivement tout en leur laissant la libert\u00e9 de juger en quoi cette histoire conditionne leur propre action.<br \/>\nLe corollaire pour le travail de nos instituts ne peut \u00eatre que l\u2019organisation d\u00e9lib\u00e9r\u00e9e et accept\u00e9e d\u2019une \u00ab tension \u00bb entre le corps militant d\u2019une part et les \u00ab experts \u00bb, dans leur diversit\u00e9, qui participent \u00e0 nos travaux, notamment ceux du \u00ab Conseil Scientifique \u00bb de l\u2019 IHS conf\u00e9d\u00e9ral. Or la vie et les initiatives de nos instituts montrent que l\u2019exercice n\u2019est pas si simple.<br \/>\nDu cot\u00e9 corps militant, les \u00e9crits et initiatives sont essentiellement centr\u00e9es sur nos gloires pass\u00e9es (ce qui n\u2019est pas \u00e0 n\u00e9gliger), et quand les th\u00e8mes choisis sont en rapport avec des enjeux d\u2019actualit\u00e9, tous n\u2019\u00e9chappent pas, dans leur fa\u00e7on de parler du pass\u00e9, \u00e0 la tentation d\u2019intervenir et peser dans les d\u00e9bats d\u2019orientation actuels\u2026..En tout cas, tr\u00e8s peu d\u2019exemples d\u2019un retour un tant soit peu critique sur tel ou tel \u00e9pisode controvers\u00e9 du si\u00e8cle pass\u00e9\u2026..Non, nous n\u2019avons pas toujours vu, analys\u00e9 ou d\u00e9cid\u00e9 juste. Et revenir sur d\u2019\u00e9ventuelles erreurs, d\u00e9cisions prises mais pas appliqu\u00e9es, objectifs non atteints, etc, peut \u00eatre aussi instructif et utile que d\u2019admirer nos acquis et r\u00e9ussites.<br \/>\nDu c\u00f4t\u00e9 experts, mon exp\u00e9rience r\u00e9cente des contributions au prochain colloque sur \u00ab la CGT et le mouvement social, producteurs de droits \u00bb, r\u00e9sume assez bien mes interrogations (c\u2019est ce qui motive cette note). Ma contribution,(sur les luttes de 68 dans la m\u00e9tallurgie et le r\u00f4le des ICT dans l\u2019\u00e9laboration d\u2019un nouveau syst\u00e8me de classifications qui sera n\u00e9goci\u00e9 \u00e0 l\u2019UIMM quatre ann\u00e9es durant pour aboutir en 1973 \u00e0 la grille actuelle et \u00e0 la cr\u00e9ation de l\u2019UFICT), a \u00e9t\u00e9 retenue par le Conseil Scientifique, mais pas les quatre autres contributions de l\u2019IHS M\u00e9tallurgie\u2026\u2026.Ce qui en soi peut ne pas poser de probl\u00e8me, \u00eatre justifi\u00e9 et accept\u00e9. Mais l\u00e0 ou il y a question, c\u2019est quand leurs auteurs et les membres de l\u2019IHS M\u00e9tallurgie qui participent aux travaux pr\u00e9paratoires au colloque sont incapables de dire pourquoi et sur quels crit\u00e8res le Comit\u00e9 a tranch\u00e9. Tous, voulons savoir ce qui a int\u00e9ress\u00e9 dans ma contribution et quelles \u00e9taient les insuffisances des autres. Il est impossible d\u2019envisager d\u2019avancer et de progresser ensemble, militants et experts, si \u00e0 l\u2019occasion de situations de ce type nous n\u2019en profitons pas pour mieux comprendre ce que cherchent les uns et les autres. Je ne peux que soutenir l\u2019IHS M\u00e9tallurgie dans sa demande de rencontre avec le Comit\u00e9 Scientifique.<\/p>\n<p>Michel DAUBA : membre du secr\u00e9tariat de l\u2019UFICT m\u00e9tallurgie de 1969 \u00e0 1976 et membre du Bureau de l\u2019UGICT de 1969 \u00e0 1983.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>R\u00e9flexions sur le travail conjoint des experts, juristes, historiens et militants syndicalistes dans nos instituts. Depuis la mise en place des diff\u00e9rends instituts auxquels je participe \u2013IHS FTM m\u00e9tallurgie, IHS Ufict m\u00e9tallurgie, IHS Ugict-, je me bats pour que soit retenue l\u2019id\u00e9e suivante : le r\u00f4le de nos instituts n\u2019est pas de chanter la gloire [&hellip;]<\/p>\n","protected":false},"author":349,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"class_list":["post-770","post","type-post","status-publish","format-standard","hentry","category-blog"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/770","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/users\/349"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/comments?post=770"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/770\/revisions"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media?parent=770"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/categories?post=770"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/tags?post=770"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}