{"id":870,"date":"2019-09-15T09:38:16","date_gmt":"2019-09-15T07:38:16","guid":{"rendered":"https:\/\/syndicoop.fr\/empreintes\/?p=870"},"modified":"2019-10-07T09:25:38","modified_gmt":"2019-10-07T07:25:38","slug":"le-travail-social-au-coeur-dinjonctions-contradictoires","status":"publish","type":"post","link":"https:\/\/syndicoop.fr\/empreintes\/2019\/09\/15\/le-travail-social-au-coeur-dinjonctions-contradictoires\/","title":{"rendered":"Le travail social au c\u0153ur d&rsquo;injonctions contradictoires"},"content":{"rendered":"<p>Un article de Jocelyne GUIHEU<\/p>\n<p><span style=\"color: #ff0000;\"><strong>Travail social : Au c\u0153ur d\u2019injonctions contradictoires d\u2019o\u00f9 la difficult\u00e9 des engagements.<\/strong><\/span><\/p>\n<p>Le travail social a un engagement ambigu, contradictoire, voire paradoxal, car il est \u00e0 la fois au service des plus pauvres et aussi repr\u00e9sentant d\u2019un syst\u00e8me producteur de pauvret\u00e9.<\/p>\n<p>Ainsi Claude Roger Julier, sociologue, d\u00e9finissait-il le travail social dans un ouvrage en 2004 : \u00ab Ce Travail serait une articulation entre l\u2019\u00e9conomie de march\u00e9 et des gouvernements d\u00e9mocratiques \u00bb.<\/p>\n<p>Ce serait-il aussi simpliste ?<\/p>\n<p>Dans un double r\u00e9f\u00e9rentiel, assistance et action sociale, nous pouvons, militant.e.s Ugict-CGT, militant.e.s \u00ab historiques \u00bb que nous avons per\u00e7u dans nos luttes et \u00e0 travers nos analyses, plus qu\u2019une articulation.<\/p>\n<p>Pour nous il s\u2019agit d\u2019une utilisation du travail social par le syst\u00e8me \u00e9conomique et des gouvernements \u00ab suppos\u00e9s \u00bb d\u00e9mocratiques ! Les moyens donn\u00e9s \u00e0 l\u2019action sociale et l\u2019assistance individuelle ne sont que des outils d\u2019accompagnement dans les crises \u00e9conomiques et sociales cr\u00e9\u00e9es par la financiarisation de toute l\u2019\u00e9conomie par le syst\u00e8me capitaliste.<\/p>\n<p>L\u2019action professionnelle se situe au c\u0153ur des contradictions dans un syst\u00e8me d\u2019in\u00e9galit\u00e9s \u00e9conomiques des populations suivies et les commandes manag\u00e9riales viennent soutenir a minima les besoins des usagers.<\/p>\n<p>Le syst\u00e8me des aides sociales devient un accompagnement permanent de la pr\u00e9carit\u00e9, sans agir sur les causes.<\/p>\n<p>Les \u00e9tudes de travail social construisent le futur professionnel en tant que \u00ab m\u00e9diateur \u00bb des probl\u00e9matiques pos\u00e9es et non comme acteur de changements ou comme \u00ab veilleur \u00bb social capable par sa clinique et ses rapports d\u2019infl\u00e9chir d\u2019une quelconque mani\u00e8re la trajectoire sociale des usagers.<\/p>\n<p>Il se trouve par ailleurs \u00ab englu\u00e9 \u00bb, bloqu\u00e9 dans son action professionnelle, dans un conflit de loyaut\u00e9, oscillant entre deux positions : s\u2019il allait jusqu\u2019au bout de sa logique de soutien des personnes, ne serait-il pas irresponsable vis-\u00e0-vis de ses mandataires, gouvernement, \u00e9lus, directions, cadres, qui lui dictent le cadre de ses missions et le moment o\u00f9 elles s\u2019arr\u00eatent ?<\/p>\n<p>Il s\u2019en suit pour les assistant.e.s de service social et les \u00e9ducateurs-trices sp\u00e9cialis\u00e9.e.s, une difficult\u00e9, une retenue \u00e0 s\u2019engager syndicalement, car il se trouve au c\u0153ur d\u2019une \u00e9norme ambivalence.<\/p>\n<p>Le travailleur social devient, comme l\u2019\u00e9crit Claude Roger Julier, \u00ab l\u2019ambulancier du progr\u00e8s \u00bb le malaise professionnel est immense, car consid\u00e9r\u00e9 comme absolument n\u00e9cessaire pour assurer une \u00ab paix sociale \u00bb, un lieu o\u00f9 peuvent s\u2019exprimer les douleurs dans les convertir en revendications, ce travail social est syst\u00e9matiquement d\u00e9nigr\u00e9 par les m\u00eames car consid\u00e9r\u00e9 comme pointant les insuffisances et les \u00e9checs des gouvernements.<\/p>\n<p>\u00ab On lui reproche ce qu\u2019on lui commande de faire\u2026 \u00bb<\/p>\n<p>Plac\u00e9s dans cette ambigu\u00eft\u00e9, il est difficile de se resituer dans ne \u00ab version \u00bb diff\u00e9rente des finalit\u00e9s du travail social en s\u2019engageant syndicalement. Il devient compliqu\u00e9 de poser des revendications professionnelles lorsque le quotidien se nourrit de contradictions. Ceux qui le tentent sont minoritaires et la majorit\u00e9 se tourne plut\u00f4t vers des supervisions qui tentent les am\u00e9nagements de conscience !<\/p>\n<p>Quand le travailleur social n\u2019a \u00e0 vendre que \u00ab mis\u00e8re, souffrances, \u00e9checs \u00bb cela rend \u00ab frileux \u00bb pour parler de ses propres interrogations et de son \u00ab mal-\u00eatre \u00bb professionnel voir de son incapacit\u00e9 \u00e0 \u00ab bien faire \u00bb son m\u00e9tier.<\/p>\n<p>Pour venir renforcer ce mal-vivre professionnel les techniques manag\u00e9riales sont venues renforcer les difficult\u00e9s : demandes de statistiques, fichage des populations, informatisation, diminution du nombre de professionnels, refus de formations continues, augmentation du nombre de r\u00e9unions et de commandes institutionnelles \u00e0 vis\u00e9es \u00e9conomiques, tout ceci s\u2019est construit progressivement au d\u00e9triment du temps d\u2019\u00e9coute, d\u2019accompagnement.<\/p>\n<p>Et pourtant ! Le fondement m\u00eame de la relation singuli\u00e8re dans l\u2019entretien avec l\u2019usager est \u00e9minemment symbolique et essentielle dans ce qui va \u00eatre \u00ab activ\u00e9 \u00bb avec l\u2019autre \u00e9cout\u00e9, conseill\u00e9, ce qui va \u00eatre n\u00e9goci\u00e9 dans une communication duelle.<\/p>\n<p>Or les politiques sociales placent le travailleur social dans une \u00ab r\u00e9duction \u00bb de sa fonction dans l\u2019action symbolique pour le positionner dans une fonction de valeur marchande. De fait le travail social se confronte en permanence \u00e0 son \u00e9thique, sa d\u00e9ontologie, ses comp\u00e9tences et aux commandes d\u2019efficience de ses actions notamment en privil\u00e9giant l\u2019application \u00ab en nombre \u00bb des dispositifs sociaux.<\/p>\n<p>Les politiques de r\u00e9sultats viennent remplacer la mise en \u0153uvre des vraies finalit\u00e9s sociales, des principes \u00e9nonc\u00e9s dans les formations :<\/p>\n<p><strong><span style=\"color: #ff0000;\">\u00ab Restaurer l\u2019autonomie de personnes en difficult\u00e9 et la citoyennet\u00e9 des usagers faisant appel aux travailleurs sociaux \u00bb.<\/span><\/strong><\/p>\n<p>Septembre 2019<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Un article de Jocelyne GUIHEU Travail social : Au c\u0153ur d\u2019injonctions contradictoires d\u2019o\u00f9 la difficult\u00e9 des engagements. Le travail social a un engagement ambigu, contradictoire, voire paradoxal, car il est \u00e0 la fois au service des plus pauvres et aussi repr\u00e9sentant d\u2019un syst\u00e8me producteur de pauvret\u00e9. Ainsi Claude Roger Julier, sociologue, d\u00e9finissait-il le travail social [&hellip;]<\/p>\n","protected":false},"author":349,"featured_media":894,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[7],"class_list":["post-870","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog","tag-travail-social"],"_links":{"self":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/870","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/users\/349"}],"replies":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/comments?post=870"}],"version-history":[{"count":0,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/posts\/870\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media\/894"}],"wp:attachment":[{"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/media?parent=870"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/categories?post=870"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/syndicoop.fr\/empreintes\/wp-json\/wp\/v2\/tags?post=870"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}